{"id":7762,"date":"2020-06-18T07:43:02","date_gmt":"2020-06-18T12:43:02","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7762"},"modified":"2020-06-30T19:17:27","modified_gmt":"2020-07-01T00:17:27","slug":"los-colores-unidos-del-islam-2","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/es\/los-colores-unidos-del-islam-2\/","title":{"rendered":"Los Colores Unidos del Islam"},"content":{"rendered":"<h3><strong>(parte 1 de 3)<\/strong><\/h3>\n<p>\u201cDios le pregunt\u00f3: \u00bfQu\u00e9 te impidi\u00f3 hacer la reverencia cuando te lo orden\u00e9? Respondi\u00f3: Yo soy mejor que \u00e9l, pues a m\u00ed me creaste de fuego y a \u00e9l de barro\u201d. (Cor\u00e1n 7:12)<\/p>\n<p>As\u00ed empieza la historia del racismo. Satan\u00e1s se consider\u00f3 a s\u00ed mismo superior a Ad\u00e1n con base en sus or\u00edgenes. Desde ese d\u00eda, Satan\u00e1s ha enga\u00f1ado a muchos de los descendientes de Ad\u00e1n llev\u00e1ndolos tambi\u00e9n a creerse superiores a otros, causando que persigan y exploten a sus cong\u00e9neres. Con mucha frecuencia, la religi\u00f3n ha sido usada para justificar el racismo. El juda\u00edsmo, por ejemplo, a pesar de sus or\u00edgenes en el Oriente Medio, es f\u00e1cilmente confundido como una religi\u00f3n occidental; pero la entrada de los jud\u00edos a todos los niveles de la sociedad occidental, de hecho, traiciona la realidad elitista del juda\u00edsmo. Una lectura piadosa del siguiente verso de la Biblia:<br \/>\n\u201c\u2026 no hay Dios en todo el mundo, sino s\u00f3lo en Israel\u201d. (2 Reyes 5:15)<\/p>\n<p>\u2026sugerir\u00eda que en aquellos d\u00edas Dios no era adorado sino por los israelitas. Sin embargo, el juda\u00edsmo hoy permanece centrado alrededor de su jactancia de superioridad racial, de ser los \u201cescogidos\u201d.<\/p>\n<p>\u201cDiles: \u00a1Oh, jud\u00edos! Si realmente son los elegidos de Allah, y las otras personas no lo son, como pretenden\u2026\u2019\u201d (Cor\u00e1n 62:6)<\/p>\n<p>Parad\u00f3jicamente, la gran mayor\u00eda de los cristianos no son jud\u00edos; mientras que Jes\u00fas, como el \u00faltimo de los profetas israelitas, no fue enviado a nadie m\u00e1s que a los jud\u00edos.[1]<\/p>\n<p>\u201cY cuando Jes\u00fas, hijo de Mar\u00eda, dijo: \u00a1Oh, hijos de Israel! Yo soy el Mensajero de Allah, enviado a vosotros para corroborar la Tora y anunciar a un Mensajero que vendr\u00e1 despu\u00e9s de m\u00ed, llamado Ahmad[2]&#8230;\u201d (Cor\u00e1n 61:6)<\/p>\n<p>Y de la misma forma, cada Profeta fue enviado exclusivamente a su propio pueblo[3], excepto Muhammad.<\/p>\n<p>\u201cAquellos que siguen al Mensajero y Profeta iletrado [Muhammad], quien se encontraba mencionado en la Tora y el Evangelio, que les ordena el bien y les proh\u00edbe el mal, les permite todo lo beneficioso y s\u00f3lo les proh\u00edbe lo perjudicial, y les abroga los preceptos dif\u00edciles que pesaban sobre ellos [la Gente del Libro]; y quienes crean en \u00e9l, lo secunden, defiendan y sigan la luz que le ha sido revelada [el Cor\u00e1n] ser\u00e1n quienes tengan \u00e9xito\u2026\u2019\u201d (Cor\u00e1n 7:158)<\/p>\n<p>Dado que Muhammad fue el Profeta y Mensajero final de Dios, su misi\u00f3n fue universal, dirigida no s\u00f3lo a su propia naci\u00f3n, los \u00e1rabes, sino para todos los pueblos del mundo. El Profeta dijo:<br \/>\n\u201cTodo Profeta anterior fue enviado a su naci\u00f3n exclusivamente, mientras que yo he sido enviado a toda la humanidad\u201d. (Sahih Al- Bujari)<\/p>\n<p>\u201cY no te enviamos [\u00a1Oh, Muhammad!] sino como albriciador y amonestador para todos los hombres\u201d. (Cor\u00e1n 34:28)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Bilal el abisinio<\/strong><\/h4>\n<p>Uno de los primeros en aceptar el Islam fue un esclavo abisinio llamado Bilal. Tradicionalmente, los africanos negros eran personas bajas a la vista de los \u00e1rabes, quienes los consideraban de poca utilidad m\u00e1s all\u00e1 del entretenimiento y la esclavitud. Cuando Bilal abraz\u00f3 el Islam, su amo pagano lo hizo torturar salvajemente en el abrasador calor del desierto, hasta que Abu Baker, el amigo m\u00e1s cercano del Profeta, lo rescat\u00f3 al comprar su libertad.<\/p>\n<p>El Profeta le asign\u00f3 a Bilal la tarea de llamar a los creyentes para la oraci\u00f3n. El adh\u00e1n, o\u00eddo desde los minaretes en cada esquina del mundo, desde entonces hace eco de las mismas palabras exactas recitadas por Bilal. Fue as\u00ed como un esclavo, otrora de baja condici\u00f3n social, gan\u00f3 un honor \u00fanico como el primer muec\u00edn del Islam.<\/p>\n<p>\u201cPor cierto que hemos honrado a los hijos de Ad\u00e1n, y les hemos facilitado los medios para transitar por la tierra y por el mar; les hemos prove\u00eddo de cosas buenas y los hemos preferido por encima de muchas otras criaturas\u201d. (Cor\u00e1n 17:70)<\/p>\n<p>Los rom\u00e1nticos occidentales exaltan a la antigua Grecia como el lugar de nacimiento de la democracia[4]. La realidad es que, por ser esclavos y mujeres, a la vasta mayor\u00eda de los atenienses le era negado el derecho a elegir a sus gobernantes. A pesar de esto, \u00a1el Islam estableci\u00f3 que un esclavo pod\u00eda ser un gobernante! El Profeta orden\u00f3:<br \/>\n\u201cObedezcan a su gobernante, incluso si es un esclavo abisinio\u201d. (Ahmad)<\/p>\n<p>Footnotes:<br \/>\n[1] La Biblia apoya este concepto. Se report\u00f3 que Jes\u00fas dijo: \u201cNo fui enviado sino a las ovejas perdidas del pueblo de Israel\u201d. (Mateo 15:24) De all\u00ed que, cada uno de sus famosos 12 disc\u00edpulos eran jud\u00edos israelitas. El pasaje b\u00edblico espec\u00edfico en el cual Jes\u00fas les dice que: \u201cPor tanto, id y doctrinad a todos los Gentiles, bautiz\u00e1ndolos en el nombre del Padre y del Hijo y del Esp\u00edritu Santo\u201d (Mateo 28:19), citado com\u00fanmente para probar la misi\u00f3n gentil as\u00ed como para probar la Trinidad, no se encuentra en ning\u00fan manuscrito anterior al siglo XVI, y de esta forma es considerado un \u201cpiadoso fraude\u201d.<br \/>\n[2] Uno de los nombres de Muhammad, que Dios lo exalte.<br \/>\n[3] \u201cNosotros enviamos a cada naci\u00f3n un Mensajero\u201d. (Cor\u00e1n 16:36)<br \/>\n[4] La Democracia es una invenci\u00f3n de Oriente Medio, vista por primera vez en la civilizaci\u00f3n de Ebla, en el tercer milenio antes de Cristo, y luego en Fenicia y Mesopotamia durante el siglo XI antes de Cristo. No apareci\u00f3 en Atenas sino hasta el siglo V antes de Cristo.<\/p>\n<p>&nbsp;<\/p>\n<h3>\n<strong>(parte 2 de 3)<\/strong><\/h3>\n<h4>\n<strong>Salm\u00e1n el persa<\/strong><\/h4>\n<p>Como la mayor\u00eda de sus compatriotas, Salman fue criado como un devoto zoroastriano. A pesar de esto, luego de un encuentro con algunos cristianos, \u00e9l acept\u00f3 el cristianismo como \u201calgo mejor\u201d. Salm\u00e1n luego viaj\u00f3 por todas partes en b\u00fasqueda de conocimiento, sirviendo a uno y otro monje instruido, el \u00faltimo de los cuales dijo: \u201c\u00a1Oh hijo! Yo no s\u00e9 de nadie que est\u00e9 en el mismo (credo) que nosotros. A pesar de esto, el tiempo de la aparici\u00f3n de un Profeta est\u00e1 cerca. Este Profeta es de la religi\u00f3n de Abraham\u201d. El monje procedi\u00f3 luego a describir a dicho Profeta, su car\u00e1cter y en d\u00f3nde aparecer\u00eda. Salman emigr\u00f3 a Arabia, la tierra de esa profec\u00eda; y cuando oy\u00f3 y conoci\u00f3 a Muhammad, inmediatamente lo reconoci\u00f3 de las descripciones de su maestro, y abraz\u00f3 el Islam. Salm\u00e1n se hizo famoso por su conocimiento y fue la primera persona en traducir el Cor\u00e1n a otro idioma, el persa. Una vez, mientras el Profeta estaba entre sus Compa\u00f1eros, lo siguiente le fue revelado:<br \/>\n\u201c\u00c9l es Quien eligi\u00f3 de entre los que no sab\u00edan leer ni escribir un Mensajero para que les recite Sus preceptos, les purifique, y les ense\u00f1e el Libro y la sabidur\u00eda. Por cierto que antes de ello se encontraban en un extrav\u00edo evidente. Y tambi\u00e9n [para que purifique y ense\u00f1e] a otros que les suceder\u00e1n. Ciertamente Dios es Poderoso, Sabio\u201d. (Cor\u00e1n 62:2-3)<\/p>\n<p>El Mensajero de Dios luego puso su mano sobre Salman y dijo:<br \/>\n\u201cIncluso si la fe estuviera cerca de (las estrellas de) Pl\u00e9yades, un hombre de entre estos (persas) de seguro la obtendr\u00eda\u201d. (Sahih Muslim)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Suhaib el romano<\/strong><\/h4>\n<p>Suhaib naci\u00f3 con privilegios en la lujosa casa de su padre, quien era un gobernador en representaci\u00f3n del emperador persa. Mientras a\u00fan era ni\u00f1o, Suhaib fue capturado por asaltantes bizantinos y vendido como esclavo en Constantinopla.<\/p>\n<p>Suhaib eventualmente escap\u00f3 de la cautividad y huy\u00f3 a La Meca, un popular lugar de asilo, en donde pronto se volvi\u00f3 un pr\u00f3spero comerciante con el apodo de \u201cAr-Rumi\u201d, el romano, debido a su idioma y crianza bizantina. Cuando Suhaib oy\u00f3 a Muhammad predicar, se convenci\u00f3 inmediatamente de la verdad de su mensaje y abraz\u00f3 el Islam. Como todos los primeros musulmanes, Suhaib fue perseguido por los paganos de La Meca. As\u00ed que intercambi\u00f3 toda su riqueza por un salvoconducto para unirse al Profeta en Medina, despu\u00e9s de lo cual el Profeta, complacido de ver a Suhaib, lo salud\u00f3 tres veces, diciendo: \u201c\u00a1Tu intercambio ha sido fruct\u00edfero [Oh Suhaib]! \u00a1Tu intercambio ha sido fruct\u00edfero, tu intercambio ha sido fruct\u00edfero!\u201d Dios hab\u00eda informado al Profeta de la acci\u00f3n de Suhaib antes de reunirse con \u00e9l, mediante esta revelaci\u00f3n:<br \/>\n\u201cY entre los hombres hay quienes dan su vida anhelando agradar a Dios; y Dios es Compasivo con Sus siervos\u201d. (Cor\u00e1n 2:207)<\/p>\n<p>El Profeta amaba en gran manera a Suhaib, y lo describi\u00f3 como habiendo precedido a los romanos en entrar al Islam. La piedad de Suhaib y su posici\u00f3n entre los primeros musulmanes eran tan altas, que cuando el Califa Umar estaba en su lecho de muerte escogi\u00f3 a Suhaib para liderarlos hasta cuando hubiera acuerdo entre ellos acerca de un sucesor.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Abdullah, el hebreo<\/strong><\/h4>\n<p>Los jud\u00edos eran otra naci\u00f3n que viv\u00eda entre los \u00e1rabes pre-isl\u00e1micos, especialmente en Medinah. Muchos jud\u00edos y cristianos hab\u00edan estado esperando que apareciera un nuevo profeta en Arabia durante el tiempo del Profeta Muhammad. Los jud\u00edos de la tribu levita, en particular, se hab\u00edan asentado en gran n\u00famero dentro y alrededor de la ciudad de Medina. A pesar de esto, cuando el tan anunciado Profeta lleg\u00f3, no como un hebreo hijo de Israel sino como un \u00e1rabe descendiente de Ismael, los jud\u00edos lo rechazaron. Excepto unos pocos, como Hussein bin Salam. Hussein era el m\u00e1s instruido rabino y l\u00edder de los jud\u00edos de Medina, pero fue denunciado y despreciado por ellos cuando acogi\u00f3 el Islam. El Profeta dio un nuevo nombre a Husain: \u201cAbdullah\u201d, que significa \u201cServidor de Dios\u201d, y le dio las buenas nuevas de que estaba destinado al Para\u00edso. Abdullah se dirigi\u00f3 a sus compa\u00f1eros de la tribu diciendo:<br \/>\n\u201c\u00a1Oh jud\u00edos! Sean conscientes de Dios y acepten lo que Muhammad ha tra\u00eddo. \u00a1Por Dios! Ustedes saben que \u00e9l es el Mensajero de Dios y pueden encontrar profec\u00edas acerca de \u00e9l y la menci\u00f3n de su nombre y sus caracter\u00edsticas en la Tora. Yo, por mi parte, declaro que \u00e9l es el Mensajero de Dios. Yo tengo fe en \u00e9l y creo que \u00e9l es veraz. Yo lo reconozco a \u00e9l\u201d. Dios revel\u00f3 lo siguiente acerca de \u2018Abdullah:<br \/>\n\u201cDiles: \u00bfPor qu\u00e9 no cre\u00e9is en el Cor\u00e1n que Dios revel\u00f3 y os ensoberbec\u00e9is, siendo que un sabio de los Hijos de Israel [\u2018Abdullah Ibn Salam] atestigu\u00f3 su veracidad y crey\u00f3 en \u00e9l? En verdad Dios no gu\u00eda a los injustos\u201d. (Cor\u00e1n 46:10)<\/p>\n<p>De esta forma, en las filas de los Compa\u00f1eros del Profeta Muhammad se pod\u00edan encontrar africanos, persas, romanos e israelitas; representantes de cada continente conocido. Como el Profeta dijo:<br \/>\n\u201cEn verdad, mis amigos y aliados no son de la tribu de tal y tal. En lugar de esto, mis amigos y aliados son los piadosos, donde sea que est\u00e9n\u201d. (Sahih Al- Bujari, Sahih Muslim)<\/p>\n<p>&nbsp;<\/p>\n<h3>\n<strong>(parte 3 de 3)<\/strong><\/h3>\n<p>Esta hermandad universal predicada por el Islam fue liderada por los Compa\u00f1eros del Profeta luego de \u00e9l. Cuando el Compa\u00f1ero Ubada bin As-Samit lider\u00f3 una delegaci\u00f3n ante Muqawqis, el patriarca cristiano de Alejandr\u00eda, este exclam\u00f3: \u201c\u00a1Ll\u00e9vense a este hombre negro lejos de m\u00ed, y en su lugar traigan a otro que me hable!&#8230; \u00bfC\u00f3mo pueden ustedes estar contentos de que un hombre negro sea el primero entre ustedes? \u00bfNo ser\u00eda mejor que \u00e9l est\u00e9 por debajo de ustedes?\u201d \u201c\u00a1En verdad no!\u201d, replicaron los camaradas de Ubada, \u201caunque \u00e9l sea negro, como t\u00fa puedes ver, \u00e9l es el primero en posici\u00f3n, inteligencia y sabidur\u00eda entre nosotros; pues la persona negra no es despreciada entre nosotros\u201d.<\/p>\n<p>\u201cEn verdad, los creyentes son todos hermanos entre s\u00ed\u2026\u201d (Cor\u00e1n 49:10)<\/p>\n<p>Es el Hayy o peregrinaje a La Meca lo que permanece como el s\u00edmbolo m\u00e1ximo de unidad y hermandad del hombre. Aqu\u00ed, los ricos y los pobres, provenientes de todas las naciones, se inclinan y se levantan al un\u00edsono ante Dios en lo que es la m\u00e1s grande reuni\u00f3n de la humanidad, testificando acerca de las palabras del Profeta cuando \u00e9l dijo:<br \/>\n\u201cVerdaderamente no hay superioridad de un \u00e1rabe sobre un no \u00e1rabe o de un no \u00e1rabe sobre un \u00e1rabe, o de un hombre blanco sobre un hombre negro o de un hombre negro sobre un hombre blanco, excepto por la piedad\u201d. (Ahmad)<\/p>\n<p>Y esto confirma al Cor\u00e1n cuando dice:<br \/>\n\u201c\u00a1Oh, humanos! Os hemos creado a partir de un hombre y una mujer, y os congregamos en pueblos y tribus para que os conozc\u00e1is los unos a los otros. En verdad, el m\u00e1s honrado de vosotros ante Dios es el m\u00e1s piadoso\u201d. (Cor\u00e1n 49:13)<\/p>\n<p>En lo que respecta al nacionalismo, el cual busca crear facciones entre musulmanes por l\u00edneas \u00e9tnicas y tribales, ello es considerado una innovaci\u00f3n malvada.<\/p>\n<p>\u201cDiles [\u00a1Oh, Muhammad!]: Si vuestros padres, hijos, hermanos, esposas y familiares, los bienes que hay\u00e1is adquirido, los negocios que tem\u00e1is perder y las propiedades que pose\u00e1is y os agraden son m\u00e1s amados para vosotros que Dios, Su Mensajero y la lucha por Su causa, pues entonces esperad que os sobrevenga el castigo de Dios; y sabed que Dios no gu\u00eda a los corruptos\u201d. (Cor\u00e1n 9:24)<\/p>\n<p>El Profeta dijo:<br \/>\n\u201c&#8230; quien luche bajo la bandera de los ciegos, volvi\u00e9ndose iracundo por el nacionalismo, llamando al nacionalismo o asistiendo al nacionalismo, y muere, entonces, habr\u00e1 sido como si hubiese muerto en la yahiliia (es decir, ignorancia e incredulidad pre-isl\u00e1mica)\u201d. (Sahih Muslim)<\/p>\n<p>En lugar de esto, el Cor\u00e1n dice:<br \/>\n\u201cCuando los incr\u00e9dulos cerraron sus corazones a la Verdad como en la \u00e9poca de la ignorancia [previa al Islam], Dios hizo descender el sosiego sobre Su Mensajero y sobre los creyentes, y les infundi\u00f3 el completo sentido de la piedad, pues eran los m\u00e1s dignos de ella; y Dios todo lo sabe\u201d. (Cor\u00e1n 48:26)<\/p>\n<p>De hecho, los musulmanes constituyen un solo cuerpo y una supra-naci\u00f3n, como el Profeta explic\u00f3:<br \/>\n\u201cLa par\u00e1bola de los creyentes en su amor y misericordia mutuos es como un cuerpo vivo: si una de las partes siente dolor, todo el cuerpo sufre de insomnio y fiebre\u201d. (Sahih Muslim)<\/p>\n<p>El Cor\u00e1n confirma esta unidad:<br \/>\n\u201cHicimos de vosotros una comunidad moderada y justa, a fin de que fuerais testigos ante la humanidad [de la llegada de los profetas anteriores], y fuera el Mensajero vuestro testigo\u201d. (Cor\u00e1n 2:143)<\/p>\n<p>Tal vez, una de las m\u00e1s grandes barreras para la aceptaci\u00f3n de Islam por parte de muchos occidentales es la falacia de que es principalmente una religi\u00f3n para orientales o para personas de piel oscura. Sin duda, las injusticias raciales en contra de muchos negros, ya sean esclavos abisinios de la Arabia pre-isl\u00e1mica o afroamericanos del siglo XX, han llevado a muchos a acoger el Islam. Pero esto no viene al caso. El mismo Profeta Muhammad fue de tez blancuzca, descrito por sus Compa\u00f1eros como \u201cblanco y colorado\u201d \u2013una descripci\u00f3n que decenas de millones de creyentes \u00e1rabes, berber\u00edes y persas comparten\u2013. Incluso los rubios de ojos azules no son tan raros entre los nuevos habitantes del Cercano Oriente. M\u00e1s a\u00fan, Europa tiene m\u00e1s musulmanes blancos que inmigrantes \u201cde color\u201d. Los bosnios, por ejemplo, cuyo n\u00famero fue diezmado a finales del siglo XX pero quienes, debido a su hero\u00edsmo y tradici\u00f3n de tolerancia, han contribuido mucho a la paz y la estabilidad de los Balcanes. Igualmente los albanos, descendientes de los antiguos ilirios de Europa, son tambi\u00e9n en su mayor\u00eda musulmanes. De hecho, uno de los principales eruditos musulmanes del siglo XX, el Imam Muhammad Nasir-Ud-Deen Al-Albani, era, como su t\u00edtulo lo sugiere, albano.<\/p>\n<p>\u201c\u2026ciertamente creamos al hombre con la m\u00e1s bella conformaci\u00f3n\u201d. (Cor\u00e1n 5:4)<\/p>\n<p>Los blancos han sido llamados \u201ccauc\u00e1sicos\u201d siempre, desde que los antrop\u00f3logos declararon a las Monta\u00f1as del C\u00e1ucaso, hogar de los picos m\u00e1s altos de Europa, como la \u201ccuna de la raza blanca\u201d. Hoy en d\u00eda, los nativos de esas monta\u00f1as son musulmanes. Entre una de las poco conocidas tribus de fieros monta\u00f1eses y agraciadas mujeres est\u00e1n los circasianos, afamados por su bravura y su belleza, y quienes, como gobernantes mamelucos de Siria y Egipto, ayudaron a defender al mundo civilizado y a salvaguardar sus tierras santas de los asaltos de las hordas mongolas. Luego, est\u00e1n los brutalmente perseguidos chechenos, discutiblemente las m\u00e1s ind\u00f3mitas de todas las criaturas de Dios, cuya tenacidad y resistencia les han ayudado a evitar el destino de los circasianos. Por otro lado, m\u00e1s de 1.000.000 de blancos cauc\u00e1sicos americanos y del norte de Europa \u2013anglosajones, francos, alemanes, escandinavos y celtas incluidos\u2013 ahora profesan el Islam. De hecho, el Islam entr\u00f3 pac\u00edficamente a ciertas partes de Europa antes que la cristiandad: \u201cHace mucho tiempo, cuando el eslavo ruso no hab\u00eda empezado a construir iglesias cristianas en el Ok\u00e1 ni hab\u00eda conquistado estos lugares en nombre de la civilizaci\u00f3n europea, el b\u00falgaro ya estaba oyendo el Cor\u00e1n en las orillas del Volga y del Kama\u201d. (Solov\u2019ev, 1965) [El 16 de mayo de 922, el Islam se convirti\u00f3 en la religi\u00f3n oficial del estado de los b\u00falgaros del Volga, con quienes los b\u00falgaros de hoy comparten un ancestro com\u00fan.]<\/p>\n<p>Toda fe aparte del Islam llama de alguna manera al culto de alg\u00fan ser creado. M\u00e1s a\u00fan, la raza y el color juegan un papel central y divisivo en casi todos los sistemas de creencia no isl\u00e1micos. Una deificaci\u00f3n cristiana de Jes\u00fas y de los santos o una deificaci\u00f3n budista de Buda y de los Dalai Lamas, tiene a gente de una raza y un color en particular siendo adorados en derogaci\u00f3n de Dios. En el juda\u00edsmo, la salvaci\u00f3n es apartada de los gentiles no jud\u00edos. El sistema de castas hinduista aparta igualmente las aspiraciones espirituales, socio-pol\u00edticas y econ\u00f3micas de las castas bajas \u201cimpuras\u201d. El Islam, a pesar de esto, busca unificar a todas las criaturas del mundo alrededor de la Unidad y la Unicidad de su Creador. De esta forma, s\u00f3lo el Islam libera a todas las personas, razas y colores mediante la adoraci\u00f3n exclusiva a Dios.<\/p>\n<p>\u201cY entre Sus signos est\u00e1 la creaci\u00f3n de los cielos y de la Tierra, la diversidad de vuestras lenguas y razas. Por cierto que en esto hay signos para quienes los comprenden\u201d. (Cor\u00e1n 30:22)<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/esp\/articles\/los-colores-unidos-del-islam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(parte 1 de 3) \u201cDios le pregunt\u00f3: \u00bfQu\u00e9 te impidi\u00f3 hacer la reverencia cuando te lo orden\u00e9? Respondi\u00f3: Yo soy mejor que \u00e9l, pues a m\u00ed me creaste de fuego y a \u00e9l de barro\u201d. (Cor\u00e1n 7:12) As\u00ed empieza la historia del racismo. Satan\u00e1s se consider\u00f3 a s\u00ed mismo superior a Ad\u00e1n con base en &#8230; <a title=\"Los Colores Unidos del Islam\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/es\/los-colores-unidos-del-islam-2\/\" aria-label=\"Leer m\u00e1s sobre Los Colores Unidos del Islam\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[178],"tags":[],"class_list":["post-7762","post","type-post","status-publish","format-standard","hentry","category-introduccion-al-islam"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/es\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(parte 1 de 3) \u201cDios le pregunt\u00f3: \u00bfQu\u00e9 te impidi\u00f3 hacer la reverencia cuando te lo orden\u00e9? Respondi\u00f3: Yo soy mejor que \u00e9l, pues a m\u00ed me creaste de fuego y a \u00e9l de barro\u201d. (Cor\u00e1n 7:12) As\u00ed empieza la historia del racismo. Satan\u00e1s se consider\u00f3 a s\u00ed mismo superior a Ad\u00e1n con base en&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-21c","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7762,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7762,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7762,"position":2},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/www.ask-a-muslim.com\/de\/abdullah-delancey-ex-christ-canada\/","url_meta":{"origin":7762,"position":3},"title":"Abdullah DeLancey, Ex-Christ, Canada","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Abdullah DeLancey. Ich bin Kanadier und ich bin beim \u00f6rtlichen Krankenhaus im Patientenservice besch\u00e4ftigt. Ich bin seit \u00fcber 20 Jahren verheiratet und wir haben drei wunderbare Kinder. Alhamdulillah, ich bin jetzt Muslim. Ich war aber nicht immer Muslim gewesen. Zuerst war ich mein Leben lang ein protestantischer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8571,"url":"https:\/\/www.ask-a-muslim.com\/de\/musa-caplan-ex-jude-usa\/","url_meta":{"origin":7762,"position":4},"title":"Musa Caplan, Ex-Jude, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Vor meiner Konvertierung zum Islam lebte ich mein Leben als Jude. Obwohl meine Familie nicht traditionell war, lernte ich das Judentum von traditionellen Juden. Ich ging zu einer orthodoxen j\u00fcdischen Synagoge und zu einer orthodoxen j\u00fcdischen Schule. Ich lebte und lebe immer noch in einer j\u00fcdischen Gemeinde in den USA,\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7762,"position":5},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/comments?post=7762"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7762\/revisions"}],"predecessor-version":[{"id":10841,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7762\/revisions\/10841"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/media?parent=7762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/categories?post=7762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/tags?post=7762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}