{"id":7784,"date":"2020-06-18T07:43:04","date_gmt":"2020-06-18T12:43:04","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7784"},"modified":"2020-06-30T18:54:28","modified_gmt":"2020-06-30T23:54:28","slug":"que-es-una-mezquita","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/es\/que-es-una-mezquita\/","title":{"rendered":"\u00bfQu\u00e9 es una Mezquita?"},"content":{"rendered":"<p>Una mezquita es el edificio en el que los musulmanes adoran a Dios. A lo largo de la historia isl\u00e1mica, la mezquita fue el centro de la comunidad y las ciudades se formaban alrededor de este edificio central. Hoy d\u00eda, especialmente en los pa\u00edses musulmanes, las mezquitas se encuentran pr\u00e1cticamente en cada esquina, facilit\u00e1ndoles a los musulmanes el realizar las cinco oraciones diarias. En Occidente, las mezquitas son parte integral de centros isl\u00e1micos que contienen adem\u00e1s instalaciones para la ense\u00f1anza y servicios comunitarios.<\/p>\n<p>Hay mezquitas de todas formas y tama\u00f1os, difieren de una regi\u00f3n a otra seg\u00fan la densidad de la poblaci\u00f3n musulmana en un \u00e1rea determinada. Los musulmanes en el pasado, y a\u00fan hoy d\u00eda, han hecho uso de artesanos y arquitectos locales para crear mezquitas hermosas y magn\u00edficas.<\/p>\n<p>Hay, sin embargo, ciertas caracter\u00edsticas que son comunes a todas las mezquitas. Toda mezquita tiene un mihrab, un nicho en la pared que indica la direcci\u00f3n hacia La Meca, la direcci\u00f3n hacia la que rezan los musulmanes. Muchas mezquitas tienen un minbar (o p\u00falpito) desde el que un erudito isl\u00e1mico puede dar un serm\u00f3n o discurso.<\/p>\n<p>Otras caracter\u00edsticas comunes incluyen minaretes, torres altas utilizadas para la llamar a la congregaci\u00f3n a la oraci\u00f3n. Los minaretes son muy visibles y se identifican estrechamente con las mezquitas. Normalmente, hay una amplia zona de oraci\u00f3n cuadrada o rectangular. A menudo toma la forma de un techo plano sostenido por columnas o por un sistema de vigas horizontales soportadas por arquitrabes. En otros dise\u00f1os comunes de mezquita, el techo consiste en una c\u00fapula grande individual sobre pechinas[1]. Por lo general, hay \u00e1reas de oraci\u00f3n separadas, con entradas distintas para hombres y mujeres.<\/p>\n<p>Las mezquitas se han desarrollado significativamente en los \u00faltimos 1.400 a\u00f1os. Muchas tienen patios que contienen fuentes y piscinas decorativas, que originalmente abastec\u00edan de agua para las abluciones antes de la oraci\u00f3n. En la actualidad, sin embargo, cuentan con instalaciones m\u00e1s privadas para la realizaci\u00f3n de las abluciones y para los servicios sanitarios. Originalmente, las mezquitas eran estructuras sencillas con pisos de tierra, ahora tienen por lo general pisos cubiertos con alfombras. En su mayor\u00eda no est\u00e1n decoradas m\u00e1s que con l\u00edneas rectas de dise\u00f1os geom\u00e9tricos que aseguran que los musulmanes se alineen en filas rectas para realizar sus cinco oraciones diarias.<\/p>\n<p>Nunca hay im\u00e1genes de seres vivos ni estatuas en las mezquitas, pues en el Islam est\u00e1 prohibido que tales cosas se mantengan o se muestren. En ocasiones, las paredes interiores de la mezquita est\u00e1n decoradas con vers\u00edculos del Cor\u00e1n en caligraf\u00eda \u00e1rabe, o con intrincados dise\u00f1os geom\u00e9tricos. Los patrones est\u00e1n hechos a partir de diversos materiales, incluyendo mosaicos, estuco, piedra, cer\u00e1mica y madera. Los dise\u00f1os m\u00e1s cl\u00e1sicos se conocen como arabescos, y toman la forma de una red radial en la que predominan las formas de c\u00edrculos y estrellas. Los dise\u00f1os pueden ser en dos o tres dimensiones.<\/p>\n<p>En su gran mayor\u00eda, incluso en pa\u00edses \u00e1ridos y des\u00e9rticos, las mezquitas son refugios frescos y serenos. Cuando una persona entra en una mezquita, se aleja del ajetreo y del bullicio del mundo material y se retira a un refugio de calma o santuario. Las mezquitas son casas de adoraci\u00f3n. Se espera que los hombres hagan todas sus cinco oraciones obligatorias en congregaci\u00f3n en una mezquita. Las mujeres son bienvenidas a la mezquita para rezar, pero es m\u00e1s loable para ellas que recen en sus casas. Sin embargo, los musulmanes tienen permitido orar en cualquier lugar, excepto en lugares sucios o impuros, como ba\u00f1os o cementerios. El Profeta Muhammad, que la misericordia y las bendiciones de Dios sean con \u00e9l, dijo: \u201cToda la Tierra ha sido hecha una masyid para m\u00ed\u201d[2]. Masyid es la palabra \u00e1rabe para mezquita. Sin embargo, mientras el t\u00e9rmino \u201cmezquita\u201d ha terminado significando espec\u00edficamente un edificio para la oraci\u00f3n, la palabramasyid mantiene muchas capas de significaci\u00f3n.<\/p>\n<p>En el sentido m\u00e1s literal, masyid significa \u201clugar de postraci\u00f3n\u201d. La palabra \u00e1rabe proviene de la ra\u00edz \u201csa-ya-da\u201d que significa \u201cpostrarse\u201d. Cuando la frente de un musulm\u00e1n toca el suelo, est\u00e1 m\u00e1s cerca que nunca de Dios. La oraci\u00f3n establece una conexi\u00f3n entre el creyente y su Se\u00f1or, y la postraci\u00f3n simboliza su completa sumisi\u00f3n.<\/p>\n<p>Mucha gente ha dicho incorrectamente que la palabra \u201cmezquita\u201d no es una traducci\u00f3n de la palabra masyid. Afirman que la palabra \u201cmezquita\u201d proviene de la palabra \u201cmosquito\u201d y se le atribuye a los reyes cat\u00f3licos de Espa\u00f1a, Fernando e Isabel, en el siglo XV. Sin embargo, las palabras \u201cmezquita\u201d y \u201cmosquito\u201d no tienen relaci\u00f3n alguna.<\/p>\n<p>La palabra mosque (mezquita) fue introducida al idioma ingl\u00e9s a finales del siglo XIV o comienzos del XV proveniente del franc\u00e9s. Proviene de la palabra francesa mosqu\u00e9e que proviene del franc\u00e9s antiguo mousquaie. A su vez, el franc\u00e9s la deriv\u00f3 de la palabra italiana moschea que proviene de moscheta. Los italianos la tomaron directamente de la palabra \u00e1rabe masyid o de la palabra del espa\u00f1ol antiguo mesquita[3].<\/p>\n<p>As\u00ed, podemos ver que la traducci\u00f3n de la palabra \u00e1rabe masyid al ingl\u00e9s se convirti\u00f3 en mosque y al espa\u00f1ol en mezquita. Una mezquita es una casa de oraci\u00f3n y un lugar de postraci\u00f3n. Es un edificio dise\u00f1ado y construido espec\u00edficamente para la adoraci\u00f3n de Allah. Es donde los musulmanes se paran hombro a hombro, unidos por su amor a Dios y su deseo de agradarlo solo a \u00c9l.<\/p>\n<p>Footnotes:<br \/>\n[1] Las pechinas son una contribuci\u00f3n isl\u00e1mica a la arquitectura, permiten colocar un domo circular sobre una habitaci\u00f3n cuadrada o un domo el\u00edptico sobre una habitaci\u00f3n rectangular.<br \/>\n[2] Sahih Al Bujari. Al decir \u201cpara m\u00ed\u201d se refer\u00eda a su naci\u00f3n.<br \/>\n[3] The American Heritage Dictionary of the English Language (Diccionario del patrimonio americano del idioma ingl\u00e9s), cuarta edici\u00f3n; \u00a9 2000 Houghton Mifflin Company.<br \/>\nDiccionario etimol\u00f3gico en l\u00ednea, http:\/\/www.etymonline.com\/m8etym.htm<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/esp\/articles\/qu-es-una-mezquita<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una mezquita es el edificio en el que los musulmanes adoran a Dios. A lo largo de la historia isl\u00e1mica, la mezquita fue el centro de la comunidad y las ciudades se formaban alrededor de este edificio central. Hoy d\u00eda, especialmente en los pa\u00edses musulmanes, las mezquitas se encuentran pr\u00e1cticamente en cada esquina, facilit\u00e1ndoles a &#8230; <a title=\"\u00bfQu\u00e9 es una Mezquita?\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/es\/que-es-una-mezquita\/\" aria-label=\"Leer m\u00e1s sobre \u00bfQu\u00e9 es una Mezquita?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[178],"tags":[],"class_list":["post-7784","post","type-post","status-publish","format-standard","hentry","category-introduccion-al-islam"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/es\/author\/admin2\/"},"uagb_comment_info":1,"uagb_excerpt":"Una mezquita es el edificio en el que los musulmanes adoran a Dios. A lo largo de la historia isl\u00e1mica, la mezquita fue el centro de la comunidad y las ciudades se formaban alrededor de este edificio central. Hoy d\u00eda, especialmente en los pa\u00edses musulmanes, las mezquitas se encuentran pr\u00e1cticamente en cada esquina, facilit\u00e1ndoles a&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-21y","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7784,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7784,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/www.ask-a-muslim.com\/de\/abdullah-delancey-ex-christ-canada\/","url_meta":{"origin":7784,"position":2},"title":"Abdullah DeLancey, Ex-Christ, Canada","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Abdullah DeLancey. Ich bin Kanadier und ich bin beim \u00f6rtlichen Krankenhaus im Patientenservice besch\u00e4ftigt. Ich bin seit \u00fcber 20 Jahren verheiratet und wir haben drei wunderbare Kinder. Alhamdulillah, ich bin jetzt Muslim. Ich war aber nicht immer Muslim gewesen. Zuerst war ich mein Leben lang ein protestantischer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7784,"position":3},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8633,"url":"https:\/\/www.ask-a-muslim.com\/de\/sally-ex-katholikin-philippinen\/","url_meta":{"origin":7784,"position":4},"title":"Sally, Ex-Katholikin, Philippinen","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Ich wuchs in einer katholischen Familie auf und lernte katholische Werte und Traditionen. Mit f\u00fcnfzehn trat ich ins Kloster ein. Im Kloster war ich gl\u00fccklich, denn ich konnte meinen Pflichten als Nonne nachkommen und alle Menschen um mich herum einschlie\u00dflich meiner Familie waren auch mit mir zufrieden. Bis zu einer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8550,"url":"https:\/\/www.ask-a-muslim.com\/de\/malcolm-x-usa\/","url_meta":{"origin":7784,"position":5},"title":"Malcolm X, USA &#8211;","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 \u201cIch bin Muslim und werde immer ein Muslim sein. Meine Religion ist der Islam.\u201d -Malcolm X \u00a0 Fr\u00fches Leben Malcolm X, geboren als Malcolm Little am 19. Mai 1925 in Omaha, Nebraska. Seine Mutter, Louis Norton Little, war Hausfrau, die sich um ihre acht Kinder\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/comments?post=7784"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7784\/revisions"}],"predecessor-version":[{"id":10822,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7784\/revisions\/10822"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/media?parent=7784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/categories?post=7784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/tags?post=7784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}