{"id":7827,"date":"2020-06-18T07:44:42","date_gmt":"2020-06-18T12:44:42","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7827"},"modified":"2020-06-30T08:41:18","modified_gmt":"2020-06-30T13:41:18","slug":"jesus-en-el-islam","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/es\/jesus-en-el-islam\/","title":{"rendered":"Jes\u00fas en el Islam"},"content":{"rendered":"<h3><strong>(parte 1 de 3)<\/strong><\/h3>\n<p>La visi\u00f3n isl\u00e1mica de la figura de Jes\u00fas, lo coloca en el justo medio entre dos opiniones extremas. Los jud\u00edos niegan que Jes\u00fas sea un profeta, y lo consideran un impostor. En el otro extremo, los cristianos dicen que Jes\u00fas es el hijo de Dios, y lo adoran como a una divinidad.<\/p>\n<p>El Islam considera a Jes\u00fas uno de los cinco Profetas mayores, junto con No\u00e9, Abraham, Mois\u00e9s y Muh\u00e1mmad (La paz sea con ellos).<\/p>\n<p>Considerar a Jes\u00fas como el Mes\u00edas, es acorde a la creencia isl\u00e1mica en la unicidad de Dios; la unicidad del origen de la gu\u00eda, y la funci\u00f3n de los Mensajeros de Dios (La paz sea con ellos).<\/p>\n<p>Los Mensajeros de Dios, ense\u00f1aron que se debe adorar s\u00f3lo y \u00fanicamente a Dios. Esto le fue ordenado a Ad\u00e1n (La paz sea con \u00e9l) y se le orden\u00f3 trasmitirlo a su descendencia.<\/p>\n<p>Las revelaciones que luego hizo descender Dios con No\u00e9, Abraham, Mois\u00e9s y Muh\u00e1mmad (La paz sea con ellos) reiteran el llamado a adorar s\u00f3lo y \u00fanicamente a Dios.<\/p>\n<p>De esta manera, el Islam no tiene contradicci\u00f3n alguna con las religiones reveladas, exceptuando lo que versa sobre aquellas cuestiones que la gente cambi\u00f3 de estas religiones.<\/p>\n<p>Las consideraciones sobre la figura de Jes\u00fas en las tres grandes religiones (Islam, cristianismo y juda\u00edsmo) no son una excepci\u00f3n a la regla citada.<\/p>\n<p>Aunque el Cor\u00e1n no incluye una historia detallada de la vida de Jes\u00fas, menciona los aspectos m\u00e1s destacables de su figura, como su nacimiento, sus milagros, su misi\u00f3n y su ascensi\u00f3n a los cielos.<\/p>\n<p>Tambi\u00e9n se\u00f1ala los errores de las creencias cristianas y jud\u00edas respecto a \u00e9l. Podemos saber qu\u00e9 fue lo que en verdad Dios le revel\u00f3 a Jes\u00fas, leyendo el Cor\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Naci\u00f3 de una madre virgen<\/strong><\/h4>\n<p>Al igual que los cristianos, los musulmanes creemos que Maria, Mariam en \u00e1rabe, era una mujer casta y virgen, y que Jes\u00fas naci\u00f3 por voluntad de Dios, de hecho su propio nacimiento es el primer milagro que Dios le concedi\u00f3, ya que no tiene padre biol\u00f3gico.<\/p>\n<p>Dios nos habla de esto en el Cor\u00e1n:<br \/>\nY narra [\u00a1Oh, Muhammad!] la historia de Mar\u00eda que se menciona en el Libro [el Cor\u00e1n], cuando se apart\u00f3 de su familia para retirarse a un lugar al este.<\/p>\n<p>Y puso un velo para apartarse de la vista [mientras adoraba a Allah] de los hombres de su pueblo. Entonces le enviamos Nuestro esp\u00edritu [el \u00c1ngel Gabriel], quien se le present\u00f3 con forma humana.<\/p>\n<p>Ella dijo: Me refugio de ti en el Clemente, si es que temes a Allah.<\/p>\n<p>Le dijo: Soy el enviado de tu Se\u00f1or para agraciarte con un hijo puro.<\/p>\n<p>Ella dijo: \u00bfC\u00f3mo he de tener un hijo si no me ha tocado ning\u00fan hombre, ni soy una indecente?<\/p>\n<p>As\u00ed ser\u00e1, le respondi\u00f3, pues tu Se\u00f1or dice: Ello es f\u00e1cil para M\u00ed. Y lo convertiremos en un signo para la humanidad y una misericordia. Es un asunto decidido. (Cor\u00e1n 19:16-21)<\/p>\n<p>Evidentemente el nacimiento milagroso de Jes\u00fas no lo hace una divinidad, de hecho, el nacimiento de Ad\u00e1n es un milagro m\u00e1s grande, ya que Jes\u00fas no ten\u00eda padre, pero Ad\u00e1n no tuvo ni padre ni madre.<\/p>\n<p>Ninguno de los dos es una divinidad, sino que ambos son siervos de Dios, El \u00danico.<\/p>\n<p>Dice Dios en el Cor\u00e1n:<br \/>\n\u201cPor cierto que el ejemplo de Jes\u00fas es similar al de Ad\u00e1n, a quien cre\u00f3 de barro y dijo \u2018S\u00e9\u2019 y fue.\u201d (Cor\u00e1n 3:59)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Milagros<\/strong><\/h4>\n<p>Al igual que los cristianos, los musulmanes creemos que Jes\u00fas realiz\u00f3 distintos milagros. Los hizo con el permiso de Dios, que es el \u00danico con poder sobre todas las cosas.<\/p>\n<p>Dice Dios:<br \/>\n\u201cCuando Dios dijo a Jes\u00fas: \u00a1Oh, Jes\u00fas, hijo de Mar\u00eda! Recuerda la gracia que os conced\u00ed a ti y a tu madre, cuando te di fuerzas mediante el Esp\u00edritu Santo (Gabriel) y hablaste a la gente estando en la cuna, y de adulto te ense\u00f1\u00e9 la sabidur\u00eda, la Tor\u00e1h y el Evangelio. Y cuando hiciste con arcilla la forma de un p\u00e1jaro, con Mi anuencia, y luego soplaste sobre \u00e9l y se convirti\u00f3 en un p\u00e1jaro con Mi anuencia, y curaste al ciego de nacimiento con Mi anuencia, y curaste al leproso, y resucitaste a los muertos con Mi anuencia, y te proteg\u00ed de los hijos de Israel cuando te presentaste ante ellos con evidencias y los incr\u00e9dulos de entre ellos dijeron: esto no es m\u00e1s que magia evidente.\u201d (Cor\u00e1n 5:110)<\/p>\n<p>Dios envi\u00f3 a los Profetas con milagros que confirmaran su veracidad, ellos no hicieron estos milagros por su propio poder, sino por la voluntad omnipotente de Dios.<\/p>\n<p>Los jud\u00edos de la \u00e9poca de Jes\u00fas hab\u00edan logrado grandes avances en la medicina, por eso, Dios le concedi\u00f3 a Jes\u00fas milagros relacionados con esta ciencia, ya que era lo conveniente para que los jud\u00edos creyeran en la autenticidad del milagro.<\/p>\n<p>&nbsp;<\/p>\n<h3>\n<strong>(parte 2 de 3)<\/strong><\/h3>\n<h4>\n<strong>Su supuesta \u201cdivinidad\u201d<\/strong><\/h4>\n<p>Los musulmanes creemos que Dios es Uno, \u00danico, y que est\u00e1 por encima de las limitaciones humanas, \u00c9l est\u00e1 muy por encima de los deseos y las necesidades humanas.<\/p>\n<p>\u00c9l no tiene semejantes ni socios en Su Divinidad, es completamente diferente de Su creaci\u00f3n, y toda adoraci\u00f3n se le debe dirigir \u00fanicamente a \u00c9l, sin intermediarios.<\/p>\n<p>Esto lo ense\u00f1aron todos los Mensajeros de Dios (La paz sea con ellos) incluyendo Jes\u00fas.<\/p>\n<p>Jes\u00fas nunca proclam\u00f3 su divinidad ni ense\u00f1\u00f3 que deb\u00eda ser adorado.<\/p>\n<p>Jes\u00fas nunca se proclamo \u201chijo\u201d de Dios, ni habl\u00f3 de \u201ctrinidad\u201d, \u00e9l ense\u00f1\u00f3 que era un Mensajero de Dios, enviado a los jud\u00edos para que adoren Dios, Uno y \u00danico.<\/p>\n<p>La mayor\u00eda de los vers\u00edculos del Cor\u00e1n que hablan de Jes\u00fas, se\u00f1alan este aspecto.<\/p>\n<p>Esto prueba que el hecho de que se lo adore, es resultado de las mentiras que inventaron sobre su personalidad.<\/p>\n<p>Con total claridad Jes\u00fas ense\u00f1\u00f3 que no era \u00e9l sino Dios quien deb\u00eda ser adorado, Jes\u00fas ense\u00f1aba con par\u00e1bolas, que explicaban que \u00e9l era de naturaleza humana y mortal, y no era hijo de Dios, ni una divinidad.<\/p>\n<p>Dios dice en el Cor\u00e1n, sobre Jes\u00fas:<br \/>\n\u201cSon incr\u00e9dulos los que dicen: Dios es el Mes\u00edas, el hijo de Maria. El mismo Mes\u00edas dijo: \u00a1Oh hijos de Israel! Adorad a Dios pues \u00c9l es vuestro Se\u00f1or y el m\u00edo, y quien atribuya copart\u00edcipes a Dios, \u00c9l le vedar\u00e1 el para\u00edso, y su morada ser\u00e1 el infierno. Los inicuos jam\u00e1s tendr\u00e1n auxiliadores.\u201d (Cor\u00e1n 5:72)<\/p>\n<p>Dios dice en referencia a la creencia de que Jes\u00fas es parte de una trinidad:<br \/>\n\u201cSon incr\u00e9dulos quienes dicen: Dios es parte de una trinidad. No hay m\u00e1s que Una sola Divinidad, y si no desisten de lo que dicen, un castigo doloroso azotar\u00e1 a quienes (por decir esto) han ca\u00eddo en la incredulidad. \u00bfAcaso no van a arrepentirse y pedir perd\u00f3n a Dios? Dios es Absolvedor, Misericordioso.<\/p>\n<p>El Mes\u00edas hijo de Mar\u00eda es s\u00f3lo un Mensajero, igual que los otros Mensajeros que le precedieron, y su Madre fue una fiel y veraz creyente. Ambos com\u00edan alimentos (c\u00f3mo el resto de la humanidad). Observa c\u00f3mo les explicamos las evidencias y observa c\u00f3mo (a pesar de esto) se desv\u00edan.\u201d (Cor\u00e1n 5:73-75)<\/p>\n<p>Tambi\u00e9n dice Dios en el Cor\u00e1n:<br \/>\n\u201c\u00a1Oh, gente de las escrituras! (Jud\u00edos y cristianos) no os extralimit\u00e9is en vuestra religi\u00f3n, no dig\u00e1is acerca de Dios sino la verdad, Ciertamente el Mes\u00edas, Jes\u00fas hijo de Mar\u00eda, es el Mensajero de Dios y Su palabra que deposit\u00f3 en Mar\u00eda, y un esp\u00edritu que proviene de \u00c9l. Creed pues, en Dios y en sus Mensajeros, No dig\u00e1is que es una trinidad, desistid, pues es lo mejor para vosotros. Por cierto Dios es la \u00fanica Divinidad, \u00a1Glorificado sea! Es inadmisible que tenga un hijo.<\/p>\n<p>A \u00c9l pertenece cuanto hay en los cielos y la tierra.<\/p>\n<p>Dios es suficiente como protector.\u201d (Cor\u00e1n 4:171)<\/p>\n<p>Dios mismo denuncia las creencias que son contrarias a su verdadera esencia:<br \/>\n\u201cDicen: El Clemente tuvo un hijo. Por cierto que han dicho algo terrible. Los cielos estuvieron a punto de hundirse, la tierra de abrirse y las monta\u00f1as de derrumbarse (por la blasfemia que profirieron).<\/p>\n<p>Porque le atribuyeron un hijo al Clemente. No es propio del Clemente tener un hijo. Todos los que habitan los cielos y la tierra se presentar\u00e1n sumisos ante el Clemente.\u201d (Cor\u00e1n 19:88-93)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Su misi\u00f3n<\/strong><\/h4>\n<p>Como dijimos antes, el Cor\u00e1n afirma que Jes\u00fas fue un Profeta, de naturaleza totalmente humana. Los Profetas (La paz sea con todos ellos) son lo mejor de la creaci\u00f3n.<\/p>\n<p>Los Profetas son los elegidos de Dios para trasmitir su Mensaje, y no deben ser adorados. Jes\u00fas no es diferente de los dem\u00e1s Profetas al respecto.<\/p>\n<p>A lo largo del Cor\u00e1n, Jes\u00fas es presentado como un Mensajero de Dios, enviado a los jud\u00edos para que retornaran al Mensaje de Mois\u00e9s.<\/p>\n<p>\u201cY cuando Jes\u00fas, hijo de Mar\u00eda, dijo: \u00a1Oh, hijos de Israel! Yo soy el Mensajero de Dios, enviado a vosotros para corroborar la Tor\u00e1h.\u201d (Cor\u00e1n 61:6)<\/p>\n<p>Jes\u00fas es el \u00faltimo de los Profetas jud\u00edos, vivi\u00f3 de acuerdo a la ley de Mois\u00e9s, y orden\u00f3 a sus seguidores hacer lo mismo. En Mateo 5:17-18, Jes\u00fas dice:<br \/>\n\u201cYo no he venido a abolir la ley de los Profetas, sino a confirmarla.\u201d<\/p>\n<p>\u00c9l y su Mensaje, no eran diferentes a los dem\u00e1s profetas elegidos de Dios, que llamaron a la gente a adorar \u00fanicamente a Dios y obedecer sus mandatos.<\/p>\n<p>A pesar de que su misi\u00f3n se evidenci\u00f3 apoyada por numerosos milagros, desde su nacimiento y durante toda su vida, a\u00fan as\u00ed, la mayor\u00eda de los jud\u00edos lo rechazaron.<\/p>\n<p>Jes\u00fas no s\u00f3lo afirm\u00f3 el mensaje de los Profetas que lo precedieron, sino que anunci\u00f3 la llegada del \u00faltimo Profeta, Dios dice:<br \/>\n\u201cY cuando Jes\u00fas, hijo de Mar\u00eda, dijo: \u00a1Oh hijos de Israel! Yo soy el Mensajero de Allah, enviado a vosotros para corroborar la Tor\u00e1 y anunciar a el Mensajero que vendr\u00e1 despu\u00e9s de m\u00ed llamado \u00c1hmad (\u00e9ste es uno de los nombres de Muh\u00e1mmad) Pero cuando se les present\u00f3 con las evidencias, dijeron \u00a1esto es magia evidente!\u201d (Cor\u00e1n 61:6)<\/p>\n<p>Esto tambi\u00e9n aparece en los evangelios, leemos en Juan 14:16-17:<br \/>\n\u00ab Yo rogar\u00e9 al Padre y les dar\u00e1 otro Protector que permanecer\u00e1 siempre con ustedes, el Esp\u00edritu de Verdad, a quien el mundo no puede recibir, porque no lo ve ni lo conoce. Pero ustedes lo conocen, porque est\u00e1 con ustedes y permanecer\u00e1 en ustedes. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<h3>\n<strong>(parte 3 de 3)<\/strong><\/h3>\n<h4>\n<strong>La crucifixi\u00f3n<\/strong><\/h4>\n<p>En el Cor\u00e1n, Dios dice que Jes\u00fas no fue crucificado. Sino que hizo creer a los jud\u00edos y romanos que esto hab\u00eda ocurrido, cuando en realidad Jes\u00fas fue elevado a los cielos.<\/p>\n<p>El Cor\u00e1n no dice expl\u00edcitamente qui\u00e9n fue la persona crucificada en lugar de Jes\u00fas.<\/p>\n<p>\u201cY dijeron: Hemos matado al Mes\u00edas, Jes\u00fas el Hijo de Mar\u00eda, el Mensajero de Allah. Pero ni le mataron ni le crucificaron, sino que se les hizo confundir con otro a quien mataron en su lugar.<\/p>\n<p>Quienes discrepan sobre \u00e9l tienen dudas al respecto. No tienen un conocimiento certero, sino que siguen suposiciones, y ciertamente, no lo mataron.\u201d (Cor\u00e1n 4:157)<\/p>\n<p>\u201cAllah lo ascendi\u00f3 al cielo (en cuerpo y alma). Allah es Poderoso, Sabio.\u201d (Cor\u00e1n 4:158)<\/p>\n<p>As\u00ed el Islam niega que Jes\u00fas viniera a la tierra con el prop\u00f3sito de cargar sobre s\u00ed los pecados de Ad\u00e1n, Eva y toda la humanidad. El Islam ense\u00f1a claramente que nadie cargar\u00e1 con los pecados de otro. Dice Dios:<br \/>\n\u00ab \u2026y sabed que nadie cargar\u00e1 con los pecados ajenos\u2026 \u00bb (Cor\u00e1n 39:7)<\/p>\n<p>Adem\u00e1s el Islam ense\u00f1a que Dios siempre acepta el arrepentimiento de Sus siervos y perdona sus pecados, y no requiere ning\u00fan sacrificio, ni sangre a cambio, y mucho menos, descender \u00c9l en forma de hombre y morir por los pecados de la gente.<\/p>\n<p>La misericordia de Dios se extiende a todas las criaturas, creyentes y no creyentes, las puertas del arrepentimiento est\u00e1n abiertas a todos.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>La segunda venida de Cristo<\/strong><\/h4>\n<p>Al igual que los cristianos, los musulmanes creemos que el Mes\u00edas Jes\u00fas volver\u00e1 a la tierra, sin embargo el prop\u00f3sito de esta segunda venida no es el que creen los cristianos. Jes\u00fas volver\u00e1 para demostrar su condici\u00f3n de mortal, y refutar a quienes le atribuyeron cualidades divinas.<\/p>\n<p>Cuando venga, vivir\u00e1 una vida normal, se casar\u00e1 y finalmente morir\u00e1 como todos los hombres.<\/p>\n<p>\u00ab En esa \u00e9poca, se har\u00e1 evidente la verdad y entonces todos creer\u00e1n que es mortal.<\/p>\n<p>Entre la gente del Libro no habr\u00e1 nadie que no crea en \u00e9l (Jes\u00fas) antes de su muerte (en su segunda venida).<\/p>\n<p>El d\u00eda de la resurrecci\u00f3n atestiguar\u00e1 contra ellos. \u00bb (Cor\u00e1n 4:159)<\/p>\n<p>Jes\u00fas tambi\u00e9n luchar\u00e1 contra el falso Mes\u00edas (anticristo), que vendr\u00e1 justo antes que \u00e9l, y llamar\u00e1 a la gente a creer que es Dios. Jes\u00fas lo derrotar\u00e1, y entonces todos aceptar\u00e1n la verdadera religi\u00f3n, el mundo conocer\u00e1 un per\u00edodo de paz como no existi\u00f3 nunca antes, todos servir\u00e1n al verdadero Dios y ser\u00e1n buenos unos con otros.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Conclusi\u00f3n<\/strong><\/h4>\n<p>Lo precedente es una breve introducci\u00f3n a lo que Dios dice sobre Jes\u00fas en Su \u00faltimo Libro Revelado, el Cor\u00e1n que le fue entregado a Muh\u00e1mmad.<\/p>\n<p>Existe s\u00f3lo Un Dios y s\u00f3lo Uno, que ha ordenado servirle a \u00c9l, no adorar nada fuera de \u00c9l y seguir su ley, ese es el mensaje del Islam. Esto les fue ordenado a los primeros humanos y luego fue repetido por cada Profeta enviado por Dios.<\/p>\n<p>Jes\u00fas, la paz sea con \u00e9l, naci\u00f3 milagrosamente de la virgen Mar\u00eda, y orden\u00f3 a los israelitas la sumisi\u00f3n a Dios (Islam) lo mismo que ense\u00f1aron los Profetas anteriores a \u00e9l.<\/p>\n<p>\u00c9l no era un Dios, ni el hijo de Dios, fue un honorable Profeta, el Mes\u00edas, Jes\u00fas no orden\u00f3 a la gente que lo adoren a \u00e9l. \u00c9l confirm\u00f3 la ley de la Tor\u00e1h, que Mois\u00e9s hab\u00eda recibido, vivi\u00f3 de acuerdo a ella, y orden\u00f3 a sus seguidores seguir esta ley, aclarando sus detalles.<\/p>\n<p>Antes de su partida, instruy\u00f3 a sus disc\u00edpulos para que supieran que luego llegar\u00eda el Profeta Muh\u00e1mmad y que cuando llegara deber\u00edan seguirlo.<\/p>\n<p>Tras la partida de Jes\u00fas, sus ense\u00f1anzas fueron distorsionadas hasta el punto en que se comenz\u00f3 a decir que era Dios. Seis siglos despu\u00e9s, la verdad sobre Jes\u00fas fue expuesta con la llegada del Profeta Muh\u00e1mmad, y permanecer\u00e1 eternamente preservada en el Cor\u00e1n, muchos aspectos de la ley de Mois\u00e9s, que Jes\u00fas segu\u00eda, fueron reconfirmados en su forma original. De tal manera que la gente recibi\u00f3 la gu\u00eda Divina sin adulteraci\u00f3n, y este camino, que ense\u00f1aron Mois\u00e9s y Jes\u00fas antes de Muh\u00e1mmad, es el Islam.<\/p>\n<p>Por todo esto, el Mensaje de los Profetas siempre fue el mismo, y se encuentra en la verdadera religi\u00f3n de Dios, el Islam, de esta manera, s\u00f3lo los musulmanes siguen hoy a Jes\u00fas y sus ense\u00f1anzas.<\/p>\n<p>De hecho, los musulmanes viven mucho m\u00e1s en consonancia con Jes\u00fas que los Cristianos de la actualidad. Respetar y amar a Jes\u00fas es obligatorio en el Islam, Dios resalta la importancia de creer en Jes\u00fas en numerosos pasajes del Cor\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/esp\/articles\/jess-en-el-islam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(parte 1 de 3) La visi\u00f3n isl\u00e1mica de la figura de Jes\u00fas, lo coloca en el justo medio entre dos opiniones extremas. Los jud\u00edos niegan que Jes\u00fas sea un profeta, y lo consideran un impostor. En el otro extremo, los cristianos dicen que Jes\u00fas es el hijo de Dios, y lo adoran como a una &#8230; <a title=\"Jes\u00fas en el Islam\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/es\/jesus-en-el-islam\/\" aria-label=\"Leer m\u00e1s sobre Jes\u00fas en el Islam\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[160],"tags":[],"class_list":["post-7827","post","type-post","status-publish","format-standard","hentry","category-jesus-pbse-en-el-islam"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/es\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(parte 1 de 3) La visi\u00f3n isl\u00e1mica de la figura de Jes\u00fas, lo coloca en el justo medio entre dos opiniones extremas. Los jud\u00edos niegan que Jes\u00fas sea un profeta, y lo consideran un impostor. En el otro extremo, los cristianos dicen que Jes\u00fas es el hijo de Dios, y lo adoran como a una&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-22f","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7827,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7827,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7827,"position":2},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8633,"url":"https:\/\/www.ask-a-muslim.com\/de\/sally-ex-katholikin-philippinen\/","url_meta":{"origin":7827,"position":3},"title":"Sally, Ex-Katholikin, Philippinen","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Ich wuchs in einer katholischen Familie auf und lernte katholische Werte und Traditionen. Mit f\u00fcnfzehn trat ich ins Kloster ein. Im Kloster war ich gl\u00fccklich, denn ich konnte meinen Pflichten als Nonne nachkommen und alle Menschen um mich herum einschlie\u00dflich meiner Familie waren auch mit mir zufrieden. Bis zu einer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/www.ask-a-muslim.com\/de\/abdullah-delancey-ex-christ-canada\/","url_meta":{"origin":7827,"position":4},"title":"Abdullah DeLancey, Ex-Christ, Canada","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Abdullah DeLancey. Ich bin Kanadier und ich bin beim \u00f6rtlichen Krankenhaus im Patientenservice besch\u00e4ftigt. Ich bin seit \u00fcber 20 Jahren verheiratet und wir haben drei wunderbare Kinder. Alhamdulillah, ich bin jetzt Muslim. Ich war aber nicht immer Muslim gewesen. Zuerst war ich mein Leben lang ein protestantischer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8493,"url":"https:\/\/www.ask-a-muslim.com\/de\/neues-aus-der-vergangenheit\/","url_meta":{"origin":7827,"position":5},"title":"Neues aus der Vergangenheit","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Einer der st\u00e4rksten Beweise f\u00fcr die Wahrhaftigkeit des Propheten Muhammad, Gottes Segen und Frieden seien auf ihm, ist seine Kenntnis von der Unsichtbaren Welt: sein genaues Wissen von fr\u00fcheren V\u00f6lkern und zuk\u00fcnftigen Prophezeihungen. Egal wie intelligent jemand ist, man kann nicht nur durch seine Intelligenz allein von der Vergangenheit reden.\u2026","rel":"","context":"En \u00abMUHAMMAD, FRIEDE SEI AUF IHM\u00bb","block_context":{"text":"MUHAMMAD, FRIEDE SEI AUF IHM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/muhammad-friede-sei-auf-ihm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/comments?post=7827"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7827\/revisions"}],"predecessor-version":[{"id":10740,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/7827\/revisions\/10740"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/media?parent=7827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/categories?post=7827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/tags?post=7827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}