{"id":8086,"date":"2020-06-18T08:05:08","date_gmt":"2020-06-18T13:05:08","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=8086"},"modified":"2020-06-29T10:56:19","modified_gmt":"2020-06-29T15:56:19","slug":"la-suplica-condiciones-y-virtudes","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/es\/la-suplica-condiciones-y-virtudes\/","title":{"rendered":"La S\u00faplica, condiciones y virtudes"},"content":{"rendered":"<p>Todas las alabanzas pertenecen a Allah, Se\u00f1or del Universo, quien nos ha pedido que le suplic\u00e1ramos y prometi\u00f3 contestar a nuestros ruegos. Atestiguo que no hay Dios sino Allah, \u00fanico, sin asociados, quien prometi\u00f3 premiar a los virtuosos. Y atestiguo que Muhammad es su siervo y mensajero, que la paz y las bendiciones de Allah sean con \u00e9l, su familia y compa\u00f1eros.<\/p>\n<p>La palabra s\u00faplica (Du\u2018a) incluye los siguientes significados: llamar, invocar, rogar, pedir, implorar.<\/p>\n<p>Este t\u00e9rmino est\u00e1 mencionado en el Cor\u00e1n y alude a diversos significados, tal como muestran los siguientes vers\u00edculos:<br \/>\nAdoraci\u00f3n<\/p>\n<p>\u201cNo suplicar (no adorar) en vez de Allah lo que no puede beneficiarme ni perjudicarme, porque de hacerlo me contar\u00eda entre los inicuos.\u201d (10:106)<br \/>\nBuscar ayuda<\/p>\n<p>\u201cSi dud\u00e1is de lo que le hemos revelado a Nuestro siervo [Muhammad] traed una sura similar, y rogad (buscad) ayuda para ello en quienes tom\u00e1is por socorredores en lugar de Allah, si es que dec\u00eds la verdad.\u201d (2:23)<\/p>\n<h4><\/h4>\n<h4>\n<strong>Invocaci\u00f3n<\/strong><\/h4>\n<p>\u201cVuestro Se\u00f1or dice: Invocadme, que responder\u00e9 [vuestras s\u00faplicas].\u201d (40:60)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Una llamada<\/strong><\/h4>\n<p>\u201cEl d\u00eda que os llame resucitar\u00e9is alab\u00e1ndole y os parecer\u00e1 que no hab\u00e9is permanecido [en las tumbas] sino poco tiempo.\u201d (17:52)<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Alabanza<\/strong><\/h4>\n<p>\u201cDiles: Y sea que Le invoqu\u00e9is diciendo: \u00a1Oh, Allah! \u00a1Oh, Clemente! O cualquier otro nombre con el que Le alab\u00e9is, \u00c9l os oir\u00e1. Sabed que \u00c9l posee los nombres [y atributos] m\u00e1s sublimes.\u201d (17:110)<\/p>\n<p>En cuanto a la definici\u00f3n de la palabra s\u00faplica (Du\u2018a), los eruditos la definieron de manera semejante.<\/p>\n<p>Al-Jatt\u00e2bi coment\u00f3: \u201cEl significado de s\u00faplica (Du\u2018a) es: un pedido de ayuda del siervo a su Se\u00f1or, un pedido de continuo apoyo. Su esencia es que una persona muestra a Allah su necesidad y se libera de todo poder o facultad de cambio (por s\u00ed mismo). Esta es la caracter\u00edstica de la devoci\u00f3n y el servicio a Allah. La s\u00faplica incluye el significado de alabanza a Allah y de atribuirle a \u00c9l la Generosidad y Dadivosidad\u201d.<\/p>\n<p>Ibn Qayim la defini\u00f3 as\u00ed: \u201cEs solicitar lo que beneficia y pedir que desaparezca aquello que causa perjuicio o aflicci\u00f3n\u201d.<\/p>\n<p>Humildemente, ante los sabios que he mencionado, mi definici\u00f3n de s\u00faplica o Du\u2019a ser\u00eda: \u201cAquel di\u00e1logo \u00edntimo donde con devoci\u00f3n se expresa la necesidad ante el Se\u00f1or Todopoderoso, con el acento pl\u00e1cido e \u00edntimo de la confianza que solamente se experimenta ante Quien conoce perfectamente nuestra situaci\u00f3n y de Quien solicitamos con la mayor humildad y entrega todo aquello que nos beneficie en esta vida y el m\u00e1s all\u00e1, y ante Quien nos refugiamos y pedimos protecci\u00f3n de todo lo que nos aflige y atormenta en esta vida y el m\u00e1s all\u00e1\u201d. Y Allah sabe m\u00e1s y mejor.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>La s\u00faplica (Du\u2018a) y su relaci\u00f3n con la doctrina (\u2018Aqidah)<\/strong><\/h4>\n<p>La s\u00faplica (Du\u2018a) tiene una estrecha relaci\u00f3n con nuestra doctrina (\u2018Aqidah) y el monote\u00edsmo (Tauhid). Es una de las mejores maneras que poseemos para aumentar nuestra fe (Im\u00e1n) y apreciar los Nombres y Atributos de Allah. Es un fuerte recordatorio de los poderes ilimitados de Allah y de la incapacidad inherente del ser humano.<\/p>\n<p>La s\u00faplica aumenta la fe debido a diversos factores. Hace evidente el hecho de que no tenemos el control absoluto sobre nuestro destino, ni tampoco tenemos el poder para beneficiarnos o apartar el mal de nosotros mismos. Nos muestra la necesidad que el musulm\u00e1n tiene de su Se\u00f1or. Prueba que aquel que suplica sinceramente cree que Allah escucha su ruego y que le responder\u00e1. Tal persona tambi\u00e9n afirma la infinita misericordia, beneficencia y generosidad de Allah. Cuanto m\u00e1s aumente su sensaci\u00f3n de necesidad de la Misericordia de su Se\u00f1or, m\u00e1s aumentar\u00e1 su fe. De la misma manera, cuanto m\u00e1s aprecie y advierta la perfecci\u00f3n de los Nombres y Atributos de Allah, m\u00e1s aumentar\u00e1 su fe. Ambos factores &#8211; conocer nuestra necesidad de Allah en todo aspecto y Su Naturaleza Perfecta &#8211; son la esencia de la fe.<\/p>\n<p>La s\u00faplica evidencia que s\u00f3lo Allah merece ser adorado (monote\u00edsmo en la adoraci\u00f3n- Tauh\u00edd Al-Uluhiiah), porque si Allah tiene el control total sobre la creaci\u00f3n, y si s\u00f3lo \u00c9l puede responder la invocaci\u00f3n de quien se encuentra afligido, es el \u00fanico que merece nuestra completa sumisi\u00f3n y adoraci\u00f3n.<\/p>\n<p>La s\u00faplica tambi\u00e9n nos indica que Allah tiene los Nombres y Atributos m\u00e1s Perfectos (monote\u00edsmo en los Nombres y Atributos de Allah &#8211; Tauh\u00edd Al-Asma\u2019 ua As-Sifat). S\u00f3lo \u00c9l puede o\u00edr la plegaria silenciosa del siervo, sin importarle donde \u00e9ste se encuentre y solamente \u00c9l es quien puede entender su situaci\u00f3n. Su conocimiento es m\u00e1s completo que el conocimiento del siervo mismo sobre la situaci\u00f3n dif\u00edcil en que \u00e9ste se encuentra. De igual manera, s\u00f3lo Allah tiene el poder completo y la autoridad m\u00e1xima para otorgarnos lo que necesitamos y anhelamos.<\/p>\n<p>En consecuencia, la s\u00faplica es un poderoso indicador del monote\u00edsmo (Tauh\u00edd) en sus tres tipos.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>La S\u00faplica y su relaci\u00f3n con la adoraci\u00f3n y devoci\u00f3n<\/strong><\/h4>\n<p>Sabemos que el Du&#8217;a (s\u00faplicas) es una de las mejores formas de adorar a Allah (alabado sea). Relat\u00f3 An-Nu&#8217;man Ibn Bashir (Allah se complazca de \u00e9l) que el Profeta (paz y bendiciones de Allah sean con \u00e9l) dijo: \u00abEl Du&#8217;a es adoraci\u00f3n\u201d y luego recit\u00f3 la aleya Cor\u00e1nica \u00ab\u2026vuestro se\u00f1or ha dicho: Pedidme, que os responder\u00e9 (vuestros ruegos), por cierto que aquellos cuya soberbia les impida adorarme, entraran en el Yahannam humillados.\u201d (40:60).<\/p>\n<p>(Relatado por Abu Dawud y At-Tirmidhi).<\/p>\n<p>Allah nos ha ordenado hacer Du\u2019a en innumerables aleyas del Sagrado Cor\u00e1n, prometiendo responder, y elogiando a sus profetas y mensajeros cuando dijo: \u00abTodos ellos se apresuraban a las buenas obras, nos ped\u00edan con anhelo y eran temerosos.\u201d (21:90).<\/p>\n<p>Allah nos ha informado (alabado sea) que est\u00e1 cerca de sus siervos, y que ha de responder a sus s\u00faplicas cuando dijo: \u201c\u2026cuando mis siervos te pregunten sobre mi\u2026yo estoy cerca y respondo al ruego del que pide cuando me pide.\u201d (2:186).<\/p>\n<p>Allah (alabado sea) nos ha ordenado suplicarle y ser humildes ante \u00c9l, especialmente ante las calamidades y aflicciones, ya que nadie puede responder las s\u00faplicas ni resolver las dificultades excepto \u00c9l. Dijo: \u201cQuien responde al que se ve en necesidad libr\u00e1ndolo del mal\u2026\u201d (27:62)<\/p>\n<p>De la misma manera, reproch\u00f3 a las personas que no hacen Du&#8217;a en tiempos de tragedias o en los d\u00edas dif\u00edciles diciendo: \u201cNo hemos enviado a una ciudad a ning\u00fan profeta sin haber castigado a su gente con la miseria y el padecimiento para que fuesen humildes.\u201d (7:94)<\/p>\n<p>Dijo Allah (alabado sea) en el Sagrado Cor\u00e1n: \u201cEs verdad que hemos mandado enviados a comunidades anteriores a ti, a las que sorprendimos con la desgracia y el infortunio para que as\u00ed pudieran ser humildes. \u00a1Si hubieran sido humildes cuando les lleg\u00f3 nuestro rigor! Sin embargo sus corazones se endurecieron, y Sheit\u00e1n hizo que vieran bueno lo que hac\u00edan.\u201d (6::42-43)<\/p>\n<p>Allah (alabado sea) responde a las s\u00faplicas por su misericordia y generosidad. Y a pesar de no tener ninguna necesidad de Sus criaturas, les ha ordenado que le suplicaran, porque ellos son los que est\u00e1n necesitados de \u00c9l. Dijo Allah en otra Aleya del Cor\u00e1n: \u201c\u00a1Hombres! Vosotros sois los que necesit\u00e1is de Allah, mientras que Allah es rico, en si mismo alabado.\u201d (35:15)<\/p>\n<p>Y nos record\u00f3 este concepto en el Sagrado Cor\u00e1n cuando dijo: \u201cY Allah esta libre de toda necesidad, siendo vosotros los que lo necesit\u00e1is.\u201d (47:38)<\/p>\n<p>Allah menciona en un hadith Qudsi: Oh siervos m\u00edos! todos est\u00e1is extraviados, salvo a quien yo gu\u00edo, as\u00ed que pedidme la gu\u00eda que os guiar\u00e9. \u00a1Oh siervos m\u00edos! Todos est\u00e1is hambrientos, salvo a quien he dado de comer. As\u00ed que \u00a1pedidme alimento! que os alimentare.<\/p>\n<p>\u00a1Oh siervos m\u00edos! Comet\u00e9is errores noche y d\u00eda, y yo os perdono todos ellos. As\u00ed que \u00a1pedidme perd\u00f3n! que he de perdonaros.\u201d<\/p>\n<p>(relatado por Muslim)<\/p>\n<h4>\n<strong>Condiciones para que las s\u00faplicas sean aceptadas<\/strong><\/h4>\n<p>Existen condiciones espec\u00edficas que deben cumplirse para que las s\u00faplicas sean aceptadas:<\/p>\n<p>1. Obediencia:<br \/>\nQue el siervo sea obediente, y no ignore las obligaciones de Allah, cometiendo el Haram.<\/p>\n<p>Dijo Allah (alabado sea): \u00bfReci\u00e9n ahora crees, luego de haber desobedecido y haberte contado entre los corruptores?\u201d (10:91)<\/p>\n<p>Fue informado que Profeta (la paz y bendiciones de Allah sean con \u00e9l) dijo: \u201cUn hombre que realiza un largo viaje, y ya desgre\u00f1ado y polvoriento, extiende sus manos al cielo diciendo: \u00a1Oh Se\u00f1or!, \u00a1Oh Se\u00f1or!, pero su comida es haram, su bebida es haram, su ropa es haram y se alimenta del haram, \u00bfcomo habr\u00e1 de serle respondida (su s\u00faplica)?\u201d (Narrado por Muslim)<\/p>\n<p>En este Hadiz el Profeta (la paz y bendiciones de Allah sean con \u00e9l) indic\u00f3 que la comida, la bebida y la vestimenta haram tienen una gran influencia tanto en que el Du\u2019a sea escuchado, como que sea respondido.<\/p>\n<p>Dijo el mensajero de Allah (la paz y bendiciones de Allah sean con \u00e9l):<br \/>\n\u00abBusca que tu comida sea del Halal, y tu Du&#8217;a ser\u00e1 respondido.\u00bb<\/p>\n<p>Abdallah, el hijo del Imam Ahmad (que Allah sea misericordioso con ambos) mencion\u00f3 en el libro de Al-Zhuhd (El ascetismo): \u00abCierta vez un tiempo de dificultad cay\u00f3 sobre los Israelitas, por lo que salieron a cazar, entonces Allah inspir\u00f3 a su Profeta para que les diga: \u00abSal\u00eds a cazar y vuestros cuerpos est\u00e1n impuros y levant\u00e1is hacia mi las manos llenas de sangre impura suplic\u00e1ndome, luego de haber llenado vuestras casas del haram. Ahora se ha multiplicado mi enojo hacia ustedes y no os hab\u00e9is sino alejado m\u00e1s y m\u00e1s de mi.\u201d<\/p>\n<p>As\u00ed que tomad conciencia de vosotros mismos y revisad las fuentes de vuestro sustento, alimento y bebida, para que Allah responda vuestras invocaciones y Du&#8217;as.\u201d<\/p>\n<p>2. Sinceridad:<br \/>\nEntre las condiciones para que el Du\u2019a sea aceptado por Allah (alabado sea) se encuentra que la s\u00faplica se haga con sinceridad. Allah dijo en una Aleya del Cor\u00e1n: \u201cAs\u00ed pues invocad a Allah sinceramente, y solo a \u00c9l adorad\u2026\u201d (40:14). Y dijo: \u201cy no invoqu\u00e9is a nadie junto a Allah\u2026\u201d (73:18) Aquellos que asocian en sus s\u00faplicas junto a Allah, a \u00eddolos, tumbas, muertos, santos u otras divinidades, Allah no habr\u00e1 de contestarles sus s\u00faplicas, puesto que se han apartado y han roto su relaci\u00f3n de monote\u00edsmo con \u00c9l. Siendo el peligro mayor, que cuando supliquen a Allah en tiempos de adversidad, no les ser\u00e1n respondidas sus s\u00faplicas. Asimismo aquellos que buscan la intermediaci\u00f3n de los muertos diciendo: \u201cTe pedimos Oh Allah por fulano, o por el grado de cercan\u00eda a Ti de fulano\u201d. Pero Allah no contesta sus s\u00faplicas porque es una forma de idolatr\u00eda e innovaci\u00f3n inv\u00e1lida y prohibida. Ya que Allah no nos indic\u00f3 buscar intermediarios al suplicarle, sino que orden\u00f3 a su \u00faltimo Profeta (la paz y bendiciones de Allah sean con \u00e9l) ense\u00f1ar a los musulmanes la necesidad de dirigirse directamente a Allah en todas las s\u00faplicas y actos de adoraci\u00f3n, abandonando todo intermediario y asociado.<\/p>\n<p>Dijo el enviado de Allah (la paz y bendiciones de Allah sean con \u00e9l): \u00abRecuerda a Allah en la prosperidad y \u00c9l te recordar\u00e1 en momentos de adversidad\u00bb. Es decir, que si el siervo teme a Allah, no sobrepasa los l\u00edmites y realiza sus deberes en tiempos de prosperidad, habr\u00e1 conseguido conocer a Allah y establecer una relaci\u00f3n especial entre \u00e9l y su Se\u00f1or. Entonces Allah lo conocer\u00e1 y recordar\u00e1 en tiempos de adversidad y considerar\u00e1 su obediencia en tiempos de prosperidad removiendo sus dificultades. Dice el Allah (alabado sea) en un hadiz Qudsi: \u201c\u2026 (mi siervo) se acerca a mi a trav\u00e9s de los actos voluntarios hasta que lo amo, y si lo amo soy el o\u00eddo con el que oye y la vista con la que ve, y la mano con la que toma y las piernas con las que anda, si me pide le concedo y si me pide protecci\u00f3n ciertamente se la dar\u00e9.\u201d (Narrado por Bujari).<\/p>\n<p>Dijo Allah en el Sagrado Cor\u00e1n: \u201cy cuando mis siervos te pregunten sobre mi\u2026yo estoy cerca y respondo al ruego del que pide cuando me pide.\u201d (2:186) y dijo tambi\u00e9n: \u00abY vuestro se\u00f1or ha dicho: Pedidme, que os responder\u00e9 (vuestros ruegos).\u201d (40:60).<\/p>\n<p>Quien tema a Allah y le obedezca en tiempos de prosperidad, Allah lo apoyar\u00e1 y sustentar\u00e1 moralmente en momentos de aflicci\u00f3n, dolor y calamidad.<br \/>\nAllah dijo acerca del profeta Yunus (Jon\u00e1s &#8211; la paz y bendiciones de Allah sean con \u00e9l) cuando lo trag\u00f3 la ballena: \u201cDe no haber sido porque era uno de los que glorificaban, habr\u00eda permanecido en su vientre hasta el d\u00eda de la resurrecci\u00f3n.\u201d (37:143-144.) Esto significa que fue salvado por las buenas obras que realizaba en tiempos de prosperidad. De no haber hecho buenas obras habr\u00eda permanecido dentro de la ballena hasta sus \u00faltimos d\u00edas. En otras palabras, el est\u00f3mago de la ballena habr\u00eda sido su tumba. Algunos de los primeros musulmanes (salaf) acu\u00f1aron la siguiente m\u00e1xima: \u201cPermanece pr\u00f3ximo a Allah en tus d\u00edas de prosperidad que \u00c9l estar\u00e1 pr\u00f3ximo de ti en d\u00edas de adversidad\u201d.<\/p>\n<p>Pero miremos el caso contrario, Fara\u00f3n era un tirano, alejado del recuerdo de Allah. Y Allah dijo: \u201cHasta que al ver que las aguas lo ahogaban, dijo: \u00a1creo\u2026!\u201d (10:90). Es decir que al ver que morir\u00eda ahogado intent\u00f3 creer y pedir a Allah la salvaci\u00f3n, pero en ese momento no le fue aceptado su pedido, porque se hab\u00eda comportado como un tirano hasta entonces, y por eso su s\u00faplica no era sincera.<\/p>\n<p>4 &#8211; Suplicar con el coraz\u00f3n atento<br \/>\nEn el libro Mustadrak del Hakim, se menciona que Abu Hurairah (Allah se complazca de \u00e9l) narr\u00f3 que el Profeta (la paz y bendiciones de Allah sean con \u00e9l) dijo: \u201csuplicadle a Allah estando seguros de su respuesta, y sabed que Allah no acepta el Du\u2019a de un coraz\u00f3n distra\u00eddo, negligente.\u201d<\/p>\n<p>5- Ordenar el bien y prohibir el mal<br \/>\nRelato Hudhaifah Ibn Al-Yaman (Allah se complazca de \u00e9l) que el Profeta (la paz y bendiciones de Allah sean con \u00e9l) dijo: \u00abPor aquel en cuyas manos se encuentra mi alma, que deb\u00e9is ordenar el bien y prohibir el mal o descender\u00e1 sobre vosotros un castigo de Allah, y entonces le suplicar\u00e9is y no recibir\u00e9is respuesta.\u201d (Transmitido por Tirmidhi). Tambi\u00e9n mencion\u00f3 Al-Hakim en su libro Al-Mustadrak de \u2018Ali Ibn Abi Talib (Allah se complazca de \u00e9l) qui\u00e9n narr\u00f3 que el Profeta (la paz y bendiciones de Allah sean con \u00e9l) dijo: \u00abEl Du&#8217;a es el arma del creyente, el pilar de la religi\u00f3n y la luz de los cielos y tierra\u00bb y dijo (la paz y bendiciones de Allah sean con \u00e9l) \u00abEl Du\u2019a siempre tiene beneficio, sea concedido o no; por lo que haced Du\u2019a, Oh siervos de Allah.\u201d (Transmitido por Al-Hakim, hadiz hasan).<\/p>\n<p>Relat\u00f3 Aisha (Allah se complazca de ella) que el Profeta (la paz y bendiciones de Allah sean con \u00e9l) dijo: \u00abAllah ama aquellos que son insistentes en sus s\u00faplicas.\u00bb<\/p>\n<p>Por consiguiente, el Du&#8217;a es una de las formas mas importantes de adoraci\u00f3n para el musulm\u00e1n. Por medio del cual se muestra la humildad y el temor del siervo hacia Allah, la necesidad de \u00c9l, la inclinaci\u00f3n del coraz\u00f3n, y la necesidad de suplicarle. Por el contrario, la renuncia al Du&#8217;a indica la arrogancia y dureza del coraz\u00f3n.<\/p>\n<p>Hacer Du&#8217;a es una raz\u00f3n para entrar al para\u00edso. Allah (alabado sea) dijo en el Cor\u00e1n: \u201cY se encontrar\u00e1n frente a frente haci\u00e9ndose preguntas. Dir\u00e1n: Antes, cuando est\u00e1bamos entre los nuestros, fuimos temerosos. Y Allah nos ha favorecido y nos ha librado del castigo del Sim\u00fan . Es verdad que antes Le rog\u00e1bamos y que \u00c9l es el Bondadoso, el Compasivo\u201d. (52:25) Dijo Allah (alabado sea) en otra aleya: \u00abY vuestro se\u00f1or ha dicho: Pedidme, que os responder\u00e9 (vuestros ruegos), es cierto que aquellos cuya soberbia les impida adorarme, entraran al Yahannam humillados.\u201d (40:60).<\/p>\n<p>Por consiguiente el musulm\u00e1n debe suplicarle a Allah y aumentar sus s\u00faplicas con sincera devoci\u00f3n. En d\u00edas de sedici\u00f3n y confusi\u00f3n sobre asuntos de religi\u00f3n y fe, especialmente en esos momentos, es de vital importancia refugiarse en la s\u00faplica.<\/p>\n<p>Recordemos siempre en nuestras Du\u2019a buscar refugio en Allah contra nuestro real enemigo, el maldito Sheit\u00e1n: \u201cRogad a vuestro se\u00f1or humilde y secretamente, es cierto que el no ama a los que se exceden. Y no corromp\u00e1is en la tierra despu\u00e9s del orden que se haya establecido, e invocadlo con temor y anhelo. Por cierto que la misericordia de Allah esta pr\u00f3xima de los que hacen el bien.\u201d (7:55-56)<\/p>\n<p>Quiera Allah concedernos las bondades del noble Cor\u00e1n y beneficiarnos de sus aleyas y sabias ense\u00f1anzas.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/esp\/articles\/la-suplica-condiciones-y-virtudes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las alabanzas pertenecen a Allah, Se\u00f1or del Universo, quien nos ha pedido que le suplic\u00e1ramos y prometi\u00f3 contestar a nuestros ruegos. Atestiguo que no hay Dios sino Allah, \u00fanico, sin asociados, quien prometi\u00f3 premiar a los virtuosos. Y atestiguo que Muhammad es su siervo y mensajero, que la paz y las bendiciones de Allah &#8230; <a title=\"La S\u00faplica, condiciones y virtudes\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/es\/la-suplica-condiciones-y-virtudes\/\" aria-label=\"Leer m\u00e1s sobre La S\u00faplica, condiciones y virtudes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[164],"tags":[],"class_list":["post-8086","post","type-post","status-publish","format-standard","hentry","category-para-los-nuevos-musulmanes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/es\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"Todas las alabanzas pertenecen a Allah, Se\u00f1or del Universo, quien nos ha pedido que le suplic\u00e1ramos y prometi\u00f3 contestar a nuestros ruegos. Atestiguo que no hay Dios sino Allah, \u00fanico, sin asociados, quien prometi\u00f3 premiar a los virtuosos. Y atestiguo que Muhammad es su siervo y mensajero, que la paz y las bendiciones de Allah&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-26q","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":8086,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":8086,"position":1},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":8086,"position":2},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"En \u00abWISSENSCHAFTLICHE WUNDER\u00bb","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/www.ask-a-muslim.com\/de\/abdullah-delancey-ex-christ-canada\/","url_meta":{"origin":8086,"position":3},"title":"Abdullah DeLancey, Ex-Christ, Canada","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Abdullah DeLancey. Ich bin Kanadier und ich bin beim \u00f6rtlichen Krankenhaus im Patientenservice besch\u00e4ftigt. Ich bin seit \u00fcber 20 Jahren verheiratet und wir haben drei wunderbare Kinder. Alhamdulillah, ich bin jetzt Muslim. Ich war aber nicht immer Muslim gewesen. Zuerst war ich mein Leben lang ein protestantischer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8634,"url":"https:\/\/www.ask-a-muslim.com\/de\/halimah-david-ex-christin-usa\/","url_meta":{"origin":8086,"position":4},"title":"Halimah David, Ex-Christin, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Vater hat mich allein als Christin aufgezogen. Er hat sich sehr angestrengt, mir christliche Werte zu vermitteln. Als ich in der Grundschule war, las ich viel in der Bibel (\u00fcbersprang die Worte, ich wei\u00df nicht wie) und ich bemerkte eine Menge Widerspr\u00fcche (zB. Schweinefleisch essen, Jesus Tod, usw.). Als\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":8086,"position":5},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/comments?post=8086"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8086\/revisions"}],"predecessor-version":[{"id":10437,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8086\/revisions\/10437"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/media?parent=8086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/categories?post=8086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/tags?post=8086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}