{"id":8187,"date":"2020-06-18T08:23:27","date_gmt":"2020-06-18T13:23:27","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=8187"},"modified":"2020-06-28T18:39:36","modified_gmt":"2020-06-28T23:39:36","slug":"coronel-donald-s-rockwell-poeta-y-critico-usa","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/es\/coronel-donald-s-rockwell-poeta-y-critico-usa\/","title":{"rendered":"Coronel Donald S. Rockwell, Poeta y Critico, USA"},"content":{"rendered":"<p>La simplicidad del Islam, el poderoso llamado y la absorbente atm\u00f3sfera de sus mezquitas, sus fervientes fieles, la confianza que inspira la realizaci\u00f3n de millones a lo largo del mundo que responden a las cinco llamadas a la oraci\u00f3n \u2013 estos factores me atrajeron desde el principio. Pero despu\u00e9s de decidir que me convertir\u00eda en un seguidor del Islam, encontr\u00e9 muchas razones profundas para confirmar mi decisi\u00f3n. El apacible concepto de vida \u2013 el fruto de la combinaci\u00f3n del curso de acci\u00f3n y contemplaci\u00f3n del Profeta \u2013 su sabio consejo, las admoniciones de caridad y piedad, el amplio humanismo, la declaraci\u00f3n de los derechos de propiedad de la mujer \u2013 estos y otros factores de las ense\u00f1anzas del hombre en La Meca, eran las evidencias m\u00e1s obvias de una religi\u00f3n pr\u00e1ctica, tan concisa y acertadamente personificada en las palabras cr\u00edticas de Muhammad, que la piedad y bendiciones de Dios lo acompa\u00f1en, \u201cConf\u00eda en Dios y ata tu camello\u201d. Nos brind\u00f3 un sistema de religi\u00f3n de acci\u00f3n normal, no fe ciega en la protecci\u00f3n de una fuerza invisible en lugar de nuestra propia negligencia, sino confianza de que hacemos todas las cosas bien y lo mejor que podamos, podemos confiar en lo que viene como Voluntad de Dios.<\/p>\n<p>El amplio criterio de la tolerancia del Islam por otras religiones conquista a todos los amantes de la libertad. Muhammad advirti\u00f3 a sus seguidores que trataran bien a los creyentes del Antiguo y Nuevo Testamento; Abraham, Mois\u00e9s y Jes\u00fas son conocidos como profetas del \u00danico Dios. Seguramente esta actitud es generosa y m\u00e1s avanzada que las de las dem\u00e1s religiones.<\/p>\n<p>El desentendimiento total de la idolatr\u00eda\u2026 es un signo de la salubre fuerza y pureza de la fe musulmana.<\/p>\n<p>Las ense\u00f1anzas originales del Profeta de Dios no est\u00e1n envueltas en el laberinto de cambios y adherencias de doctrinas. El Cor\u00e1n contin\u00faa siendo como lleg\u00f3 a las corruptas y polite\u00edstas personas de los tiempos de Muhammad, incambiable como el sagrado Coraz\u00f3n del Islam mismo.<\/p>\n<p>La moderaci\u00f3n y la templanza en todas las cosas, las claves del Islam, ganaron mi incalificable aprobaci\u00f3n. La salud de estas personas era apreciada por el Profeta, quien disfrutaba observar una estricta pulcritud y espec\u00edficos ayunos y subordinados apetitos carnales\u2026 cuando me detuve en las inspiradoras mezquitas de Estambul, Damasco, Jerusal\u00e9n, el Cairo, Argel, T\u00e1nger, Fez y otras ciudades, fui consciente de la poderosa reacci\u00f3n a la potente elevaci\u00f3n del simple llamado del Islam al sentido de cosas m\u00e1s elevadas, sin la ayuda de trampas elaboradas, figuras, dibujos, m\u00fasica y rituales ceremoniales. La mezquita es un lugar de tranquila contemplaci\u00f3n y auto inscripci\u00f3n en la grandiosa realidad del \u00danico Dios.<\/p>\n<p>La democracia del Islam siempre hab\u00eda llamado mi atenci\u00f3n. Los ricos y los pobres tienen los mismos derechos en el piso de la mezquita, en sus frentes, en la humilde adoraci\u00f3n. No hay bancos comprados ni asientos reservados.<\/p>\n<p>El musulm\u00e1n no acepta a ning\u00fan hombre como mediador entre \u00e9l y su Dios. Va directamente a la fuente invisible de creaci\u00f3n y vida, Dios, sin dependencia de una f\u00f3rmula de salvaci\u00f3n o arrepentimiento de pecados y la creencia en el poder de un maestro para lograr la salvaci\u00f3n.<br \/>\nLa universal hermandad del Islam, sin importar la raza, pol\u00edtica, color o pa\u00eds, me ha brindado los mejores tiempos de mi vida y esa es otra caracter\u00edstica que me acerc\u00f3 a la Fe.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/esp\/articles\/coronel-donald-s&#8211;rockwell-poeta-y-critico-usa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La simplicidad del Islam, el poderoso llamado y la absorbente atm\u00f3sfera de sus mezquitas, sus fervientes fieles, la confianza que inspira la realizaci\u00f3n de millones a lo largo del mundo que responden a las cinco llamadas a la oraci\u00f3n \u2013 estos factores me atrajeron desde el principio. Pero despu\u00e9s de decidir que me convertir\u00eda en &#8230; <a title=\"Coronel Donald S. Rockwell, Poeta y Critico, USA\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/es\/coronel-donald-s-rockwell-poeta-y-critico-usa\/\" aria-label=\"Leer m\u00e1s sobre Coronel Donald S. Rockwell, Poeta y Critico, USA\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[163],"tags":[],"class_list":["post-8187","post","type-post","status-publish","format-standard","hentry","category-por-que-me-converti-en-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/es\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"La simplicidad del Islam, el poderoso llamado y la absorbente atm\u00f3sfera de sus mezquitas, sus fervientes fieles, la confianza que inspira la realizaci\u00f3n de millones a lo largo del mundo que responden a las cinco llamadas a la oraci\u00f3n \u2013 estos factores me atrajeron desde el principio. Pero despu\u00e9s de decidir que me convertir\u00eda en&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-283","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":8187,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":8187,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":8187,"position":2},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/www.ask-a-muslim.com\/de\/abdullah-delancey-ex-christ-canada\/","url_meta":{"origin":8187,"position":3},"title":"Abdullah DeLancey, Ex-Christ, Canada","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Mein Name ist Abdullah DeLancey. Ich bin Kanadier und ich bin beim \u00f6rtlichen Krankenhaus im Patientenservice besch\u00e4ftigt. Ich bin seit \u00fcber 20 Jahren verheiratet und wir haben drei wunderbare Kinder. Alhamdulillah, ich bin jetzt Muslim. Ich war aber nicht immer Muslim gewesen. Zuerst war ich mein Leben lang ein protestantischer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":8187,"position":4},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8633,"url":"https:\/\/www.ask-a-muslim.com\/de\/sally-ex-katholikin-philippinen\/","url_meta":{"origin":8187,"position":5},"title":"Sally, Ex-Katholikin, Philippinen","author":"Site Admin","date":"20 de junio de 2020","format":false,"excerpt":"Ich wuchs in einer katholischen Familie auf und lernte katholische Werte und Traditionen. Mit f\u00fcnfzehn trat ich ins Kloster ein. Im Kloster war ich gl\u00fccklich, denn ich konnte meinen Pflichten als Nonne nachkommen und alle Menschen um mich herum einschlie\u00dflich meiner Familie waren auch mit mir zufrieden. Bis zu einer\u2026","rel":"","context":"En \u00abWARUM WURDE ICH MUSLIM\u00bb","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/comments?post=8187"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8187\/revisions"}],"predecessor-version":[{"id":9978,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/posts\/8187\/revisions\/9978"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/media?parent=8187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/categories?post=8187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/es\/wp-json\/wp\/v2\/tags?post=8187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}