{"id":7367,"date":"2020-06-17T01:46:14","date_gmt":"2020-06-17T06:46:14","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7367"},"modified":"2020-07-01T00:44:30","modified_gmt":"2020-07-01T05:44:30","slug":"la-mission-prophetique-en-islam","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/la-mission-prophetique-en-islam\/","title":{"rendered":"La mission proph\u00e9tique en islam"},"content":{"rendered":"<h3><strong>(partie 1 de 2): La nature de la proph\u00e9tie<\/strong><\/h3>\n<p>La mission proph\u00e9tique est commune \u00e0 toutes les religions r\u00e9v\u00e9l\u00e9es par Dieu, comme le juda\u00efsme, le christianisme et l\u2019islam. En islam, cependant, elle occupe un statut particulier et poss\u00e8de une signification diff\u00e9rente.<\/p>\n<p>Selon l\u2019islam, Dieu a cr\u00e9\u00e9 l\u2019homme pour une noble raison, c\u2019est-\u00e0-dire pour L\u2019adorer et pour mener une vie vertueuse fond\u00e9e sur Ses enseignements et Son message. Comment l\u2019homme pourrait-il conna\u00eetre le r\u00f4le que Dieu attend de lui et la raison de son existence s\u2019il ne re\u00e7oit pas de directives claires et applicables de la part de Dieu? C\u2019est ici que la mission proph\u00e9tique entre en jeu. Parmi chaque nation, Dieu a choisi au moins un proph\u00e8te afin que celui-ci transmette Son message \u00e0 son peuple.<\/p>\n<p>Comment ces proph\u00e8tes ont-ils \u00e9t\u00e9 choisis et qui donc \u00e9taient-ils pour m\u00e9riter un tel honneur ?<\/p>\n<p>La mission proph\u00e9tique est une b\u00e9n\u00e9diction et une faveur de Dieu, qu\u2019Il accorde \u00e0 qui Il veut. Cependant, si l\u2019on consid\u00e8re les diff\u00e9rents messagers qui ont \u00e9t\u00e9 envoy\u00e9s, dans le pass\u00e9, on reconna\u00eet chez chacun d\u2019eux trois caract\u00e9ristiques communes :<br \/>\n1. Il est le meilleur homme de sa communaut\u00e9, \u00e0 la fois moralement et intellectuellement. Cela va de soi lorsque l\u2019on sait que la vie d\u2019un proph\u00e8te sert de mod\u00e8le \u00e0 suivre pour ses fid\u00e8les. Sa personnalit\u00e9 doit pouvoir inciter les gens \u00e0 accepter son message, car il est naturel que les gens soient rebut\u00e9s par une personne au mauvais caract\u00e8re. Puis, apr\u00e8s avoir re\u00e7u le message qu\u2019il doit transmettre, il devient infaillible, c\u2019est-\u00e0-dire qu\u2019il ne commet plus de p\u00e9ch\u00e9s. Il peut, certes, commettre certaines erreurs sans gravit\u00e9; dans ce cas, il re\u00e7oit habituellement une r\u00e9v\u00e9lation qui vient la corriger.<\/p>\n<p>2. Pour prouver aux gens qu\u2019il n\u2019est pas un imposteur, Dieu le soutient par des miracles. Ces miracles ne sont pas accomplis par le proph\u00e8te lui-m\u00eame, mais sont rendus possibles par le pouvoir et par la permission de Dieu, et touchent habituellement les domaines dans lesquels le peuple auxquels ils s\u2019adressent excellent ou sont reconnus comme sup\u00e9rieurs. Nous pouvons illustrer ce fait en donnant pour exemple les grands miracles accord\u00e9s aux trois proph\u00e8tes des trois grandes religions : le juda\u00efsme, le christianisme et l\u2019islam.<\/p>\n<p>De nombreuses personnes du peuple de Mo\u00efse excellaient dans la pratique de la magie; alors son plus grand miracle a \u00e9t\u00e9 de vaincre la magie des plus grands magiciens de l\u2019\u00c9gypte, \u00e0 son \u00e9poque. Les contemporains de J\u00e9sus \u00e9taient connus pour \u00eatre de bons m\u00e9decins; ses miracles ont donc consist\u00e9 \u00e0 faire revivre le mort et \u00e0 gu\u00e9rir celui qui \u00e9tait atteint d\u2019une maladie incurable. Les Arabes, \u00e0 l\u2019\u00e9poque du proph\u00e8te Mohammed (paix et b\u00e9n\u00e9dictions de Dieu soient sur lui), \u00e9taient connus pour leur \u00e9loquence et pour leur grand talent en po\u00e9sie. Alors le plus grand miracle de Mohammed a \u00e9t\u00e9 le Coran, que des l\u00e9gions de po\u00e8tes et d\u2019orateurs n\u2019ont jamais \u00e9t\u00e9 capables d\u2019imiter bien qu\u2019ils en aient \u00e9t\u00e9 mis au d\u00e9fi par le Coran lui-m\u00eame. Le miracle de Mohammed est particulier. En effet, tous les miracles apport\u00e9s par les autres proph\u00e8tes \u00e9taient limit\u00e9s dans l\u2019espace et dans le temps, c\u2019est-\u00e0-dire qu\u2019ils ont \u00e9t\u00e9 pr\u00e9sent\u00e9s \u00e0 des peuples particuliers, \u00e0 des moments particuliers. Mais le miracle du proph\u00e8te Mohammed (paix et b\u00e9n\u00e9dictions de Dieu soient sur lui), le Coran, est universel et \u00e9ternel. Les g\u00e9n\u00e9rations pass\u00e9es en ont \u00e9t\u00e9 t\u00e9moin, et les g\u00e9n\u00e9rations futures seront \u00e9galement t\u00e9moin de sa nature miraculeuse du point de vue du style, du contenu et de sa haute spiritualit\u00e9. Ces caract\u00e9ristiques du Coran sont une preuve de son origine divine.<\/p>\n<p>3. Chaque proph\u00e8te affirme clairement que le message qu\u2019il re\u00e7oit n\u2019est pas de sa propre invention mais qu\u2019il provient de Dieu et qu\u2019il est destin\u00e9 au bien-\u00eatre de l\u2019humanit\u00e9. Il confirme \u00e9galement ce qui a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 avant lui et ce qui sera peut-\u00eatre r\u00e9v\u00e9l\u00e9 apr\u00e8s lui. Il fait cela pour d\u00e9montrer qu\u2019il n\u2019est l\u00e0 que pour transmettre le message qui lui a \u00e9t\u00e9 confi\u00e9 par l\u2019Unique v\u00e9ritable Dieu, Dieu de tous les peuples et de toutes les \u00e9poques. Le message, donc, est essentiellement le m\u00eame et sert le m\u00eame objectif. Ainsi, lorsqu\u2019un proph\u00e8te transmet un message, celui-ci ne doit pas d\u00e9vier de ce qui avait \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 avant lui ou de ce qui pourrait \u00eatre r\u00e9v\u00e9l\u00e9 apr\u00e8s lui.<\/p>\n<p>Les proph\u00e8tes sont essentiels pour transmettre les instructions et le message de Dieu \u00e0 l\u2019humanit\u00e9. Nous n\u2019avons aucun autre moyen de conna\u00eetre la raison pour laquelle nous avons \u00e9t\u00e9 cr\u00e9\u00e9s. Qu\u2019adviendra-t-il de nous apr\u00e8s notre mort? Y a-t-il une vie apr\u00e8s la mort? Sommes-nous redevables de nos actions? Ces questions et beaucoup d\u2019autres sur Dieu, les anges, le Paradis, l\u2019Enfer et d\u2019autres sujets connexes ne peuvent trouver r\u00e9ponse si ce n\u2019est par l\u2019interm\u00e9diaire d\u2019une r\u00e9v\u00e9lation directe du Cr\u00e9ateur, de Celui qui conna\u00eet le monde invisible. Ces r\u00e9ponses doivent \u00eatre authentiques et doivent \u00eatre apport\u00e9es par des individus que nous respectons et en qui nous avons confiance. Voil\u00e0 pourquoi les messagers occupent une si haute position par rapport au commun des mortels sur le plan de la conduite morale et de l\u2019intelligence.<\/p>\n<p>Ainsi, les histoires calomniant certains proph\u00e8tes, que l\u2019on retrouve dans la Bible, sont, pour les musulmans, totalement inacceptables. Par exemple, la Bible raconte que le proph\u00e8te Lot aurait eu des rapports incestueux alors qu\u2019il \u00e9tait ivre et que le proph\u00e8te David aurait envoy\u00e9 un de ses leaders \u00e0 sa mort pour pouvoir \u00e9pouser sa femme. Mais pour les musulmans, les proph\u00e8tes se situent bien au-del\u00e0 de ce qui est rapport\u00e9 dans ces r\u00e9cits. Du point de vue islamique, ces r\u00e9cits ne contiennent aucune v\u00e9rit\u00e9.<\/p>\n<p>Les proph\u00e8tes sont aussi soutenus miraculeusement par Dieu et ont pour ordre d\u2019assurer la continuit\u00e9 du message. Le contenu du message des proph\u00e8tes aux hommes peut \u00eatre r\u00e9sum\u00e9 comme suit :<br \/>\na) Un concept de Dieu clair et facile \u00e0 comprendre : Ses attributs, Sa cr\u00e9ation, ce qui peut et ce qui ne doit pas Lui \u00eatre attribu\u00e9.<br \/>\nb) Un concept clair du monde invisible, des anges, des djinns, du Paradis et de l\u2019Enfer.<br \/>\nc) La raison pour laquelle Dieu nous a cr\u00e9\u00e9s, ce qu\u2019Il attend de nous, les r\u00e9compenses pour Lui avoir ob\u00e9i, et les ch\u00e2timents pour Lui avoir d\u00e9sob\u00e9i.<br \/>\nd) Comment diriger nos soci\u00e9t\u00e9s selon Sa volont\u00e9, c\u2019est-\u00e0-dire des instructions et des lois claires qui, lorsque appliqu\u00e9es correctement et honn\u00eatement, ne peuvent que r\u00e9sulter en une soci\u00e9t\u00e9 qui fonctionne de fa\u00e7on harmonieuse.<\/p>\n<p>Il est clair, d\u2019apr\u00e8s ce qui pr\u00e9c\u00e8de, que rien ni personne ne peut pr\u00e9tendre remplacer les proph\u00e8tes. M\u00eame de nos jours, avec les progr\u00e8s de la science, la seule source d\u2019information authentique sur le monde surnaturel demeure la r\u00e9v\u00e9lation. Ni la science ni les exp\u00e9riences \u00ab mystiques \u00bb ne peuvent servir de guide \u00e0 l\u2019homme. La premi\u00e8re est trop mat\u00e9rialiste et limit\u00e9e, tandis que les secondes sont trop subjectives et trompeuses.<\/p>\n<p>&nbsp;<\/p>\n<h3>\n<strong>(partie 2 de 2): Croire en tous les proph\u00e8tes, sans distinction<\/strong><\/h3>\n<p>Combien de proph\u00e8tes Dieu a-t-Il envoy\u00e9 \u00e0 l\u2019humanit\u00e9? Nous ne pouvons \u00eatre certains que de ce qui est clairement mentionn\u00e9 dans le Coran, c\u2019est-\u00e0-dire qu\u2019Il a envoy\u00e9 un proph\u00e8te \u00e0 chaque nation. Car un des principes de Dieu est qu\u2019Il ne demandera jamais de comptes \u00e0 un peuple \u00e0 moins de l\u2019avoir clairement inform\u00e9 de ce qui lui est permis et de ce qui lui est interdit. Le Coran mentionne les noms de 25 proph\u00e8tes et laisse entendre qu\u2019il y en a eu d\u2019autres dont les noms n\u2019ont pas \u00e9t\u00e9 transmis au proph\u00e8te Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui). Parmi ces 25 noms, on retrouve ceux de No\u00e9, Abraham, Mo\u00efse, J\u00e9sus et Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur eux tous), qui sont les cinq plus grands proph\u00e8tes de Dieu. On les appelle les \u00ab proph\u00e8tes r\u00e9solus \u00bb.<\/p>\n<p>Un aspect remarquable de la croyance islamique en la proph\u00e9tie est le fait que les musulmans croient en tous les messagers de Dieu sans exception et leur vouent \u00e0 tous le plus grand respect. Tous les proph\u00e8tes ont \u00e9t\u00e9 envoy\u00e9s par le m\u00eame Dieu unique et pour la m\u00eame raison : guider l\u2019humanit\u00e9 vers Dieu. Croire en chacun d\u2019eux est donc essentiel et logique. Certaines personnes ne croient qu\u2019en certains d\u2019entre eux tout en rejetant les autres; cette attitude ne peut que d\u00e9couler d\u2019une mauvaise compr\u00e9hension du r\u00f4le jou\u00e9 par les proph\u00e8tes ou d\u2019un pr\u00e9jug\u00e9 racial. Les musulmans sont les seuls au monde \u00e0 consid\u00e9rer la croyance en tous les proph\u00e8tes comme un des articles de la foi. Les juifs rejettent J\u00e9sus et Mohammed (que la paix soit sur eux) et les chr\u00e9tiens rejettent Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui). Les musulmans, quant \u00e0 eux, les consid\u00e8rent tous comme des messagers de Dieu, qui ont transmis Son message \u00e0 l\u2019humanit\u00e9 afin de la guider. Cependant, les r\u00e9v\u00e9lations transmises par les proph\u00e8tes qui ont pr\u00e9c\u00e9d\u00e9 Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui) ont toutes \u00e9t\u00e9 alt\u00e9r\u00e9es d\u2019une fa\u00e7on ou d\u2019une autre.<\/p>\n<p>Dans le Coran, Dieu enjoint les musulmans \u00e0 croire en tous les proph\u00e8tes:<br \/>\n\u00ab Dites, (\u00f4 musulmans) : \u00ab Nous croyons en Dieu et en ce qui nous est r\u00e9v\u00e9l\u00e9, et en ce qui a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 \u00e0 Abraham, Isma\u00ebl, Isaac, Jacob et les Tribus, en ce qui a \u00e9t\u00e9 donn\u00e9 \u00e0 Mo\u00efse et \u00e0 J\u00e9sus, et en ce qui a \u00e9t\u00e9 donn\u00e9 \u00e0 (tous) les proph\u00e8tes, de la part de leur Seigneur. Nous ne faisons aucune distinction entre eux et nous nous soumettons enti\u00e8rement \u00e0 Dieu. \u00bb (Coran 2:136)<\/p>\n<p>Aux versets suivants, le Coran dit aux musulmans que cette croyance est la seule qui soit v\u00e9ritable et juste. Si les autres nations y croient \u00e9galement, c\u2019est qu\u2019elles suivent la bonne voie; mais si elles n\u2019y croient pas, c\u2019est qu\u2019elles suivent leurs caprices et leurs pr\u00e9jug\u00e9s et Dieu saura s\u2019occuper d\u2019elles :<br \/>\n\u00ab S\u2019ils croient \u00e0 ce \u00e0 quoi vous croyez, ils seront alors guid\u00e9s [dans la bonne voie]. Mais s\u2019ils se d\u00e9tournent, alors ils seront coupables de schisme et Dieu vous suffira (pour vous d\u00e9fendre) contre eux. Certes, Il entend tout et Il sait tout. \u00ab (Notre religion est) la religion de Dieu, [l\u2019islam]. Et quelle religion est meilleure que celle de Dieu? \u00bb \u00bb (Coran 2:137-138)<\/p>\n<p>Il y a deux points importants, au sujet de la proph\u00e9tie, qui doivent \u00eatre clarifi\u00e9s. Ils concernent les r\u00f4les de J\u00e9sus et de Mohammed (que la paix soit sur eux) comme proph\u00e8tes.<\/p>\n<p>Les versets coraniques relatant l\u2019histoire de J\u00e9sus rejettent cat\u00e9goriquement le concept de sa \u00ab divinit\u00e9 \u00bb et l\u2019id\u00e9e qu\u2019il serait le \u00ab fils de Dieu \u00bb, et le pr\u00e9sentent plut\u00f4t comme un des grands proph\u00e8tes de Dieu. Le Coran pr\u00e9cise clairement que le fait que J\u00e9sus soit n\u00e9 sans avoir \u00e9t\u00e9 con\u00e7u par un homme ne fait pas de lui le fils de Dieu, et il donne comme exemple Adam, qui a \u00e9t\u00e9 cr\u00e9\u00e9 par Dieu et qui n\u2019a eu ni p\u00e8re ni m\u00e8re.<\/p>\n<p>\u00ab Certes, pour Dieu, J\u00e9sus est comme Adam, qu\u2019Il cr\u00e9a de poussi\u00e8re (de la terre), puis lui dit : \u00ab Sois! \u00bb et il fut. \u00bb (Coran 3:59)<\/p>\n<p>Comme d\u2019autres proph\u00e8tes, J\u00e9sus a accompli des miracles. Par exemple, il a fait revivre le mort et il a gu\u00e9ri l\u2019aveugle et le l\u00e9preux; mais \u00e0 chaque fois, il a clairement affirm\u00e9 que ces miracles \u00e9taient l\u2019\u0153uvre de Dieu et non la sienne. En fait, si tant d\u2019id\u00e9es fausses sur la personnalit\u00e9 et la mission de J\u00e9sus (que la paix soit sur lui) ont pu se r\u00e9pandre parmi ses fid\u00e8les, c\u2019est que le message divin qu\u2019il pr\u00eachait n\u2019a jamais \u00e9t\u00e9 mis par \u00e9crit de son vivant; il ne l\u2019a \u00e9t\u00e9 qu\u2019environ un si\u00e8cle plus tard. Selon le Coran, J\u00e9sus a \u00e9t\u00e9 envoy\u00e9 au peuple d\u2019Isra\u00ebl; il a confirm\u00e9 la validit\u00e9 de la Torah, qui avait \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e par Mo\u00efse (que la paix soit sur lui), et il a annonc\u00e9 la bonne nouvelle de la venue d\u2019un dernier messager apr\u00e8s lui.<\/p>\n<p>\u00ab Et quand J\u00e9sus, fils de Marie, dit : \u00ab \u00d4 enfants d\u2019Isra\u00ebl! Je suis vraiment le messager de Dieu, qui vous est [envoy\u00e9] pour confirmer ce qui a \u00e9t\u00e9 (r\u00e9v\u00e9l\u00e9), avant ma venue, dans la Torah, et pour vous annoncer la bonne nouvelle d\u2019un messager qui viendra apr\u00e8s moi et dont le nom sera \u00ab Ahmed \u00bb. (Coran 61:6)<\/p>\n<p>Cependant, la majorit\u00e9 des juifs ont rejet\u00e9 son minist\u00e8re. Ils ont complot\u00e9 pour le tuer et l\u2019ont crucifi\u00e9 (ou du moins se sont-ils imagin\u00e9 l\u2019avoir crucifi\u00e9). Mais le Coran r\u00e9fute cette croyance et affirme qu\u2019ils ne l\u2019ont ni tu\u00e9 ni crucifi\u00e9. La v\u00e9rit\u00e9, c\u2019est que J\u00e9sus a \u00e9t\u00e9 \u00e9lev\u00e9 vers Dieu. Il y a un verset, dans le Coran, qui laisse entendre que J\u00e9sus reviendra sur terre et que tous les chr\u00e9tiens et les juifs croiront en lui avant sa mort. D\u2019ailleurs, cette affirmation est corrobor\u00e9e par plusieurs hadiths du proph\u00e8te Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui).<\/p>\n<p>Le dernier des proph\u00e8tes envoy\u00e9s par Dieu, Mohammed, est n\u00e9 en Arabie au sixi\u00e8me si\u00e8cle de l\u2019\u00e8re chr\u00e9tienne. Jusqu\u2019\u00e0 l\u2019\u00e2ge de quarante ans, les gens de la Mecque ne le connaissaient que comme un homme poss\u00e9dant un tr\u00e8s bon caract\u00e8re et d\u2019excellentes mani\u00e8res; ils l\u2019appelaient d\u2019ailleurs \u00ab al-Amin \u00bb, c\u2019est-\u00e0-dire \u00ab l\u2019int\u00e8gre \u00bb. \u00c0 ce moment-l\u00e0, il ignorait qu\u2019il allait bient\u00f4t \u00eatre appel\u00e9 \u00e0 devenir proph\u00e8te et recevoir une r\u00e9v\u00e9lation de Dieu. Une fois investi de sa mission, il appela les idol\u00e2tres de la Mecque \u00e0 n\u2019adorer que Dieu, le seul et unique m\u00e9ritant d\u2019\u00eatre ador\u00e9, et \u00e0 l\u2019accepter, lui Mohammed, comme Son proph\u00e8te. La r\u00e9v\u00e9lation qu\u2019il re\u00e7ut fut m\u00e9moris\u00e9e de son vivant par ses compagnons et mise par \u00e9crit par diff\u00e9rents moyens (morceaux de cuir, pierres, grandes feuilles de palmier, etc.). C\u2019est ainsi que le Coran que nous retrouvons de nos jours est exactement le m\u00eame qui fut r\u00e9v\u00e9l\u00e9 au Proph\u00e8te; pas une seule lettre n\u2019en a \u00e9t\u00e9 retir\u00e9e ou modifi\u00e9e, Dieu Lui-m\u00eame en ayant garanti la pr\u00e9servation. Ce Coran constitue un guide pour toute l\u2019humanit\u00e9, en tous lieux et tous temps, et il affirme clairement que Mohammed (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui) est le dernier des proph\u00e8tes envoy\u00e9s par Dieu.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/-la-mission-prophtique-en-islam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2): La nature de la proph\u00e9tie La mission proph\u00e9tique est commune \u00e0 toutes les religions r\u00e9v\u00e9l\u00e9es par Dieu, comme le juda\u00efsme, le christianisme et l\u2019islam. En islam, cependant, elle occupe un statut particulier et poss\u00e8de une signification diff\u00e9rente. Selon l\u2019islam, Dieu a cr\u00e9\u00e9 l\u2019homme pour une noble raison, c\u2019est-\u00e0-dire pour L\u2019adorer et &#8230; <a title=\"La mission proph\u00e9tique en islam\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/la-mission-prophetique-en-islam\/\" aria-label=\"Read more about La mission proph\u00e9tique en islam\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[144],"tags":[],"class_list":["post-7367","post","type-post","status-publish","format-standard","hentry","category-doctrine-et-sectes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 2): La nature de la proph\u00e9tie La mission proph\u00e9tique est commune \u00e0 toutes les religions r\u00e9v\u00e9l\u00e9es par Dieu, comme le juda\u00efsme, le christianisme et l\u2019islam. En islam, cependant, elle occupe un statut particulier et poss\u00e8de une signification diff\u00e9rente. Selon l\u2019islam, Dieu a cr\u00e9\u00e9 l\u2019homme pour une noble raison, c\u2019est-\u00e0-dire pour L\u2019adorer et\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1UP","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7367,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8500,"url":"https:\/\/www.ask-a-muslim.com\/de\/die-barmherzigkeit-muhammads-gegenueber-nicht-muslimen\/","url_meta":{"origin":7367,"position":1},"title":"Die Barmherzigkeit Muhammads gegen\u00fcber Nicht-Muslimen","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Der Prophet Muhammad - Gottes Lob und Friede seien auf ihm - wurde als \u201cGnade f\u00fcr alle Welten\u201d angek\u00fcndigt, wie Gott im Quran sagte: \u201cWir sandten dich als Gnade f\u00fcr alle Welten.\u201d \u00a0 Die Empf\u00e4nger dieser Gnade waren nicht nur auf die muslimische Gemeinschaft beschr\u00e4nkt,\u2026","rel":"","context":"Dans &quot;MUHAMMAD, FRIEDE SEI AUF IHM&quot;","block_context":{"text":"MUHAMMAD, FRIEDE SEI AUF IHM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/muhammad-friede-sei-auf-ihm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8501,"url":"https:\/\/www.ask-a-muslim.com\/de\/aus-einem-feind-wird-ein-freund\/","url_meta":{"origin":7367,"position":2},"title":"Aus einem Feind wird ein Freund","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Im sechsten Jahr nach der Hijra (der Auswanderung nach Medina) entschloss sich der Prophet, Gottes Segen und Frieden seien auf ihm, den Kreis seiner Mission auszuweiten. Er schickte acht Briefe an Herrscher auf der arabischen Halbinsel und den angrenzenden Gebieten, um sie zum Islam einzuladen. Einer dieser Herrscher war Thumamah\u2026","rel":"","context":"Dans &quot;MUHAMMAD, FRIEDE SEI AUF IHM&quot;","block_context":{"text":"MUHAMMAD, FRIEDE SEI AUF IHM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/muhammad-friede-sei-auf-ihm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8499,"url":"https:\/\/www.ask-a-muslim.com\/de\/die-letzte-predigt-des-propheten-muhammad-eine-abschliessende-ermahnung\/","url_meta":{"origin":7367,"position":3},"title":"Die letzte Predigt des Propheten Muhammad: Eine abschlie\u00dfende Ermahnung","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Der geliebte Prophet Muhammad, m\u00f6ge Gott ihn loben und segnen, wurde etwa 570 nChr. in Mekka, Saudi Arabien, geboren. Er ist ein Vorbild f\u00fcr die gesamte Menschheit. Er war durchweg ein bemerkenswerter Mann. Er zeichnete sich in allen Lebenslagen aus: als Prophet, Gesetzgeber, Philosoph, Redner, K\u00e4mpfer, Ehemann, Freund, Vater, Onkel,\u2026","rel":"","context":"Dans &quot;MUHAMMAD, FRIEDE SEI AUF IHM&quot;","block_context":{"text":"MUHAMMAD, FRIEDE SEI AUF IHM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/muhammad-friede-sei-auf-ihm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8659,"url":"https:\/\/www.ask-a-muslim.com\/de\/moisha-krivitsky-ex-rabbi-dagestan\/","url_meta":{"origin":7367,"position":4},"title":"Moisha Krivitsky, Ex-Rabbi, Dagestan","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Der Rabbi der Makhachkala Synagoge nahm den Islam an. Jeder Mensch hat einen anderen Weg, die Wahrheit zu finden. F\u00fcr Moisha Krivitski f\u00fchrte dieser Weg \u00fcber die Fakult\u00e4t f\u00fcr Jura, eine Synagoge und ein Gef\u00e4ngnis. Der angehende Jurist wird erst Rabbi, dann konvertiert er zum Islam und findet sich im\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8571,"url":"https:\/\/www.ask-a-muslim.com\/de\/musa-caplan-ex-jude-usa\/","url_meta":{"origin":7367,"position":5},"title":"Musa Caplan, Ex-Jude, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Vor meiner Konvertierung zum Islam lebte ich mein Leben als Jude. Obwohl meine Familie nicht traditionell war, lernte ich das Judentum von traditionellen Juden. Ich ging zu einer orthodoxen j\u00fcdischen Synagoge und zu einer orthodoxen j\u00fcdischen Schule. Ich lebte und lebe immer noch in einer j\u00fcdischen Gemeinde in den USA,\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7367"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7367\/revisions"}],"predecessor-version":[{"id":11032,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7367\/revisions\/11032"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}