{"id":7382,"date":"2020-06-17T01:51:10","date_gmt":"2020-06-17T06:51:10","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7382"},"modified":"2020-07-01T00:32:42","modified_gmt":"2020-07-01T05:32:42","slug":"les-interdits-lies-a-lihram","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/les-interdits-lies-a-lihram\/","title":{"rendered":"Les interdits li\u00e9s \u00e0 l\u2019Ihram"},"content":{"rendered":"<h4><strong>Les interdits li\u00e9s \u00e0 l\u2019Ihr\u00e2m<\/strong><\/h4>\n<p>Extraits de : El Manhaj Li Mur\u00eed el \u2018Umra wa el Hadj de She\u00efkh Mohammed ibn S\u00e2lih el \u2018Utha\u00efm\u00een (p. 29-35).<\/p>\n<p>Que les pri\u00e8res d\u2019Allah et Son Salut soient sur Mohammed, ainsi que sur ses proches,<br \/>\net tous ses Compagnons !<\/p>\n<p>Les interdits (Mahdh\u00fbr\u00e2t) de l\u2019Ihr\u00e2m correspondent aux actions que le p\u00e8lerin doit s\u2019abstenir de commettre au cours de l\u2019Ihr\u00e2m (l\u2019\u00e9tat de sacralisation). Ces derniers se r\u00e9partissent en trois cat\u00e9gories :<br \/>\n\u2022 La premi\u00e8re cat\u00e9gorie concerne indiff\u00e9remment les hommes et les femmes,<br \/>\n\u2022 La deuxi\u00e8me cat\u00e9gorie concerne les hommes ind\u00e9pendamment des femmes,<br \/>\n\u2022 La troisi\u00e8me cat\u00e9gorie concerne les femmes ind\u00e9pendamment des hommes.<\/p>\n<p>Les interdits li\u00e9s \u00e0 la premi\u00e8re cat\u00e9gorie :<br \/>\n1- Se raser ou se couper les cheveux de la t\u00eate. Les poils du corps selon l\u2019opinion la plus r\u00e9pandue des savants ont le m\u00eame statut que les cheveux. Cependant, il est possible de se d\u00e9barrasser des cheveux ou des poils qui portent pr\u00e9judice de sorte que le seul moyen de s\u2019\u00e9pargner de cette nuisance est de s\u2019en d\u00e9barrasser. Dans ce cas, il est permis de le faire sans que le p\u00e8lerin n\u2019ait aucun grief \u00e0 son encontre. Ce dernier peut \u00e9galement se gratter la t\u00eate avec mod\u00e9ration et si des cheveux chutent sans le faire expr\u00e8s, il n\u2019a rien non plus \u00e0 son encontre.<\/p>\n<p>2- Se mettre du parfum sur le v\u00eatement ou le corps apr\u00e8s s\u2019\u00eatre sacralis\u00e9. Il est possible toutefois de se parfumer le corps avant d\u2019entrer en sacralisation sans qu\u2019il n\u2019y ait d\u2019inconv\u00e9nient \u00e0 ce que ses effets persistent au cours de l\u2019Ihr\u00e2m. Il est interdit en effet de se mettre du parfum en \u00e9tat d\u2019Ihr\u00e2m mais sentir encore le parfum pendant l\u2019Ihr\u00e2m est permis. Dans ce registre, il n\u2019est pas permis au p\u00e8lerin de boire du caf\u00e9 m\u00e9lang\u00e9 au safran qui est une forme de parfum, sauf si le go\u00fbt et l\u2019odeur se sont \u00e9vapor\u00e9s avec la cuisson et bien qu\u2019il en reste encore la couleur.<\/p>\n<p>3- Regarder ou toucher une personne de l\u2019autre sexe avec jouissance.<\/p>\n<p>4- Porter des gants.<\/p>\n<p>5- Chasser du gibier qui correspond \u00e0 tuer un animal sauvage que l\u2019homme a le droit de manger comme le l\u00e9zard du d\u00e9sert, le lapin, le pigeon, et m\u00eame les sauterelles ou les crickets. Il est permis toutefois pour le p\u00e8lerin de p\u00eacher du poisson et de tuer un animal domestique \u00e0 l\u2019exemple de la poule. Si des sauterelles se trouvent sur son chemin et qu\u2019il n\u2019y a aucun moyen de les \u00e9viter, il ne lui sera fait aucun grief s\u2019ils en \u00e9crasent involontairement quelques-unes. Ceci, car il ne peut faire autrement et que son intention n\u2019est pas de les tuer.<\/p>\n<p>Au demeurant, il n\u2019est pas interdit de couper une branche ou une feuille d\u2019un arbre ; cela n\u2019a aucune influence sur l\u2019\u00e9tat de sacralisation. Cette interdiction s\u2019applique \u00e0 tout le p\u00e9rim\u00e8tre de la ville Sainte et celle-ci concerne aussi bien les p\u00e8lerins que les non-p\u00e8lerins. Ainsi, il est autoris\u00e9 de toucher aux arbres de \u2018Arafa, qui n\u2019entre pas dans le p\u00e9rim\u00e8tre sacr\u00e9 contrairement \u00e0 Mouzdalifa et \u00e0 Mina qui appartiennent au territoire sacr\u00e9. Si le p\u00e8lerin arrache involontairement une branche d\u2019un arbre, il n\u2019aura rien \u00e0 son encontre. Cette interdiction ne concerne pas les arbres morts qu\u2019il est permis de couper.<\/p>\n<p>Quant aux interdits qui frappent les hommes ind\u00e9pendamment des femmes, ceux-ci sont au nombre de deux :<br \/>\n1- Porter des v\u00eatements cousus qui correspondent aux habits ou autre qui \u00e9pousent g\u00e9n\u00e9ralement la forme du corps comme le Qam\u00ees (chemise), le pull, et le pantalon. Il n\u2019est donc pas permis \u00e0 l\u2019homme en \u00e9tat d\u2019Ihr\u00e2m de porter normalement ce genre de v\u00eatements. Il peut toutefois s\u2019en servir sans les enfiler en portant par exemple son Qam\u00ees sur les \u00e9paules ou son manteau en le renversant. Il n\u2019y a pas d\u2019inconv\u00e9nient non plus \u00e0 porter un haut de l\u2019Ihr\u00e2m (Rid\u00e2) ou un bas (Iz\u00e2z) raccommod\u00e9 ou en une seule pi\u00e8ce. Il est possible \u00e9galement de porter une ceinture, une montre, des lunettes ou encore de faire tenir son habit avec des \u00e9pingles ou autre \u00e9tant donn\u00e9 que le Proph\u00e8te (\uf072) n\u2019a pas interdit ce genre de choses. Rien ne prouve au niveau du sens des Textes une telle interdiction. Par contre, lorsqu\u2019on interrogea le L\u00e9gislateur (\uf072) au sujet de l\u2019habit du p\u00e8lerin, il ne fit que r\u00e9pondre : \u00ab Il ne porte pas de Qam\u00ees, de \u2018Im\u00e2ma (turban), de Sar\u00e2w\u00eel (pantalon), de Burn\u00fbs (manteau), et de chaussons. \u00bb \u00c0 la question de savoir ce qu\u2019il doit porter, il a r\u00e9pondu par ce qu\u2019il ne doit pas porter ; cela d\u00e9montre qu\u2019il est possible de mettre toute sorte de choses qui ne figurent pas dans cette liste. Le Proph\u00e8te (\uf072) a par ailleurs autoris\u00e9 au p\u00e8lerin de v\u00eatir des chaussons en absence de sandales, car se prot\u00e9ger les pieds est un besoin. De la m\u00eame fa\u00e7on, il est alors autoris\u00e9 de porter des lunettes qui prot\u00e8gent les yeux. Selon l\u2019opinion la plus r\u00e9pandue de notre \u00c9cole, les l\u00e9gistes autorisent notamment \u00e0 l\u2019homme de porter un anneau en \u00e9tat d\u2019Ihr\u00e2m. S\u2019il ne trouve pas d\u2019Iz\u00e2r ou s\u2019il n\u2019a pas les moyens d\u2019en acheter, le p\u00e8lerin peut porter un pantalon de la m\u00eame fa\u00e7on qu\u2019il peut porter des chaussons s\u2019il n\u2019a pas de chaussures et s\u2019il n\u2019a pas les moyens de les acheter conform\u00e9ment au Hadith d\u2019ibn \u2018Abb\u00e2s (\uf074), selon lequel le Proph\u00e8te (\uf072) a d\u00e9clar\u00e9 lors de son sermon de \u2018Arafa : \u00ab Celui qui ne trouve pas de sandales peut porter des chaussons et celui qui ne trouve pas d\u2019Iz\u00e2r peut porter un Sar\u00e2w\u00eel. \u00bb<\/p>\n<p>2- Se couvrir la t\u00eate avec un turban, une \u2018Ghutra (keffieh), une T\u00e2qiya (calotte), etc. il n\u2019y a pas d\u2019inconv\u00e9nient \u00e0 se couvrir avec quelque chose qui ne s\u2019appuie pas directement sur la t\u00eate comme une tente, une ombrelle, le toit d\u2019une voiture ; il est interdit en effet de se couvrir la t\u00eate non de se mettre \u00e0 l\u2019ombre. Selon le Hadith d\u2019\u00dbm el Husa\u00efn el Ahmasiya, cette derni\u00e8re explique : \u00ab Nous \u00e9tions avec le Proph\u00e8te (\uf072) lors du P\u00e8lerinage de l\u2019Adieu. Je l\u2019ai vu au moment du \u00ab jet de pierre \u00bb \u00e0 Jamra el \u2018Aqaba. Il s\u2019est \u00e9loign\u00e9 en compagnie de Bilal et d\u2019Us\u00e2ma. Ensuite, alors qu\u2019il se tenait sur sa monture ; l\u2019un la conduisait et l\u2019autre tenait un v\u00eatement au-dessus de la t\u00eate du Proph\u00e8te (\uf072) pour le couvrir du soleil. \u00bb Une autre version pr\u00e9cise : \u00ab Il l\u2019a couvert contre la chaleur du soleil jusqu\u2019\u00e0 ce qu\u2019il ait lanc\u00e9 \u00e0 Jamra el \u2018Aqaba. \u00bb Rapport\u00e9 par Muslim et Ahmed. Cette sc\u00e8ne a eu lieu le jour de l\u2019A\u00efd avant que le Proph\u00e8te (\uf072) se soit d\u00e9sacralis\u00e9 \u00e9tant donn\u00e9 qu\u2019il a effectu\u00e9 les autres lancers de pierre \u00e0 pied et non sur sa chamelle. Il est \u00e9galement permis au p\u00e8lerin de porter des affaires sur sa t\u00eate si son intention n\u2019est pas de se la couvrir, comme il peut \u00e9galement plonger la t\u00eate sous l\u2019eau.<\/p>\n<p>&nbsp;<\/p>\n<h4>\n<strong>Quant aux interdits qui frappent les femmes ind\u00e9pendamment des hommes<\/strong><\/h4>\n<p>Il est sp\u00e9cifiquement interdit aux femmes de se voiler le visage avec un Niqab qui couvre une partie du visage en laissant les yeux \u00e0 l\u2019air libre afin de lui permettre de voir. Certains savants avancent cependant que l\u2019interdiction ne porte pas uniquement sur le Niqab, mais qu\u2019elle englobe n\u2019importe quel voile recouvrant le visage, sauf dans la situation o\u00f9 des hommes venaient \u00e0 passer devant une femme ; dans ce cas, il lui est impos\u00e9 de se couvrir le visage sans n\u2019avoir aucune compensation \u00e0 sa charge, que son voile vienne \u00e0 toucher la peau ou non.<\/p>\n<p>Une personne enfreint un interdit dans trois cas diff\u00e9rents :<br \/>\nPremi\u00e8rement : il y a le cas o\u00f9 la personne enfreint un interdit sans excuse valable et pour aucune raison. Le cas \u00e9ch\u00e9ant, elle est passible d\u2019un p\u00e9ch\u00e9 et elle est soumise \u00e0 une compensation.<\/p>\n<p>Deuxi\u00e8mement : il y a le cas o\u00f9 elle l\u2019enfreint pour une raison quelconque, par exemple si elle a besoin de porter un v\u00eatement en raison du froid ou si elle craint pour elle-m\u00eame. Dans ce cas pr\u00e9cis, elle peut le faire, mais elle doit compenser malgr\u00e9 tout cette action comme ce fut le cas pour Ka\u2019b ibn \u2018Ajwa (\uf074) qui re\u00e7ut la permission du Proph\u00e8te (\uf072) de se raser la t\u00eate \u00e9tant donn\u00e9 que les poux lui rongeaient les cheveux et le visage.<\/p>\n<p>Troisi\u00e8mement : il y a le cas o\u00f9 la personne ayant enfreint un interdit b\u00e9n\u00e9ficie d\u2019une circonstance att\u00e9nuante : par ignorance, oubli, inconscience ou contrainte. Le cas \u00e9ch\u00e9ant, elle n\u2019est ni est passible d\u2019un p\u00e9ch\u00e9 ni elle est soumise \u00e0 une compensation conform\u00e9ment au Verset suivant : \uf028Il ne vous sera pas tenu compte de vos erreurs, mais de ce que vos c\u0153urs \u00e9prouvent consciemment \uf029. Le Tr\u00e8s-Haut dit \u00e9galement : \uf028Seigneur ! Ne nous tiens pas rigueur de nos oublis et de nos erreurs \uf029. \u00c0 Allah de r\u00e9pondre : \u00ab Je m\u2019y engage ! \u00bb Le Proph\u00e8te (\uf072) nous apprend \u00e9galement \u00e0 travers un Hadith : \u00ab Allah ne tient pas rigueur \u00e0 ma communaut\u00e9 des actes faits par erreur, par oubli, et sous la contrainte. \u00bb<\/p>\n<p>Ces textes englobent notamment les fautes, au cours de la sacralisation, commises par erreur, par ignorance, ou sous la contrainte. Allah (\uf049) d\u00e9cr\u00e8te concernant sp\u00e9cialement l\u2019un des interdits de l\u2019Ihr\u00e2m qui consiste \u00e0 chasser du gibier : \uf028\u00d4 croyants ! Ne tuez pas du gibier alors que vous \u00eates en \u00e9tat de sacralisation. Quiconque parmi vous tue consciemment un animal devra en compensation offrir une b\u00eate \u00e9quivalente \uf029. Cette compensation incombe au fautif dans la condition o\u00f9 ce dernier l\u2019ait fait intentionnellement ; l\u2019acte intentionnel correspondait parfaitement \u00e0 l\u2019obligation de se soumettre \u00e0 une compensation. Il est tout \u00e0 fait ad\u00e9quat pour devenir ici le crit\u00e8re de consid\u00e9ration, dans le sens o\u00f9 la faute non intentionnelle n\u2019est pas soumise au p\u00e9ch\u00e9 ni \u00e0 aucune compensation.<\/p>\n<p>Or, \u00e0 partir du moment o\u00f9 la personne se r\u00e9veille, n\u2019est plus soumise \u00e0 la contrainte, se souvient ou apprend qu\u2019elle ait commise une erreur, elle n\u2019aura plus d\u2019excuse et devra imm\u00e9diatement cesser son erreur. Si elle persiste dans la faute alors qu\u2019elle n\u2019est plus excusable, elle sera passible d\u2019un p\u00e9ch\u00e9 et sera soumise \u00e0 une compensation. Par exemple, si un homme se couvre la t\u00eate au cours de son sommeil, il n\u2019aura aucun grief \u00e0 son encontre mais d\u00e8s son r\u00e9veil, il devra se d\u00e9couvrir la t\u00eate sur-le-champ. S\u2019il persiste \u00e0 se la couvrir en sachant pertinemment que cela lui est interdit, il devra expier sa faute.<\/p>\n<p>En cas de violation de l\u2019un des interdits que nous avons pr\u00e9c\u00e9demment \u00e9num\u00e9r\u00e9s, la compensation correspondante se d\u00e9compose de la fa\u00e7on suivante :<br \/>\n1- Concernant le fait de se couper les cheveux et les poils du corps, se parfumer, toucher sa femme avec envie, porter des gants, et pour les hommes uniquement porter des v\u00eatements cousus et se couvrir la t\u00eate, et enfin porter le Niqab pour la femme ; la compensation correspondante consiste au choix pour chacun de ces interdits \u00e0 :<br \/>\n-soit \u00e9gorg\u00e9 un mouton,<br \/>\n-soit nourrir six pauvres soit je\u00fbner trois jours.<\/p>\n<p>Le mouton \u00e0 immoler doit \u00eatre adulte qu\u2019il soit un m\u00e2le ou une femelle, selon les m\u00eames crit\u00e8res que l\u2019Udhhiya (le sacrifice de l\u2019A\u00efd) ; il est possible de choisir un septi\u00e8me d\u2019un chameau ou d\u2019une vache. Il faudra distribuer toute la viande aux pauvres sans rien en manger.<\/p>\n<p>Si l\u2019on choisit de nourrir six pauvres, il incombe de donner \u00e0 chaque pauvre la moiti\u00e9 d\u2019un Sa\u2019 de nourriture que l\u2019on consomme habituellement comme les dattes, le bl\u00e9, etc.<\/p>\n<p>Si l\u2019on choisit de je\u00fbner, il faut le faire pendant trois jours qu\u2019ils soient au choix cons\u00e9cutif ou non.<\/p>\n<p>2- Concernant la chasse, si le gibier dispose d\u2019un \u00e9quivalent, trois possibilit\u00e9s se pr\u00e9sentent alors :<br \/>\n-Il est possible d\u2019\u00e9gorger une b\u00eate \u00e9quivalente et de distribuer toute sa viande aux pauvres de La Mecque ;<br \/>\n-Il est possible \u00e9galement d\u2019\u00e9valuer en argent cette b\u00eate \u00e9quivalente et de convertir la somme correspondante en nourriture afin de distribuer \u00e0 chaque pauvre la moiti\u00e9 d\u2019un Sar de nourriture ;<br \/>\n-Il est possible enfin de je\u00fbner un nombre de jours \u00e9quivalent au nombre de pauvres \u00e0 nourrir.<br \/>\nSi le gibier ne dispose pas d\u2019\u00e9quivalent, on pourra choisir l\u2019une des deux options suivantes :<br \/>\n-On peut soit \u00e9valuer le prix de l\u2019animal tu\u00e9 et de le convertir ensuite en nourriture afin de le distribuer aux pauvres en veillant \u00e0 donner \u00e0 chacun d\u2019entre eux la moiti\u00e9 d\u2019un Sa\u2019 de nourriture,<br \/>\n-Soit je\u00fbner un nombre de jours \u00e9quivalent au nombre de pauvres \u00e0 nourrir.<\/p>\n<p>Si quelqu\u2019un tue un pigeon par exemple dont l\u2019\u00e9quivalent est un mouton, nous disons que le fautif \u00e0 le choix entre soit \u00e9gorger un mouton, soit \u00e9valuer le mouton en argent afin de distribuer la somme correspondante aux pauvres habitants de la Mecque et en veillant \u00e0 donner \u00e0 chacun d\u2019entre eux la moiti\u00e9 d\u2019un Sa\u2019 de nourriture ou soit de je\u00fbner un nombre de jours \u00e9quivalent au nombre de pauvres \u00e0 nourrir.<\/p>\n<p>Dans le cas o\u00f9 l\u2019animal tu\u00e9 volontairement n\u2019a pas d\u2019\u00e9quivalent en offrande comme la sauterelle ou le cricket, le fautif peut soit convertir son \u00e9quivalent en nourriture en faveur des pauvres habitants de la Mecque en veillant \u00e0 donner \u00e0 chacun d\u2019entre eux la moiti\u00e9 d\u2019un Sa\u2019 de nourriture, soit je\u00fbner un nombre de jours \u00e9quivalent au nombre de pauvres \u00e0 nourrir.<\/p>\n<p>Que les pri\u00e8res d\u2019Allah et Son Salut soient sur Mohammed, ainsi que sur ses proches, et tous ses Compagnons !<\/p>\n<p>Traduit pour Islamhouse par :<br \/>\nKarim ZENTICI<br \/>\nPubli\u00e9 par<br \/>\nLe bureau de pr\u00eache de Rabwah (Riyadh)<br \/>\nwww.islamhouse.com<br \/>\nL\u2019islam \u00e0 la port\u00e9e de tous !<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/les-interdits-lies-a-lihram<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les interdits li\u00e9s \u00e0 l\u2019Ihr\u00e2m Extraits de : El Manhaj Li Mur\u00eed el \u2018Umra wa el Hadj de She\u00efkh Mohammed ibn S\u00e2lih el \u2018Utha\u00efm\u00een (p. 29-35). Que les pri\u00e8res d\u2019Allah et Son Salut soient sur Mohammed, ainsi que sur ses proches, et tous ses Compagnons ! Les interdits (Mahdh\u00fbr\u00e2t) de l\u2019Ihr\u00e2m correspondent aux actions que &#8230; <a title=\"Les interdits li\u00e9s \u00e0 l\u2019Ihram\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/les-interdits-lies-a-lihram\/\" aria-label=\"Read more about Les interdits li\u00e9s \u00e0 l\u2019Ihram\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[182],"tags":[],"class_list":["post-7382","post","type-post","status-publish","format-standard","hentry","category-french-jurisprudence"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"Les interdits li\u00e9s \u00e0 l\u2019Ihr\u00e2m Extraits de : El Manhaj Li Mur\u00eed el \u2018Umra wa el Hadj de She\u00efkh Mohammed ibn S\u00e2lih el \u2018Utha\u00efm\u00een (p. 29-35). Que les pri\u00e8res d\u2019Allah et Son Salut soient sur Mohammed, ainsi que sur ses proches, et tous ses Compagnons ! Les interdits (Mahdh\u00fbr\u00e2t) de l\u2019Ihr\u00e2m correspondent aux actions que\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1V4","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7382,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7382,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7382,"position":2},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8653,"url":"https:\/\/www.ask-a-muslim.com\/de\/raphael-narbaez-jr-priester-der-zeugen-jehovas-usa\/","url_meta":{"origin":7382,"position":3},"title":"Raphael Narbaez, Jr., Priester der Zeugen Jehovas, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) Der zweiundvierzig j\u00e4hrige Latino, Raphael, ist Komiker und Prediger in Los Angeles. Er wurde in Texas geboren, wo er auch schon im Alter von sechs an seinem ersten Treffen der Zeugen Jehovas teilnahm. Er hielt seine erste Bibelpredigt (bald nachdem er dreizehn war), f\u00fchrte mit zwanzig\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7382,"position":4},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7382,"position":5},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7382"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7382\/revisions"}],"predecessor-version":[{"id":11022,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7382\/revisions\/11022"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}