{"id":7464,"date":"2020-06-17T02:06:34","date_gmt":"2020-06-17T07:06:34","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7464"},"modified":"2020-06-30T22:25:16","modified_gmt":"2020-07-01T03:25:16","slug":"sommes-nous-nes-pour-etre-libres","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/sommes-nous-nes-pour-etre-libres\/","title":{"rendered":"Sommes-nous \u00ab n\u00e9s pour \u00eatre libres \u00bb?"},"content":{"rendered":"<h3><strong>(partie 1 de 2) : La libert\u00e9, un cadeau inestimable<\/strong><\/h3>\n<p>\u00ab Le libre-arbitre est l\u2019un des cadeaux de Dieu les plus difficiles \u00e0 comprendre ou appr\u00e9cier. Celui qui abandonne sa libert\u00e9 \u00e9go\u00efste et qui accepte d\u2019\u00eatre le serviteur de Dieu, celui-l\u00e0 est r\u00e9ellement libre. \u00bb<\/p>\n<p>La libert\u00e9 est l\u2019un des cadeaux de Dieu les plus inestimables, bien que la plupart d\u2019entre nous n\u2019ont aucune id\u00e9e de son importance jusqu\u2019\u00e0 ce qu\u2019ils la perdent. Elle est l\u2019un des droits humains les plus fondamentaux, et tenter d\u2019en priver autrui sans raison l\u00e9gitime est un p\u00e9ch\u00e9 grave. Nous aimons tous \u00e0 penser que nous sommes libres et que nous poss\u00e9dons un libre-arbitre qui nous permet de faire divers choix dans notre vie. Mais r\u00e9fl\u00e9chissons un moment : sommes-nous r\u00e9ellement n\u00e9s pour \u00eatre libres? Et si oui, de quelle fa\u00e7on? Que signifie cette libert\u00e9 pour nous?<\/p>\n<p>Tout d\u2019abord, la libert\u00e9 dont nous jouissons est plus limit\u00e9e que nous ne le soup\u00e7onnons. Pour illustrer ce propos, prenons des exemples relatifs \u00e0 notre corps. Quel contr\u00f4le avons-nous sur nos b\u00e2illements, nos \u00e9ternuements, notre sudation, nos saignements, notre respiration et notre digestion? Quel contr\u00f4le avons-nous sur notre acuit\u00e9 visuelle et auditive, sur nos sensations physiques ou sur le fonctionnement de nos muscles et de nos organes? Plus jeune, j\u2019arrivais \u00e0 courir pour attraper l\u2019autobus et \u00e0 grimper des montagnes; mais m\u00eame si je m\u2019efforce de le faire aujourd\u2019hui, en affirmant que je suis libre de le faire, je n\u2019y arrive plus. Je ne peux m\u00eame pas choisir de me lever si j\u2019en ai envie; lorsque je passe de longs moments assise, mes jambes deviennent si douloureuses que je n\u2019arrive plus \u00e0 me lever d\u2019un bond. Je n\u2019ai absolument aucun contr\u00f4le sur ce qui se passe \u00e0 l\u2019int\u00e9rieur de mon corps; je ne sais pas comment mes reins filtrent mon sang ni comment ils savent filtrer et quoi rejeter. Je ne sais pas quand mon c\u0153ur s\u2019arr\u00eatera de battre, je ne choisis pas de saliver ni d\u2019uriner, je n\u2019ai aucun contr\u00f4le sur la coagulation de mon sang, sur la division de mes cellules, sur leur d\u00e9t\u00e9rioration ou leur d\u00e9sint\u00e9gration.<\/p>\n<p>Si je consid\u00e8re les gens auxquels je suis apparent\u00e9e, je n\u2019ai choisi ni mes anc\u00eatres ni mes parents ni mes fr\u00e8res et s\u0153urs. Je n\u2019ai pas non plus choisi mon bagage g\u00e9n\u00e9tique. J\u2019ai essay\u00e9 de choisir \u00e0 quel moment je concevrais mes enfants, mais cela n\u2019a pas fonctionn\u00e9 comme je l\u2019esp\u00e9rais. Je ne savais pas de quel sexe seraient mes enfants et j\u2019ignorais tout de leurs traits.<\/p>\n<p>Certains croient que ce n\u2019est plus qu\u2019une question de temps et que nous pourrons bient\u00f4t manipuler la g\u00e9n\u00e9tique de fa\u00e7on \u00e0 produire des enfants sur commande, mais cet enfant n\u2019aura pas \u00e9t\u00e9 libre de choisir son apparence physique&#8230; Consid\u00e9rant tous ces exemples, il semble bien que l\u2019\u00eatre humain ne jouisse pas d\u2019une libert\u00e9 aussi grande qu\u2019il le croit, n\u2019est-ce pas?<\/p>\n<p>Et pourtant, la croyance en la libert\u00e9 de l\u2019esprit humain est l\u2019une des r\u00e9v\u00e9lations-cl\u00e9s transmises par Dieu \u00e0 travers les \u00e2ges. En islam, on nous enseigne que cette libert\u00e9, Dieu l\u2019a accord\u00e9e aux \u00eatres humains mais pas aux anges. Nous ne pouvons choisir nos caract\u00e9ristiques physiques, mais nous pouvons choisir la fa\u00e7on dont notre \u00e2me se comporte. Dieu nous demande d\u2019exercer un contr\u00f4le sur nous-m\u00eames, de faire des choix particuliers et de nous conduire de certaines fa\u00e7ons; nous y sommes encourag\u00e9s, mais pas forc\u00e9s. Nous sommes m\u00eame libres de ne pas croire en Lui, de L\u2019ignorer et de Lui d\u00e9sob\u00e9ir. Des millions de personnes le font.<\/p>\n<p>Il se trouve que nous ne sommes pas des robots programm\u00e9s. Nous ne r\u00e9agissons pas tous de la m\u00eame fa\u00e7on aux m\u00eames situations. Certains d\u2019entre nous sont moins \u00e9go\u00efstes, plus g\u00e9n\u00e9reux, indulgents et altruistes, et arrivent \u00e0 mieux composer avec les situations de stress. Mais nous n\u2019y sommes pas oblig\u00e9s. Si nous voyons une vieille dame avancer p\u00e9niblement sur le trottoir, transportant de lourds paquets, nous pouvons choisir de l\u2019aider, de l\u2019assommer et de voler ses paquets, de l\u2019ignorer ou encore de l\u2019insulter en passant pr\u00e8s d\u2019elle. Voil\u00e0 qui nous am\u00e8ne \u00e0 une r\u00e9flexion int\u00e9ressante; il est assez facile de deviner quels genres d\u2019individus auront tel ou tel comportement envers la vieille dame, mais au fond, la plupart d\u2019entre nous ont ce sens du \u00ab devoir \u00bb, et nous savons quel comportement aura la bonne personne, la personne religieuse ou la personne de confiance.<\/p>\n<p>Chaque fois que nous pensons qu\u2019une personne \u00ab doit \u00bb faire telle ou telle chose, c\u2019est que nous pr\u00e9sumons que cette personne est libre et capable de la faire. Il ne sert \u00e0 rien de se dire, en soi-m\u00eame, que telle personne pourrait aider la vieille femme si cette personne est handicap\u00e9e, inconsciente ou menott\u00e9e, par exemple. \u00ab Devoir \u00bb, ici, implique \u00ab pouvoir \u00bb. Si Dieu peut faire tout ce qu\u2019Il veut, il Lui est donc parfaitement possible de contr\u00f4ler nos esprits et les choix que nous faisons. Mais le fait qu\u2019Il donne aux gens le choix de croire en Lui ou non, de Lui ob\u00e9ir ou non, d\u00e9montre assez clairement le libre-arbitre qu\u2019Il nous a accord\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>(partie 2 de 2) : Ce que Dieu attend de nous<\/strong><\/h3>\n<p>Chaque proph\u00e8te, incluant Abraham, Mo\u00efse, J\u00e9sus et Mohammed, a enseign\u00e9 aux gens que les choix qu\u2019ils font relativement \u00e0 leur croyance en Dieu et \u00e0 leur ob\u00e9issance envers Lui feront toute la diff\u00e9rence en fin de parcours. Les \u00eatres humains ont cette capacit\u00e9 profonde d\u2019aimer et d\u2019\u00eatre bons, ou de ha\u00efr et de se montrer destructifs. Cela signifie que m\u00eame s\u2019ils sont tous n\u00e9s \u00e9gaux, ils ne demeurent pas \u00e9gaux jusqu\u2019\u00e0 la fin. Le libre-arbitre est l\u2019un des cadeaux de Dieu les plus difficiles \u00e0 comprendre ou appr\u00e9cier. Le libre-arbitre est l\u00e0 pour donner un sens \u00e0 la moralit\u00e9 humaine; sans lui, il ne pourrait y avoir de \u00ab bonne \u00bb ou de \u00ab mauvaise \u00bb conduite, car nous serions tous des automates.<\/p>\n<p>Si nous n\u2019avions pas de libre-arbitre, et donc aucune possibilit\u00e9 de faire des choix personnels, nous ne pourrions \u00eatre jug\u00e9s, car cela irait \u00e0 l\u2019encontre du concept m\u00eame de justice. Dans toute circonstance o\u00f9 nous ne sommes pas libres de choisir, nous ne pouvons \u00eatre tenus responsables. \u2018Aisha, l\u2019\u00e9pouse du Proph\u00e8te (que la paix et les b\u00e9n\u00e9dictions de Dieu soient sur lui), a clairement mentionn\u00e9 que ceux dont l\u2019intellect est limit\u00e9 \u2013 par exemple, ceux qui sont trop jeunes et trop ignorants, ou qui souffrent de probl\u00e8mes de sant\u00e9 mentale \u2013 ne pourront \u00eatre tenus moralement responsables de leurs actes, ni ici-bas ni dans l\u2019au-del\u00e0.<\/p>\n<p>Et qu\u2019en est-il du destin (ou al-qadr, en arabe), ce contr\u00f4le total de Dieu sur la r\u00e9alisation des \u00e9v\u00e9nements? Comment concilier l\u2019id\u00e9e d\u2019un Dieu qui sait tout et contr\u00f4le tout avec celle du libre-arbitre? Si Dieu sait d\u2019avance tout ce qui doit arriver, la vie d\u2019une personne est donc certainement pr\u00e9destin\u00e9e? Par ailleurs, si Dieu n\u2019intervient pas pour faire cesser certains \u00e9v\u00e9nements, peut-on dire qu\u2019Il en est enti\u00e8rement responsable? Cette question est reli\u00e9e au probl\u00e8me du mal : qui est responsable du mal, des mauvaises actions, si Dieu est Celui qui contr\u00f4le tout? Un voleur pourrait plaider l\u2019innocence en pr\u00e9tendant que le vol \u00e9tait pr\u00e9destin\u00e9 et demander comment il pourrait alors en \u00eatre accus\u00e9.<\/p>\n<p>Plusieurs voient les musulmans comme des fatalistes qui croient que puisque tout est \u00e9crit d\u2019avance et que Dieu sait tout d\u2019avance, alors tout, absolument tout doit \u00eatre pr\u00e9d\u00e9termin\u00e9. Personne n\u2019a encore r\u00e9ussi \u00e0 \u00e9claircir enti\u00e8rement ce probl\u00e8me, mais le fait que Dieu ait envoy\u00e9 des messagers et transmis Ses r\u00e9v\u00e9lations par leur interm\u00e9diaire indique certainement que les hommes sont cens\u00e9s \u00e9couter, apprendre, puis faire des choix et modifier leur mode de vie en cons\u00e9quence (Coran 6:91, 23:73). Dieu dit :<br \/>\n\u00ab En v\u00e9rit\u00e9, tant que les gens [qui composent] un peuple ne changent pas ce qui se trouve dans leur c\u0153ur, Dieu ne modifie en rien leur condition. \u00bb (Coran 13:11)<\/p>\n<p>Cela indique \u00e9galement que les \u00eatres humains ont le pouvoir de changer en exer\u00e7ant leur libre-arbitre et que les d\u00e9cisions qu\u2019ils prennent ont un effet sur leur destin. S\u2019il est vrai que Dieu sait tout, il demeure que les humains n\u2019ont pas cette omniscience. S\u2019ils font certains choix, donc, il en r\u00e9sultera des cons\u00e9quences particuli\u00e8res menant \u00e0 une conclusion particuli\u00e8re. S\u2019ils font d\u2019autres choix, alors les cons\u00e9quences et l\u2019aboutissement seront diff\u00e9rents. Si vous choisissez d\u2019avaler tout un pot d\u2019antidouleurs, vous mourrez peu de temps apr\u00e8s; mais si vous n\u2019en avalez que deux, cela soulagera peut-\u00eatre votre migraine et vous continuerez \u00e0 vivre. Dieu conna\u00eet tous les aboutissements possibles, mais Il vous laisse prendre vos propres d\u00e9cisions. Et m\u00eame s\u2019Il conna\u00eet d\u2019avance les d\u00e9cisions que vous prendrez, cela n\u2019enl\u00e8ve rien au fait que vous les prenez librement.<\/p>\n<p>La v\u00e9rit\u00e9 se trouve en fait dans la sph\u00e8re du ghayb (ou monde invisible). Tout ce que les croyants peuvent faire, c\u2019est prier pour \u00eatre guid\u00e9s en cette vie.<\/p>\n<p>M\u00eame si nous ne savons pas quelle route nous suivrons tout au long de notre vie, nous pouvons demander \u00e0 Dieu de nous montrer la voie \u00e0 suivre, un pas \u00e0 la fois. S\u2019il \u00e9tait r\u00e9ellement impossible pour les gens de prendre des d\u00e9cisions en toute libert\u00e9, non seulement Dieu serait-Il injuste, mais nous n\u2019aurions aucune raison de nous efforcer de mener une vie vertueuse. Le fatalisme m\u00e8ne au d\u00e9sespoir et au d\u00e9faitisme, et d\u00e9courage les gens de chercher \u00e0 am\u00e9liorer leur propre vie ou celle des autres autour d\u2019eux.<\/p>\n<p>Qu\u2019attend Dieu de nous? Il veut nous voir r\u00e9ussir et \u00eatre heureux. Il veut nous voir trouver la v\u00e9ritable libert\u00e9. Si la v\u00e9ritable libert\u00e9 m\u00e8ne au bonheur, il semble donc que la r\u00e9alit\u00e9 soit diff\u00e9rente de ce que pensent la plupart des gens. Une personne peut se sentir heureuse d\u2019avoir un nouveau partenaire sexuel chaque semaine ou de s\u2019empiffrer de fast-food, ou encore de d\u00e9penser des fortunes en v\u00eatements et bijoux, de fumer, de dispara\u00eetre jusqu\u2019\u00e0 tard dans la nuit sans aviser ses proches, d\u2019\u00e9viter de participer aux t\u00e2ches m\u00e9nag\u00e8res avec les autres membres de sa famille, de gagner son pain de fa\u00e7on malhonn\u00eate ou d\u2019\u00eatre c\u00e9l\u00e8bre et admir\u00e9e par les gens. Beaucoup de gens croient que ces choses rendent heureux&#8230;<\/p>\n<p>Comme les choses seraient simples s\u2019il ne suffisait que de cela. Il est si facile de s\u2019abuser et de croire que la voie qui m\u00e8ne \u00e0 notre propre destruction est la plus agr\u00e9able. Mais il faut s\u2019arr\u00eater et r\u00e9fl\u00e9chir : beaucoup de gens riches et puissants, en ce monde, se sentent terriblement seuls. Ceux qui s\u2019empiffrent d\u00e9veloppent toutes sortes de probl\u00e8mes de sant\u00e9. Ceux qui sont paresseux et qui n\u00e9gligent leurs \u00e9tudes quand ils sont jeunes se r\u00e9veillent trop tard, quand leur vie est devenue un vrai d\u00e9sastre. Les fumeurs prenant plaisir \u00e0 chaque cigarette risquent plus que quiconque de mourir d\u2019un cancer ou d\u2019une maladie du c\u0153ur, causant du chagrin \u00e0 leurs proches. Ceux qui sont libertins ne connaissent pas le v\u00e9ritable amour et n\u00e9gligent souvent leurs enfants quand ils ne les abandonnent pas ou ne les tuent pas (en se faisant avorter).<\/p>\n<p>Le v\u00e9ritable bonheur, c\u2019est de prendre soin de ce que Dieu nous a pr\u00eat\u00e9 pour un temps : notre corps, notre famille, nos talents, nos habilet\u00e9s, nos belles qualit\u00e9s. Cela signifie que nous n\u2019avons pas la libert\u00e9 de laisser libre cours \u00e0 nos d\u00e9sirs de toutes sortes, ce qui de toute fa\u00e7on finit toujours par nous causer du tort ou causer du tort aux gens autour de nous. La personne qui laisse tomber ce genre de libert\u00e9 \u00e9go\u00efste et qui d\u00e9cide de se soumettre \u00e0 la volont\u00e9 de Dieu, celle-l\u00e0 est v\u00e9ritablement libre. Elle sait qu\u2019elle fait de son mieux, sa conscience est tranquille, elle se sent en confiance et le c\u0153ur rempli d\u2019espoir, et elle ne sera jamais l\u2019esclave de ses d\u00e9sirs ni d\u2019autrui.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/sommes-nous&#8211;ns-pour-tre-libres-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) : La libert\u00e9, un cadeau inestimable \u00ab Le libre-arbitre est l\u2019un des cadeaux de Dieu les plus difficiles \u00e0 comprendre ou appr\u00e9cier. Celui qui abandonne sa libert\u00e9 \u00e9go\u00efste et qui accepte d\u2019\u00eatre le serviteur de Dieu, celui-l\u00e0 est r\u00e9ellement libre. \u00bb La libert\u00e9 est l\u2019un des cadeaux de Dieu les plus &#8230; <a title=\"Sommes-nous \u00ab n\u00e9s pour \u00eatre libres \u00bb?\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/sommes-nous-nes-pour-etre-libres\/\" aria-label=\"Read more about Sommes-nous \u00ab n\u00e9s pour \u00eatre libres \u00bb?\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[143],"tags":[],"class_list":["post-7464","post","type-post","status-publish","format-standard","hentry","category-le-but-de-la-vie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 2) : La libert\u00e9, un cadeau inestimable \u00ab Le libre-arbitre est l\u2019un des cadeaux de Dieu les plus difficiles \u00e0 comprendre ou appr\u00e9cier. Celui qui abandonne sa libert\u00e9 \u00e9go\u00efste et qui accepte d\u2019\u00eatre le serviteur de Dieu, celui-l\u00e0 est r\u00e9ellement libre. \u00bb La libert\u00e9 est l\u2019un des cadeaux de Dieu les plus\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Wo","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7464,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8660,"url":"https:\/\/www.ask-a-muslim.com\/de\/reverend-david-benjamin-keldani-katholischer-priester-rumaenien\/","url_meta":{"origin":7464,"position":1},"title":"Reverend David Benjamin Keldani, katholischer Priester, Rum\u00e4nien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Auf die Frage, wie er zum Islam gekommen war, schrieb er: \u201cMeine Konvertierung zum Islam kann man keinem anderen Grund zuordnen, als der gn\u00e4digen Rechtleitung Allahs, des Allm\u00e4chtigen. Ohne diese G\u00f6ttliche Leitung kann einen jedes Lernen, Suchen und andere Anstrengungen, die Wahrheit zu finden, sogar in die Irre f\u00fchren. Von\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7464,"position":2},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7464,"position":3},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7464,"position":4},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7464,"position":5},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7464"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7464\/revisions"}],"predecessor-version":[{"id":10944,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7464\/revisions\/10944"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}