{"id":7472,"date":"2020-06-17T02:07:54","date_gmt":"2020-06-17T07:07:54","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7472"},"modified":"2020-06-30T20:52:07","modified_gmt":"2020-07-01T01:52:07","slug":"ce-que-dit-le-coran-sur-les-mers-et-les-rivieres","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/ce-que-dit-le-coran-sur-les-mers-et-les-rivieres\/","title":{"rendered":"Ce que dit le Coran sur les mers et les rivi\u00e8res"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_es\/images\/The_Quran_on_Seas_and_Rivers_001.jpg\" alt=\"\" \/><\/p>\n<p>La science moderne a d\u00e9couvert qu\u2019aux endroits o\u00f9 deux mers diff\u00e9rentes se rencontrent, il y a une barri\u00e8re entre elles. Cette barri\u00e8re s\u00e9pare les deux mers de fa\u00e7on \u00e0 ce que chacune conserve la temp\u00e9rature, la salinit\u00e9 et la densit\u00e9 qui lui sont propres.[1] Par exemple, l\u2019eau de la mer M\u00e9diterran\u00e9e est chaude, saline et moins dense que celle de l\u2019oc\u00e9an Atlantique. Lorsque l\u2019eau de la mer M\u00e9diterran\u00e9e p\u00e9n\u00e8tre dans l\u2019oc\u00e9an Atlantique, au niveau du d\u00e9troit de Gibraltar, elle avance de plusieurs centaines de kilom\u00e8tres dans l\u2019Atlantique \u00e0 une profondeur d\u2019environ 1000 m\u00e8tres, tout en conservant la temp\u00e9rature, la salinit\u00e9 et la densit\u00e9 moins \u00e9lev\u00e9e qui la caract\u00e9risent. C\u2019est \u00e0 cette profondeur que l\u2019eau de la M\u00e9diterran\u00e9e se stabilise[2] (voir illustration 1).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Seas_and_Rivers_002.jpg\" alt=\"Illustration 13 (agrandie)\" width=\"350\" height=\"157\" \/><br \/>\nIllustration 1: L\u2019eau de la M\u00e9diterran\u00e9e p\u00e9n\u00e8tre dans l\u2019Atlantique au niveau du d\u00e9troit de Gibraltar en conservant la temp\u00e9rature, la salinit\u00e9 et la densit\u00e9 moins \u00e9lev\u00e9e qui la caract\u00e9risent, gr\u00e2ce \u00e0 la barri\u00e8re qui les distingue. Les temp\u00e9ratures sont en degr\u00e9s Celsius (C\u00b0). (Marine Geology [La g\u00e9ologie marine], Kuenen, p. 43, avec une l\u00e9g\u00e8re am\u00e9lioration.)<\/p>\n<p>Malgr\u00e9 la pr\u00e9sence de grosses vagues, de forts courants et de mar\u00e9es dans ces mers, elles ne se m\u00e9langent pas et ne d\u00e9passent pas cette barri\u00e8re.<\/p>\n<p>Le Coran fait mention d\u2019une barri\u00e8re entre deux mers qui se rencontrent et que ces derni\u00e8res ne d\u00e9passent pas. Dieu a dit:<br \/>\n\u201cIl a donn\u00e9 libre cours aux deux mers pour se rencontrer; il y a entre elles une barri\u00e8re qu\u2019elles ne d\u00e9passent pas.\u201d (Coran 55:19-20)<\/p>\n<p>Mais quand le Coran parle de ce qui divise l\u2019eau douce de l\u2019eau sal\u00e9e, il mentionne l\u2019existence d\u2019un \u00ab\u00a0barrage infranchissable\u00a0\u00bb en plus de la barri\u00e8re.<\/p>\n<p>\u201cEt c\u2019est Lui qui donne libre cours aux deux mers: l\u2019une douce, rafra\u00eechissante, l\u2019autre sal\u00e9e, am\u00e8re. Et Il assigne entre les deux une barri\u00e8re et un barrage infranchissable.\u201d (Coran 25:53)<\/p>\n<p>On peut se demander pourquoi le Coran fait mention d\u2019un barrage infranchissable lorsqu\u2019il parle de ce qui divise l\u2019eau douce de l\u2019eau sal\u00e9e, mais n\u2019en fait pas mention lorsqu\u2019il parle de ce qui divise deux mers.<\/p>\n<p>La science moderne a d\u00e9couvert que dans les estuaires, o\u00f9 l\u2019eau douce et l\u2019eau sal\u00e9e se rencontrent, le ph\u00e9nom\u00e8ne est en quelque sorte diff\u00e9rent de celui que l\u2019on retrouve dans les endroits o\u00f9 deux mers se rencontrent. Il a \u00e9t\u00e9 d\u00e9couvert que ce qui distingue l\u2019eau douce de l\u2019eau sal\u00e9e dans les estuaires est une \u00ab\u00a0zone de pycnocline avec une discontinuit\u00e9 marqu\u00e9e au niveau de la densit\u00e9, qui s\u00e9pare les deux couches.\u00a0\u00bb[3] Ce barrage (ou zone de s\u00e9paration) a une salinit\u00e9 diff\u00e9rente de celle de l\u2019eau douce et de celle de l\u2019eau sal\u00e9e[4] (voir illustration 2).<\/p>\n<p>Illustration 2: Coupe longitudinale montrant la salinit\u00e9 (parties par milli\u00e8me \u2030 ) dans un estuaire. Nous pouvons voir le barrage (ou zone de s\u00e9paration) entre l\u2019eau douce et l\u2019eau sal\u00e9e. (Introductory Oceanography [Introduction \u00e0 l\u2019oc\u00e9anographie], Thurman, p. 301, avec une l\u00e9g\u00e8re am\u00e9lioration.)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Seas_and_Rivers_003.jpg\" alt=\"Illustration 14 (agrandie)\" width=\"350\" height=\"118\" \/><br \/>\nCes informations n\u2019ont \u00e9t\u00e9 d\u00e9couvertes que r\u00e9cemment \u00e0 l\u2019aide d\u2019\u00e9quipements de pointe servant \u00e0 mesurer la temp\u00e9rature, la salinit\u00e9, la densit\u00e9, la dissolubilit\u00e9 de l\u2019oxyg\u00e8ne, etc. L\u2019oeil humain ne peut percevoir la diff\u00e9rence qui existe entre deux mers qui se rencontrent; car \u00e0 l\u2019oeil nu, les deux mers nous apparaissent comme une seule mer homog\u00e8ne. De la m\u00eame fa\u00e7on, l\u2019oeil humain ne peut percevoir, dans les estuaires, la division de l\u2019eau en trois types: l\u2019eau douce, l\u2019eau sal\u00e9e, et le barrage (ou zone de s\u00e9paration).<\/p>\n<p>Footnotes:<br \/>\n[1] Principles of Oceanography [Les principes de l\u2019oc\u00e9anographie], Davis, pp. 92-93.<br \/>\n[2] Principles of Oceanography [Les principes de l\u2019oc\u00e9anographie], Davis, p. 93.<br \/>\n[3] Oceanography [L\u2019oc\u00e9anographie], Gross, p. 242. Voir aussi Introductory Oceanography[Introduction \u00e0 l\u2019oc\u00e9anographie], Thurman, pp. 300-301.<br \/>\n[4] Oceanography [L\u2019oc\u00e9anographie], Gross, p. 244, et Introductory Oceanography[Introduction \u00e0 l\u2019oc\u00e9anographie], Thurman, pp. 300-301.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/ce-que-dit-le-coran-sur-les-mers-et-les-rivires<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La science moderne a d\u00e9couvert qu\u2019aux endroits o\u00f9 deux mers diff\u00e9rentes se rencontrent, il y a une barri\u00e8re entre elles. Cette barri\u00e8re s\u00e9pare les deux mers de fa\u00e7on \u00e0 ce que chacune conserve la temp\u00e9rature, la salinit\u00e9 et la densit\u00e9 qui lui sont propres.[1] Par exemple, l\u2019eau de la mer M\u00e9diterran\u00e9e est chaude, saline et &#8230; <a title=\"Ce que dit le Coran sur les mers et les rivi\u00e8res\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/ce-que-dit-le-coran-sur-les-mers-et-les-rivieres\/\" aria-label=\"Read more about Ce que dit le Coran sur les mers et les rivi\u00e8res\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[131],"tags":[],"class_list":["post-7472","post","type-post","status-publish","format-standard","hentry","category-les-miracles-scientifiques"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"La science moderne a d\u00e9couvert qu\u2019aux endroits o\u00f9 deux mers diff\u00e9rentes se rencontrent, il y a une barri\u00e8re entre elles. Cette barri\u00e8re s\u00e9pare les deux mers de fa\u00e7on \u00e0 ce que chacune conserve la temp\u00e9rature, la salinit\u00e9 et la densit\u00e9 qui lui sont propres.[1] Par exemple, l\u2019eau de la mer M\u00e9diterran\u00e9e est chaude, saline et\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Ww","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7472,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7472,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8669,"url":"https:\/\/www.ask-a-muslim.com\/de\/der-quran-ueber-meere-und-fluesse\/","url_meta":{"origin":7472,"position":2},"title":"Der Quran \u00fcber Meere und Fl\u00fcsse","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Moderne Wissenschaften haben entdeckt, dass sich an den Stellen, wo zwei Meere aufeinandertreffen, eine Barriere zwischen ihnen befindet. Diese Barriere teilt die zwei Meere derart, dass jedes Meer seine eigene Temperatur, seinen eigenen Salzgehalt und seine eigene Dichte besitzt.[1] Zum Beispiel ist das Wasser des Mittelmeeres warm, salzig und verglichen\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7472,"position":3},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7472,"position":4},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7472,"position":5},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7472"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7472\/revisions"}],"predecessor-version":[{"id":10921,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7472\/revisions\/10921"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}