{"id":7474,"date":"2020-06-17T02:07:54","date_gmt":"2020-06-17T07:07:54","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7474"},"modified":"2020-06-30T20:56:59","modified_gmt":"2020-07-01T01:56:59","slug":"ce-que-dit-le-coran-au-sujet-des-nuages","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/ce-que-dit-le-coran-au-sujet-des-nuages\/","title":{"rendered":"Ce que dit le Coran au sujet des nuages"},"content":{"rendered":"<p>L\u2019\u00e9tude des divers types de nuages a permis aux scientifiques de r\u00e9aliser que la formation et l\u2019aspect des nuages de pluie sont r\u00e9gis selon des syst\u00e8mes bien pr\u00e9cis et suivent certaines \u00e9tapes qui varient selon les types de vents et de nuages.<\/p>\n<p>Un des types de nuages de pluie est le cumulo-nimbus. Les m\u00e9t\u00e9orologues ont \u00e9tudi\u00e9 la formation des cumulo-nimbus et la fa\u00e7on dont ils produisent la pluie, la gr\u00eale et les \u00e9clairs.<\/p>\n<p>Ils ont d\u00e9couvert que les cumulo-nimbus passent \u00e0 travers les diff\u00e9rentes \u00e9tapes suivantes pour produire de la pluie:<br \/>\n1) Les nuages sont pouss\u00e9s par le vent: Les cumulo-nimbus commencent \u00e0 se former lorsque le vent pousse des fragments de nuages (cumulus) vers une aire o\u00f9 ces nuages convergent (voir illustrations 1 and 2).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_002.jpg\" alt=\"\" width=\"350\" height=\"247\" \/><br \/>\nIllustration 1: Photo satellite montrant les nuages se d\u00e9pla\u00e7ant vers les aires de convergence B, C, et D. Les fl\u00e8ches indiquent les directions du vent. (The Use of Satellite Pictures in Weather Analysis and Forecasting [L\u2019utilisation des images satellites dans l\u2019analyse et les pr\u00e9visions m\u00e9t\u00e9orologiques], Anderson et al., p. 188.)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_003.jpg\" alt=\"\" width=\"350\" height=\"297\" \/><br \/>\nIllustration 2: Petits fragments de nuages (cumulus) se dirigeant vers une zone de convergence pr\u00e8s de l\u2019horizon, o\u00f9 l\u2019on aper\u00e7oit un gros cumulo-nimbus. (Clouds and Storms [Les nuages et les temp\u00eates], Ludlam, clich\u00e9 7.4.)<\/p>\n<p>2) Les nuages se rassemblent: Ensuite les fragments de nuages se rassemblent pour former un nuage plus gros[1] (voir illustrations 1 and 2).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_004.jpg\" alt=\"\" width=\"350\" height=\"145\" \/><br \/>\nIllustration 2: A) Fragments de nuages isol\u00e9s (cumulus). (B) Lorsque les fragments de nuages de rassemblent, les courants d\u2019air ascendants augmentent \u00e0 l\u2019int\u00e9rieur du gros nuage nouvellement form\u00e9; le nuage se d\u00e9veloppe alors en hauteur. Les gouttes d\u2019eau sont indiqu\u00e9es par les \u00b7. (The Atmosphere [L\u2019atmosph\u00e8re], Anthes et al., p. 269.)<\/p>\n<p>3) Le nuage se d\u00e9veloppe en hauteur: Lorsque les petits nuages se rassemblent, les courants d\u2019air ascendants augmentent \u00e0 l\u2019int\u00e9rieur du gros nuage nouvellement form\u00e9. Les courants d\u2019air ascendants qui sont situ\u00e9s pr\u00e8s du centre du nuage sont plus forts que ceux situ\u00e9s pr\u00e8s des bords.[2] Ces courants d\u2019air ascendants provoquent le d\u00e9veloppement en hauteur du nuage, formant une structure en forme d\u2019enclume (voir illustrations 2 (B), 3, and 4). Ce d\u00e9veloppement en hauteur fait en sorte que le nuage s\u2019\u00e9tend jusqu\u2019\u00e0 des r\u00e9gions plus froides de l\u2019atmosph\u00e8re, et c\u2019est l\u00e0 que des gouttes d\u2019eau et des gr\u00ealons se forment et augmentent de volume. Lorsque ces gouttes d\u2019eau et ces gr\u00ealons deviennent trop lourds pour \u00eatre soutenus par les courants d\u2019air ascendants, ils commencent \u00e0 tomber du nuage sous forme de pluie et de gr\u00eale.[3]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_005.jpg\" alt=\"\" width=\"226\" height=\"260\" align=\"right\" hspace=\"10\" \/><br \/>\nIllustration 3: Un cumulo-nimbus. Apr\u00e8s que le nuage se soit d\u00e9velopp\u00e9 en hauteur, formant une structure en forme d\u2019enclume, de la pluie s\u2019en \u00e9chappe. (Weather and Climate [Conditions atmosph\u00e9riques et climats], Bodin, p.123.)<\/p>\n<p>Illustration 4: Un cumulo-nimbus. (A Colour Guide to Clouds [Guide illustr\u00e9 des nuages], Scorer et Wexler, p. 23.)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_006.jpg\" alt=\"\" width=\"310\" height=\"203\" \/><br \/>\nDieu a dit, dans le Coran:<br \/>\n\u201cN\u2019as-tu pas vu que Dieu pousse les nuages? Ensuite Il les r\u00e9unit et Il en fait un amas, et tu vois la pluie sortir de son sein.\u201d (Coran 24:43)<\/p>\n<p>Ce n\u2019est que r\u00e9cemment que les m\u00e9t\u00e9orologues ont d\u00e9couvert ces d\u00e9tails sur la formation, la structure et la fonction des nuages, en utilisant des \u00e9quipements de pointe tels que des avions, des satellites, des ordinateurs, des ballons d\u2019essai, etc. pour \u00e9tudier les directions du vent, mesurer l\u2019humidit\u00e9 et ses variations, et pour d\u00e9terminer les niveaux et les variations de la pression atmosph\u00e9rique.[4]<\/p>\n<p>Le verset pr\u00e9c\u00e9dent, apr\u00e8s avoir mentionn\u00e9 les nuages et la pluie, parle de la gr\u00eale et des \u00e9clairs:<br \/>\n\u201c&#8230;Et Il fait descendre, du ciel, de la gr\u00eale provenant de nuages comparables \u00e0 des montagnes. Il en frappe qui Il veut et l\u2019\u00e9carte de qui Il veut. Peu s\u2019en faut que l\u2019\u00e9clat de son \u00e9clair ne ravisse la vue.\u201d (Coran 24:43)<\/p>\n<p>Les m\u00e9t\u00e9orologues ont d\u00e9couvert que ces cumulo-nimbus, desquels tombe la gr\u00eale, atteignent une hauteur variant entre 25 000 et 30 000 pieds (7600 \u00e0 9100 m\u00e8tres) , ou 4.7 \u00e0 5.7 milles (7,5 \u00e0 9,2 kilom\u00e8tres),[5] une hauteur rappelant celle des montagnes, comme le dit le Coran: \u201c&#8230;Et Il fait descendre, du ciel, de la gr\u00eale provenant de nuages comparables \u00e0 des montagnes.\u201d (voir illustration 4 ci-haut).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.islamreligion.com\/articles_fr\/images\/The_Quran_on_Clouds_007.jpg\" alt=\"\" width=\"200\" height=\"273\" align=\"right\" hspace=\"10\" \/><br \/>\nCe verset peut nous amener \u00e0 nous poser la question suivante: pourquoi est-il dit, dans ce verset, \u201cson \u00e9clair\u201d en parlant de la gr\u00eale? Cela signifie-t-il que la gr\u00eale est la cause principale de la formation de l\u2019\u00e9clair? Voici ce que le livreMeteorology Today (La m\u00e9t\u00e9orologie d\u2019aujourd\u2019hui) dit \u00e0 ce sujet. Il dit qu\u2019un nuage devient \u00e9lectrifi\u00e9 lorsque les grains de gr\u00eale traversent une partie du nuage o\u00f9 circulent des gouttelettes tr\u00e8s froides et des cristaux de glace. Lorsque les gouttelettes heurtent les grains de gr\u00eale, elles g\u00e8lent \u00e0 leur contact et lib\u00e8rent en m\u00eame temps de la chaleur latente. Cela fait en sorte que la surface des grains de gr\u00eale reste plus chaude que celle des cristaux de glace environnants. Lorsque les grains de gr\u00eale entrent en contact avec les cristaux de glace, un ph\u00e9nom\u00e8ne important se produit: des \u00e9lectrons circulent de l\u2019objet le plus chaud \u00e0 l\u2019objet le plus froid. C\u2019est alors que les grains de gr\u00eale deviennent n\u00e9gativement charg\u00e9s. La m\u00eame chose se produit lorsque des gouttelettes tr\u00e8s froides entrent en contact avec des grains de gr\u00eale et que de minuscules \u00e9clats de glace charg\u00e9s positivement se d\u00e9tachent. Ces particules positivement charg\u00e9es, qui sont plus l\u00e9g\u00e8res, sont alors transport\u00e9es dans la partie sup\u00e9rieure du nuage par les courants d\u2019air ascendants. La gr\u00eale, qui est rest\u00e9e avec une charge n\u00e9gative, descend dans la partie inf\u00e9rieure du nuage; cette partie devient donc n\u00e9gativement charg\u00e9e. Ces charges n\u00e9gatives sont alors d\u00e9charg\u00e9es sous forme d\u2019\u00e9clairs.[6] Nous pouvons conclure de cette explication que la gr\u00eale est la cause principale de la formation de l\u2019\u00e9clair.<\/p>\n<p>Ces informations sur la formation des \u00e9clairs n\u2019ont \u00e9t\u00e9 d\u00e9couvertes que r\u00e9cemment. Jusqu\u2019en l\u2019an 1600, les id\u00e9es d\u2019Aristote sur la m\u00e9t\u00e9orologie \u00e9taient dominantes. Il croyait, par exemple, que l\u2019atmosph\u00e8re contenait deux sortes d\u2019\u00e9manations, l\u2019une humide, l\u2019autre s\u00e8che. Il affirmait \u00e9galement que le tonnerre \u00e9tait le bruit de la collision entre l\u2019\u00e9manation s\u00e8che et les nuages environnants, et que l\u2019\u00e9clair \u00e9tait l\u2019inflammation de l\u2019\u00e9manation s\u00e8che \u00e0 l\u2019aide d\u2019un faible feu de forme amincie.[7] Ce sont l\u00e0 quelques id\u00e9es sur la m\u00e9t\u00e9orologie qui \u00e9taient dominantes \u00e0 l\u2019\u00e9poque de la r\u00e9v\u00e9lation du Coran, il y a quatorze si\u00e8cles.<\/p>\n<p>Footnotes:<br \/>\n[1] Voir The Atmosphere [L\u2019atmosph\u00e8re], Anthes et al., pp. 268-269, et Elements of Meteorology [\u00c9l\u00e9ments de m\u00e9t\u00e9orologie], Miller et Thompson, p. 141.<br \/>\n[2] Les courants d\u2019air ascendants qui sont pr\u00e8s du centre sont plus forts parce qu\u2019ils sont prot\u00e9g\u00e9s du refroidissement par la partie du nuage qui entoure le centre.<br \/>\n[3] Voir The Atmosphere [L\u2019atmosph\u00e8re], Anthes et al., p. 269, et Elements of Meteorology [\u00c9l\u00e9ments de m\u00e9t\u00e9orologie], Miller et Thompson, pp. 141-142.<br \/>\n[4] Voir Ee\u2019jaz al-Quran al-Kareem fee Wasf Anwa\u2019 al-Riyah, al-Sohob, al-Matar, Makky et al., p. 55.<br \/>\n[5] Elements of Meteorology [\u00c9l\u00e9ments de m\u00e9t\u00e9orologie], Miller et Thompson, p. 141.<br \/>\n[6] Meteorology Today [La m\u00e9t\u00e9orologie d\u2019aujourd\u2019hui], Ahrens, p. 437.<br \/>\n[7] The Works of Aristotle Translated into English: Meteorologica [Les travaux d\u2019Aristote traduits en langue anglaise: Meteorologica], vol. 3, Ross et al., pp. 369a-369b.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/ce-que-dit-le-coran-au-sujet-des-nuages<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9tude des divers types de nuages a permis aux scientifiques de r\u00e9aliser que la formation et l\u2019aspect des nuages de pluie sont r\u00e9gis selon des syst\u00e8mes bien pr\u00e9cis et suivent certaines \u00e9tapes qui varient selon les types de vents et de nuages. Un des types de nuages de pluie est le cumulo-nimbus. Les m\u00e9t\u00e9orologues ont &#8230; <a title=\"Ce que dit le Coran au sujet des nuages\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/ce-que-dit-le-coran-au-sujet-des-nuages\/\" aria-label=\"Read more about Ce que dit le Coran au sujet des nuages\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[131],"tags":[],"class_list":["post-7474","post","type-post","status-publish","format-standard","hentry","category-les-miracles-scientifiques"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019\u00e9tude des divers types de nuages a permis aux scientifiques de r\u00e9aliser que la formation et l\u2019aspect des nuages de pluie sont r\u00e9gis selon des syst\u00e8mes bien pr\u00e9cis et suivent certaines \u00e9tapes qui varient selon les types de vents et de nuages. Un des types de nuages de pluie est le cumulo-nimbus. Les m\u00e9t\u00e9orologues ont\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Wy","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7474,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7474,"position":1},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7474,"position":2},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8660,"url":"https:\/\/www.ask-a-muslim.com\/de\/reverend-david-benjamin-keldani-katholischer-priester-rumaenien\/","url_meta":{"origin":7474,"position":3},"title":"Reverend David Benjamin Keldani, katholischer Priester, Rum\u00e4nien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Auf die Frage, wie er zum Islam gekommen war, schrieb er: \u201cMeine Konvertierung zum Islam kann man keinem anderen Grund zuordnen, als der gn\u00e4digen Rechtleitung Allahs, des Allm\u00e4chtigen. Ohne diese G\u00f6ttliche Leitung kann einen jedes Lernen, Suchen und andere Anstrengungen, die Wahrheit zu finden, sogar in die Irre f\u00fchren. Von\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7474,"position":4},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7474,"position":5},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7474"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7474\/revisions"}],"predecessor-version":[{"id":10927,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7474\/revisions\/10927"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}