{"id":7479,"date":"2020-06-17T02:07:54","date_gmt":"2020-06-17T07:07:54","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7479"},"modified":"2020-06-30T21:36:24","modified_gmt":"2020-07-01T02:36:24","slug":"laisser-la-moisson-en-epi","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/laisser-la-moisson-en-epi\/","title":{"rendered":"LAISSER LA MOISSON EN \u00c9PI"},"content":{"rendered":"<p>l est dit dans le Saint Coran : [ \u201c\u00d4 toi, Youssef (Joseph), le v\u00e9ridique ! \u00c9claire-nous au sujet de sept vaches grasses que mangent sept autres tr\u00e8s maigres, et sept \u00e9pis verts et autant d&rsquo;autres, secs, afin que je retourne aux gens et qu&rsquo;ils sachent [l&rsquo;interpr\u00e9tation exacte du r\u00eave]\u201d. Alors [Joseph dit] : \u201cVous s\u00e8merez pendant sept ann\u00e9es cons\u00e9cutives. Tout ce que vous aurez moissonn\u00e9, laissez-le en \u00e9pi, sauf le peu que vous consommerez. Viendront ensuite sept ann\u00e9es de disette qui consommeront tout ce que vous aurez amass\u00e9 pour elles sauf le peu que vous aurez r\u00e9serv\u00e9 [comme semence].<\/p>\n<p>Puis, viendra apr\u00e8s cela une ann\u00e9e o\u00f9 les gens seront secourus [par la pluie] et iront au pressoir.\u201d] (Youssef : 46-49) Il est dit dans le Saint Coran : [\u201c\u00d4 toi, Youssef (Joseph), le v\u00e9ridique ! \u00c9claire-nous au sujet de sept vaches grasses que mangent sept autres tr\u00e8s maigres, et sept \u00e9pis verts et autant d&rsquo;autres, secs, afin que je retourne aux gens et qu&rsquo;ils sachent [l&rsquo;interpr\u00e9tation exacte du r\u00eave]\u201d. Alors [Joseph dit] : \u201cVous s\u00e8merez pendant sept ann\u00e9es cons\u00e9cutives. Tout ce que vous aurez moissonn\u00e9, laissez-le en \u00e9pi, sauf le peu que vous consommerez. Viendront ensuite sept ann\u00e9es de disette qui consommeront tout ce que vous aurez amass\u00e9 pour elles sauf le peu que vous aurez r\u00e9serv\u00e9 [comme semence]. Puis, viendra apr\u00e8s cela une ann\u00e9e o\u00f9 les gens seront secourus [par la pluie] et iront au pressoir.\u201d] (Youssef : 46-49)<\/p>\n<p>La V\u00e9rit\u00e9 Scientifique :<br \/>\nStocker les grains en \u00e9pis est un syst\u00e8me fondamental de pr\u00e9servation de la production dans des environnements tr\u00e8s hostiles. Ces directives englobent l&rsquo;agriculture, les techniques de stockages et de pr\u00e9servation de la production autrement les techniques de gestion de la production.<\/p>\n<p>Le docteur `Abd al-Maj\u00eed bel-`\u00c2bid et ses coll\u00e8gues de l&rsquo;Universit\u00e9 de Rabat au Maroc, ont fait une \u00e9tude exp\u00e9rimentale sur des grains de bl\u00e9 conserv\u00e9s en \u00e9pis. Ces grains rest\u00e8rent intacts durant deux ans contrairement aux grains battus. Les r\u00e9sultats pr\u00e9liminaires montr\u00e8rent que 100% des grains en \u00e9pis \u00e9taient rest\u00e9s en bon \u00e9tat. Sans oublier que le lieu de stockage \u00e9tait un lieu ordinaire qui ne jouissait d&rsquo;aucune condition climatique sp\u00e9ciale. Dans ce cadre, il apparut que les grains en \u00e9pis perdirent une grande quantit\u00e9 d&rsquo;eau et devinrent secs avec le temps. Et ce, contrairement aux grains battus.<\/p>\n<p>Autrement dit, l&rsquo;on se rendit compte que le bl\u00e9 battu \u00e9tait constitu\u00e9 de 20.3% d&rsquo;eau. Ce qui a un effet n\u00e9faste sur sa productivit\u00e9, sa croissance et sa valeur nutritive. Car l&rsquo;eau favorise son pourrissement et sa d\u00e9t\u00e9rioration.<\/p>\n<p>Puis les chercheurs compar\u00e8rent les facteurs de croissance des grains rest\u00e9s en \u00e9pis et celles des grains battus. Et ce, durant deux ans. Les r\u00e9sultats furent les suivantes : les grains en \u00e9pis s&rsquo;av\u00e9r\u00e8rent plus croissants de 20% du point de vue de la longueur des racines, et de 32% du point de vue de la longueur des tiges. Apr\u00e8s quoi, les chercheurs \u00e9valu\u00e8rent les prot\u00e9ines et les glucides qui restent intacts. Concernant les grains battus, ils perdirent 32% de prot\u00e9ines apr\u00e8s deux ans et 20% apr\u00e8s un an. Quant aux grains en \u00e9pis, ils ne perdirent rien du tout.<\/p>\n<p>Aspect Miraculeux :<br \/>\nIl est dit dans le Saint Coran : [Tout ce que vous aurez moissonn\u00e9, laissez-le en \u00e9pi\u2026] Ce qui veut dire que pr\u00e9server les grains en \u00e9pis est la bonne m\u00e9thode de pr\u00e9servation des grains \u00e0 long terme.<\/p>\n<p>Il y a deux remarques scientifiques qui ont trait \u00e0 ce verset :<\/p>\n<p>1- La d\u00e9termination de la productivit\u00e9 des semences \u00e0 15 ans repartis comme suit : sept ann\u00e9es de vache grasses pendant lesquelles les gens s\u00e8meront et r\u00e9colteront sans coup f\u00e9rir, suivis de sept ann\u00e9es de vaches maigres qui seront suivis de l&rsquo;ann\u00e9e du retour \u00e0 la fertilit\u00e9 au bout de laquelle les gens se rendront aux pressoirs. Et les exp\u00e9riences scientifiques ont prouv\u00e9 que les semences gardent leurs facteurs de productivit\u00e9 et de croissance durant 15 ans au maximum.<\/p>\n<p>2- Le proc\u00e9d\u00e9 de stockage mentionn\u00e9 dans le Coran en ces termes : [ Tout ce que vous aurez moissonn\u00e9, laissez-le en \u00e9pi\u2026] est le proc\u00e9d\u00e9 qui s&rsquo;av\u00e9ra dans l&rsquo;\u00e9tude exp\u00e9rimentale comme le proc\u00e9d\u00e9 le plus fiable.<\/p>\n<p>Ainsi, devint-il \u00e9vident que la meilleure m\u00e9thode de stockage est la m\u00e9thode indiqu\u00e9e par le Proph\u00e8te d&rsquo;Allah Youssef (salut sur lui), m\u00e9thode qu&rsquo;il tint de la r\u00e9v\u00e9lation divine.<\/p>\n<p>Il va de soi que cette m\u00e9thode \u00e9tait m\u00e9connue auparavant notamment chez les anciens \u00e9gyptiens qui conservaient les grains apr\u00e8s battage. Mentionner ainsi la bonne m\u00e9thode, est l&rsquo;un des aspects miraculeux de ce verset coranique qui prouve encore une fois de plus la pr\u00e9cision et la justesse des informations contenues dans le Coran et partant, la v\u00e9rit\u00e9 irr\u00e9vocable que le Coran est une r\u00e9v\u00e9lation d&rsquo;Allah.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/laisser-la-moisson-en-pi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l est dit dans le Saint Coran : [ \u201c\u00d4 toi, Youssef (Joseph), le v\u00e9ridique ! \u00c9claire-nous au sujet de sept vaches grasses que mangent sept autres tr\u00e8s maigres, et sept \u00e9pis verts et autant d&rsquo;autres, secs, afin que je retourne aux gens et qu&rsquo;ils sachent [l&rsquo;interpr\u00e9tation exacte du r\u00eave]\u201d. Alors [Joseph dit] : \u201cVous &#8230; <a title=\"LAISSER LA MOISSON EN \u00c9PI\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/laisser-la-moisson-en-epi\/\" aria-label=\"Read more about LAISSER LA MOISSON EN \u00c9PI\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[131],"tags":[],"class_list":["post-7479","post","type-post","status-publish","format-standard","hentry","category-les-miracles-scientifiques"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"l est dit dans le Saint Coran : [ \u201c\u00d4 toi, Youssef (Joseph), le v\u00e9ridique ! \u00c9claire-nous au sujet de sept vaches grasses que mangent sept autres tr\u00e8s maigres, et sept \u00e9pis verts et autant d&rsquo;autres, secs, afin que je retourne aux gens et qu&rsquo;ils sachent [l&rsquo;interpr\u00e9tation exacte du r\u00eave]\u201d. Alors [Joseph dit] : \u201cVous\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1WD","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7479,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8660,"url":"https:\/\/www.ask-a-muslim.com\/de\/reverend-david-benjamin-keldani-katholischer-priester-rumaenien\/","url_meta":{"origin":7479,"position":1},"title":"Reverend David Benjamin Keldani, katholischer Priester, Rum\u00e4nien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Auf die Frage, wie er zum Islam gekommen war, schrieb er: \u201cMeine Konvertierung zum Islam kann man keinem anderen Grund zuordnen, als der gn\u00e4digen Rechtleitung Allahs, des Allm\u00e4chtigen. Ohne diese G\u00f6ttliche Leitung kann einen jedes Lernen, Suchen und andere Anstrengungen, die Wahrheit zu finden, sogar in die Irre f\u00fchren. Von\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7479,"position":2},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8655,"url":"https:\/\/www.ask-a-muslim.com\/de\/philobus-aegyptischer-koptischer-priester-und-missionar\/","url_meta":{"origin":7479,"position":3},"title":"Philobus, \u00c4gyptischer Koptischer Priester und Missionar","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) Al-Haj Ibrahim Khalil Ahmad, der fr\u00fchere Ibrahim Khalil Philobus, war ein \u00e4gyptischer koptischer Priester gewesen, der Theologie studiert hatte und einen hohen Grad an der Princeton Universit\u00e4t erreicht hatte. Er studierte den Islam, um L\u00fccken zu finden; anstatt dessen nahmen er und seine vier Kinder den\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8618,"url":"https:\/\/www.ask-a-muslim.com\/de\/anne-collins-ex-christin-usa\/","url_meta":{"origin":7479,"position":4},"title":"Anne Collins, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin in einer christlicher Familie aufgewachsen. Zu jener Zeit waren Amerikaner religi\u00f6ser als sie es heute sind \u2013 die meisten Familien gingen beispielsweise jeden Sonntag zur Kirche. Meine Eltern waren in der Kirchengemeinde involviert. Bei uns waren oft Pfarrer (Protestantische \u201cPriester\u201d) zu Hause. Meine Mutter lehrte in der Sonntagsschule\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8577,"url":"https:\/\/www.ask-a-muslim.com\/de\/ali-ex-christ-usa\/","url_meta":{"origin":7479,"position":5},"title":"Ali, Ex-Christ, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Ali, ich bin ein 31 j\u00e4hriger Mexikaner, der in Amerika Geboren wurde, besser gesagt ein Chicano. Ich dachte mir, ich mache eine Website, um meine Geschichte zu erz\u00e4hlen, wie ich Muslim geworden bin. Ich denke, das wird inschaAllah (wenn Gott will) den Menschen dabei helfen, den Islam\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7479"}],"version-history":[{"count":1,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7479\/revisions"}],"predecessor-version":[{"id":10933,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7479\/revisions\/10933"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}