{"id":7598,"date":"2020-06-17T02:21:18","date_gmt":"2020-06-17T07:21:18","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7598"},"modified":"2020-07-01T07:37:23","modified_gmt":"2020-07-01T12:37:23","slug":"khalil-ibrahim-abdulmajid-ex-chretien-etats-unis","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/khalil-ibrahim-abdulmajid-ex-chretien-etats-unis\/","title":{"rendered":"Khalil Ibrahim Abdulmajid, ex-chr\u00e9tien, \u00c9tats-Unis"},"content":{"rendered":"<h3><strong>(partie 1 de 2)<\/strong><\/h3>\n<p>En 1988, je commen\u00e7ai \u00e0 travailler sur un projet, avec mon p\u00e8re, qui \u00e9tait m\u00e9decin en Arabie. Il travaillait l\u00e0-bas, tandis que j\u2019\u00e9tais aux \u00c9tats-Unis. Cette m\u00eame ann\u00e9e, j\u2019allai lui rendre visite et demeurai dans la ville de Dhahran, puis me d\u00e9pla\u00e7ai \u00e0 Al-Khobar pour faire avancer mon projet. Ce que j\u2019y vis me frappa de plusieurs fa\u00e7ons. Et lorsque j\u2019entendis les appels \u00e0 la pri\u00e8re, j\u2019en fus remu\u00e9 jusqu\u2019au plus profond de mon \u00eatre. Suite \u00e0 ces appels (adhan), je voyais des propri\u00e9taires de boutique fermer quelques minutes, mais sans verrouiller leurs portes, ce qui m\u2019\u00e9tonnait.<\/p>\n<p>Je voyais des musulmans se rendre \u00e0 la mosqu\u00e9e pour prier et revenir totalement rafra\u00eechis et de bonne humeur. Alors je m\u2019interrogeai. Je posai de nombreuses questions aux gens autour de moi et on m\u2019invita \u00e0 entrer dans une mosqu\u00e9e, o\u00f9 j\u2019allai m\u2019assoir \u00e0 l\u2019arri\u00e8re. La situation me rendait quelque peu nerveux, mais mon c\u0153ur et mon esprit \u00e9taient ouverts. Personne d\u2019autre, pas m\u00eame mon p\u00e8re, n\u2019avait \u00e9t\u00e9 invit\u00e9. Peut-\u00eatre Mohammed, celui qui m\u2019avait invit\u00e9, avait-il vu en moi quelque chose que j\u2019ignorais moi-m\u00eame, \u00e0 l\u2019\u00e9poque.<\/p>\n<p>On me donna une copie du Coran en arabe et en anglais. Parmi tous les objets que je rapportai de mon voyage, plus tard, le Coran \u00e9tait celui auquel je tenais le plus. Je ne le lus pas imm\u00e9diatement, lorsque je le re\u00e7us; je le consid\u00e9rai plut\u00f4t comme un objet int\u00e9ressant \u00e0 poss\u00e9der, un livre qui ferait bonne impression dans ma biblioth\u00e8que (quelle erreur!). Cet endroit, qui m\u2019avait \u00e9t\u00e9 compl\u00e8tement \u00e9tranger quelque temps auparavant, laissa en moi une impression durable. Et, c\u2019est la t\u00eate remplie de souvenirs inoubliables que je rentrai chez moi.<\/p>\n<p>Des ann\u00e9es plus tard, j\u2019y trouvai du travail et y retournai avec ma jeune famille, i.e. mon \u00e9pouse et mes deux fils. Ils s\u2019habitu\u00e8rent tous rapidement \u00e0 la vie en Arabie. Mon quotidien \u00e9tait essentiellement compos\u00e9 de travail, d\u2019exercice et de temps pass\u00e9 en famille. Il m\u2019arrivait de prier, seul, tout au plus une fois par jour. J\u2019\u00e9tais alors chr\u00e9tien et, comme vous le savez sans doute, les chr\u00e9tiens n\u2019ont pas de pri\u00e8res obligatoires. Je ne pouvais m\u2019emp\u00eacher d\u2019observer mes employ\u00e9s, alors qu\u2019ils travaillaient, dans les minutes pr\u00e9c\u00e9dant et suivant leurs pri\u00e8res. Au fond, je sais, maintenant, avec le recul, qu\u2019Allah m\u2019appelait \u00e0 Lui; mais je faisais la sourde oreille, bien que je fusse \u00e0 Riyadh, travaillant dans un h\u00f4pital voisin d\u2019une mosqu\u00e9e, entour\u00e9 de musulmans.<\/p>\n<p>Je maintenais les gens \u00e0 distance, me r\u00e9fugiant dans ma compr\u00e9hension toute personnelle du christianisme. Les ann\u00e9es pass\u00e8rent et, honn\u00eatement, je dois avouer que je perdis tout int\u00e9r\u00eat dans la pri\u00e8re; mes contacts avec Dieu ne devinrent alors qu\u2019occasionnels. Mon contrat de travail prit fin en 2001 et nous retourn\u00e2mes tous en Floride, aux \u00c9tats-Unis.<\/p>\n<p>Une fois aux \u00c9tats-Unis, nous retourn\u00e2mes tous \u00e0 l\u2019\u00e9glise en famille, mais je savais, tout au fond de mon \u00eatre, que je n\u2019\u00e9tais plus la m\u00eame personne. J\u2019\u00e9tais incapable de comprendre et d\u2019accepter le concept de la trinit\u00e9. Je comprenais que quelque chose clochait, mais j\u2019ignorais quoi. Alors je me mis \u00e0 parler \u00e0 Dieu, et seulement \u00e0 Lui. N\u2019avait-Il pas tout cr\u00e9\u00e9? Pourquoi devais-je alors passer par des interm\u00e9diaires pour m\u2019adresser \u00e0 Lui? Cela n\u2019avait aucun sens. Durant cette m\u00eame p\u00e9riode, les p\u00e9ch\u00e9s abond\u00e8rent, dans ma vie, provenant soit de moi-m\u00eame, soit de celle qui est maintenant mon ex-\u00e9pouse.<\/p>\n<p>Je sombrai dans la p\u00e9riode de ma vie la plus difficile et la plus d\u00e9cevante. Le chemin menant \u00e0 l\u2019Enfer est large et facile \u00e0 suivre, tandis que celui menant au Paradis est \u00e9troit et difficile \u00e0 suivre. J\u2019avais non seulement l\u2019impression de me diriger tout droit vers l\u2019Enfer, mais de vivre un enfer sur terre. Durant cette p\u00e9riode, je tentai, tant bien que mal, d\u2019\u00e9quilibrer ma vie en priant et en allant \u00e0 l\u2019\u00e9glise de temps \u00e0 autre, m\u00eame si le c\u0153ur n\u2019y \u00e9tait pas. Cette situation se poursuivit quelques ann\u00e9es durant, jusqu\u2019\u00e0 ce que j\u2019accepte le poste que j\u2019occupe toujours \u00e0 l\u2019h\u00f4pital d\u2019Al-Khobar.<\/p>\n<p>J\u2019avais le c\u0153ur rempli de tristesse, car mon mariage, qui avait dur\u00e9 vingt-trois ans, avait pris fin \u00e0 cause des mauvaises ann\u00e9es ayant pr\u00e9c\u00e9d\u00e9 mon retour \u00e0 Al-Khobar. Je ne croyais pas me retrouver aussi bas, un jour; mais Il m\u2019amena jusqu\u2019au fond, l\u00e0 o\u00f9 il n\u2019est plus possible de faire autrement que de remonter. Ceux qui m\u2019entouraient savaient que j\u2019avais constamment mal et que ma vie \u00e9tait devenue compl\u00e8tement vide. Et pourtant, chaque jour, seconde apr\u00e8s seconde, je continuais d\u2019avancer. Je priais pratiquement chaque matin et lisais souvent la Bible, des livres entiers \u00e0 la fois. Mes vies personnelle et professionnelle s\u2019am\u00e9lior\u00e8rent petit \u00e0 petit.<\/p>\n<p>Je dus retourner aux \u00c9tats-Unis pour finaliser mon divorce et, lors de mon retour \u00e0 Al-Khobar, un des cadres sup\u00e9rieurs de ma division me donna des pamphlets d\u2019information sur l\u2019islam. Je le remerciai, mais je ne pris pas la peine de les lire et les regardai \u00e0 peine avant de les envoyer au fond d\u2019un tiroir. Pourtant, cet homme, et d\u2019autres autour de moi, avait vu en moi quelque chose que je ne r\u00e9alisais pas moi-m\u00eame. Un membre de mon personnel me fit cadeau d\u2019un chapelet de pri\u00e8re musulman. Je pris l\u2019habitude de le porter dans ma poche droite et, chaque fois que je me retrouvais dans une situation tendue, j\u2019y portais la main et faisais rouler les billes entre mes doigts, un geste qui m\u2019apaisait. Puis, ma vie continua, les bons jours succ\u00e9dant aux mauvais et inversement.<\/p>\n<p>Puis, en novembre dernier, je retournai aux \u00c9tats-Unis pour rendre visite \u00e0 ma famille. Et, \u00e9trangement, je n\u2019arrivai pas \u00e0 me sentir chez moi, pas plus que je ne mis les pieds dans une \u00e9glise.<\/p>\n<p>Lorsque je retournai en Arabie, d\u00e9but d\u00e9cembre, j\u2019\u00e9tais int\u00e9rieurement agit\u00e9. J\u2019avais de la difficult\u00e9 \u00e0 prendre des d\u00e9cisions et \u00e9vitais le plus souvent d\u2019en prendre. Je l\u00e2chai de plus en plus de lest et commen\u00e7ai \u00e0 \u00e9couter avec mon c\u0153ur et mon esprit. Les gens autour de moi devaient se demander ce qui m\u2019arrivait, car j\u2019avais sans doute l\u2019air tr\u00e8s pr\u00e9occup\u00e9. \u00c0 l\u2019h\u00f4pital, lors de mes pauses, je pris l\u2019habitude d\u2019aller marcher et de passer devant la mosqu\u00e9e aux heures de pri\u00e8re. Je restais cependant en retrait, \u00e9coutant l\u2019appel \u00e0 la pri\u00e8re et observant les hommes entrer et sortir. Je voyais clairement qu\u2019en sortant, ils \u00e9taient diff\u00e9rents; ils semblaient insouciants du monde autour d\u2019eux. Je me sentais attir\u00e9 par cette religion; je le savais, tout au fond de moi, mais en m\u00eame temps, je tentais de le nier. Le foss\u00e9 qui me s\u00e9parait de ce mode de vie, de cette voie spirituelle, me semblait bien trop large pour que je puisse le traverser. Et pourtant, je me demandais comment faire et je r\u00e9fl\u00e9chissais, r\u00e9fl\u00e9chissais\u2026<\/p>\n<h3><\/h3>\n<h3><strong>(partie 2 de 2)<\/strong><\/h3>\n<p>D\u00e9but janvier, je ressentis un besoin urgent et inexplicable de poss\u00e9der un Coran. Je mis cela sur ma liste de choses prioritaires \u00e0 faire. Deux jours plus tard, je rentrai du travail, un jeudi apr\u00e8s-midi, et fis une sieste. Je ne r\u00e9glai pas mon r\u00e9veil, mais je me promis qu\u2019apr\u00e8s la pri\u00e8re, quand les boutiques rouvriraient, j\u2019irais acheter une traduction anglaise du Coran. Je fus r\u00e9veill\u00e9 par l\u2019appel \u00e0 la pri\u00e8re, mais comme j\u2019\u00e9tais tr\u00e8s fatigu\u00e9, je me dis que j\u2019allais me recoucher et que j\u2019irais chercher un Coran plus tard; en avais-je vraiment besoin de toute fa\u00e7on? Mais aussit\u00f4t que cette pens\u00e9e traversa mon esprit, une autre vint s\u2019y opposer; je bondis hors du lit et m\u2019habillai. Mes cheveux \u00e9taient en bataille, alors je m\u2019enfon\u00e7ai une casquette sur la t\u00eate.<\/p>\n<p>Je h\u00e9lai un taxi et, en chemin, lui expliquai que je voulais devenir musulman. L\u2019id\u00e9e sembla lui plaire et il me conduisit chez le libraire. Il y avait beaucoup de circulation et, lorsque nous arriv\u00e2mes enfin, je fus \u00e0 la fois stup\u00e9fait et m\u00e9content de constater qu\u2019une foule faisait la file pour y entrer. Je me frayai un chemin et regardai de tous c\u00f4t\u00e9s; il y avait tant de livres et de gens! Je ne savais o\u00f9 chercher et je finis par trouver un vendeur, qui me montra la section des corans. Il m\u2019expliqua qu\u2019ils \u00e9taient en rupture de stock, ce qui m\u2019aga\u00e7a au plus haut point. \u00ab Comment est-ce possible? \u00bb, demandai-je. Nous sommes en Arabie, au c\u0153ur m\u00eame de l\u2019islam, et vous n\u2019avez plus de traduction anglaise du Coran? \u00bb D\u00e9courag\u00e9, je retournai vers le taxi les mains vides.<\/p>\n<p>Nous \u00e9tions tous deux f\u00e2ch\u00e9s de cette situation, le chauffeur et moi, mais je me souvins tout \u00e0 coup qu\u2019il y avait une autre succursale de la libraire Jarir pr\u00e8s de l\u2019h\u00f4pital o\u00f9 je travaillais. Nous y arriv\u00e2mes \u00e0 temps pour la pri\u00e8re du coucher du soleil. Mon chauffeur se rendit \u00e0 la mosqu\u00e9e pour prier, tandis que j\u2019allai attendre devant la librairie, comme les autres non-musulmans. Quelqu\u2019un finit par ouvrir la porte et j\u2019interrogeai tout de suite un vendeur, qui me donna une copie d\u2019une traduction anglaise du Coran. Je payai et retournai voir mon chauffeur, qui fut bien heureux que nous n\u2019ayons pas baiss\u00e9 les bras.<\/p>\n<p>Je me mis \u00e0 lire le Coran sans en parler \u00e0 personne. Plus je lisais, plus je me posais de questions; mais je ne voulais les poser \u00e0 qui que ce soit, ce qui aurait d\u00e9voil\u00e9 au grand jour mon int\u00e9r\u00eat pour l\u2019islam. Certains jours, j\u2019\u00e9tais si occup\u00e9, au travail, que je n\u2019avais aucun temps \u00e0 consacrer \u00e0 ma lecture. Mais je tins bon et poursuivis mes recherches, relisant la Bible, entre autres. Je m\u2019attardai au cas de J\u00e9sus (que la mis\u00e9ricorde et les b\u00e9n\u00e9dictions de Dieu soient sur lui) : qui \u00e9tait-il vraiment? \u00c9tait-il vraiment Dieu et faisait-il partie d\u2019une trinit\u00e9? Cette question me tracassait, car je croyais fermement qu\u2019il n\u2019existait qu\u2019un seul Dieu. Et, en tant que chr\u00e9tien, je me demandais si Dieu et Allah \u00e9taient, en r\u00e9alit\u00e9, un seul et m\u00eame Dieu? Oui, il n\u2019existait qu\u2019un seul Dieu, me disais-je; tous mes amis musulmans attestaient de ce fait et affirmaient que ce Dieu unique s\u2019appelait Allah. Je remis en question toutes mes croyances pass\u00e9es, mais \u00e0 cette \u00e9tape de ma qu\u00eate, je ne me sentais pas encore pr\u00eat \u00e0 devenir musulman.<\/p>\n<p>Peu de temps apr\u00e8s, j\u2019entrai un jour dans le bureau de mon patron, un musulman, tenant \u00e0 la main, plut\u00f4t que dans ma poche, le fameux chapelet qui m\u2019avait \u00e9t\u00e9 offert. Me voyant ainsi, il me dit : \u00ab Tu as l\u2019air d\u2019un musulman, Michael. Songes-tu \u00e0 embrasser l\u2019islam? \u00bb, me demanda-t-il, mi-s\u00e9rieux mi-blagueur. Je m\u2019assis devant lui et r\u00e9pondis : \u00ab Oui! \u00bb Je crois que ni lui ni moi n\u2019oublierons ce matin. L\u2019\u00e9motion \u00e9tait \u00e0 son comble. Il fit le tour de son bureau pour venir vers moi et me serra la main, en me disant qu\u2019il ferait tout son possible pour m\u2019aider \u00e0 trouver ma voie. J\u2019acceptai son aide et le remerciai. Je me sentis soulag\u00e9 d\u2019un grand poids et me plongeai encore plus profond\u00e9ment dans ma qu\u00eate de v\u00e9rit\u00e9. Un soir, tard, je jetai un coup d\u2019\u0153il aux derni\u00e8res pages de ma traduction anglaise du Coran et vis que des sections avaient \u00e9t\u00e9 ajout\u00e9es. L\u2019une d\u2019elles s\u2019intitulait \u00ab J\u00e9sus et Mohammed (que Dieu les loue tous les deux) dans la Bible et le Coran : preuves bibliques d\u00e9montrant que J\u00e9sus \u00e9tait un serviteur de Dieu et qu\u2019il ne partageait pas la divinit\u00e9 de Dieu. \u00bb<\/p>\n<p>Je lus ces dix pages lentement et avec grande attention, plusieurs fois. Ainsi, J\u00e9sus n\u2019\u00e9tait pas Dieu. Je lus les \u00e9vangiles de Matthieu, de Jean et de Marc. Je pris ma Bible et cherchai une indication sur celui ou ceux qui l\u2019avaient r\u00e9dig\u00e9e. Je cherchai \u00e0 savoir si J\u00e9sus avait r\u00e9ellement \u00e9crit les paroles du Nouveau Testament. Tout ce que j\u2019arrivai \u00e0 d\u00e9terminer, c\u2019est qu\u2019un groupe d\u2019\u00e9rudits avait r\u00e9vis\u00e9 la Bible \u00e0 deux reprises, dans les ann\u00e9es soixante-dix et les ann\u00e9es quatre-vingt; mais nulle part il n\u2019\u00e9tait indiqu\u00e9 que J\u00e9sus avait lui-m\u00eame r\u00e9dig\u00e9, ou m\u00eame dict\u00e9, les paroles du Nouveau Testament. Tout ce que ce dernier contenait avait \u00e9t\u00e9 r\u00e9dig\u00e9 par des hommes, pour la plupart inconnus, longtemps apr\u00e8s la mort de J\u00e9sus. Je me remis \u00e0 la lecture du Coran et j\u2019y d\u00e9couvris des versets affirmant clairement que Dieu avait cr\u00e9\u00e9 J\u00e9sus et Marie et que cette derni\u00e8re \u00e9tait vierge lors de la conception de son fils.<\/p>\n<p>Dieu n\u2019eut qu\u2019\u00e0 dire \u00ab sois! \u00bb et J\u00e9sus fut! J\u00e9sus \u00e9tait un musulman, envoy\u00e9 par Dieu \u00e0 son peuple pour leur montrer le droit chemin. Le Coran affirme \u00e9galement qu\u2019il n\u2019a jamais go\u00fbt\u00e9 \u00e0 la mort, mais qu\u2019il a \u00e9t\u00e9 \u00e9lev\u00e9 au ciel, vers Dieu, et qu\u2019il reviendra sur terre pour enfin y mourir. Allah (Dieu) transmit ensuite Son message au proph\u00e8te Mohammed. Ce message fut transcrit par des scribes et rev\u00e9rifi\u00e9 par Mohammed, pour finalement former le Coran. Je sentais que mon esprit, autant que mon c\u0153ur, s\u2019ouvraient maintenant \u00e0 l\u2019islam. Je ne doutais plus du tout qu\u2019il n\u2019y avait pas d\u2019autre Dieu qu\u2019Allah et que Mohammed \u00e9tait Son dernier messager. Comment les chr\u00e9tiens pouvaient-ils croire \u00e0 la trinit\u00e9, alors qu\u2019il est tellement \u00e9vident que Dieu n\u2019est qu\u2019Un. Pas \u00e9tonnant que j\u2019avais eu tant de mal \u00e0 comprendre l\u2019id\u00e9e selon laquelle J\u00e9sus \u00e9tait Dieu! Il ne l\u2019\u00e9tait pas! Oui, il fut un important messager et proph\u00e8te, mais il ne fut jamais Dieu Lui-m\u00eame.<\/p>\n<p>Lorsque je r\u00e9alisai cela, au fond de mon c\u0153ur, je d\u00e9cidai d\u2019embrasser l\u2019islam sur-le-champ. Je demandai, autour de moi, qui je devais voir pour devenir officiellement musulman. On me r\u00e9f\u00e9ra \u00e0 un homme de religion. J\u2019avais l\u2019impression, \u00e0 ce moment, d\u2019avancer \u00e0 grandes enjamb\u00e9es; jamais je n\u2019avais ressenti de telles \u00e9motions. Je rencontrai cet homme, \u00e0 qui on m\u2019avait r\u00e9f\u00e9r\u00e9, et pronon\u00e7ai l\u2019attestation de foi devant lui apr\u00e8s une longue discussion. Il m\u2019\u00e9treignit en me disant que j\u2019\u00e9tais maintenant musulman et je me mis presque \u00e0 pleurer! Ce soir-l\u00e0, je fis ma premi\u00e8re pri\u00e8re \u00e0 la mosqu\u00e9e et re\u00e7us de nombreuses embrassades. Le jour suivant, j\u2019allai voir l\u2019imam de la mosqu\u00e9e et pronon\u00e7ai \u00e0 nouveau la shahadah (attestation de foi) devant lui. Il me demanda de venir \u00e0 la pri\u00e8re du midi, ce que je fis.<\/p>\n<p>Apr\u00e8s la pri\u00e8re, il me pr\u00e9senta \u00e0 tous les fid\u00e8les pr\u00e9sents et me demanda si j\u2019avais quelque chose \u00e0 dire. Je ne pus me retenir et pronon\u00e7ai \u00e0 nouveau la shahadah devant toute la salle. Je me pr\u00e9sentai ensuite et expliquai bri\u00e8vement mon cheminement vers l\u2019islam. Lorsque j\u2019eus termin\u00e9, \u00e0 peu pr\u00e8s chaque homme, dans la mosqu\u00e9e, vint me serrer la main et m\u2019\u00e9treindre. Jamais, nulle part, je n\u2019avais \u00e9t\u00e9 accueilli de mani\u00e8re aussi chaleureuse. J\u2019en avais les larmes aux yeux. Quelque temps apr\u00e8s, un musulman vint m\u2019enseigner \u00e0 accomplir la pri\u00e8re correctement. Maintenant, je fais toutes mes pri\u00e8res \u00e0 l\u2019heure. J\u2019ai lu une trentaine de livres sur l\u2019islam et j\u2019ai plus de 2000 fichiers \u00e9lectroniques sur le sujet.<\/p>\n<p>J\u2019appelai mon p\u00e8re, ma m\u00e8re, mon fils et mon fr\u00e8re pour tout leur expliquer en d\u00e9tail et ils accept\u00e8rent tous ma conversion sans aucun probl\u00e8me.<\/p>\n<p>J\u2019ai fait une demande officielle pour changer mon nom, Michael Allen Wilson, pour Khalil Ibrahim Abdoulmajid.<\/p>\n<p>J\u2019aime tant ma nouvelle religion que je n\u2019ai de cesse d\u2019en parler \u00e0 qui veut bien \u00e9couter.<\/p>\n<p>Lorsque des musulmans et des chr\u00e9tiens me demandent pourquoi j\u2019ai embrass\u00e9 l\u2019islam, je r\u00e9ponds que depuis que j\u2019ai d\u00e9couvert qu\u2019Allah a transmis Son message par l\u2019interm\u00e9diaire du proph\u00e8te Mohammed, demandant aux hommes de L\u2019adorer de mani\u00e8re exclusive et de mener leurs vies en conformit\u00e9 avec Sa volont\u00e9, car c\u2019est l\u2019unique voie menant au succ\u00e8s ici-bas et dans l\u2019au-del\u00e0, j\u2019y ai fermement adh\u00e9r\u00e9 dans l\u2019espoir de go\u00fbter \u00e0 la r\u00e9compense du Paradis. Et voil\u00e0 pourquoi je suis si heureux, maintenant.<\/p>\n<p>Gloire \u00e0 Allah.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/khalil-ibrahim-abdulmajid-ex-chrtien-tats-unis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) En 1988, je commen\u00e7ai \u00e0 travailler sur un projet, avec mon p\u00e8re, qui \u00e9tait m\u00e9decin en Arabie. Il travaillait l\u00e0-bas, tandis que j\u2019\u00e9tais aux \u00c9tats-Unis. Cette m\u00eame ann\u00e9e, j\u2019allai lui rendre visite et demeurai dans la ville de Dhahran, puis me d\u00e9pla\u00e7ai \u00e0 Al-Khobar pour faire avancer mon projet. Ce que &#8230; <a title=\"Khalil Ibrahim Abdulmajid, ex-chr\u00e9tien, \u00c9tats-Unis\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/khalil-ibrahim-abdulmajid-ex-chretien-etats-unis\/\" aria-label=\"Read more about Khalil Ibrahim Abdulmajid, ex-chr\u00e9tien, \u00c9tats-Unis\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7598","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 2) En 1988, je commen\u00e7ai \u00e0 travailler sur un projet, avec mon p\u00e8re, qui \u00e9tait m\u00e9decin en Arabie. Il travaillait l\u00e0-bas, tandis que j\u2019\u00e9tais aux \u00c9tats-Unis. Cette m\u00eame ann\u00e9e, j\u2019allai lui rendre visite et demeurai dans la ville de Dhahran, puis me d\u00e9pla\u00e7ai \u00e0 Al-Khobar pour faire avancer mon projet. Ce que\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Yy","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7598,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7598,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8688,"url":"https:\/\/www.ask-a-muslim.com\/de\/respirationsapparat-ist-ausser-betrieb-in-hochluftschichten\/","url_meta":{"origin":7598,"position":2},"title":"RESPIRATIONSAPPARAT IST AUSSER BETRIEB IN HOCHLUFTSCHICHTEN","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den Islam. Und wen Er irref\u00fchren will, dem macht Er die Brust beklommen und bedr\u00fcckt, so als ob er in den Himmel hoch steigen w\u00fcrde Allah, der Erhabene sagt: \"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7598,"position":3},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8571,"url":"https:\/\/www.ask-a-muslim.com\/de\/musa-caplan-ex-jude-usa\/","url_meta":{"origin":7598,"position":4},"title":"Musa Caplan, Ex-Jude, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Vor meiner Konvertierung zum Islam lebte ich mein Leben als Jude. Obwohl meine Familie nicht traditionell war, lernte ich das Judentum von traditionellen Juden. Ich ging zu einer orthodoxen j\u00fcdischen Synagoge und zu einer orthodoxen j\u00fcdischen Schule. Ich lebte und lebe immer noch in einer j\u00fcdischen Gemeinde in den USA,\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8643,"url":"https:\/\/www.ask-a-muslim.com\/de\/latasha-ex-christin-usa\/","url_meta":{"origin":7598,"position":5},"title":"Latasha, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin Amerikanerin, die in einer streng religi\u00f6sen christlichen Familie aufgewachsen ist. W\u00e4hrend der Zeit, als ich 16 wurde, wurde ich selbst sehr fromm und religi\u00f6s. Die Kirche war wie ein Heim weit entfernt von zuhause. Ich genoss sie von Grund auf. Ich hatte die Bibel regelm\u00e4\u00dfig gelesen und studiert.\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7598"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7598\/revisions"}],"predecessor-version":[{"id":11185,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7598\/revisions\/11185"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}