{"id":7616,"date":"2020-06-17T02:21:21","date_gmt":"2020-06-17T07:21:21","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7616"},"modified":"2020-07-01T08:02:02","modified_gmt":"2020-07-01T13:02:02","slug":"lynda-fitzgerald-ex-catholique-irlande","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/lynda-fitzgerald-ex-catholique-irlande\/","title":{"rendered":"Lynda Fitzgerald, ex-catholique, Irlande"},"content":{"rendered":"<h3><strong>(partie 1 de 4)<\/strong><\/h3>\n<h4><strong>Introduction<\/strong><\/h4>\n<p>Lynda Fitzgerald, qui s\u2019appelle maintenant Khadija, est une Irlandaise native de la ville de Wicklow, pr\u00e8s de Dublin. Elle est issue d\u2019une famille catholique tr\u00e8s stricte et elle a huit fr\u00e8res et s\u0153urs. Son p\u00e8re est \u00e9lectricien et sa m\u00e8re demeure au foyer.<\/p>\n<p>Lynda est all\u00e9e \u00e0 l\u2019\u00e9cole \u00e0 Wicklow avant de s\u2019inscrire au Coll\u00e8ge de secr\u00e9tariat. Puis elle a travaill\u00e9 neuf ans \u00e0 Dublin.<\/p>\n<p>Elle s\u2019est convertie \u00e0 l\u2019islam apr\u00e8s son arriv\u00e9e en Arabie Saoudite. Dans cet article, elle raconte les \u00e9v\u00e9nements qui l\u2019ont amen\u00e9e dans ce pays et qui lui ont fait d\u00e9couvrir la bonne voie. Que Dieu la b\u00e9nisse.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Ce qui m\u2019a amen\u00e9e en Arabie Saoudite<\/strong><\/h4>\n<p>Je faisais partie d\u2019un club jeunesse. Nous nous r\u00e9unissions chaque lundi, puis terminions la soir\u00e9e au pub. Je ne suivais pas souvent les autres au pub, mais j\u2019y allais parfois. Un soir, une nouvelle fille se joignit \u00e0 nous, au club, et je d\u00e9cidai de suivre le groupe au pub, par la suite, afin de mieux la conna\u00eetre et de faire en sorte qu\u2019elle se sente \u00e0 l\u2019aise parmi nous. Il s\u2019av\u00e9ra qu\u2019elle travaillait pour une agence qui recrutait des gens d\u00e9sirant aller travailler en Arabie Saoudite. Elle m\u2019expliqua comment cela fonctionnait et moi, je l\u2019\u00e9coutais, fascin\u00e9e. Avant cette soir\u00e9e, je n\u2019avais presque jamais entendu parler de ce pays, mais plus elle parlait, plus mon int\u00e9r\u00eat s\u2019\u00e9veillait, et au moment de quitter le pub, je souhaitais d\u00e9j\u00e0 aller travailler en Arabie.<\/p>\n<p>Je postulai donc pour un emploi, mais je ne l\u2019obtins pas (c\u2019\u00e9tait en 1993).<\/p>\n<p>Puis, je finis par oublier tout cela. Je retournai chez moi pour No\u00ebl, o\u00f9 je m\u2019ennuyai ferme, et l\u2019envie me prit de faire de nouvelles choses et de transformer ma vie. Toutes mes amies \u00e9taient en couple ou mari\u00e9es, et elles avaient toutes emprunt\u00e9 des voies diff\u00e9rentes. Tout \u00e0 coup, je ne me sentais plus attach\u00e9e \u00e0 rien ni \u00e0 personne. Lorsque je revins en ville, apr\u00e8s No\u00ebl, je t\u00e9l\u00e9phonai \u00e0 cette fille qui travaillait pour l\u2019agence de recrutement et lui demandai de me proposer pour n\u2019importe quel poste en Arabie Saoudite. Elle me dit : \u00ab Tu ne me croira pas : je viens tout juste de recevoir un fax de l\u2019H\u00f4pital des forces de s\u00e9curit\u00e9 qui demande une secr\u00e9taire. \u00bb D\u00e8s le 15 mars (1994), mon avion atterrissait en Arabie Saoudite.<\/p>\n<h4><\/h4>\n<h4><strong>Mes premi\u00e8res impressions sur l\u2019islam<\/strong><\/h4>\n<p>Lorsque vous arrivez en Arabie Saoudite, la premi\u00e8re chose que viennent vous dire les autres Occidentaux qui y sont d\u00e9j\u00e0 install\u00e9s est que les musulmans sont vraiment terribles, qu\u2019ils maltraitent leurs femmes, qu\u2019ils partent pour prier pendant des heures et qu\u2019ils se rendent r\u00e9guli\u00e8rement \u00e0 Bahre\u00efn pour boire et fr\u00e9quenter des prostitu\u00e9es. Alors vous adoptez cette opinion d\u00e8s le d\u00e9part&#8230; et vous croyez que c\u2019est \u00e7a, l\u2019islam. Mais ce n\u2019est pas l\u2019islam. Et malheureusement, la plupart des Occidentaux ne comprennent pas cela.<\/p>\n<h4><\/h4>\n<h4><strong>Comment j\u2019en suis venue \u00e0 modifier mon point de vue<\/strong><\/h4>\n<p>D\u00e8s le d\u00e9part, ma curiosit\u00e9 l\u2019emporta. Je voyais des gens prier et je trouvais extraordinaire qu\u2019une personne ait une foi si grande qu\u2019elle adore Dieu \u00e0 chaque instant. Je trouvais parfois des d\u00e9pliants sur l\u2019islam et je les prenais dans l\u2019intention de les lire, mais mes ami(e)s occidentaux me disaient \u00ab pourquoi veux-tu lire cela? Ils ne cherchent qu\u2019\u00e0 t\u2019endoctriner \u00bb et alors, g\u00ean\u00e9e, je les laissais tomber et ne les lisais pas. Puis, un jour, je d\u00e9cidai de prendre un cours d\u2019arabe et le professeur, un \u00c9gyptien, me fit une bonne impression. Il \u00e9tait tr\u00e8s diff\u00e9rent de la plupart des musulmans que j\u2019avais rencontr\u00e9s jusque-l\u00e0. Sa foi \u00e9tait grande. Je devins plus famili\u00e8re avec lui, car je vivais des probl\u00e8mes avec un musulman, au travail, et j\u2019avais besoin d\u2019en parler \u00e0 quelqu\u2019un. Ce probl\u00e8me me troublait beaucoup et j\u2019en jetais le bl\u00e2me sur l\u2019islam. Mais il m\u2019\u00e9couta patiemment, il m\u2019expliqua certaines choses et m\u2019aida \u00e0 comprendre que le probl\u00e8me n\u2019\u00e9tait pas l\u2019islam et que tous les musulmans ne se comportaient pas comme mon coll\u00e8gue de travail.<\/p>\n<p>Une autre chose que vous diront les Occidentaux est que tout ce que veulent les musulmans, c\u2019est vous convertir \u00e0 leur religion, et qu\u2019ils vous laveront le cerveau \u00e0 la premi\u00e8re occasion. Alors \u00e9videmment, vous \u00eates imm\u00e9diatement sur vos gardes d\u00e8s que l\u2019un d\u2019entre eux mentionne quoi que ce soit sur l\u2019islam, et vous \u00e9rigez tout de suite une barri\u00e8re entre eux et vous, afin de ne pas avoir \u00e0 \u00e9couter ce qu\u2019ils essaient de vous dire. Mon professeur d\u2019arabe, Khaled, ne me parlait jamais d\u2019islam avant que je n\u2019aie moi-m\u00eame abord\u00e9 le sujet ou \u00e0 moins que j\u2019aie tenu des propos erron\u00e9s \u00e0 ce sujet. Il m\u2019arrivait aussi, parfois, de l\u2019attaquer injustement sur un sujet qui n\u2019avait pourtant rien \u00e0 voir avec l\u2019islam. Mais il demeurait toujours calme et patient et il \u00e9tait clair que tout ce qu\u2019il souhaitait, c\u2019\u00e9tait me faire conna\u00eetre la v\u00e9rit\u00e9; il souhaitait me faire comprendre que j\u2019\u00e9tais injuste dans mes affirmations et que j\u2019avais manifestement \u00e9t\u00e9 mal inform\u00e9e.<\/p>\n<p>Puis, arriva le mois de Ramadan. Plusieurs des Saoudiens qui travaillaient avec nous se plaignaient : \u00ab l\u2019odeur de votre nourriture vient jusqu\u2019\u00e0 nous; vous ne devriez pas manger dans vos bureaux, ayez donc un peu de respect pour nous \u00bb. Je ne comprenais pas pourquoi je ne pouvais m\u00eame pas avoir un verre d\u2019eau sur mon bureau; apr\u00e8s tout, ils \u00e9taient cens\u00e9s faire ce sacrifice pour Dieu, alors mon verre d\u2019eau n\u2019\u00e9tait pas cens\u00e9 les d\u00e9ranger. Voici un extrait de mon journal intime qui illustre assez bien mes sentiments, lors des premiers jours de Ramadan :<\/p>\n<p>\u00ab C\u2019est Ramadan. Mon Dieu, quel mois! C\u2019est si aga\u00e7ant. On ne peut m\u00eame pas prononcer le mot \u00ab nourriture \u00bb. Ils sont tous l\u00e0, \u00e0 aller et venir tels de grands martyrs, et la plupart d\u2019entre eux travaillent \u00e0 peine. Ils n\u2019ont que six heures par jour \u00e0 faire, alors ils passent toute la nuit \u00e9veill\u00e9s \u00e0 manger et ils ont le culot de nous faire sentir comme de v\u00e9ritables pa\u00efens durant le jour. \u00bb<\/p>\n<p>Mon ami Khaled tenta de m\u2019expliquer tout cela. Il me parla des pri\u00e8res du Ramadan, en fin de soir\u00e9e (tarawih), des efforts d\u00e9ploy\u00e9s par les musulmans pour faire le plus de bonnes actions possible, donner en charit\u00e9, et \u00e9viter d\u2019utiliser un mauvais langage, de se plaindre ou de m\u00e9dire des autres. Il me dit que certains Occidentaux essayaient de je\u00fbner, eux aussi, pour savoir comment se sentent les musulmans durant cette p\u00e9riode, et que certains finissaient par y prendre go\u00fbt au point o\u00f9 ils je\u00fbnaient maintenant chaque ann\u00e9e. Alors un matin, je me levai et je d\u00e9cidai d\u2019essayer de je\u00fbner, moi aussi. Je n\u2019en fis part \u00e0 personne, pas m\u00eame \u00e0 Khaled, m\u00eame s\u2019il finit par s\u2019en rendre compte par la suite.<\/p>\n<p>Un jour, j\u2019allai le voir et il me dit qu\u2019il avait de la lecture pour moi. Il ouvrit une copie du Coran pour me montrer un passage sur J\u00e9sus (que la paix soit sur lui). Lorsqu\u2019il mit le livre entre mes mains, c\u2019\u00e9tait comme s\u2019il d\u00e9posait sur elles une pr\u00e9cieuse pi\u00e8ce de cristal. Je ne voulais pas lui redonner le livre et je me sentais ridicule, craignant qu\u2019il se moque de moi si je lui d\u00e9crivais mon sentiment. Mais je finis par le lui redonner. Cet \u00e9pisode me tourmenta des jours durant, jusqu\u2019\u00e0 ce qu\u2019il me pose clairement la question : \u00ab mais pourquoi ne lis-tu pas le Coran? \u00bb. Je me sentis alors soulag\u00e9e d\u2019un grand poids; j\u2019amenai le Coran chez moi, ce soir-l\u00e0, et je commen\u00e7ai \u00e0 le lire.<\/p>\n<h4><\/h4>\n<h3><strong>(partie 2 de 4)<\/strong><\/h3>\n<p>Deux choses se produisirent, en moi, lorsque je lus le Coran pour la premi\u00e8re fois. Lors de ma lecture de la deuxi\u00e8me sourate, al-Baqarah (verset 21), je m\u2019arr\u00eatai soudain de lire. Je fermai les yeux, je pensai \u00e0 Dieu, et tout \u00e0 coup, je compris Son unicit\u00e9, et je ressentis Sa sup\u00e9riorit\u00e9. Je compris pourquoi Il n\u2019a aucunement besoin d\u2019associ\u00e9s, et je compris que nul ne peut se trouver \u00e0 Ses c\u00f4t\u00e9s, \u00e0 Son niveau; Il n\u2019a besoin de personne. J\u2019en \u00e9tais maintenant convaincue. Je sentis une grande paix au fond de moi, accompagn\u00e9e de la certitude qu\u2019il n\u2019y a pas d\u2019autre dieu qu\u2019Allah. J\u2019aurais voulu que ce sentiment dure pour toujours, mais il me quitta apr\u00e8s quelques minutes.<\/p>\n<p>La seconde chose qui se produisit en moi fut lors de ma lecture du verset 5 de la sourate al-Hajj. Je fermai \u00e0 nouveau les yeux et je vis le monde dans son \u00e9tat primitif. Je vis un monticule de terre, puis une graine germant, grandissant et prenant la forme d\u2019un arbre, et je me dis : \u00ab d\u2019o\u00f9 est venue cette graine? D\u2019o\u00f9 proviennent toutes les merveilleuses vari\u00e9t\u00e9s de plantes que l\u2019on trouve \u00e0 travers le monde? Elles ne peuvent provenir que de Dieu. \u00bb Encore une fois, je ressentis une grande paix et je pris conscience de la grandeur de Dieu.<\/p>\n<h4><\/h4>\n<h4><strong>Les mois pr\u00e9c\u00e9dant ma conversion<\/strong><\/h4>\n<p>Ces mois furent \u00e0 la fois les plus beaux et les plus difficiles de ma vie. \u00c0 certains moments, j\u2019\u00e9tais en pleine euphorie tandis qu\u2019\u00e0 d\u2019autres, j\u2019\u00e9tais totalement d\u00e9sesp\u00e9r\u00e9e. Voici un extrait de mon journal intime, au mois d\u2019avril de cette ann\u00e9e-l\u00e0 :<br \/>\n\u00ab Quelque chose d\u2019\u00e9trange m\u2019arrive et je ne sais trop qu\u2019en penser, si c\u2019est une bonne chose ou une mauvaise chose, si mon imagination me joue des tours ou si je suis simplement entrain de subir un lavage de cerveau. Mais encore l\u00e0, ce pourrait \u00eatre pour le mieux et peut-\u00eatre que cela fait tout simplement partie de mon destin.<\/p>\n<p>\u00ab J\u2019ai \u00e9tudi\u00e9 l\u2019islam et je pense s\u00e9rieusement \u00e0 me convertir&#8230; Que Dieu me vienne en aide. En ce moment, je ne sais trop que penser; tout cela m\u2019effraie beaucoup, au fond. Je n\u2019aurais jamais cru qu\u2019une telle chose puisse m\u2019arriver. Je n\u2019ai jamais vraiment voulu me convertir \u00e0 une autre religion; je me suis toujours consid\u00e9r\u00e9e comme catholique, j\u2019ai toujours cru en Dieu et j\u2019ai toujours cru que J\u00e9sus \u00e9tait le fils de Dieu. Aujourd\u2019hui, je remets tout cela en question, je remets en question toutes les croyances qui m\u2019ont \u00e9t\u00e9 inculqu\u00e9es et en fait, tout mon mode de vie. \u00bb<\/p>\n<p>\u00c0 cette \u00e9poque, je pensais \u00e0 l\u2019islam d\u00e8s mon r\u00e9veil et j\u2019y pensais encore au moment o\u00f9 je rentrais chez moi, le soir. Puis, vint un moment o\u00f9 chaque fois que j\u2019entendais le adhan [appel \u00e0 la pri\u00e8re], je ressentais un besoin pressant de prier et, dans les premiers temps, je priais \u00e0 la fa\u00e7on chr\u00e9tienne, qui \u00e9tait la seule que j\u2019avais apprise. Quelque temps apr\u00e8s, je demandai \u00e0 un coll\u00e8gue de travail de m\u2019apporter un livre sur la fa\u00e7on de prier, en islam. Apr\u00e8s l\u2019avoir lu, avoir regard\u00e9 des gens prier \u00e0 la t\u00e9l\u00e9vision et pos\u00e9 de nombreuses questions, je me mis \u00e0 prier. Personne n\u2019\u00e9tait au courant \u00e0 part deux de mes coll\u00e8gues de travail, un \u00c9gyptien et un Jordanien.<\/p>\n<p>Au d\u00e9but, je priais sans couvrir mes cheveux, car j\u2019ignorais que c\u2019\u00e9tait une obligation. Et lorsque quelqu\u2019un finit par me le faire remarquer, j\u2019eus de la difficult\u00e9 \u00e0 comprendre pourquoi. J\u2019eus une longue discussion anim\u00e9e avec Khaled \u00e0 ce sujet, suite \u00e0 laquelle je n\u2019arrivais toujours pas \u00e0 comprendre. Puis, en revenant chez moi, ce soir-l\u00e0, alors que je marchais en direction de l\u2019arr\u00eat d\u2019autobus, je me mis \u00e0 penser \u00e0 la grandeur de Dieu et \u00e0 quel point j\u2019\u00e9tais insignifiante par rapport \u00e0 Lui; je me sentis aussi petite qu\u2019une fourmi voyant le monde entier \u00e9tendu devant elle. Je compris alors que je devais couvrir mes cheveux lors de mes pri\u00e8res, car Il pouvait me voir en tout temps, et je n\u2019avais aucun droit de me montrer arrogante en refusant de me plier \u00e0 Ses commandements.<\/p>\n<h4><\/h4>\n<h4><strong>Extrait de mon journal dat\u00e9 du 23 avril 1995<\/strong><\/h4>\n<p>\u00ab Je me sens toujours aussi confuse. \u00c0 certains moments, tout me semble tr\u00e8s clair et je me dis \u00ab oui, j\u2019y crois et j\u2019ai envie de le crier sur les toits \u00bb. Mais \u00e0 d\u2019autres moments, le doute et la crainte m\u2019envahissent et je ne sais plus o\u00f9 j\u2019en suis. C\u2019est tr\u00e8s difficile. Il s\u2019agit pourtant d\u2019une tr\u00e8s belle religion. Le Coran est tr\u00e8s beau et contient tout ce dont nous avons besoin, nous \u00eatres humains, pour guider nos vies : les r\u00e8gles du comportement et de la pri\u00e8re, les choses permises et les interdictions, entre autres. On ne trouve rien de tout cela dans le catholicisme, sans compter qu\u2019\u00e0 p\u00e9riodes r\u00e9guli\u00e8res, ils modifient les r\u00e8gles afin de les rendre conformes \u00e0 leurs d\u00e9sirs.<\/p>\n<p>Si vous suivez l\u2019islam tel qu\u2019il a \u00e9t\u00e9 prescrit, vous ne pouvez \u00eatre mauvais envers qui que ce soit. Vous ne pouvez \u00eatre que bon, patient et tol\u00e9rant et vous ne pouvez jamais oublier Dieu, car vous L\u2019adorez au moins cinq fois quotidiennement. J\u2019aime prier, depuis toujours. Prier m\u2019aide \u00e0 me rappeler toutes les bonnes choses que Dieu m\u2019a accord\u00e9es et \u00e0 en \u00eatre \u00e9ternellement reconnaissante. Cela m\u2019apporte une paix dans ma vie quotidienne. \u00bb<\/p>\n<p>Parfois, j\u2019\u00e9tais vraiment heureuse d\u2019avoir d\u00e9couvert l\u2019islam, mais \u00e0 d\u2019autres moments, je souhaitais n\u2019en avoir jamais entendu parler, car maintenant que je savais que c\u2019\u00e9tait la v\u00e9rit\u00e9, je savais \u00e9galement que je n\u2019avais d\u2019autre choix que de me convertir. M\u00eame si j\u2019avais cess\u00e9 de boire et de participer aux f\u00eates de toutes sortes, je m\u2019accrochais encore \u00e0 mon ancienne vie; je craignais de perdre tous mes amis occidentaux et d\u2019affronter leurs pr\u00e9jug\u00e9s une fois que j\u2019aurais commenc\u00e9 \u00e0 me couvrir les cheveux. J\u2019en parlai plusieurs fois \u00e0 Khaled et je lui r\u00e9p\u00e9tai chaque fois que jamais je ne trouverais le courage de porter le hijab; et chaque fois, sa r\u00e9ponse fut : \u00ab quand Dieu le voudra, tu trouveras le courage \u00bb.<\/p>\n<p>Dans mon journal intime, j\u2019\u00e9crivais \u00e9galement : \u00ab Le probl\u00e8me, c\u2019est que je suis une trouillarde-n\u00e9e. Je suis paralys\u00e9e en pensant \u00e0 la r\u00e9action des gens que je connais, lorsqu\u2019ils me verront pour la premi\u00e8re fois avec un hijab. Comment annoncer cette nouvelle \u00e0 ma m\u00e8re ou \u00e0 Liz, en Australie? Comment aller en Australie, ou m\u00eame en Irlande, la t\u00eate couverte d\u2019un hijab? Je me sens incapable de faire face \u00e0 cela. Que Dieu m\u2019en donne la force. \u00bb<\/p>\n<h3><\/h3>\n<h3><strong>(partie 3 de 4)<\/strong><\/h3>\n<h4><strong>Changer d\u2019emploi<\/strong><\/h4>\n<p>Au travail, deux postes se lib\u00e9r\u00e8rent en juin, l\u2019un aux ressources humaines et l\u2019autre dans le d\u00e9partement de l\u2019\u00e9ducation et de la formation. J\u2019avais le choix entre les deux et les directeurs des deux d\u00e9partements m\u2019invitaient \u00e0 postuler pour leurs postes respectifs. Aux ressources humaines, je me serais retrouv\u00e9e au c\u0153ur de l\u2019action et au courant de la plupart des choses qui se passaient dans l\u2019h\u00f4pital, en plus de jouir possiblement d\u2019une hausse de salaire dans le futur. Tandis qu\u2019\u00e0 l\u2019\u00e9ducation, j\u2019aurais \u00e9t\u00e9 plus expos\u00e9e et je n\u2019aurais pu cacher aux gens ma conversion \u00e0 l\u2019islam, me sentant par le fait m\u00eame forc\u00e9e d\u2019agir en fonction de cette \u00e9vidence et de commencer \u00e0 porter le hijab. Je jonglai avec ces pens\u00e9es des semaines durant. Puis je d\u00e9cidai que je pr\u00e9f\u00e9rais me retrouver au c\u0153ur de l\u2019action et occuper un poste influent, mais en m\u00eame temps, quelque chose me retenait.<\/p>\n<p>Finalement, une amie me conseilla de prier deux rakat [unit\u00e9s de pri\u00e8re] suppl\u00e9mentaires apr\u00e8s ma derni\u00e8re pri\u00e8re du soir et de demander \u00e0 Dieu de me guider [ce qu\u2019on appelle la pri\u00e8re de consultation, ou istikhara]. C\u2019est ce que je fis durant plusieurs jours, mais sans r\u00e9sultat. Je crois que je savais, au fond, qu\u2019il \u00e9tait pr\u00e9f\u00e9rable que je choisisse le d\u00e9partement d\u2019\u00e9ducation, mais j\u2019avais de la difficult\u00e9 \u00e0 prendre une d\u00e9cision, j\u2019avais peur de faire face \u00e0 l\u2019opinion des autres et j\u2019\u00e9tais assaillie de pens\u00e9es \u00e0 l\u2019effet que j\u2019allais me retrouver dans une position influente si je choisissais les ressources humaines.<\/p>\n<p>Puis, un soir, alors que je lisais le Coran, je me mis \u00e0 penser que toutes ces choses, i.e. l\u2019argent, le pouvoir et l\u2019opinion d\u2019autrui, n\u2019avaient aucune signification \u00e0 mes yeux et n\u2019en avaient jamais r\u00e9ellement eu. Je me demandai pourquoi j\u2019y avais accord\u00e9 tant d\u2019importance au cours des semaines pr\u00e9c\u00e9dentes et je compris que le diable m\u2019avait sugg\u00e9r\u00e9 tout cela. En effet, celui-ci savait que si je choisissais le d\u00e9partement d\u2019\u00e9ducation, j\u2019y trouverais plus de soutien car plus de musulmans y travaillaient et ma spiritualit\u00e9 s\u2019en trouverait enrichie. Je sentis que le nuage qui m\u2019enveloppait se dissipait tout \u00e0 coup et je pris enfin ma d\u00e9cision, c\u2019est-\u00e0-dire celle d\u2019aller au d\u00e9partement d\u2019\u00e9ducation.<\/p>\n<h4><\/h4>\n<h4><strong>Porter le hijab<\/strong><\/h4>\n<p>Apr\u00e8s, tout se pr\u00e9cipita. Je me mis \u00e0 fr\u00e9quenter la mosqu\u00e9e aux heures de pri\u00e8res et je re\u00e7us un soutien inesp\u00e9r\u00e9 des membres du d\u00e9partement d\u2019\u00e9ducation. Puis, mon (tr\u00e8s religieux) patron entendit parler de ma conversion et m\u2019encouragea fortement \u00e0 porter le hijab. J\u2019y r\u00e9fl\u00e9chis donc s\u00e9rieusement, car je ne voulais pas le faire pour les mauvaises raisons. Je voulais le faire au moment o\u00f9 j\u2019allais me sentir pr\u00eate et d\u00e9termin\u00e9e. Puis, mon patron partit en vacances, ce qui enleva un peu de pression de mes \u00e9paules, m\u00eame si je continuais d\u2019y penser \u00e0 chaque instant. J\u2019avais de fr\u00e9quentes discussions avec mes amis \u00e0 ce sujet et je n\u2019\u00e9tais toujours pas convaincue que le port du hijab \u00e9tait obligatoire.<\/p>\n<p>Un week-end, j\u2019\u00e9tais chez une amie, dans l\u2019enceinte o\u00f9 nous logions, et j\u2019y rencontrai de nouvelles filles qui venaient d\u2019arriver. Elles \u00e9taient gentilles et je crus un instant pouvoir devenir amies avec elles; mais je me ravisai, pensant en moi-m\u00eame : \u00ab Bon, de nouvelles personnes arrivent et ce sera de plus en plus difficile d\u2019en parler ouvertement et de m\u2019affirmer. Si elles me voient avec le hijab d\u00e8s le d\u00e9part, elles s\u2019y feront et ne me poseront pas tellement de questions. \u00bb Alors je pris la d\u00e9cision de commencer \u00e0 le porter d\u00e8s le lendemain. Voici un extrait de mon journal intime :<\/p>\n<p>\u00ab Je crois que je commencerai \u00e0 me couvrir les cheveux d\u00e8s demain. Une partie de moi crois que c\u2019est le bon moment, tandis que l\u2019autre me crie de n\u2019en rien faire. J\u2019essaie d\u2019ignorer cette derni\u00e8re. C\u2019est si difficile&#8230; Qu\u2019arrivera-t-il si, d\u00e8s le lendemain ou la semaine suivante, je n\u2019ai plus envie de le porter? Ou si je r\u00e9alise, une semaine ou un mois plus tard, que j\u2019ai commis une erreur? Je sais qu\u2019une fois que j\u2019aurai commenc\u00e9, je ne pourrai plus revenir en arri\u00e8re, \u00e0 moins de vouloir perdre le respect de tous. Quand serai-je s\u00fbre \u00e0 100%? Quand serai-je encore plus s\u00fbre que je ne le suis en ce moment? Je dois prendre ce risque, je dois croire que si c\u2019est ce que Dieu souhaite, alors j\u2019arriverai \u00e0 passer au travers.<\/p>\n<p>\u00ab Voil\u00e0 que je traverse une crise d\u2019angoisse. \u00c0 l\u2019aide! Est-ce que je crois vraiment en cette religion? Ai-je vraiment envie d\u2019adopter ce mode de vie? Ai-je envie de passer toutes mes soir\u00e9es et tous mes week-ends seule? \u00c0 l\u2019aide! Au secours! \u00d4 mon Dieu, pourquoi est-ce si difficile? Pourquoi suis-je ainsi? \u00c0 l\u2019\u00e2ge de 29 ans, je me comporte encore comme une fillette de 5 ans. Comment suis-je arriv\u00e9e \u00e0 prendre des d\u00e9cisions, par la pass\u00e9, alors que je n\u2019arrive m\u00eame pas \u00e0 en prendre une dans ce cas-ci? Je ne me consid\u00e8re m\u00eame pas comme une \u00ab bonne \u00bb personne; je dois faire de r\u00e9els efforts pour arriver \u00e0 \u00eatre bonne ne serait-ce qu\u2019\u00e0 moiti\u00e9&#8230; En ce moment, ce que je voudrais faire, c\u2019est sortir de ce pays et rentrer chez moi, aller dans une discoth\u00e8que, danser follement, me saouler, hurler, crier et chanter.<\/p>\n<p>Puis-je vraiment envisager passer le reste de mes jours sans boire, sans avoir d\u2019amoureux, et contrainte \u00e0 me couvrir la t\u00eate chaque fois que je dois sortir? Si Kate \u00e9tait ici, en ce moment, je crois que je l\u2019appellerais et lui demanderais de me pr\u00e9parer un margarita. Mais elle n\u2019est pas ici! Je crois que le diable fait des heures suppl\u00e9mentaires chez moi, en ce moment. Dire que les gens croient que je suis une personne raisonnable&#8230; S\u2019ils savaient!<\/p>\n<p>\u00ab Bon, bon&#8230; \u00e7a y est, j\u2019ai pris ma d\u00e9cision. Je dois le faire. Au pire, je reviendrai \u00e0 la raison et r\u00e9aliserai \u00e0 quel point je suis ridicule. Au mieux, je r\u00e9aliserai que j\u2019ai pris la bonne d\u00e9cision et que je suis sur la bonne voie \u2013 incha\u2019Allah (si Dieu le veut). \u00bb<\/p>\n<p>Cette nuit-l\u00e0, je n\u2019arrivai pas \u00e0 fermer l\u2019\u0153il un seul instant. Jusqu\u2019\u00e0 la derni\u00e8re minute, je me disais que je n\u2019aurais pas le courage de le faire. Mais tout juste avant de sortir, je couvris mes cheveux d\u2019un hijab. Depuis, je ne suis jamais revenue sur ma d\u00e9cision.<\/p>\n<p>Je sentis que tous mes doutes s\u2019\u00e9taient dissip\u00e9s, que le diable avait l\u00e2ch\u00e9 prise sur moi. J\u2019\u00e9tais fi\u00e8re et je marchais la t\u00eate haute. Je voulais que tous sachent que j\u2019\u00e9tais musulmane. Je savais que j\u2019avais pris la bonne d\u00e9cision et que jamais je ne la regretterais. Soubhanallah, Dieu m\u2019a grandement facilit\u00e9 les choses.<\/p>\n<h3><\/h3>\n<h3><strong>(partie 4 de 4)<\/strong><\/h3>\n<h4><strong>La conversion<\/strong><\/h4>\n<p>Deux semaines plus tard, je me rendis au Da\u2019wah Center [centre d\u2019information sur l\u2019islam]. J\u2019\u00e9tais terrifi\u00e9e et j\u2019avais peur de dire quelque chose de d\u00e9plac\u00e9. Khaled et son \u00e9pouse m\u2019y conduisirent; ce fut un moment tr\u00e8s \u00e9motif. En sortant du centre, nous avions tous les larmes aux yeux. Je pleurai tout au long sur le chemin du retour.<\/p>\n<p>Par la suite&#8230;<\/p>\n<p>Je sentais toutefois que quelque chose n\u2019allait pas. \u00c9trangement, en changeant de mode de vie, j\u2019\u00e9tais devenue totalement accro \u00e0 la t\u00e9l\u00e9vision. Toute ma vie \u00e9tait ax\u00e9e sur mes pri\u00e8res et sur la t\u00e9l\u00e9vision en soir\u00e9e. Je n\u2019\u00e9tais pas heureuse de ce changement, mais je me sentais trop lasse pour y rem\u00e9dier. J\u2019essayais de lire des livres sur l\u2019islam, mais je me sentais satur\u00e9e d\u2019informations. Puis, \u00e0 l\u2019h\u00f4pital o\u00f9 je travaillais, des rumeurs commenc\u00e8rent \u00e0 circuler \u00e0 mon sujet et vinrent \u00e0 mes oreilles.<\/p>\n<p>Cela me mit vraiment en col\u00e8re, car je d\u00e9testais voir ma vie personnelle devenir le centre d\u2019int\u00e9r\u00eat de mes coll\u00e8gues. Un soir, en rentrant du travail, je sentis que je ne pouvais continuer ainsi; je d\u00e9testais rentrer et passer la soir\u00e9e assise devant la t\u00e9l\u00e9; je ne pouvais plus supporter de n\u2019avoir personne \u00e0 qui parler ni \u00e0 visiter, et mes week-ends \u00e9taient devenus de v\u00e9ritables cauchemars. Je me sentais seule et perdue.<\/p>\n<p>Ce soir-l\u00e0, lorsque vint l\u2019heure de la pri\u00e8re du \u2018Isha, je ne ressentis aucune envie de la faire. Cela ne m\u2019\u00e9tait jamais arriv\u00e9 auparavant, et je passai deux longues heures \u00e0 pleurer tout mon so\u00fbl.<\/p>\n<p>Le jour suivant, j\u2019avais les yeux affreusement gonfl\u00e9s et durant la journ\u00e9e, j\u2019\u00e9clatai en sanglots \u00e0 tout moment. Khaled me demanda plusieurs fois ce que j\u2019avais, mais je n\u2019arrivais pas \u00e0 lui r\u00e9pondre; je me sentais terriblement honteuse, m\u00eame si j\u2019avais fini par faire la pri\u00e8re du \u2018Isha, la veille, car je savais que je devais la faire.<\/p>\n<p>Je finis par tout lui avouer et il me rassura en me disant que m\u00eame lui, parfois, traversait des p\u00e9riodes similaires, et que je ne devais pas avoir une mauvaise opinion de moi-m\u00eame \u00e0 cause de cela. Ce dont j\u2019avais besoin, c\u2019\u00e9tait de changer mes habitudes; il me sugg\u00e9ra de faire du sport, jouer au tennis, aller faire les magasins, lire un bon livre&#8230; Je lui dis que cela ne m\u2019aiderait en rien car je me sentais tr\u00e8s seule et ce dont j\u2019avais besoin, c\u2019\u00e9tait de gens \u00e0 qui parler.<\/p>\n<p>Ce soir-l\u00e0, en rentrant chez moi, je sentis que j\u2019allais perdre la t\u00eate. Je ne pouvais plus continuer ainsi. Apr\u00e8s ma pri\u00e8re, je me prosternai et je priai, de tout mon c\u0153ur, demandant \u00e0 Dieu : \u00ab \u00d4 Dieu, je t\u2019en prie, ne me laisse pas Te perdre, ne me laisse pas Te perdre&#8230; \u00bb. Je m\u2019assis et jetai un coup d\u2019\u0153il sur les versets inscrits sur la couverture arri\u00e8re du Coran; j\u2019y vis al-Taakathour et apr\u00e8s l\u2019avoir lu, je compris que je devais laisser tomber toutes ces choses auxquelles j\u2019\u00e9tais attach\u00e9e, comme la t\u00e9l\u00e9vision, et toutes ces choses auxquelles j\u2019accordais trop d\u2019importance, comme l\u2019opinion que se font les autres de moi. Je devais apprendre \u00e0 me d\u00e9tacher de ces choses. Je sentis tous mes soucis me quitter, comme s\u2019ils quittaient mon corps et mon esprit un \u00e0 un.<\/p>\n<p>Le jour suivant, apr\u00e8s la pri\u00e8re du Fajr, je d\u00e9cidai de faire mes du\u2019a de la m\u00eame fa\u00e7on que j\u2019avais vu les autres faire, c\u2019est-\u00e0-dire en tournant mes paumes vers le ciel. Je priai Dieu de m\u2019aider \u00e0 me d\u00e9tacher des choses insignifiantes et de faire de moi une meilleure personne. Je sentis une paix et un bien-\u00eatre tels descendre en moi que je bougeai le moins possible de crainte qu\u2019ils me quittent.<\/p>\n<p>Ce jour-l\u00e0, au travail, je re\u00e7us la visite d\u2019un coll\u00e8gue du d\u00e9partement informatique : Anwar. Je ne l\u2019avais jamais rencontr\u00e9, mais il avait entendu parler de moi. Il me parla de la mosqu\u00e9e Rajhi et me dit qu\u2019on y donnait des cours en anglais le vendredi. Je d\u00e9cidai donc d\u2019y aller d\u00e8s le vendredi suivant. Cette semaine-l\u00e0, je n\u2019allumai m\u00eame pas la t\u00e9l\u00e9, je jouai au tennis et je demandai \u00e0 l\u2019un de nos chauffeurs, auquel je faisait confiance, de me conduire \u00e0 cette mosqu\u00e9e.<\/p>\n<p>Le vendredi matin, je me sentais tr\u00e8s nerveuse et \u00e0 la derni\u00e8re minute, j\u2019h\u00e9sitai \u00e0 m\u2019y rendre. Et si on se perdait et que je me rendais \u00e0 la mauvaise mosqu\u00e9e? Et si je faisais tout de travers? Mais comme j\u2019allais enfin sortir de chez moi, je priai Dieu de me guider et de m\u2019accorder l\u2019issue la plus favorable. Et Il r\u00e9pondit \u00e0 ma pri\u00e8re. Je fis la rencontre des Samir, une famille sri-lankaise venue vivre et travailler en Arabie Saoudite. Ce fut comme une nouvelle famille, pour moi; ils m\u2019invit\u00e8rent chez eux et me trait\u00e8rent comme l\u2019une de leurs. Que Dieu les b\u00e9nisse et les r\u00e9tribue. Je Le remercie chaque jour de les avoir choisis pour moi et de les avoir mis sur ma route.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/lynda-fitzgerald-ex-catholique-irlande<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 4) Introduction Lynda Fitzgerald, qui s\u2019appelle maintenant Khadija, est une Irlandaise native de la ville de Wicklow, pr\u00e8s de Dublin. Elle est issue d\u2019une famille catholique tr\u00e8s stricte et elle a huit fr\u00e8res et s\u0153urs. Son p\u00e8re est \u00e9lectricien et sa m\u00e8re demeure au foyer. Lynda est all\u00e9e \u00e0 l\u2019\u00e9cole \u00e0 Wicklow &#8230; <a title=\"Lynda Fitzgerald, ex-catholique, Irlande\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/lynda-fitzgerald-ex-catholique-irlande\/\" aria-label=\"Read more about Lynda Fitzgerald, ex-catholique, Irlande\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7616","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 4) Introduction Lynda Fitzgerald, qui s\u2019appelle maintenant Khadija, est une Irlandaise native de la ville de Wicklow, pr\u00e8s de Dublin. Elle est issue d\u2019une famille catholique tr\u00e8s stricte et elle a huit fr\u00e8res et s\u0153urs. Son p\u00e8re est \u00e9lectricien et sa m\u00e8re demeure au foyer. Lynda est all\u00e9e \u00e0 l\u2019\u00e9cole \u00e0 Wicklow\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1YQ","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7616,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8607,"url":"https:\/\/www.ask-a-muslim.com\/de\/lynda-fitzgerald-ex-katholikin-irland\/","url_meta":{"origin":7616,"position":1},"title":"Lynda Fitzgerald, Ex-Katholikin, Irland","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 4) Einleitung Lynda Fitzgerald, jetzt als Khadija bekannt, ist ein irisches M\u00e4dchen aus einer Stadt namens Wicklow, in der N\u00e4he von Dublin. Sie stammt von einer streng r\u00f6misch-katholischen Familie, die aus neun Kindern bestand. Ihr Vater ist Elektriker und ihre Mutter Hausfrau. Lynda wurde in Wicklow ausgebildet\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7616,"position":2},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7616,"position":3},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8631,"url":"https:\/\/www.ask-a-muslim.com\/de\/aisha-canlas-ex-katholikin-philippinen\/","url_meta":{"origin":7616,"position":4},"title":"Aisha Canlas, Ex-Katholikin, Philippinen","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aisha Canlas. Bevor ich hier nach Riyadh gekommen bin, ins K\u00f6nigreich Saudi Arabien, war ich katholisch gewesen, denn meine Eltern sind auch katholisch. Wir gingen zu verschiedenen Kirchen um zu Gott zu beten, aber durch von Menschenhand hergestellte Bildnisse. W\u00e4hrend dieser Zeit fragte ich mich: \u00b4Ist dies\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8641,"url":"https:\/\/www.ask-a-muslim.com\/de\/emily-ex-christin-neuseeland\/","url_meta":{"origin":7616,"position":5},"title":"Emily, Ex-Christin, Neuseeland","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"In Neuseeland aufgewachsen, wurde ich als Christin erzogen, obwohl meine Eltern nicht \u00fcberm\u00e4\u00dfig religi\u00f6s gewesen sind. Als junges M\u00e4dchen ging ich jede Woche zur Sonntagsschule und mit meiner Gro\u00dfmutter zur Kirche und im Rahmen des Schulunterrichts nahm ich am christlichen Religionsunterricht teil. Als ich \u00e4lter wurde, h\u00f6rte ich damit auf,\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7616"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7616\/revisions"}],"predecessor-version":[{"id":11209,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7616\/revisions\/11209"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}