{"id":7620,"date":"2020-06-17T02:21:21","date_gmt":"2020-06-17T07:21:21","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7620"},"modified":"2020-07-01T07:54:36","modified_gmt":"2020-07-01T12:54:36","slug":"s-e-levine-ex-juive-etats-unis","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/s-e-levine-ex-juive-etats-unis\/","title":{"rendered":"S. E. Levine, ex-juive, \u00c9tats-Unis"},"content":{"rendered":"<h3><strong>(partie 1 de 2)<\/strong><\/h3>\n<p>Mon mari et moi nous \u00e9tions rendus dans une mosqu\u00e9e pour assister \u00e0 une conf\u00e9rence. C\u2019\u00e9tait la premi\u00e8re fois qu\u2019il m\u2019invitait dans une mosqu\u00e9e depuis notre mariage, un an auparavant. Nous avions fait connaissance alors que nous travaillions tous deux en tant qu\u2019intervenants dans un centre de d\u00e9sintoxication.<\/p>\n<p>Nous ne pouvions \u00eatre plus diff\u00e9rents : il est noir et musulman, je suis blanche et juive. Mais nous nous sommes plus mutuellement. Bien qu\u2019il ne m\u2019ait jamais demand\u00e9 de me convertir \u00e0 l\u2019islam avant notre mariage, il me pr\u00eachait l\u2019islam, sans le savoir, par son excellent exemple.<\/p>\n<p>Il poss\u00e9dait une biblioth\u00e8que islamique volumineuse et, comme j\u2019aime beaucoup lire, je lus un grand nombre de ses livres. J\u2019admirais sa modestie, l\u2019observais lorsqu\u2019il accomplissait ses pri\u00e8res. Je savais qu\u2019il se rendait tous les vendredis \u00e0 la pri\u00e8re du joumou\u2019ah et je l\u2019enviais un peu lorsqu\u2019il je\u00fbnait le mois de Ramadan. C\u2019est donc tout naturellement que je me suis mise \u00e0 d\u00e9velopper un int\u00e9r\u00eat pour sa religion.<\/p>\n<p>Ce jour-l\u00e0, donc, lorsque nous arriv\u00e2mes \u00e0 la mosqu\u00e9e, il me montra o\u00f9 se trouvait l\u2019entr\u00e9e pour les femmes et nous nous donn\u00e2mes rendez-vous dans le stationnement apr\u00e8s la fin de la conf\u00e9rence. \u00ab Ok, tu es capable \u00bb, me dis-je \u00e0 moi-m\u00eame, au moment d\u2019entrer dans la mosqu\u00e9e.<\/p>\n<p>\u00c9tant d\u2019un naturel sociable, je n\u2019avais jamais eu de difficult\u00e9 \u00e0 me faire des amies et je m\u2019\u00e9tais toujours sentie \u00e0 l\u2019aise dans un contexte multiculturel. Il n\u2019y avait donc aucune raison pour que cette fois-ci soit diff\u00e9rente et c\u2019est avec une certaine h\u00e2te que je montai les marches int\u00e9rieures de la mosqu\u00e9e.<\/p>\n<p>Mon mari m\u2019avait conseill\u00e9 de porter quelque chose de modeste pour l\u2019occasion. Je portais donc une robe \u00e0 manches longues, confiante que ma tenue serait approuv\u00e9e par les autres musulmanes, dans la mosqu\u00e9e.<\/p>\n<p>Toutefois, lorsque j\u2019arrivai sur le palier et m\u2019engouffrai dans l\u2019ouverture de la porte au-dessus de laquelle il \u00e9tait \u00e9crit \u00ab s\u0153urs \u00bb, je sentis imm\u00e9diatement l\u2019air se figer; je sentis une tension palpable, de la suspicion, de la froideur et de la confusion. Chaque t\u00eate voil\u00e9e pr\u00e9sente se tourna dans ma direction et les femmes me d\u00e9visag\u00e8rent comme si j\u2019\u00e9tais un \u00eatre \u00e0 deux t\u00eates. Je figeai sur place, les d\u00e9visageant \u00e0 mon tour.<\/p>\n<p>Je n\u2019avais jamais vu autant de musulmanes en un seul endroit. La plupart portaient le hijab, mais deux d\u2019entre elles attir\u00e8rent mon attention, car elles portaient un voile qui ne montrait que leurs yeux. Quelques autres \u00e9taient assises avec leur foulard enroul\u00e9 autour des \u00e9paules et lorsqu\u2019elles m\u2019aper\u00e7urent, elles le mirent sur leur t\u00eate.<\/p>\n<p>Puis, l\u2019une d\u2019entre elles se leva et s\u2019approcha de moi. Elle se pr\u00e9senta \u00e0 moi sous le nom de Basimah. Celle-l\u00e0, au moins, avait un air accueillant.<\/p>\n<p>Je lui dis : \u00ab Bonjour, je m\u2019appelle Sharon et je suis venue assister \u00e0 la conf\u00e9rence. \u00bb<\/p>\n<p>\u00ab Y a-t-il quelqu\u2019un d\u2019autre avec toi? \u00bb, me demanda-t-elle.<\/p>\n<p>\u00ab Mon mari est en haut \u00bb, que je lui r\u00e9pondis.<\/p>\n<p>\u00ab Oh! Ton mari est musulman? \u00bb, qu\u2019elle me demanda.<\/p>\n<p>\u00ab Oui, il est musulman \u00bb, que je dis.<\/p>\n<p>Elle r\u00e9pondit : \u00ab Alhamdoulillah, viens par ici et assied-toi avec nous. \u00bb<\/p>\n<p>Elle me guida vers une table \u00e0 laquelle \u00e9taient assises trois autres femmes. Elles \u00e9taient tr\u00e8s belles et faisaient tr\u00e8s exotiques. Apr\u00e8s les pr\u00e9sentations, j\u2019oubliai imm\u00e9diatement leurs noms, car ils sonnaient tr\u00e8s \u00e9trangers \u00e0 mes oreilles. Basimah se leva \u00e0 nouveau pour aller accueillir de nouvelles venues.<\/p>\n<p>\u00ab D\u2019o\u00f9 viens-tu? \u00bb, me demanda l\u2019une des femmes \u00e0 la table. Je lui r\u00e9pondis que j\u2019\u00e9tais une Am\u00e9ricaine d\u2019origine est-europ\u00e9enne, n\u00e9e \u00e0 New York.<\/p>\n<p>\u00ab Et d\u2019o\u00f9 vient ton mari? \u00bb, me demanda-t-on ensuite.<\/p>\n<p>\u00ab Des \u00c9tats-Unis. \u00bb<\/p>\n<p>\u00ab Oui, mais d\u2019o\u00f9? \u00bb<\/p>\n<p>\u00ab De Philadelphie. \u00bb<\/p>\n<p>\u00ab Non, je veux dire dans quel pays est-il n\u00e9? \u00bb<\/p>\n<p>\u00ab Il est Am\u00e9ricain, n\u00e9 aux \u00c9tats-Unis. Il est Afro-Am\u00e9ricain, plus pr\u00e9cis\u00e9ment, de Philadelphie. \u00bb Je commen\u00e7ais \u00e0 croire que la barri\u00e8re de la langue nous emp\u00eachait de nous comprendre. Mais j\u2019appris plus tard que la majorit\u00e9 des femmes converties, dans la mosqu\u00e9e, \u00e9taient mari\u00e9es \u00e0 des hommes d\u2019origine arabe.<\/p>\n<p>\u00ab Hmmm \u00bb, dirent-elles alors toutes \u00e0 l\u2019unisson, baissant le regard.<\/p>\n<p>\u00ab Songes-tu \u00e0 devenir musulmane? \u00bb, me demanda l\u2019une d\u2019elles en me regardant d\u2019un air rempli d\u2019espoir.<\/p>\n<p>\u00ab Non \u00bb, r\u00e9pondis-je, \u00ab je suis juive \u00bb. Vous auriez d\u00fb voir l\u2019expression sur leurs visages. D\u00e8s qu\u2019elles le purent, elles chang\u00e8rent rapidement de sujet.<\/p>\n<p>\u00ab Vos enfants sont-ils musulmans? \u00bb, me demanda une autre, reprenant le sujet.<\/p>\n<p>\u00ab Je n\u2019ai pas d\u2019enfants. \u00bb, dis-je. Puis, ce fut tout. Leur tentative de trouver des points communs sur lesquels discuter avec moi avait \u00e9chou\u00e9. Elles sourirent timidement. Puis, il se passa une chose incroyable, \u00e0 laquelle je ne me serais jamais attendue; la conversation se poursuivit entre elles seulement et\u2026 en arabe.<\/p>\n<p>Je demeurai assise \u00e0 ma place; je n\u2019avais aucun autre endroit o\u00f9 aller. Et elles continu\u00e8rent de discuter entre elles, dans leur langue. Au fur et \u00e0 mesure que d\u2019autres femmes venaient se joindre \u00e0 nous, elles me pr\u00e9sentaient en anglais en disant : \u00ab Elle s\u2019appelle Sharon. Elle est juive. \u00bb Puis, elles recommen\u00e7aient \u00e0 discuter entre elles en arabe.<\/p>\n<p>Quand la conf\u00e9rence fut sur le point de commencer, les femmes se d\u00e9plac\u00e8rent vers la salle de pri\u00e8re et toutes s\u2019install\u00e8rent par terre, sur le sol recouvert de tapis. Mais, apr\u00e8s cinq minutes, les femmes recommenc\u00e8rent \u00e0 discuter les unes avec les autres, enterrant la voix du conf\u00e9rencier qui nous parvenait d\u2019un haut-parleur.<\/p>\n<h3><\/h3>\n<h3><strong>(partie 2de 2)<\/strong><\/h3>\n<p>Apr\u00e8s la conf\u00e9rence, des femmes se rendirent \u00e0 la cuisine pour pr\u00e9parer des choses \u00e0 manger. Basimah me dit de m\u2019installer confortablement jusqu\u2019\u00e0 ce que la nourriture soit apport\u00e9e.<br \/>\nJe lui offris de l\u2019aider, mais elle me dit : \u00ab Non, tu es notre invit\u00e9e. Des s\u0153urs am\u00e9ricaines converties viennent d\u2019arriver, je vais te les pr\u00e9senter. \u00bb<\/p>\n<p>Basimah fit signe \u00e0 une femme assise \u00e0 l\u2019autre bout de la pi\u00e8ce. Elle vint vers nous et les deux se firent la bise, tout en se saluant en arabe. Puis, elles se tourn\u00e8rent vers moi et Basimah dit \u00e0 l\u2019autre femme :<br \/>\n\u00ab Voici Sharon. Elle est juive. Tu veux bien lui tenir compagnie jusqu\u2019\u00e0 ce qu\u2019on mange? \u00bb<\/p>\n<p>\u00ab Bien s\u00fbr \u00bb, r\u00e9pondit-elle. \u00ab Bonjour, Sharon, je m\u2019appelle Arwa. \u00bb<br \/>\nElle et moi nous install\u00e2mes et f\u00eemes connaissance. Je lui posai des questions sur sa conversion, sur son statut matrimonial, etc. Puis, elle largua la bombe :<\/p>\n<p>\u00ab Pourquoi avez-vous tu\u00e9 J\u00e9sus? \u00bb, me demanda-t-elle.<\/p>\n<p>\u00ab Pardon? \u00bb Nul doute que mon visage refl\u00e9tait ma profonde stup\u00e9faction.<br \/>\nCherchant \u00e0 se reprendre, elle reformula : \u00ab Je veux dire, pourquoi les juifs ont-ils tu\u00e9 J\u00e9sus? \u00bb<\/p>\n<p>Je n\u2019arrivais tout simplement pas \u00e0 croire ce que j\u2019entendais. J\u2019\u00e9tais \u00e0 la fois stup\u00e9faite et irrit\u00e9e par sa question. Mais son regard innocent me fit douter de son intention malveillante. Peut-\u00eatre n\u2019avait-elle jamais rencontr\u00e9 de juive auparavant et qu\u2019elle profitait de cette premi\u00e8re occasion de poser une question qui lui br\u00fblait les l\u00e8vres. Lorsqu\u2019on m\u2019avait pr\u00e9sent\u00e9e \u00e0 elle, j\u2019\u00e9tais heureuse de rencontrer une Am\u00e9ricaine convertie. Mais \u00e0 ce moment pr\u00e9cis, je n\u2019avais envie que d\u2019une chose, soit de me lever et d\u2019aller m\u2019asseoir \u00e0 une autre table. Puis, au fond de moi, la col\u00e8re prit le dessus.<\/p>\n<p>Lui jetant un regard sinistre, je lui r\u00e9pondis, les dents serr\u00e9es : \u00ab Nous n\u2019avons pas tu\u00e9 J\u00e9sus. Ce sont les Romains qui l\u2019ont tu\u00e9! \u00bb. Elle me d\u00e9visagea comme un animal bless\u00e9. Elle ouvrit la bouche pour dire quelque chose, mais avant qu\u2019elle ne puisse prononcer quoi que ce soit, quelqu\u2019un l\u2019appela.<\/p>\n<p>\u00ab Excuse-moi \u00bb, me dit-elle, \u00ab je reviens \u00bb. Je pus sentir le soulagement dans sa voix.<\/p>\n<p>Un groupe de s\u0153urs afro-am\u00e9ricaines arriv\u00e8rent alors et je passai le reste de la soir\u00e9e en leur compagnie. Avant de quitter pour aller rejoindre mon mari, Basimah me laissa son num\u00e9ro de t\u00e9l\u00e9phone et m\u2019invita \u00e0 l\u2019appeler pour organiser une rencontre chez elle.<\/p>\n<p>Je l\u2019appelai peu de temps apr\u00e8s et nous d\u00e9velopp\u00e2mes une belle relation. Elle me parla beaucoup de Dieu et d\u2019islam et c\u2019est d\u2019elle que j\u2019appris que personne n\u2019avait tu\u00e9 J\u00e9sus, mais que Dieu l\u2019avait \u00e9lev\u00e9 vers Lui!<\/p>\n<p>Elle savait que je m\u2019int\u00e9ressais \u00e0 l\u2019islam et elle percevait, en moi, cette qu\u00eate de sens et de paix spirituelle. Un soir, alors que mon mari et moi \u00e9tions chez elle, elle finit par m\u2019inviter ouvertement \u00e0 embrasser l\u2019islam.<\/p>\n<p>Elle m\u2019expliqua que tous mes p\u00e9ch\u00e9s seraient pardonn\u00e9s \u00e0 la minute o\u00f9 je deviendrais musulmane et que je serais comme un nouveau-n\u00e9, sans p\u00e9ch\u00e9s \u00e0 mon actif. J\u2019en fus si \u00e9mue que je me mis \u00e0 pleurer. Je voulais cette seconde chance de renouer avec Dieu. J\u2019avais eu un pass\u00e9 tr\u00e8s mouvement\u00e9. J\u2019avais toujours aim\u00e9 Dieu, mais je m\u2019\u00e9tais \u00e9gar\u00e9e. Le mari de Basimah vint me voir pour m\u2019aider \u00e0 r\u00e9p\u00e9ter la shahadah (profession de foi).<\/p>\n<p>Lorsque je dis \u00e0 mon mari que je m\u2019appr\u00eatais \u00e0 prononcer la shahadah, il fut \u00e0 la fois fort \u00e9tonn\u00e9 et heureux. Il me demanda si j\u2019\u00e9tais bien certaine, comme s\u2019il n\u2019arrivait pas \u00e0 le croire. Je lui dis que, de ma vie, je n\u2019avais jamais \u00e9t\u00e9 aussi certaine d\u2019une chose. En effet, aucune bataille int\u00e9rieure ne se livrait, en moi, et je n\u2019\u00e9prouvais ni crainte ni doutes.<\/p>\n<p>Apr\u00e8s que j\u2019eus prononc\u00e9 la shahadah, le mari de Basimah dit : \u00ab Mabrook (f\u00e9licitations)! Tu es maintenant musulmane! \u00bb<br \/>\nLorsque nous rev\u00eenmes \u00e0 la maison, mon mari m\u2019offrit un Coran et une version abr\u00e9g\u00e9e de Sahih al-Boukhari. Et, avant que je ne quitte la maison de Basimah, elle me donna un livret sur la modestie de la femme musulmane, un tapis de pri\u00e8re, une robe de pri\u00e8re et un hijab (foulard).<\/p>\n<p>Alhamdoulillah, je porte le hijab depuis ce jour et je ne l\u2019ai jamais enlev\u00e9, pas m\u00eame apr\u00e8s les terribles \u00e9v\u00e9nements du 11 septembre 2001.<br \/>\nLorsque je devins musulmane, en juillet de l\u2019ann\u00e9e 1998, mon p\u00e8re me renia sur-le-champ. Il \u00e9tait d\u00e9j\u00e0 en col\u00e8re contre moi pour avoir \u00e9pous\u00e9 un musulman et refusait de reconna\u00eetre mon mari comme son gendre.<\/p>\n<p>\u00ab Mais, Sharon, ces gens nous ha\u00efssent! \u00bb, s\u2019\u00e9tait-il \u00e9cri\u00e9, en apprenant la nouvelle de mon mariage.<\/p>\n<p>Tous mes efforts pour lui expliquer la diff\u00e9rence entre l\u2019islam comme tel et le conflit politique entre Palestiniens et Isra\u00e9liens furent vains. Pourtant, il avait lui-m\u00eame \u00e9t\u00e9 le premier, dans sa famille, \u00e0 \u00e9pouser une non-juive (ma m\u00e8re \u00e9tait catholique pratiquante).<\/p>\n<p>Pire encore, aux yeux de mon p\u00e8re, \u00e9tait le fait que mon mari soit, en plus d\u2019\u00eatre musulman, afro-am\u00e9ricain. Avant le 11 septembre 2001, la plupart des Am\u00e9ricains faisaient un lien avec Malcolm X lorsqu\u2019on leur parlait d\u2019islam. Plusieurs autres membres de ma famille me firent part de leur d\u00e9ception et de leur frustration devant ma d\u00e9cision d\u2019\u00e9pouser un \u00ab musulman noir \u00bb.<\/p>\n<p>Mon p\u00e8re mourut en ao\u00fbt 2001, un mois avant les \u00e9v\u00e9nements de septembre. \u00c0 la demande de la seconde \u00e9pouse de mon p\u00e8re, ma famille ne m\u2019informa de son d\u00e9c\u00e8s qu\u2019apr\u00e8s ses fun\u00e9railles. Craignaient-ils donc que je me pr\u00e9sente \u00e0 la synagogue v\u00eatue en musulmane et accompagn\u00e9e de mon mari noir?<\/p>\n<p>L\u2019islam est une religion qui s\u2019adresse \u00e0 toute l\u2019humanit\u00e9, sans limite dans l\u2019espace ni dans le temps. Le fait qu\u2019un musulman vienne d\u2019\u00c9gypte, du Pakistan, des \u00c9tats-Unis, de l\u2019Arabie, de l\u2019Indon\u00e9sie ou de la Palestine ne devrait avoir aucune importance, tout comme la couleur de sa peau ou la langue qu\u2019il parle. Notre diversit\u00e9 culturelle ne devrait pas nous diviser, mais nous unir. Dieu dit, dans le Coran :<br \/>\n\u00ab Nous avons fait de vous des nations et des tribus, afin que vous fassiez connaissance entre vous. \u00bb (Coran 49:13)<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/s-e-levine-ex-juive-tats-unis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) Mon mari et moi nous \u00e9tions rendus dans une mosqu\u00e9e pour assister \u00e0 une conf\u00e9rence. C\u2019\u00e9tait la premi\u00e8re fois qu\u2019il m\u2019invitait dans une mosqu\u00e9e depuis notre mariage, un an auparavant. Nous avions fait connaissance alors que nous travaillions tous deux en tant qu\u2019intervenants dans un centre de d\u00e9sintoxication. Nous ne pouvions &#8230; <a title=\"S. E. Levine, ex-juive, \u00c9tats-Unis\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/s-e-levine-ex-juive-etats-unis\/\" aria-label=\"Read more about S. E. Levine, ex-juive, \u00c9tats-Unis\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7620","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":4,"uagb_excerpt":"(partie 1 de 2) Mon mari et moi nous \u00e9tions rendus dans une mosqu\u00e9e pour assister \u00e0 une conf\u00e9rence. C\u2019\u00e9tait la premi\u00e8re fois qu\u2019il m\u2019invitait dans une mosqu\u00e9e depuis notre mariage, un an auparavant. Nous avions fait connaissance alors que nous travaillions tous deux en tant qu\u2019intervenants dans un centre de d\u00e9sintoxication. Nous ne pouvions\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1YU","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7620,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8688,"url":"https:\/\/www.ask-a-muslim.com\/de\/respirationsapparat-ist-ausser-betrieb-in-hochluftschichten\/","url_meta":{"origin":7620,"position":1},"title":"RESPIRATIONSAPPARAT IST AUSSER BETRIEB IN HOCHLUFTSCHICHTEN","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den Islam. Und wen Er irref\u00fchren will, dem macht Er die Brust beklommen und bedr\u00fcckt, so als ob er in den Himmel hoch steigen w\u00fcrde Allah, der Erhabene sagt: \"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8590,"url":"https:\/\/www.ask-a-muslim.com\/de\/jonathan-abdilla-ex-christ-canada\/","url_meta":{"origin":7620,"position":2},"title":"Jonathan Abdilla, Ex-Christ, Canada","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich f\u00fchle mich geehrt, ein Muslim zu sein\u2026Und so f\u00fchle ich mich aus verschiedenen Gr\u00fcnden. Es gibt viele Normen in der Gesellschaft, in der ich lebe, die genau das Gegenteil dessen sind, wie Muslime es tun. Und als ich zuerst zu dieser Lebensweise kam, wusste ich nicht so genau wie\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8643,"url":"https:\/\/www.ask-a-muslim.com\/de\/latasha-ex-christin-usa\/","url_meta":{"origin":7620,"position":3},"title":"Latasha, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin Amerikanerin, die in einer streng religi\u00f6sen christlichen Familie aufgewachsen ist. W\u00e4hrend der Zeit, als ich 16 wurde, wurde ich selbst sehr fromm und religi\u00f6s. Die Kirche war wie ein Heim weit entfernt von zuhause. Ich genoss sie von Grund auf. Ich hatte die Bibel regelm\u00e4\u00dfig gelesen und studiert.\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8616,"url":"https:\/\/www.ask-a-muslim.com\/de\/diana-ex-mormone-usa\/","url_meta":{"origin":7620,"position":4},"title":"Diana, Ex-Mormone, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin als in einem gem\u00e4\u00dfigten christlichen Heim in Colorado aufgewachsen. Religion war bei uns zuhause nie ein Thema gewesen. Mein Vater war Mormone, meine Mutter Protestantin. Als ich gr\u00f6\u00dfer wurde, fragte ich mich neugierig \u00fcber Gott, ob Er existiert und wenn, was dies f\u00fcr die Menschen bedeutete. Ich studierte\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8650,"url":"https:\/\/www.ask-a-muslim.com\/de\/angelene-mclaren-ex-katholikin-usa\/","url_meta":{"origin":7620,"position":5},"title":"Angelene McLaren, Ex-Katholikin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Schon immer seit ich ein kleines M\u00e4dchen gewesen bin, habe ich eine tiefgr\u00fcndige Beziehung zu Gott gehabt. Obwohl ich als Katholikin erzogen worden bin, trotz all den Unklarheiten, Widerspr\u00fcchen und Verwirrungen, tat ich mein Bestes, um Gott-bezogen zu bleiben und nicht den Lehren der Kirche nachzugeben, denn selbst f\u00fcr mich\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7620"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7620\/revisions"}],"predecessor-version":[{"id":11201,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7620\/revisions\/11201"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}