{"id":7646,"date":"2020-06-17T02:21:23","date_gmt":"2020-06-17T07:21:23","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7646"},"modified":"2020-07-02T06:48:00","modified_gmt":"2020-07-02T11:48:00","slug":"valerie-wright-ex-chretienne-etats-unis","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/valerie-wright-ex-chretienne-etats-unis\/","title":{"rendered":"Valerie Wright, ex-chr\u00e9tienne, \u00c9tats-Unis"},"content":{"rendered":"<h3><strong>(partie 1 de 2)<\/strong><\/h3>\n<p>Je dirais que mon cheminement vers l\u2019islam a d\u00e9but\u00e9 avant m\u00eame que j\u2019en aie conscience. Je suis n\u00e9e avec un probl\u00e8me de perte d\u2019audition progressive. Ma m\u00e8re n\u2019a pas r\u00e9alis\u00e9 que j\u2019avais un probl\u00e8me d\u2019audition avant que je n\u2019aie l\u2019\u00e2ge de quatre ans. Une fois diagnostiqu\u00e9e, je re\u00e7us mes premi\u00e8res proth\u00e8ses auditives et fus inscrite dans une \u00e9cole pour enfants sourds et malentendants.<\/p>\n<p>Au d\u00e9but, on me mit dans une classe qui n\u2019\u00e9tait occup\u00e9e que par des enfants sourds. Puis, on me transf\u00e9ra dans une classe avec d\u2019autres enfants malentendants, o\u00f9 je me sentis plus \u00e0 l\u2019aise, avec des gens comme moi. Je ne savais pas, \u00e0 ce moment-l\u00e0, que l\u2019on me pr\u00e9parait \u00e0 quitter cette \u00e9cole pour int\u00e9grer une \u00e9cole ordinaire.<\/p>\n<p>Une fois \u00e0 l\u2019\u00e9cole publique, j\u2019eus beaucoup de difficult\u00e9 \u00e0 m\u2019adapter. Les d\u00e9m\u00e9nagements fr\u00e9quents de mes parents exacerb\u00e8rent le probl\u00e8me d\u2019adaptation, car je changeais constamment d\u2019\u00e9cole. Ce n\u2019est qu\u2019\u00e0 l\u2019\u00e9cole secondaire que je connus enfin un peu de stabilit\u00e9. Je vivais dans une toute petite ville du Texas appel\u00e9e Wylie. \u00c0 l\u2019\u00e2ge de 12 ans, j\u2019eus une enseignante d\u2019anglais un peu sp\u00e9ciale; elle \u00e9tait originaire de Turquie. Quiconque conna\u00eet Wylie sait qu\u2019\u00e0 cette \u00e9poque, il s\u2019agissait de quelque chose de tr\u00e8s inhabituel.<\/p>\n<p>Cette enseignante s\u2019\u00e9tait retrouv\u00e9e dans notre petite ville gr\u00e2ce \u00e0 un programme d\u2019\u00e9change entre professeurs. \u00c9videmment, elle ne parla jamais de religion devant la classe. Elle nous proposa un projet d\u2019\u00e9changes \u00e9pistolaires avec des \u00e9tudiants turcs. Le nom de ma correspondante \u00e9tait Yasemin. Je poss\u00e8de encore une carte qu\u2019elle m\u2019avait envoy\u00e9e, avec une photo sur laquelle il y avait des mosqu\u00e9es et des \u00e9glises c\u00f4te-\u00e0-c\u00f4te. Je n\u2019y vis, \u00e0 l\u2019\u00e9poque, aucune signification particuli\u00e8re, mais je compris, plus tard, qu\u2019il s\u2019agissait de l\u2019un des nombreux signes que Dieu avait d\u00e9cid\u00e9 de mettre sur ma voie.<\/p>\n<p>Durant cette p\u00e9riode de ma vie, je souhaitais ardemment me rapprocher de Dieu, Lui plaire et recevoir Son amour. Je devins tr\u00e8s impliqu\u00e9e au sein de l\u2019\u00e9glise que fr\u00e9quentait mon grand-p\u00e8re. Sa famille et lui \u00e9taient pentec\u00f4tistes et son p\u00e8re et son fr\u00e8re \u00e9taient tous deux pr\u00e9dicateurs.<\/p>\n<p>Chaque apr\u00e8s-midi, en rentrant de l\u2019\u00e9cole, je jouais du piano. Je jouais pour Dieu et aussi pour moi, pour le sentiment de paix que cela m\u2019apportait. On m\u2019avait appris que les louanges \u00e0 Dieu montaient au ciel comme la fum\u00e9e de l\u2019encens. C\u2019est cette image que j\u2019avais \u00e0 l\u2019esprit lorsque je jouais. Parfois, je chantais quelques paroles tout en jouant, mais la plupart du temps, la musique \u00e0 elle seule suffisait \u00e0 exprimer mes sentiments profonds.<\/p>\n<p>Un jour, je sentis la pr\u00e9sence de Dieu, dans la pi\u00e8ce o\u00f9 je me trouvais. C\u2019\u00e9tait \u00e0 la fois immense et \u00e9crasant. L\u2019atmosph\u00e8re devint extr\u00eamement alourdie par la majest\u00e9 de Son \u00catre. Je cessai de chanter et mes doigts se fig\u00e8rent sur les touches du piano. Je me mis \u00e0 trembler, je ne savais trop que faire. Puis, tout doucement, par instinct, je m\u2019\u00e9loignai du piano et j\u2019allai me prosterner, front contre terre.<\/p>\n<p>Tremblante et sans mots, je pensai : \u00ab Dieu, je T\u2019en prie, b\u00e9nis-moi. Fais de moi quelqu\u2019un de sp\u00e9cial. Fais en sorte que je sois \u00e0 Ton service. \u00bb Je demeurai prostern\u00e9e quelques minutes puis, prenant une profonde inspiration, je me relevai et retournai \u00e0 mes activit\u00e9s.<\/p>\n<p>Une autre fois, au cours de la m\u00eame p\u00e9riode de ma vie, j\u2019\u00e9tais \u00e0 l\u2019\u00e9cole, o\u00f9 les parents et les \u00e9l\u00e8ves \u00e9taient rassembl\u00e9s pour une remise de m\u00e9ritas. On appela mon nom et je me rendis \u00e0 l\u2019avant afin d\u2019y recevoir mon prix. Plus tard, ma m\u00e8re me raconta une chose \u00e9trange qui s\u2019\u00e9tait produite \u00e0 ce moment-l\u00e0. Elle me dit : \u00ab Alors que tu marchais vers l\u2019avant pour aller chercher ton prix, une femme \u00e9trange, que je ne connais pas, s\u2019est approch\u00e9e de moi et m\u2019a dit : \u00ab Je regarde votre fille et je ne peux m\u2019emp\u00eacher de penser que Dieu projette quelque chose de sp\u00e9cial pour elle. \u00bb Je me demandai ce que pouvait bien \u00eatre ce plan qu\u2019Il avait pour moi.<\/p>\n<p>Les nombreuses restrictions de l\u2019\u00e9glise pentec\u00f4tiste me submergeaient, surtout parce que je ne comprenais pas leur raison d\u2019\u00eatre. J\u2019\u00e9tais aussi tr\u00e8s perturb\u00e9e par certaines choses que je lisais dans la Bible et quand je posais des questions \u00e0 leur sujet, je n\u2019obtenais jamais de r\u00e9ponses claires. En fait, il \u00e9tait \u00e9vident que l\u2019on d\u00e9sapprouvait mes questions. Alors ma m\u00e8re et moi change\u00e2mes d\u2019\u00e9glise.<\/p>\n<p>Je me souviens, une fois, avoir demand\u00e9 une rencontre priv\u00e9e avec un pr\u00e9dicateur pour discuter d\u2019un sujet qui me tracassait. Une des questions que je lui posai \u00e9tait : \u00ab Est-ce que j\u2019irai au Paradis? \u00bb Il me dit : \u00ab Crois-tu en J\u00e9sus? \u00bb J\u2019h\u00e9sitai, puis je r\u00e9pondis par l\u2019affirmative. Il me dit : \u00ab Alors tu iras au Paradis. \u00bb Tout au fond de moi, je n\u2019\u00e9tais pas satisfaite par sa r\u00e9ponse. J\u2019avais des doutes. L\u2019\u00e9t\u00e9 arriva et je partis pour le camp estival affili\u00e9 \u00e0 notre \u00e9glise, o\u00f9 deux \u00e9v\u00e9nements importants se produisirent.<\/p>\n<p>D\u2019abord, le pr\u00e9dicateur qui nous avait rassembl\u00e9s pour nous parler, \u00e0 nous les jeunes, demanda \u00e0 tous ceux qui souhaitaient qu\u2019il prie pour eux de venir \u00e0 l\u2019avant. Il dit : \u00ab Si vous sentez une quelconque barri\u00e8re entre Dieu et vous et que vous souhaitez que je prie pour vous afin que tombe cette barri\u00e8re et que vous soyez plus proche de Dieu, venez vers moi. \u00bb Plusieurs jeunes se pr\u00e9cipit\u00e8rent vers l\u2019avant, moi y compris. Nous \u00e9tions debout et il commen\u00e7a \u00e0 mettre sa main sur le front de chaque personne, tout en pronon\u00e7ant une invocation. C\u2019est l\u00e0 que quelque chose d\u2019\u00e9trange se produisit : ces jeunes tomb\u00e8rent tous sur le dos, un \u00e0 un, comme des dominos, suite au toucher du pr\u00e9dicateur. Je commen\u00e7ai \u00e0 me sentir nerveuse, ne comprenant pas ce qui se passait.<\/p>\n<p>Le pr\u00e9dicateur arriva \u00e0 ma hauteur. Il appuya fortement sa main sur mon front et, dans ce mouvement, me poussa un peu vers l\u2019arri\u00e8re. Mais je tins bon sur mes pieds et je restai debout, tandis qu\u2019il passait au suivant et le faisait tomber \u00e0 son tour. \u00c0 la fin, nous n\u2019\u00e9tions qu\u2019une poign\u00e9e encore debout. Je me demandai ce qui \u00e9tait arriv\u00e9, au juste, \u00e0 tous ceux qui \u00e9taient tomb\u00e9s et pourquoi quelques-uns d\u2019entre nous \u00e9taient rest\u00e9 debout.<\/p>\n<p>L\u2019autre exp\u00e9rience \u00e9trange se produisit alors qu\u2019un autre pr\u00e9dicateur pronon\u00e7ait un sermon tr\u00e8s \u00e9motif devant des centaines d\u2019entre nous. Tout \u00e0 coup, sans crier gare, il me regarda directement et dit : \u00ab Valerie, l\u00e8ve-toi. \u00bb Je me levai et il poursuivit : \u00ab Je veux que tu saches que Dieu souhaite gu\u00e9rir tes oreilles. \u00bb Il se croyait anim\u00e9 du Saint-Esprit, rien de moins.<\/p>\n<p>Il mit ses mains sur mes oreilles et pria. Mais rien ne se produisit. Je me sentis tr\u00e8s embarrass\u00e9e. Le dimanche suivant, un des \u00e9tudiants de ma classe lui demanda pourquoi, puisque tout est possible lorsque demand\u00e9 au nom du Christ, certaines pri\u00e8res ne sont pas exauc\u00e9es. Le pr\u00e9dicateur ne me regarda pas directement, mais il lan\u00e7a un crayon dans ma direction. Puis il r\u00e9pondit : \u00ab Dieu r\u00e9pond aux pri\u00e8res, mais parfois, les gens n\u2019ont pas assez de foi pour recevoir cette r\u00e9ponse. \u00bb Lorsque ma m\u00e8re fut mise au courant, elle fut tr\u00e8s contrari\u00e9e et nous d\u00e9cid\u00e2mes de quitter cette \u00e9glise.<\/p>\n<p>Pendant un certain temps, je passai d\u2019une \u00e9glise \u00e0 une autre sans vraiment en fr\u00e9quenter une sur une base r\u00e9guli\u00e8re. Je me sentais perdue. J\u2019\u00e9prouvais un sentiment d\u2019\u00e9chec et je ne savais plus quelle direction emprunter. Et un sentiment ind\u00e9finissable me saisissait en permanence.<\/p>\n<h3><\/h3>\n<h3><strong>(partie 2 de 2)<\/strong><\/h3>\n<p>\u00c0 l\u2019\u00e2ge de 15 ans, je partis vivre avec mon p\u00e8re. Je demeurai avec lui deux ans et demi, au cours desquels je fr\u00e9quentai r\u00e9guli\u00e8rement une \u00e9glise m\u00e9thodiste. Il m\u2019arrivait aussi, \u00e0 l\u2019occasion, d\u2019aller \u00e0 l\u2019\u00e9glise baptiste que fr\u00e9quentait ma belle-m\u00e8re. Mais dans chaque \u00e9glise que je visitais, je sentais qu\u2019il manquait quelque chose. Et m\u00eame si tous les fid\u00e8les se montraient aimables et accueillants envers moi, je sentais toujours que je ne faisais pas vraiment partie de leur groupe, surtout avec ceux de mon \u00e2ge. Malgr\u00e9 tout, je ne pensai jamais, \u00e0 ce moment-l\u00e0, \u00e0 chercher une autre religion.<\/p>\n<p>Une nuit, \u00e0 l\u2019\u00e2ge de 17 ans, je fis un r\u00eave \u00e9trange. J\u2019\u00e9tais debout pr\u00e8s d\u2019un buisson \u00e0 petites feuilles et \u00e0 petites fleurs jaunes. J\u2019entendis le bruissement d\u2019un ange qui passait pr\u00e8s de moi, mais je ne pouvais voir l\u2019ange en question, \u00e0 l\u2019exception d\u2019un d\u00e9coupage lumineux repr\u00e9sentant sa forme. Il fit une cueillette parmi les petites fleurs jaunes du buisson, en fit un bouquet et me le tendit. Les fleurs scintillaient. Puis, l\u2019ange me souleva et me transporta jusqu\u2019\u00e0 un endroit sp\u00e9cial. Parce que je ne pouvais voir l\u2019ange qui me transportait, je voyais tout, autour de nous, tandis que nous volions dans les airs.<\/p>\n<p>Je me retrouvai dans un endroit ensoleill\u00e9, mais le soleil \u00e9tait comme filtr\u00e9 \u00e0 travers une bruine l\u00e9g\u00e8re. Je vis des herbes hautes et des arbres avec de larges feuilles de marronnier. Au fur et \u00e0 mesure que nous avancions, l\u2019herbe devenait plus courte et des arbres apparaissaient, portant des fleurs aux couleurs tr\u00e8s vives, rouges, roses et blanches, avec un point noir en leur centre. Les fleurs \u00e9taient abondantes; elles recouvraient les branches et les troncs, et m\u00eame le sol, \u00e0 la base des arbres. Les arbres suivants \u00e9taient de la famille des conif\u00e8res.<\/p>\n<p>Je me retournai et regardai dans toutes les directions et je vis, au loin, \u00e0 ma droite, un grand rectangle de terre cultiv\u00e9e. Il me semblait, de cette distance, que des plantes tr\u00e8s hautes y poussaient. Je vis \u00e9galement un rectangle plus petit, recouvert d\u2019iris pourpres. Tout pr\u00e8s, une maison de bois. L\u2019ange me fit marcher autour de cette maison une fois et je constatai qu\u2019elle \u00e9tait parfaitement carr\u00e9e. L\u2019ange me d\u00e9posa et nous p\u00e9n\u00e9tr\u00e2mes \u00e0 l\u2019int\u00e9rieur.<\/p>\n<p>Dans la maison se trouvaient plusieurs adultes et enfants, qui semblaient tous tr\u00e8s heureux. En nous voyant entrer, ils s\u2019\u00e9loign\u00e8rent. Devant nous, un hall avec deux sofas et une petite table japonaise entre eux. Sur l\u2019un d\u2019eux, une vieille dame aux cheveux blancs ramass\u00e9s en chignon et une grande robe noire avec un col de dentelle blanche. Elle me fit signe de m\u2019asseoir et me demanda si je voulais quelque chose \u00e0 boire. Apr\u00e8s que je me fus install\u00e9e, elle se mit \u00e0 me parler et me r\u00e9v\u00e9la certaines choses au sujet de mon avenir (je ne me souviens d\u2019aucune d\u2019elles).<\/p>\n<p>Elle conclut en disant : \u00ab Mais tu dois apporter certains changements \u00e0 ta vie, auparavant. \u00bb \u00c0 ces mots, je sentis une crainte m\u2019\u00e9trangler, car je ne savais pas si je serais assez forte pour apporter ces changements n\u00e9cessaires dans ma vie. Je me tournai vers l\u2019ange et lui dit : \u00ab Je ne sais pas si j\u2019y arriverai. \u00bb Alors il me prit et me lan\u00e7a dans les airs; c\u2019est alors que mon r\u00eave prit fin.<\/p>\n<p>Vers la fin de l\u2019ann\u00e9e scolaire, j\u2019assistai \u00e0 une f\u00eate d\u2019adieu organis\u00e9e pour une amie qui \u00e9tait venue parmi nous dans le cadre d\u2019un projet d\u2019\u00e9change d\u2019\u00e9tudiants. La m\u00e8re d\u2019une des filles pr\u00e9sentes s\u2019approcha de moi; je connaissais sa fille, mais elle, je ne l\u2019avais jamais vue auparavant. Elle me dit : \u00ab Quand ma fille me parle de toi, je ressens une sorte de bonheur, au fond de mon c\u0153ur. \u00bb<\/p>\n<p>Quelques mois s\u2019\u00e9coul\u00e8rent et j\u2019\u00e9tais sur le point d\u2019obtenir mon dipl\u00f4me d\u2019\u00e9tudes secondaires. C\u2019est alors que je fis la rencontre de musulmans avec lesquels je devins amie. Ils ne pratiquaient pas vraiment leur religion, mais j\u2019aimais leur fa\u00e7on de se comporter les uns avec les autres. Il semblait y avoir, entre eux, un lien plus fort que celui de la simple amiti\u00e9. Ils parlaient arabe, entre eux, et je souhaitais r\u00e9ellement comprendre ce qu\u2019ils disaient. Alors je me mis \u00e0 la recherche d\u2019un cours d\u2019arabe en pensant que j\u2019allais les surprendre.<\/p>\n<p>Le seul cours que je trouvai qui concordait avec mon horaire \u00e9tait donn\u00e9 dans une mosqu\u00e9e du district, alors je d\u00e9cidai d\u2019y aller. Je n\u2019y appris pas beaucoup l\u2019arabe, mais les s\u0153urs, dans la mosqu\u00e9e, m\u2019en apprirent beaucoup sur l\u2019islam. \u00c0 chaque question que je leur posais, elles me donnaient une r\u00e9ponse claire, simple et logique. Je sentis, au fond de moi, que l\u2019islam \u00e9tait une religion que je pourrais \u00e9ventuellement embrasser. Alors, le jour de mon 19e anniversaire de naissance, je pronon\u00e7ai officiellement la shahada (profession de foi). Apr\u00e8s l\u2019avoir prononc\u00e9e, je ressentis une joie profonde emplir mon c\u0153ur. Je levai les bras au ciel et m\u2019exclamai : \u00ab Je suis une musulmane, maintenant! Gloire \u00e0 Dieu! \u00bb<\/p>\n<p>Apr\u00e8s \u00eatre devenue musulmane, je me sentis beaucoup plus en paix avec moi-m\u00eame et avec ma spiritualit\u00e9. Ma famille fut tr\u00e8s contrari\u00e9e, en apprenant la nouvelle; mais aucun d\u2019entre eux ne cessa de me parler ni de me d\u00e9montrer son affection. Certains ont fini par mieux comprendre l\u2019islam et sont devenus plus \u00e0 l\u2019aise vis-\u00e0-vis de ma d\u00e9cision. Gloire \u00e0 Dieu.<\/p>\n<p>Avec son mode de vie qui englobe tous les aspects du quotidien, l\u2019islam a n\u00e9cessairement influenc\u00e9 de nombreuses d\u00e9cisions que j\u2019ai prises, dans ma vie, suite \u00e0 ma conversion. L\u2019islam n\u2019est pas une religion \u00e0 temps partiel. Je ne mets pas en doute le fait que des chr\u00e9tiens sinc\u00e8res font l\u2019effort de pratiquer leur religion dans leur vie de tous les jours, mais l\u2019islam est beaucoup plus complet et comporte de plus nombreuses lignes de conduite \u00e0 observer. Dans tout ce que je fais, je garde constamment \u00e0 l\u2019esprit que je serai redevable de mes actions et je demande souvent pardon \u00e0 Dieu pour mes erreurs.<\/p>\n<p>L\u2019islam a donn\u00e9 \u00e0 ma vie le sens que je cherchais \u00e0 lui donner. Avant l\u2019islam, je n\u2019avais aucune id\u00e9e de ce que souhaitais faire de ma vie. L\u2019un de mes plus grands souhaits serait d\u2019aider une autre personne \u00e0 devenir musulmane et j\u2019esp\u00e8re qu\u2019il se concr\u00e9tisera.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/valerie-wright-ex-chrtienne-tats-unis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) Je dirais que mon cheminement vers l\u2019islam a d\u00e9but\u00e9 avant m\u00eame que j\u2019en aie conscience. Je suis n\u00e9e avec un probl\u00e8me de perte d\u2019audition progressive. Ma m\u00e8re n\u2019a pas r\u00e9alis\u00e9 que j\u2019avais un probl\u00e8me d\u2019audition avant que je n\u2019aie l\u2019\u00e2ge de quatre ans. Une fois diagnostiqu\u00e9e, je re\u00e7us mes premi\u00e8res proth\u00e8ses &#8230; <a title=\"Valerie Wright, ex-chr\u00e9tienne, \u00c9tats-Unis\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/valerie-wright-ex-chretienne-etats-unis\/\" aria-label=\"Read more about Valerie Wright, ex-chr\u00e9tienne, \u00c9tats-Unis\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7646","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 2) Je dirais que mon cheminement vers l\u2019islam a d\u00e9but\u00e9 avant m\u00eame que j\u2019en aie conscience. Je suis n\u00e9e avec un probl\u00e8me de perte d\u2019audition progressive. Ma m\u00e8re n\u2019a pas r\u00e9alis\u00e9 que j\u2019avais un probl\u00e8me d\u2019audition avant que je n\u2019aie l\u2019\u00e2ge de quatre ans. Une fois diagnostiqu\u00e9e, je re\u00e7us mes premi\u00e8res proth\u00e8ses\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Zk","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7646,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8590,"url":"https:\/\/www.ask-a-muslim.com\/de\/jonathan-abdilla-ex-christ-canada\/","url_meta":{"origin":7646,"position":1},"title":"Jonathan Abdilla, Ex-Christ, Canada","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich f\u00fchle mich geehrt, ein Muslim zu sein\u2026Und so f\u00fchle ich mich aus verschiedenen Gr\u00fcnden. Es gibt viele Normen in der Gesellschaft, in der ich lebe, die genau das Gegenteil dessen sind, wie Muslime es tun. Und als ich zuerst zu dieser Lebensweise kam, wusste ich nicht so genau wie\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8688,"url":"https:\/\/www.ask-a-muslim.com\/de\/respirationsapparat-ist-ausser-betrieb-in-hochluftschichten\/","url_meta":{"origin":7646,"position":2},"title":"RESPIRATIONSAPPARAT IST AUSSER BETRIEB IN HOCHLUFTSCHICHTEN","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den Islam. Und wen Er irref\u00fchren will, dem macht Er die Brust beklommen und bedr\u00fcckt, so als ob er in den Himmel hoch steigen w\u00fcrde Allah, der Erhabene sagt: \"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8591,"url":"https:\/\/www.ask-a-muslim.com\/de\/charlie-alcala-ex-christ-philippinen\/","url_meta":{"origin":7646,"position":3},"title":"Charlie Alcala, Ex-Christ, Philippinen","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Das gegenw\u00e4rtige Leben kann dich an einen Platz bringen, an den du nie gedacht h\u00e4ttest. Unser Schicksal ist nicht in unseren H\u00e4nden, auch wenn es das zu sein scheint; in seinen Venen sind Spuren eines Handabdrucks, der einen v\u00f6lligen Gegensatz zu unserem bildet. Ich habe diese wundervolle Wahrheit in meinem\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8650,"url":"https:\/\/www.ask-a-muslim.com\/de\/angelene-mclaren-ex-katholikin-usa\/","url_meta":{"origin":7646,"position":4},"title":"Angelene McLaren, Ex-Katholikin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Schon immer seit ich ein kleines M\u00e4dchen gewesen bin, habe ich eine tiefgr\u00fcndige Beziehung zu Gott gehabt. Obwohl ich als Katholikin erzogen worden bin, trotz all den Unklarheiten, Widerspr\u00fcchen und Verwirrungen, tat ich mein Bestes, um Gott-bezogen zu bleiben und nicht den Lehren der Kirche nachzugeben, denn selbst f\u00fcr mich\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8643,"url":"https:\/\/www.ask-a-muslim.com\/de\/latasha-ex-christin-usa\/","url_meta":{"origin":7646,"position":5},"title":"Latasha, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin Amerikanerin, die in einer streng religi\u00f6sen christlichen Familie aufgewachsen ist. W\u00e4hrend der Zeit, als ich 16 wurde, wurde ich selbst sehr fromm und religi\u00f6s. Die Kirche war wie ein Heim weit entfernt von zuhause. Ich genoss sie von Grund auf. Ich hatte die Bibel regelm\u00e4\u00dfig gelesen und studiert.\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7646"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7646\/revisions"}],"predecessor-version":[{"id":11330,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7646\/revisions\/11330"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}