{"id":7653,"date":"2020-06-17T02:21:28","date_gmt":"2020-06-17T07:21:28","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7653"},"modified":"2020-07-02T06:42:34","modified_gmt":"2020-07-02T11:42:34","slug":"aaminah-hernandez-ex-chretienne-etats-unis","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/aaminah-hernandez-ex-chretienne-etats-unis\/","title":{"rendered":"Aaminah Hernandez, ex-chr\u00e9tienne, \u00c9tats-Unis"},"content":{"rendered":"<h3><strong>(partie 1 de 2)<\/strong><\/h3>\n<p>J\u2019ai grandi aux \u00c9tats-Unis, dans les ann\u00e9es 80, et \u00e0 l\u2019\u00e9poque, mes connaissances sur l\u2019islam \u00e9taient \u00e0 peu pr\u00e8s nulles. Mon p\u00e8re nous apprit, \u00e0 mon fr\u00e8re et \u00e0 moi, \u00e0 nous int\u00e9resser \u00e0 ce qui se passait dans le monde, aux autres cultures et aux autres nations, et nous inculqua l&rsquo;amour de la lecture. \u00c0 cette \u00e9poque, les m\u00e9dias nous faisaient de l\u2019islam un portrait bas\u00e9 sur la r\u00e9volution iranienne et sur le conflit palestinien. Tout ce que nous savions des femmes musulmanes se r\u00e9sumait \u00e0 \u00ab Jamais sans ma fille \u00bb et autres ouvrages ou documentaires \u00e0 sensation du m\u00eame genre.<\/p>\n<p>Bien que je ne lus jamais ce livre, j\u2019en tirai des conclusions sur ce qu\u2019en disaient les gens autour de moi : les musulmanes \u00e9taient esclaves de leur mari, ces derniers pouvaient avoir un nombre illimit\u00e9 d\u2019\u00e9pouses, les battre comme bon leur semblait et m\u00eame les tuer si elles donnaient naissance \u00e0 une fille ou les rejeter si elles ne mettaient pas de gar\u00e7on au monde dans un certain d\u00e9lai. L\u2019image de femmes recouvertes de noir, dont les v\u00eatements tr\u00e8s lourds \u00e9taient superpos\u00e9s, incluant un voile recouvrant le visage \u2013 une telle image \u00e9tait terrifiante pour une jeune fille \u00e9lev\u00e9e \u00e0 l\u2019\u00e8re de Madonna et de Cindy Lauper. De plus, on nous apprenait, \u00e0 l\u2019\u00e9cole, que les femmes du Moyen-Orient n\u2019\u00e9taient pas autoris\u00e9es \u00e0 quitter leur maison et vivaient, pour la plupart, dans une grande pauvret\u00e9; elles \u00e9taient oblig\u00e9es de partager leurs lieux de vie avec leurs co-\u00e9pouses et tous les enfants de celles-ci et voyaient rarement leur mari. Bref, dans les rares informations qui nous parvenaient sur l\u2019islam, jamais de distinction n\u2019\u00e9tait faite entre les diverses cultures du Moyen-Orient et les diverses fa\u00e7ons de vivre l\u2019islam. Pour moi, seuls les Arabes et quelques Afro-am\u00e9ricains \u00e9taient musulmans et j\u2019ignorais que tous les Arabes n\u2019\u00e9taient pas musulmans.<\/p>\n<p>Parce que mon p\u00e8re m\u2019avait appris que la meilleure \u00e9ducation que je pouvais recevoir \u00e9tait celle que je me donnerais \u00e0 moi-m\u00eame en lisant, je devins une lectrice assidue. Je passais plus de temps \u00e0 la biblioth\u00e8que que n\u2019importe o\u00f9 ailleurs et je lisais tant que lorsque mes parents souhaitaient me punir, ils m\u2019enlevaient mes livres. Alhamdoulillah (gloire \u00e0 Dieu), cet amour des livres ne m\u2019a jamais quitt\u00e9e et, bien que je ne l\u2019aurais jamais imagin\u00e9, c\u2019est cet amour qui m\u2019amena \u00e0 d\u00e9couvrir l\u2019islam. J\u2019avais lu l\u2019autobiographie de Malcolm X lorsque j\u2019\u00e9tais en cinqui\u00e8me ann\u00e9e du primaire et, m\u00eame si cette lecture ne m\u2019avait pas attir\u00e9e vers l\u2019islam, j\u2019avais d\u00e9cid\u00e9, par la suite, de ne plus consommer de porc. M\u00eame si cela ne m\u2019avait pas amen\u00e9e \u00e0 changer radicalement ma fa\u00e7on de penser, je r\u00e9alisai, des ann\u00e9es plus tard, que cela avait sem\u00e9 quelque chose de particulier dans mon c\u0153ur et mon esprit. Mais \u00e0 un \u00e2ge aussi jeune, je n\u2019\u00e9tais simplement pas pr\u00eate \u00e0 l\u2019accepter ou \u00e0 le prendre au s\u00e9rieux.<\/p>\n<p>Au fil des ans, on abusa de moi; je fus agress\u00e9e sexuellement et manipul\u00e9e par plusieurs personnes faisant partie de mon entourage. Cela m\u2019amena \u00e0 quitter le domicile familial alors que j\u2019avais \u00e0 peine 16 ans. Mon fr\u00e8re resta \u00e0 la maison et d\u00fb composer avec ses propres probl\u00e8mes, incluant des activit\u00e9s au sein des gangs de rue. Je r\u00e9ussis \u00e0 terminer mes \u00e9tudes secondaires et poursuivis mon chemin toute seule, fi\u00e8re d\u2019avoir r\u00e9ussi \u00e0 m\u2019en sortir par moi-m\u00eame. \u00c0 cette \u00e9poque, je ne pensais pas souvent \u00e0 Dieu. Je m\u2019int\u00e9ressai temporairement \u00e0 la magie blanche, sans grand s\u00e9rieux, et aujourd\u2019hui, avec du recul, je suis soulag\u00e9e de ne pas m\u2019\u00eatre impliqu\u00e9e davantage dans ce genre d\u2019activit\u00e9. Je m\u2019int\u00e9ressai \u00e9galement aux spiritualit\u00e9s celte et am\u00e9rindienne, \u00e0 l\u2019hindouisme et au bouddhisme, mais sans r\u00e9ellement les comprendre.<\/p>\n<p>Je menai, pour un temps, une vie d\u00e9sordonn\u00e9e faite de sexe, de drogues et de f\u00eates continuelles. J\u2019 \u00ab aimais \u00bb tout le monde et prenais part \u00e0 tous les plaisirs de la vie, sans jamais me soucier de mon avenir, f\u00fbt-ce sur cette terre ou dans l\u2019au-del\u00e0. Malgr\u00e9 cela, je finis par sombrer dans la d\u00e9pression \u00e0 plus d\u2019une reprise. En fait, mes cycles de d\u00e9pression avaient commenc\u00e9 quand j\u2019\u00e9tais toute jeune, en partie \u00e0 cause des restrictions que m\u2019imposaient mes parents. Je devins \u00e9galement suicidaire et c\u2019est seulement par la gr\u00e2ce d\u2019Allah que mes tentatives de suicide ne laiss\u00e8rent aucune s\u00e9quelle, chez moi.<\/p>\n<p>M\u00eame si j\u2019avais une conscience sociale tr\u00e8s d\u00e9velopp\u00e9e et que j\u2019\u00e9tais toujours la premi\u00e8re \u00e0 \u00e9pouser toutes sortes de causes, il n\u2019en demeurait pas moins que je vivais ma vie de mani\u00e8re totalement irresponsable. J\u2019\u00e9tais incapable de garder un emploi, vivais au jour le jour et m\u2019arrangeais pour avoir le moins de responsabilit\u00e9s possible. M\u00eame si j\u2019avais tr\u00e8s peu de moyens, je n\u2019en \u00e9tais pas moins mat\u00e9rialiste et \u00e9gocentrique. Au fond, je ne faisais rien dont la soci\u00e9t\u00e9 aurait pu profiter positivement et j\u2019\u00e9tais un fardeau pour mes amis et les membres de ma famille.<\/p>\n<p>C\u2019est durant cette p\u00e9riode que je fis la rencontre d\u2019un membre du gang de mon fr\u00e8re et que je tombai \u00e9perdument amoureuse de lui. M\u00eame si, \u00e0 cause de notre relation, mon fr\u00e8re et mon nouveau copain quitt\u00e8rent le gang, nous ne f\u00fbmes pas au bout de nos peines. Mon nouveau copain \u00e9tait aux prises avec un s\u00e9rieux probl\u00e8me de consommation de drogue et je n\u2019\u00e9tais pas du tout outill\u00e9e pour composer avec cette situation. Nous e\u00fbmes toutes sortes de probl\u00e8mes avec la justice et fin\u00eemes par fuir vers un autre \u00e9tat du pays pour \u00e9viter d\u2019\u00eatre poursuivis. \u00c0 ce moment, je sentis que j\u2019avais touch\u00e9 le fond; nous vivions dans des parcs, nous n\u2019avions rien \u00e0 manger, je subis plus d\u2019une fausse couche et, pour avoir un peu d\u2019argent, je finis par faire des choses que je ne me serais jamais cru capable de faire.<\/p>\n<p>Nous retourn\u00e2mes au bercail et mon copain fut arr\u00eat\u00e9 par la police. C\u2019est alors que je d\u00e9couvris que j\u2019\u00e9tais \u00e0 nouveau enceinte. Par je ne sais quel miracle d\u2019Allah, le b\u00e9b\u00e9 \u00e9tait en sant\u00e9 et je le menai \u00e0 terme. Par ailleurs, durant mon absence, mon fr\u00e8re se retrouva en prison, o\u00f9 il se convertit \u00e0 l\u2019islam. Mais lorsqu\u2019il fut lib\u00e9r\u00e9, il quitta la ville sans dire o\u00f9 il allait. Apr\u00e8s la naissance de mon fils, il revint nous visiter. Il me parla longuement de ce qu\u2019il avait appris, sur l\u2019islam, et je ne pus m\u2019emp\u00eacher d\u2019\u00eatre impressionn\u00e9e par le changement dans sa personnalit\u00e9 et dans ses mani\u00e8res. Manifestement, l\u2019islam avait un effet positif sur lui. Il avait \u00e9t\u00e9 diagnostiqu\u00e9 avec un d\u00e9sordre schizo-affectif (schizophr\u00e9nie accompagn\u00e9e d\u2019hallucinations et de d\u00e9pression s\u00e9v\u00e8re), mais depuis sa conversion, il n\u2019\u00e9prouvait plus aucun sympt\u00f4mes et ne prenait plus de m\u00e9dicaments. Mon fr\u00e8re \u00e9tait devenu un jeune homme doux et calme, habill\u00e9 \u00e0 la mani\u00e8re traditionnelle des musulmans et se tenant avec beaucoup de dignit\u00e9. Il me parla des fondements de l\u2019islam et, m\u00eame si j\u2019\u00e9tais tr\u00e8s heureuse qu\u2019il ait trouv\u00e9 une voie dans laquelle il se sentait bien, je n\u2019avais aucune envie de bouleverser ma vie pour une religion.<\/p>\n<h3><\/h3>\n<h3><strong>(partie 2 de 2)<\/strong><\/h3>\n<p>Le p\u00e8re de mon fils en prison, je d\u00e9cidai de devenir un peu plus responsable et de mettre de l\u2019ordre dans ma vie pour le bien-\u00eatre de mon fils. Je recommen\u00e7ai \u00e0 assister aux messes, \u00e0 l\u2019\u00e9glise, en compagnie de ma m\u00e8re. Quelques mois apr\u00e8s la visite de mon fr\u00e8re, il revint nous voir en compagnie d\u2019une femme qu\u2019il venait d\u2019\u00e9pouser et qui \u00e9tait totalement voil\u00e9e; quelques mois plus tard, elle \u00e9tait enceinte de leur premier gar\u00e7on. J\u2019aurais voulu ressentir de la sympathie et de l\u2019amiti\u00e9 pour ma belle-s\u0153ur, mais j\u2019avais de la difficult\u00e9 avec sa fa\u00e7on de se v\u00eatir. Avec du recul, en y repensant, je crois que ce qui m\u2019emp\u00eachait de l\u2019appr\u00e9cier \u00e9tait la honte que je ressentais par rapport \u00e0 mon propre mode de vie. Qu\u2019Allah la r\u00e9tribue pour sa patience et sa volont\u00e9 de partager avec moi ce qu\u2019elle savait sur l\u2019islam en d\u00e9pit de mon attitude un peu froide \u00e0 son \u00e9gard.<\/p>\n<p>Un jour, mon fr\u00e8re amena un ami, \u00e0 la maison, pour parler d\u2019islam avec ma m\u00e8re. C\u2019\u00e9tait le premier musulman, en dehors de mon fr\u00e8re, avec lequel j\u2019entrais en contact et je me souviens que sa visite fit ressortir, chez moi, un c\u00f4t\u00e9 de ma personnalit\u00e9 dont j\u2019ignorais l\u2019existence. Chaque fois que je repensai \u00e0 lui, par la suite, je le revis comme tr\u00e8s blanc. Je sais maintenant que c\u2019\u00e9tait parce qu\u2019il avait une lumi\u00e8re (nour) sur le visage, lumi\u00e8re qui refl\u00e9tait sa foi; mais j\u2019\u00e9tais trop timide pour le regarder directement. Chaque fois qu\u2019il revint, par la suite, je me surpris \u00e0 me pr\u00e9cipiter dans ma chambre pour rev\u00eatir des v\u00eatements plus couvrants. Il fit une telle impression, sur moi, qu\u2019aujourd\u2019hui encore, je fais r\u00e9guli\u00e8rement des dou\u2019as (invocations) pour sa s\u00e9curit\u00e9 et son bien-\u00eatre. Je ne le revis plus jamais apr\u00e8s ses quelques visites chez nous.<\/p>\n<p>Je fis la rencontre d\u2019un homme qui me semblait bon et responsable, avec lequel j\u2019entamai des fr\u00e9quentations. Mon fr\u00e8re et son \u00e9pouse emm\u00e9nag\u00e8rent temporairement chez nous, avec ma m\u00e8re, mon fils et moi, et mon nouveau copain nous rendait chaque jour visite. Quelques mois avant la naissance de mon neveu, mon fr\u00e8re et son \u00e9pouse d\u00e9m\u00e9nag\u00e8rent dans leur propre appartement, car j\u2019avais tellement jou\u00e9 avec les nerfs de ma belle-s\u0153ur que nous ne pouvions plus nous trouver dans la m\u00eame pi\u00e8ce. Puis, j\u2019\u00e9pousai mon copain et d\u00e9m\u00e9nageai \u00e9galement de mon c\u00f4t\u00e9.<\/p>\n<p>Apr\u00e8s la naissance de mon neveu, je commen\u00e7ai \u00e0 rendre des visites plus r\u00e9guli\u00e8res \u00e0 mon fr\u00e8re et son \u00e9pouse. J\u2019\u00e9tais \u00e9mue par la qui\u00e9tude de leur appartement et de leur vie familiale. Ma belle-s\u0153ur faisait beaucoup d\u2019efforts pour nous mettre \u00e0 l\u2019aise, mon fils et moi, lorsque nous lui rendions visite et elle me parla \u00e0 nouveau d\u2019islam. Mon mari n\u2019aimait pas mon fr\u00e8re et lui jeta des commentaires d\u00e9sobligeants \u00e0 la figure, en plus de parler dans son dos, ce qui m\u2019embarrassa beaucoup. Cela d\u00e9clencha un conflit au sein de mon mariage et je me mis \u00e0 passer de plus en plus de temps chez mon fr\u00e8re, puisque mon mari refusait que je travaille.<\/p>\n<p>Avec le temps, je m\u2019int\u00e9ressai aux habits de ma belle-s\u0153ur et finis par comprendre qu\u2019elle devait se sentir \u00e0 l\u2019aise, physiquement et moralement. Je pus \u00e9galement constater que les tissus de ses v\u00eatements n\u2019\u00e9taient ni lourds ni chauds, comme je me l\u2019\u00e9tais imagin\u00e9. Lorsque je laissai entendre \u00e0 mon mari que j\u2019aimerais peut-\u00eatre me couvrir de la sorte, un jour, il se moqua de moi. Cela ne m\u2019\u00e9tonna pas outre mesure, car il m\u2019avait toujours encourag\u00e9e \u00e0 porter des v\u00eatements suggestifs; il aimait avoir une femme \u00ab sexy \u00bb, mais personnellement, je ne me sentais pas respect\u00e9e. \u00c0 peine quelques mois apr\u00e8s notre mariage, il m\u2019avoua qu\u2019il avait une aventure avec une autre femme et qu\u2019il ne voulait plus de moi. Ma vie \u00e9tait \u00e0 nouveau un d\u00e9sastre et, avec mon fils, je retournai chez ma m\u00e8re.<\/p>\n<p>Il va sans dire qu\u2019\u00e0 partir de ce moment, je passai de plus en plus de temps avec ma belle-s\u0153ur. Mon fr\u00e8re et sa femme furent les seules personnes qui m\u2019apport\u00e8rent du soutien apr\u00e8s mon divorce. \u00c0 l\u2019\u00e9glise que je fr\u00e9quentais, on me dit qu\u2019il y avait toujours une raison pour laquelle un homme allait voir ailleurs et que c\u2019\u00e9tait n\u00e9cessairement ma faute. On me dit \u00e9galement que je ne devais pas chercher du travail ni quitter la maison de mon mari, m\u00eame s\u2019il m\u2019avait demand\u00e9 de le faire, car je commettais un p\u00e9ch\u00e9 ce faisant et je devais plut\u00f4t \u00eatre patiente et attendre qu\u2019il revienne \u00e0 moi. L\u2019\u00e9glise ne s\u2019offrit toutefois pas pour payer la nourriture, les v\u00eatements ou les couches de mon fils pendant que j\u2019attendrais que \u00ab Dieu ouvre le c\u0153ur de mon mari et le ram\u00e8ne \u00e0 moi \u00bb<\/p>\n<p>. Ils ne firent rien d\u2019autre que de me juger, ce qui me rendit tr\u00e8s cynique. Mon fr\u00e8re et son \u00e9pouse, de leur c\u00f4t\u00e9, comprenaient que mon mariage \u00e9tait bel et bien termin\u00e9 et que j\u2019allais devoir prendre soin de mon fils toute seule. Ils m\u2019offrirent m\u00eame d\u2019habiter chez eux et ma belle-s\u0153ur offrit de garder mon fils pour que je puisse aller travailler. Ils m\u2019expliqu\u00e8rent, aussi, le point de vue de l\u2019islam sur le mariage, le divorce et les droits de la femme. Je fus tr\u00e8s \u00e9tonn\u00e9e de d\u00e9couvrir que cette religion que l\u2019on croit faite pour les hommes seulement \u00e9tait en fait plus r\u00e9aliste et compr\u00e9hensive, devant ma situation, que ne l\u2019\u00e9tait l\u2019\u00e9glise.<\/p>\n<p>Malheureusement, avant que je ne puisse dire \u00e0 mon fr\u00e8re que j\u2019avais d\u00e9cid\u00e9 d\u2019accepter leur offre de vivre avec eux, sa famille et lui furent contraints de quitter la ville de mani\u00e8re inattendue. Apr\u00e8s leur installation dans leur nouvel appartement, ma belle-s\u0153ur m\u2019\u00e9crivit et nous gard\u00e2mes contact. Quelques mois plus tard, sentant que je n\u2019arrivais pas \u00e0 me sortir du gouffre dans lequel je me trouvais, j\u2019allai trouver l\u2019ancien employeur de mon fr\u00e8re, qui \u00e9tait lui aussi musulman, et je le suppliai de nous conduire, mon fils et moi, chez mon fr\u00e8re. Il accepta avec plaisir et me donna m\u00eame un Coran \u00e0 lire en chemin. Ce fr\u00e8re fut vraiment tr\u00e8s gentil et tr\u00e8s respectueux envers moi, en plus de se montrer attentionn\u00e9 envers mon fils. Il me proposa de l\u2019\u00e9pouser, mais je fus choqu\u00e9e par cette proposition et lui demandai de me permettre de passer du temps avec mon fr\u00e8re avant de me reparler de ce sujet. Il me d\u00e9posa chez mon fr\u00e8re et retourna chez lui sans aucune rancune \u00e0 mon endroit.<\/p>\n<p>Vivre avec mon fr\u00e8re et son \u00e9pouse s\u2019av\u00e9ra plus difficile que je ne l\u2019avais pr\u00e9vu. Nous \u00e9tions extr\u00eamement pauvres. Mais je finis par prononcer la shahadah (attestation de foi musulmane) et je vivais dans un endroit o\u00f9 j\u2019entendais l\u2019adhan (l\u2019appel \u00e0 la pri\u00e8re) cinq fois par jour et o\u00f9 j\u2019\u00e9tais entour\u00e9e de musulmans. Et m\u00eame s\u2019il y avait beaucoup de probl\u00e8mes, le souvenir de cette p\u00e9riode est tr\u00e8s cher \u00e0 mon c\u0153ur. Mon fr\u00e8re et ma belle-s\u0153ur me montr\u00e8rent comment faire les ablutions, prier, nourrir ma conscience de Dieu et la plupart des choses que j\u2019avais besoin de savoir pour commencer ma vie de musulmane.<\/p>\n<p>Je finis par me voir oblig\u00e9e de retourner chez moi pour trouver du travail et tenter de donner une meilleure vie \u00e0 mon fils. Je cessai de porter le hijab et le niqab et fis ce que j\u2019avais \u00e0 faire pour trouver du travail. Moralement, je consid\u00e8re que j\u2019\u00e9tais devenue une meilleure personne et j\u2019\u00e9tais fi\u00e8re de dire que j\u2019\u00e9tais musulmane. Il n\u2019en demeure pas moins que je trouvais difficile d\u2019appliquer l\u2019islam dans ma vie de tous les jours. Il n\u2019y avait pas de communaut\u00e9 musulmane unie, dans ma ville, et certaines personnes firent circuler toutes sortes d\u2019informations sur mon pass\u00e9, de sorte que plusieurs musulmanes pr\u00e9f\u00e9raient ne pas m\u2019adresser la parole. Mais alhamdoulillah, je trouvai un emploi o\u00f9 j\u2019avais acc\u00e8s \u00e0 l\u2019internet et je pus, dans mes moments libres, trouver des informations sur l\u2019islam et acheter des livres islamiques en ligne. J\u2019achetai \u00e9galement des hijabs, et m\u00eame des niqab, m\u00eame si mon employeur refusait que je porte le hijab au travail.<\/p>\n<p>Je rencontrai plusieurs musulmanes en ligne et fis partie d\u2019une petite communaut\u00e9 virtuelle. Je trouvai \u00e9galement un nouveau mari. Mais \u00e0 cause de mon impatience et de mes points de vue un peu trop rigides, ce mariage \u00e9choua rapidement et je quittai mon mari.<\/p>\n<p>Apr\u00e8s l\u2019avoir quitt\u00e9, je laissai \u00e0 nouveau tomber le hijab et le niqab et me remis \u00e0 vivre un peu follement. Je passai m\u00eame un long moment sans islam dans mon quotidien, mais je parvins \u00e0 le dissimuler aux gens que je connaissais. Aujourd\u2019hui encore, je me demande si ma vie aurait \u00e9t\u00e9 meilleure si j\u2019\u00e9tais rest\u00e9e avec mon second mari, mais apparemment, Allah avait d\u2019autres plans pour moi.<\/p>\n<p>Je fis de nouveau la rencontre d\u2019un homme. Il \u00e9tait bon, gentil et g\u00e9n\u00e9reux et je tombai amoureuse de lui. Mais il n\u2019\u00e9tait pas musulman. Je fus honn\u00eate d\u00e8s le d\u00e9part et lui dis que j\u2019\u00e9tais musulmane et que je ne pouvais \u00e9pouser qu\u2019un musulman. Je recommen\u00e7ai \u00e0 porter le hijab et il l\u2019accepta. Il accepta \u00e9galement de devenir musulman et se convertit. Nous nous mari\u00e2mes.<\/p>\n<p>Apr\u00e8s un temps, je trouvai un nouvel emploi avec acc\u00e8s \u00e0 l\u2019internet et commen\u00e7ai \u00e0 faire ce que j\u2019avais toujours voulu faire : \u00e9crire. Avec l\u2019appui de s\u0153urs musulmanes en ligne, je commen\u00e7ai m\u00eame \u00e0 r\u00e9diger des histoires et des articles sur l\u2019islam. Mon employeur appr\u00e9ciait le point de vue islamique que j\u2019apportais \u00e0 notre travail de service social, de m\u00eame que mon int\u00e9grit\u00e9. Il n\u2019avait \u00e9galement aucun probl\u00e8me avec mon hijab.<\/p>\n<p>J\u2019ai encore de la difficult\u00e9 avec l\u2019application de l\u2019islam, dans ma vie de tous les jours. Comme chez la plupart des gens, ma foi conna\u00eet des hauts et des bas. Mais je garde \u00e0 l\u2019esprit que tout est entre les mains d\u2019Allah et que tant que je m\u2019efforce de lutter contre mes propres d\u00e9sirs (nafs) et de Lui ob\u00e9ir, Il me prot\u00e8ge. J\u2019esp\u00e8re, un jour, aller vivre dans un endroit abritant une communaut\u00e9 musulmane tr\u00e8s unie. Jamais je n\u2019oublierai qu\u2019Allah m\u2019a guid\u00e9e vers l\u2019islam par l\u2019interm\u00e9diaire de mon jeune fr\u00e8re et je reconnais cette b\u00e9n\u00e9diction comme unique. M\u00eame si mes parents refusent d\u2019entendre parler d\u2019islam, je suis tout de m\u00eame heureuse d\u2019avoir une famille avec laquelle je peux partager mes tracas quotidiens. Je prie Allah pour que mes \u00e9crits servent \u00e0 guider d\u2019autres personnes vers l\u2019islam, la seule et unique voie menant au bonheur, ici-bas comme dans l\u2019au-del\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/aaminah-hernandez-ex-chrtienne-tats-unis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) J\u2019ai grandi aux \u00c9tats-Unis, dans les ann\u00e9es 80, et \u00e0 l\u2019\u00e9poque, mes connaissances sur l\u2019islam \u00e9taient \u00e0 peu pr\u00e8s nulles. Mon p\u00e8re nous apprit, \u00e0 mon fr\u00e8re et \u00e0 moi, \u00e0 nous int\u00e9resser \u00e0 ce qui se passait dans le monde, aux autres cultures et aux autres nations, et nous inculqua &#8230; <a title=\"Aaminah Hernandez, ex-chr\u00e9tienne, \u00c9tats-Unis\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/aaminah-hernandez-ex-chretienne-etats-unis\/\" aria-label=\"Read more about Aaminah Hernandez, ex-chr\u00e9tienne, \u00c9tats-Unis\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7653","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"(partie 1 de 2) J\u2019ai grandi aux \u00c9tats-Unis, dans les ann\u00e9es 80, et \u00e0 l\u2019\u00e9poque, mes connaissances sur l\u2019islam \u00e9taient \u00e0 peu pr\u00e8s nulles. Mon p\u00e8re nous apprit, \u00e0 mon fr\u00e8re et \u00e0 moi, \u00e0 nous int\u00e9resser \u00e0 ce qui se passait dans le monde, aux autres cultures et aux autres nations, et nous inculqua\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1Zr","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7653,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8679,"url":"https:\/\/www.ask-a-muslim.com\/de\/die-sonne-ist-eine-leuchte-der-mond-widerspiegelt-das-licht\/","url_meta":{"origin":7653,"position":1},"title":"DIE SONNE IST EINE LEUCHTE DER MOND WIDERSPIEGELT DAS LICHT","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Allah der Erhabene sagt im Heiligen Koran: \u201eGesegnet sei der, der im Himmel Sternzeichen gesetzt und darin eine Leuchte und einen hellen Mond gesetzt hat! (Sure 25, Vers 61) Allah der Erhabene sagt im Heiligen Koran: \u201eGesegnet sei der, der im Himmel Sternzeichen gesetzt und darin eine Leuchte und einen\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8686,"url":"https:\/\/www.ask-a-muslim.com\/de\/die-ruecklaeufigen-planeten-die-am-himmelsgewoelbe-dahinziehen-und\/","url_meta":{"origin":7653,"position":2},"title":"Die r\u00fcckl\u00e4ufigen Planeten, die am Himmelsgew\u00f6lbe dahinziehen und","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Allah der Erhabene sagt: \u201eNein, Ich schw\u00f6re bei den r\u00fcckl\u00e4ufigen Planeten, 16 die dahineilen und sich in ihrem Bau verbergen.\u201c Allah der Erhabene sagt: \u201eNein, Ich schw\u00f6re bei den r\u00fcckl\u00e4ufigen Planeten, 16 die dahineilen und sich in ihrem Bau verbergen.\u201c Sure 81 Verse 15, 16 \u00a0 Eine wissenschaftliche Tatsache Es\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8681,"url":"https:\/\/www.ask-a-muslim.com\/de\/das-erschaffen-des-embryos-in-phasen\/","url_meta":{"origin":7653,"position":3},"title":"DAS ERSCHAFFEN DES EMBRYOS IN PHASEN","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Allah hat gesagt: \u201eWarum strebt ihr nicht danach, Gott geb\u00fchrend zu verehren? Er hat euch doch in verschiedenen Entwicklungsphasen erschaffen.\u201c (Sure 71, Vers 13-14) Allah hat gesagt: \u201eWarum strebt ihr nicht danach, Gott geb\u00fchrend zu verehren? Er hat euch doch in verschiedenen Entwicklungsphasen erschaffen.\u201c (Sure 71, Vers 13-14) Das wissenschaftliche\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8692,"url":"https:\/\/www.ask-a-muslim.com\/de\/der-verbot-des-schweinfleischgeniessens-hat-wissenschaftliche\/","url_meta":{"origin":7653,"position":4},"title":"Der Verbot des Schweinfleischgenie\u00dfens hat wissenschaftliche","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Allah, der Erhabene sagt: \u201eIn dem, was mir offenbart wurde, finde ich nicht, dass etwas f\u00fcr Essenden zu essen verboten w\u00e4re, es sei denn, es ist Verendetes oder ausgeflossenes Blut oder Schweinfleisch- es ist ein Greuel- oder ein Frevler, wor\u00fcber ein andrer als Gott angerufen worden ist. Wenn aber einer\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7653,"position":5},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7653"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7653\/revisions"}],"predecessor-version":[{"id":11319,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7653\/revisions\/11319"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}