{"id":7677,"date":"2020-06-17T02:23:35","date_gmt":"2020-06-17T07:23:35","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7677"},"modified":"2020-07-02T06:17:58","modified_gmt":"2020-07-02T11:17:58","slug":"laurence-brown-medecin-etats-unis","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/laurence-brown-medecin-etats-unis\/","title":{"rendered":"Laurence Brown, m\u00e9decin, \u00c9tats-Unis"},"content":{"rendered":"<h3><strong>(partie 1 de 2)<\/strong><\/h3>\n<p>Ayant eu \u00e0 expliquer \u00e0 de nombreuses reprises ce qui m\u2019avait amen\u00e9 \u00e0 devenir musulman, j\u2019ai d\u00e9cid\u00e9 de relater le r\u00e9cit de ma conversion une derni\u00e8re fois, mais par \u00e9crit. Toutefois, je consid\u00e8re qu\u2019\u00e0 moins d\u2019en tirer les le\u00e7ons qui s\u2019imposent, les histoires de conversion sont inutiles. Je compte donc commencer par ces le\u00e7ons.<\/p>\n<p>Les gens sont ind\u00e9niablement fascin\u00e9s par les histoires de conversion et avec raison. La plupart du temps, elles font \u00e9tat d\u2019\u00e9v\u00e9nements dramatiques qui ont boulevers\u00e9 le cours de la vie des convertis et qui les ont fait subitement passer du monde mat\u00e9rialiste dans lequel ils vivaient \u00e0 un univers beaucoup plus spirituel. Ceux qui font l\u2019exp\u00e9rience de tels drames dans leur vie se retrouvent souvent, pour la premi\u00e8re fois, forc\u00e9s \u00e0 se poser des questions quant \u00e0 la finalit\u00e9 de leur existence; des questions comme \u00ab qui nous a cr\u00e9es? \u00bb, ou encore \u00ab pourquoi sommes-nous sur terre? \u00bb.<\/p>\n<p>Il y a cependant d\u2019autres \u00e9l\u00e9ments communs aux r\u00e9cits de conversion et l\u2019un d\u2019eux est qu\u2019en pareils moments, la personne qui est sur le point de se convertir s\u2019agenouille en toute humilit\u00e9 devant Dieu; et lorsqu\u2019elle y repense, plus tard, elle se rappelle avoir pri\u00e9 avec sinc\u00e9rit\u00e9 pour la toute premi\u00e8re fois de sa vie. J\u2019ai \u00e9t\u00e9 intrigu\u00e9 par ces corr\u00e9lations et j\u2019en ai tir\u00e9 quelques le\u00e7ons qui m\u00e9ritent qu\u2019on s\u2019y arr\u00eate. La premi\u00e8re est que la plupart des convertis qui ont v\u00e9cu des moments d\u2019\u00e9preuve extr\u00eame et de panique ont adress\u00e9 leurs pri\u00e8res directement \u00e0 Dieu sans s\u2019en d\u00e9tourner une seconde, et sans aucun interm\u00e9diaire. Par exemple, lorsqu\u2019ils font face \u00e0 un d\u00e9sastre, m\u00eame ceux qui ont pass\u00e9 leur vie \u00e0 croire \u00e0 la trinit\u00e9 adressent instinctivement leurs pri\u00e8res \u00e0 Dieu et rarement aux autres \u00e9l\u00e9ments de la trinit\u00e9.<\/p>\n<p>L\u2019histoire suivante en est un exemple. Dans son \u00e9mission t\u00e9l\u00e9vis\u00e9e, un \u00e9vang\u00e9liste de renom avait invit\u00e9 une dame pour parler de son histoire de conversion et de sa \u00ab renaissance dans le christianisme \u00bb. L\u2019histoire \u00e9tait centr\u00e9e sur un terrible naufrage duquel elle avait \u00e9t\u00e9 l\u2019unique survivante. Cette dame racontait comment, tout au long des jours et des nuits qu\u2019a dur\u00e9 sa survie parmi des \u00e9l\u00e9ments implacables, en plein milieu de l\u2019oc\u00e9an, Dieu lui parlait, Dieu la guidait, Dieu la prot\u00e9geait etc. Pendant pr\u00e8s de cinq ou dix minutes, elle raconta ce qui lui \u00e9tait arriv\u00e9; c\u2019\u00e9tait effectivement dramatique et captivant, et tout au long de son r\u00e9cit, elle ne manquait pas de dire comment Dieu avait fait ceci et avait fait cela, et comment elle avait implor\u00e9 Sa gr\u00e2ce, comment elle avait pri\u00e9 Dieu et adress\u00e9 ses pri\u00e8res uniquement \u00e0 Lui. Cependant, lorsqu\u2019un navire de passage l\u2019eut rep\u00each\u00e9e, elle d\u00e9crivit comment \u00e0 la minute m\u00eame o\u00f9 elle se retrouva sur le pont du bateau, elle ouvrit grand ses bras vers le ciel et cria : \u00ab Merci, J\u00e9sus. \u00bb<\/p>\n<p>Il y a bien une le\u00e7on, ici, relative \u00e0 la sinc\u00e9rit\u00e9. Dans les moments de panique et de stress, les gens, instinctivement, prient Dieu directement; mais lorsqu\u2019ils se consid\u00e8rent hors de danger et en s\u00e9curit\u00e9, ils reviennent \u00e0 leurs anciens rep\u00e8res religieux, qui les servent mal dans la plupart des cas. Tout le monde sait, bien s\u00fbr, que les chr\u00e9tiens pensent que J\u00e9sus et Dieu ne font qu\u2019un (\u00e0 ceux et celles qui veulent d\u00e9battre de ce point je sugg\u00e8re la lecture de mon livre intitul\u00e9 : The First and Final Commandment (Amana Publications)). Pour tous les autres, je poursuivrai en disant que la vraie question qui se pose est : \u00ab qui est r\u00e9ellement sauv\u00e9? \u00bb Il existe une multitude de r\u00e9cits de convertis, qui racontent tous comment le dieu de telle ou telle religion a sauv\u00e9 la personne en question, et tous ces convertis pensent \u00eatre sur le droit chemin et sur la voie de la v\u00e9rit\u00e9 \u00e0 cause, justement, de leur salut miraculeux.<\/p>\n<p>Mais comme il n\u2019y a qu\u2019un seul et unique Dieu, et par le fait m\u00eame une seule religion bas\u00e9e sur la v\u00e9rit\u00e9 absolue, un seul groupe \u00e0 raison alors que tous les autres vivent dans l\u2019illusion, leurs miracles personnels les ayant confort\u00e9s dans leur incroyance ou les ayant incit\u00e9s \u00e0 devenir m\u00e9cr\u00e9ants plut\u00f4t qu\u2019\u00e0 suivre la religion de v\u00e9rit\u00e9. Dieu nous enseigne ce qui suit dans le Coran :<br \/>\n\u00ab \u2026 En v\u00e9rit\u00e9, Dieu \u00e9gare qui Il veut, et Il guide vers Lui tous ceux qui se repentent&#8230; \u00bb (Coran 13:27)<br \/>\n\u2026 et<\/p>\n<p>\u00ab Alors ceux qui croient en Dieu et s\u2019attachent \u00e0 Lui, Il les fera entrer dans Sa mis\u00e9ricorde et dans Sa gr\u00e2ce, et Il les guidera vers Lui par un chemin droit. \u00bb (Coran 4:175)<\/p>\n<p>Quant \u00e0 ceux qui errent dans l\u2019incroyance, ils seront laiss\u00e9s dans leur \u00e9garement, car tel aura \u00e9t\u00e9 leur choix.<\/p>\n<p>Cependant, la puissance de la foi, m\u00eame la plus corrompue, ne doit pas \u00eatre sous-estim\u00e9e. Qui donc deviendra musulman en lisant mon r\u00e9cit de conversion? Une seule personne \u2013 moi. Les musulmans peuvent trouver un peu d\u2019encouragement dans mon histoire, mais les autres y resteront indiff\u00e9rents, tout comme les musulmans soupirent et hochent la t\u00eate en d\u00e9sespoir lorsqu\u2019ils entendent certains parler de \u00ab miracles \u00bb survenus suite \u00e0 des pri\u00e8res aux saints patrons, \u00e0 des membres de la trinit\u00e9 ou \u00e0 tout autre \u00ab divinit\u00e9 \u00bb invent\u00e9e de toutes pi\u00e8ces pour remplacer l\u2019unique v\u00e9ritable Dieu. Car si une personne adresse ses pri\u00e8res \u00e0 qui que ce soit ou quoi que ce soit d\u2019autre que le Cr\u00e9ateur, qui donc, si ce n\u2019est Dieu, pourrait bien r\u00e9pondre \u00e0 ces pri\u00e8res? Ne pourrait-il pas s\u2019agir de quelqu\u2019un [le diable] qui a un int\u00e9r\u00eat particulier \u00e0 conforter ceux qui s\u2019\u00e9garent dans leur \u00e9garement, et \u00e0 confirmer \u00e0 chaque m\u00e9cr\u00e9ant la saveur particuli\u00e8re de son incroyance? \u00ab Quelqu\u2019un \u00bb qui se consacre enti\u00e8rement \u00e0 \u00e9garer et \u00e0 perdre l\u2019humanit\u00e9?<\/p>\n<p>Quelles que soient les r\u00e9ponses que l\u2019on donne \u00e0 ces questions, ce sont des sujets dont je traite en profondeur dans The First and Final Commandment (Les premier et dernier commandements), et ceux que cela int\u00e9resse peuvent poursuivre leurs recherches. Mais pour l\u2019instant, je vais vous raconter mon histoire.<\/p>\n<h3><\/h3>\n<h3><strong>(partie 2 de 2):<\/strong><\/h3>\n<p>Ma deuxi\u00e8me fille vint au monde durant l\u2019hiver de 1990. Elle fut transf\u00e9r\u00e9e d\u2019urgence de la salle d\u2019accouchement \u00e0 l\u2019unit\u00e9 de soins intensifs du d\u00e9partement de n\u00e9onatologie, o\u00f9 fut diagnostiqu\u00e9e une coarctation de l&rsquo;aorte, c\u2019est-\u00e0-dire un r\u00e9tr\u00e9cissement majeur du canal art\u00e9riel en provenance du c\u0153ur. De la poitrine jusqu\u2019aux orteils, sa peau \u00e9tait de la m\u00eame couleur mate et bleu fonc\u00e9 qu\u2019un canon d\u2019arme \u00e0 feu, car il n\u2019y avait tout simplement pas assez de flux sanguin dans son corps et, n\u2019\u00e9tant pas suffisamment irrigu\u00e9s, ses tissus s\u2019asphyxiaient. Lorsque je pris connaissance du diagnostic, je fus d\u00e9vast\u00e9. \u00c9tant moi-m\u00eame m\u00e9decin, je comprenais que cela voulait dire une chirurgie thoracique d\u2019urgence avec une probabilit\u00e9 tr\u00e8s minime de survie \u00e0 long terme.<\/p>\n<p>On fit appel \u00e0 un sp\u00e9cialiste en chirurgie cardiothoracique du Pediatric Hospital de Washington, D.C., \u00e0 l\u2019autre bout de la ville, et d\u00e8s son arriv\u00e9e, on me demanda de quitter l\u2019unit\u00e9 de soins intensifs (USI), car j\u2019\u00e9tais devenu exag\u00e9r\u00e9ment \u00e9motif. Avec ma crainte comme unique compagnon et ne sachant vers o\u00f9 me tourner pour chercher du r\u00e9confort en attendant les r\u00e9sultats de l\u2019examen du sp\u00e9cialiste, je me dirigeai vers la salle de pri\u00e8res de l\u2019h\u00f4pital o\u00f9 je m\u2019effondrai, \u00e0 genoux. Pour la toute premi\u00e8re fois de ma vie, je priai avec une sinc\u00e9rit\u00e9 r\u00e9elle et un engagement total. J\u2019avais \u00e9t\u00e9 ath\u00e9e toute ma vie et c\u2019\u00e9tait la premi\u00e8re fois que je reconnaissais, m\u00eame de mani\u00e8re partielle, l\u2019existence de Dieu.<\/p>\n<p>Je dis de mani\u00e8re partielle, car m\u00eame en ce moment de panique, je ne croyais pas totalement. J\u2019adressai donc une pri\u00e8re plut\u00f4t sceptique dans laquelle je promis \u00e0 Dieu, si bien s\u00fbr Il existait, que s\u2019Il sauvait ma fille, alors je ferais tous les efforts pour trouver et pratiquer la religion qui Lui plaisait le plus. Dix \u00e0 quinze minutes plus tard, lorsque je retournai \u00e0 l\u2019USI du d\u00e9partement de n\u00e9onatologie, je fus renvers\u00e9 quand le m\u00e9decin sp\u00e9cialiste me dit que finalement, ma fille se portait plut\u00f4t bien. Il disait vrai, car dans les deux jours qui suivirent, l\u2019\u00e9tat de ma fille s\u2019am\u00e9liora sans aucune m\u00e9dication et sans aucun recours \u00e0 la chirurgie, et elle connut par la suite un d\u00e9veloppement tout \u00e0 fait normal et une enfance sans souci.<\/p>\n<p>Je sais bien s\u00fbr qu\u2019il y a une explication m\u00e9dicale \u00e0 tout cela. Je l\u2019ai d\u00e9j\u00e0 dit, je suis m\u00e9decin. Donc quand le sp\u00e9cialiste me parla de persistance du canal art\u00e9riel, de faible oxyg\u00e9nation et de r\u00e9solution finale spontan\u00e9e, je compris. Mais je n\u2019y croyais simplement pas. Et surtout, le sp\u00e9cialiste en r\u00e9animation de l\u2019USI de n\u00e9onatologie, qui avait le premier \u00e9mis le diagnostic, n\u2019y croyait pas non plus. Encore aujourd\u2019hui, je me souviens de lui, debout en face de moi, le visage bl\u00eame et sans voix&#8230; Mais bon, il s\u2019av\u00e9ra que le sp\u00e9cialiste avait raison et ma fille s\u2019\u00e9tait bel et bien r\u00e9tablie spontan\u00e9ment. Hannah quitta l\u2019h\u00f4pital en parfaite sant\u00e9, comparable en tout point aux autres b\u00e9b\u00e9s. Cependant \u2013 et voil\u00e0 le hic \u2013 beaucoup de ceux qui font des promesses \u00e0 Dieu dans des moments de panique se trouvent des excuses ou s\u2019en inventent pour ne pas tenir leur engagement une fois le danger pass\u00e9.<\/p>\n<p>En tant qu\u2019ath\u00e9e, il aurait \u00e9t\u00e9 facile pour moi de maintenir mon rejet de Dieu et d\u2019attribuer la r\u00e9mission de ma fille \u00e0 l\u2019explication du m\u00e9decin plut\u00f4t qu\u2019\u00e0 Dieu. Mais je ne pouvais pas. Nous avions fait faire des \u00e9chocardiographies avant et apr\u00e8s, et le r\u00e9tr\u00e9cissement, clairement visible la veille, avait disparu le lendemain et on ne pouvait m\u2019enlever de la t\u00eate que Dieu avait tenu Sa part de l\u2019engagement et que je me devais de tenir la mienne. Et m\u00eame s\u2019il y avait une explication m\u00e9dicale satisfaisante, cette partie-l\u00e0 aussi \u00e9tait sous le contr\u00f4le de Dieu Tout-Puissant. Donc peu importe le moyen que Dieu avait choisi pour Se manifester, Il avait r\u00e9pondu \u00e0 ma pri\u00e8re. Point final. Aujourd\u2019hui comme alors, je n\u2019accepte aucune autre explication.<\/p>\n<p>Au cours des ann\u00e9es qui suivirent, je tentai de remplir ma part de l\u2019engagement que j\u2019avais pris avec Dieu, mais sans succ\u00e8s. J\u2019\u00e9tudiai le juda\u00efsme et un certain nombre de sectes chr\u00e9tiennes, mais jamais je n\u2019eus le sentiment d\u2019avoir d\u00e9couvert la v\u00e9rit\u00e9. Au fil des ans, je joignis les rangs d\u2019une grande vari\u00e9t\u00e9 d\u2019\u00e9glises chr\u00e9tiennes, passant la plus longue p\u00e9riode au sein d\u2019une congr\u00e9gation catholique romaine. Cependant, je n\u2019embrassai jamais la foi chr\u00e9tienne, pour la simple raison que je ne pouvais concilier les enseignements bibliques de J\u00e9sus avec les enseignements des diverses sectes du christianisme. Finalement, je d\u00e9cidai de rester chez moi et de lire.<\/p>\n<p>C\u2019est durant cette p\u00e9riode que je fis la d\u00e9couverte du Coran et de la biographie du proph\u00e8te Mohammed \u00e9crite par Martin Ling et intitul\u00e9e, Muhammad, His Life Based on the Earliest Sources.<\/p>\n<p>Au cours de mes ann\u00e9es de recherche, j\u2019avais d\u00e9couvert que les \u00e9critures juives faisaient r\u00e9f\u00e9rence \u00e0 trois proph\u00e8tes qui viendraient apr\u00e8s Mo\u00efse. Avec Jean (que les chr\u00e9tiens appellent Jean-le-Baptiste) et J\u00e9sus, cela faisait deux; selon l\u2019Ancien Testament, il en manquait donc un.<\/p>\n<p>Dans le Nouveau Testament, J\u00e9sus lui-m\u00eame mentionne la venue d\u2019un dernier proph\u00e8te. Ce n\u2019est qu\u2019apr\u00e8s avoir d\u00e9couvert les enseignements du Coran \u00e0 propos de l\u2019unicit\u00e9 de Dieu et constat\u00e9 qu\u2019ils \u00e9taient en parfait accord avec ce que Mo\u00efse et J\u00e9sus avaient tous deux enseign\u00e9, et apr\u00e8s avoir lu la biographie de Mohammed que je fus v\u00e9ritablement convaincu. Soudain, tout semblait avoir un sens. La continuit\u00e9 dans la cha\u00eene de proph\u00e9tie et de r\u00e9v\u00e9lation divine, le caract\u00e8re unique et indivisible de Dieu Tout-Puissant et le parach\u00e8vement de la r\u00e9v\u00e9lation par le Coran, toutes les pi\u00e8ces s\u2019imbriquaient parfaitement, et c\u2019est \u00e0 ce moment-l\u00e0 que je devins musulman.<\/p>\n<p>Ainsi donc j\u2019\u00e9tais un petit fut\u00e9? Eh bien pas du tout! Ce serait en effet une grossi\u00e8re erreur de penser que j\u2019avais r\u00e9solu l\u2019\u00e9nigme par moi-m\u00eame. Une des le\u00e7ons que j\u2019ai apprises en tant que musulman, au cours des dix derni\u00e8res ann\u00e9es, est qu\u2019il y a une multitude de personnes qui, bien que beaucoup plus intelligentes que moi, n\u2019ont pas pu comprendre la v\u00e9rit\u00e9 de l\u2019islam. Ce n\u2019est pas une question d\u2019intelligence, mais d\u2019illumination, car Allah nous dit que ceux qui ne croient pas demeureront m\u00e9cr\u00e9ants m\u00eame si on les met en garde; pour les punir d\u2019avoir reni\u00e9 Allah, Allah leur refuse le tr\u00e9sor de Sa v\u00e9rit\u00e9.<\/p>\n<p>Comme Allah nous l\u2019enseigne dans le Coran :<br \/>\n\u00ab Quant aux m\u00e9cr\u00e9ants, que tu les avertisses ou non, cela leur est \u00e9gal : ils ne croiront jamais. Dieu a scell\u00e9 leurs oreilles et leur c\u0153ur et un voile leur couvre la vue\u2026 \u00bb (Coran 2:6-7)<\/p>\n<p>Mais d\u2019un autre c\u00f4t\u00e9, la bonne nouvelle est que:<br \/>\n\u00ab \u2026Quiconque croit en Dieu, Dieu guide son c\u0153ur. \u00bb (Coran 64:11)<br \/>\n\u00ab \u2026Dieu admet qui Il veut au nombre de Ses \u00e9lus, et Il guide vers Lui ceux qui se tournent (en Sa direction). \u00bb (Coran 42:13)<br \/>\n\u00ab \u2026 Et Dieu guide qui Il veut vers le droit chemin. \u00bb (Coran 24:46)<\/p>\n<p>Pour conclure, je remercie Dieu d\u2019avoir choisi de me guider, et j\u2019attribue cela \u00e0 une formule unique et toute simple : reconna\u00eetre que Dieu existe, n\u2019adresser ses pri\u00e8res qu\u2019\u00e0 Lui exclusivement, promettre avec sinc\u00e9rit\u00e9 de suivre Sa religion de v\u00e9rit\u00e9, et enfin, lorsqu\u2019on est guid\u00e9 de par Sa gr\u00e2ce, TENIR SA PROMESSE.<\/p>\n<p>Tous droits r\u00e9serv\u00e9s \u00a9 2007 Laurence B. Brown; utilisation permise.<\/p>\n<p>\u00c0 propos de l\u2019auteur.<\/p>\n<p>Laurence B. Brown, MD, peut \u00eatre contact\u00e9 \u00e0 BrownL38@yahoo.com Il est l\u2019auteur de The First and Final Commandment (Amana Publications) etBearing True Witness (Dar-us-Salam). Il travaille pr\u00e9sentement sur un livre \u00e0 suspense historique, The Eighth Scroll, et sur une seconde \u00e9dition de The First and Final Commandment, compl\u00e8tement revue et corrig\u00e9e, divis\u00e9e enMisGod&rsquo;ed et sa deuxi\u00e8me partie, God\u2019ed.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/laurence-brown-mdecin-tats-unis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(partie 1 de 2) Ayant eu \u00e0 expliquer \u00e0 de nombreuses reprises ce qui m\u2019avait amen\u00e9 \u00e0 devenir musulman, j\u2019ai d\u00e9cid\u00e9 de relater le r\u00e9cit de ma conversion une derni\u00e8re fois, mais par \u00e9crit. Toutefois, je consid\u00e8re qu\u2019\u00e0 moins d\u2019en tirer les le\u00e7ons qui s\u2019imposent, les histoires de conversion sont inutiles. Je compte donc commencer &#8230; <a title=\"Laurence Brown, m\u00e9decin, \u00c9tats-Unis\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/laurence-brown-medecin-etats-unis\/\" aria-label=\"Read more about Laurence Brown, m\u00e9decin, \u00c9tats-Unis\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7677","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":1,"uagb_excerpt":"(partie 1 de 2) Ayant eu \u00e0 expliquer \u00e0 de nombreuses reprises ce qui m\u2019avait amen\u00e9 \u00e0 devenir musulman, j\u2019ai d\u00e9cid\u00e9 de relater le r\u00e9cit de ma conversion une derni\u00e8re fois, mais par \u00e9crit. Toutefois, je consid\u00e8re qu\u2019\u00e0 moins d\u2019en tirer les le\u00e7ons qui s\u2019imposent, les histoires de conversion sont inutiles. Je compte donc commencer\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1ZP","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7677,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7677,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7677,"position":2},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8660,"url":"https:\/\/www.ask-a-muslim.com\/de\/reverend-david-benjamin-keldani-katholischer-priester-rumaenien\/","url_meta":{"origin":7677,"position":3},"title":"Reverend David Benjamin Keldani, katholischer Priester, Rum\u00e4nien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Auf die Frage, wie er zum Islam gekommen war, schrieb er: \u201cMeine Konvertierung zum Islam kann man keinem anderen Grund zuordnen, als der gn\u00e4digen Rechtleitung Allahs, des Allm\u00e4chtigen. Ohne diese G\u00f6ttliche Leitung kann einen jedes Lernen, Suchen und andere Anstrengungen, die Wahrheit zu finden, sogar in die Irre f\u00fchren. Von\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8647,"url":"https:\/\/www.ask-a-muslim.com\/de\/aysha-ex-katholikin-ungarn\/","url_meta":{"origin":7677,"position":4},"title":"Aysha, Ex-Katholikin, Ungarn","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Mein Name ist Aysha, and ich komme aus dem Norden Ungarns. Mein Interesse am Islam begann mit dem Geschichtsunterricht, als wir in der Mittelschule lernten, dass Ungarn 150 Jahre lang zum ottomanischen Reich geh\u00f6rt hatte. Mein Interesse verst\u00e4rkte sich, als ich an meiner Universit\u00e4t Muslime traf. Ich belegte Molekularbiologie und\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8603,"url":"https:\/\/www.ask-a-muslim.com\/de\/akifah-baxter-ex-christin-usa\/","url_meta":{"origin":7677,"position":5},"title":"Akifah Baxter, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich war mir der Existenz Gottes immer bewu\u00dft. Ich habe immer gef\u00fchlt, dass Er da ist. Manchmal war das Gef\u00fchl etwas entfernt, und oft habe ich es ignoriert. Aber ich konnte dieses Wissen nie leugnen. Aus diesem Grund habe ich mich mein ganzes Leben lang damit besch\u00e4ftigt, nach der Wahrheit\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7677"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7677\/revisions"}],"predecessor-version":[{"id":11283,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7677\/revisions\/11283"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}