{"id":7679,"date":"2020-06-17T02:23:35","date_gmt":"2020-06-17T07:23:35","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7679"},"modified":"2020-07-02T06:15:10","modified_gmt":"2020-07-02T11:15:10","slug":"peter-sanders-photographe-royaume-uni","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/peter-sanders-photographe-royaume-uni\/","title":{"rendered":"Peter Sanders, photographe, Royaume-Uni"},"content":{"rendered":"<p>Peter Sanders est n\u00e9 \u00e0 Londres en 1946. Il d\u00e9bute sa carri\u00e8re professionnelle vers le milieu des ann\u00e9es soixante, \u00e9poque o\u00f9 il photographe la plupart des grandes stars du moment dont Bob Dylan, Jimi Hendrix, The Doors, The Who et les Rolling Stones. Vers la fin des ann\u00e9es soixante, il se met \u00e0 r\u00e9fl\u00e9chir sur sa vie et son destin; il entame alors une qu\u00eate spirituelle qui l\u2019am\u00e8ne d\u2019abord en Inde, puis dans le monde musulman, o\u00f9 la beaut\u00e9 spirituelle de l\u2019islam laisse chez lui une impression ind\u00e9l\u00e9bile. De retour en Angleterre, il d\u00e9cide d\u2019embrasser l\u2019islam et adopte le nom d\u2019Abd al-Adhim. En 1971, on lui accorde une permission unique de photographier les p\u00e8lerins lors des rituels du Hajj (p\u00e8lerinage annuel des musulmans \u00e0 la Mecque). Ces images rares sont publi\u00e9es dans le Sunday Times Magazine et The Observer, parmi plusieurs autres grands journaux et magazines.<\/p>\n<p>Pour Peter Sanders, la foi et la photographie ont toujours fait partie de son d\u00e9veloppement spirituel. C\u2019est sa tentative de saisir l\u2019essence m\u00eame de la r\u00e9alit\u00e9 qui l\u2019a amen\u00e9 vers l\u2019islam et, cam\u00e9ra \u00e0 la main, vers la porte de la Ka\u2019aba. Des photographies de rock stars \u00e0 celles des lieux les plus sacr\u00e9s du monde musulman, le cheminement et la carri\u00e8re de Peter Sanders ont connu des virages majeurs.<\/p>\n<p>\u00ab J\u2019arrivai \u00e0 un point o\u00f9 j\u2019avais photographi\u00e9 \u00e0 peu pr\u00e8s toutes les stars de l\u2019industrie de la musique; je m\u2019ennuyais et je d\u00e9cidai d\u2019entreprendre une qu\u00eate spirituelle. Je cherchais un plus \u00e0 ma vie et je partis pour l\u2019Inde, \u00e0 la recherche d\u2019une personne qui puisse me guider. Je trouvai cette personne; il s\u2019agissait d\u2019un hindou qui poss\u00e9dait plusieurs de ce qu\u2019on appelle les \u00ab qualit\u00e9s musulmanes \u00bb. J\u2019\u00e9tudiai avec lui durant pr\u00e8s de six mois et lorsque je revins en Angleterre, je d\u00e9couvris que quelques-uns de mes amis s\u2019\u00e9taient convertis \u00e0 l\u2019islam. J\u2019appris \u00e9galement que certains autres \u00e9taient tomb\u00e9s dans l\u2019enfer de la drogue et de l\u2019alcool. C\u2019\u00e9tait comme si Dieu me demandait : \u00ab Et toi : quelle direction souhaites-tu prendre? \u00bb.<\/p>\n<p>\u00ab Je ne connaissais pas grand\u2019chose \u00e0 l\u2019islam, mais je fis l\u2019exp\u00e9rience de certains r\u00eaves et des choses \u00e9tranges m\u2019arriv\u00e8rent. Lorsque je pris la d\u00e9cision de devenir musulman, je n\u2019\u00e9tais pas tr\u00e8s inform\u00e9 sur l\u2019islam. J\u2019avais 24 ans, \u00e0 l\u2019\u00e9poque, et trois mois apr\u00e8s ma conversion, je d\u00e9cidai d\u2019aller faire le Hajj. Je n\u2019en avais pas les moyens, mais l\u2019intention seulement. L\u2019homme \u00e2g\u00e9 qui m\u2019enseignait l\u2019islam \u00e0 ce moment-l\u00e0 en avait \u00e9galement l\u2019intention. Puis, quelqu\u2019un m\u2019offrit un billet en cadeau; je pus donc y aller. C\u2019est devant la Ka\u2019aba que j\u2019appris que celui qui m\u2019enseignait \u00e9tait d\u00e9c\u00e9d\u00e9 alors qu\u2019il se rendait lui aussi \u00e0 la Mecque. \u00bb<\/p>\n<p>En 1971, les photographes \u00e9taient tr\u00e8s rarement admis au Hajj. Mais Peter Sanders re\u00e7ut une permission sp\u00e9ciale dont il s\u2019\u00e9tonne encore aujourd\u2019hui. \u00ab C\u2019\u00e9tait une occasion unique pour un Occidental que de pouvoir prendre des photos du Hajj. J\u2019ai d\u00fb faire preuve de d\u00e9termination et me pr\u00e9senter de bureaux en bureaux, \u00e0 Jeddah et \u00e0 la Mecque, jusqu\u2019\u00e0 ce que je trouve un homme dont l\u2019autorit\u00e9 lui permettait de m\u2019accorder cette permission. Nombreux furent ceux qui refus\u00e8rent de prendre la responsabilit\u00e9 de m\u2019accorder cette permission. De toute fa\u00e7on, d\u2019une mani\u00e8re g\u00e9n\u00e9rale, la plupart n\u2019\u00e9taient pas particuli\u00e8rement d\u2019accord avec le principe m\u00eame de la photographie, surtout si elle \u00e9tait faite par un converti. Mais cet homme \u00e9tait en position de m\u2019accorder l\u2019autorisation et, sans vraiment me conna\u00eetre, il m\u2019a aussi accord\u00e9 sa confiance. \u00bb<\/p>\n<p>Pour Peter Sanders, la photographie est essentiellement un moyen de capturer sur pellicule l\u2019esprit de l\u2019islam. Alors qu\u2019il nous d\u00e9crit ses efforts en ce sens, les paroles d\u2019un po\u00e8te ourdou nous reviennent \u00e0 l\u2019esprit : \u00ab Pour saisir la r\u00e9alit\u00e9 de M\u00e9dine, tu as besoin de plus que tes yeux; tu as besoin de vision. \u00bb Comme si poss\u00e9der cette vision ne lui suffisait pas, Peter Sanders cherche \u00e0 la transmettre aux autres. Il a pass\u00e9 les trente derni\u00e8res ann\u00e9es \u00e0 photographier et documenter ce qui reste des soci\u00e9t\u00e9s islamiques traditionnelles, car elles disparaissent de la surface de la terre \u00e0 un rythme effarant. L\u2019un de ses projets actuels consiste d\u2019ailleurs \u00e0 compiler des albums contenant les photos des grands \u00e9rudits musulmans de notre \u00e9poque. Les deux volumes, pour la publication desquels il esp\u00e8re collecter suffisamment de fonds, comprennent des photographies de gens qui n\u2019avaient jamais \u00e9t\u00e9 photographi\u00e9s auparavant, et d\u2019autres de gens qui nous ont quitt\u00e9 au cours des derni\u00e8res ann\u00e9es ou des derniers mois.<\/p>\n<h4><\/h4>\n<h4><strong>Au sujet de Peter Sanders<\/strong><\/h4>\n<p>Peter Sanders est reconnu au niveau international comme l\u2019un des plus grands photographes du monde musulman.<\/p>\n<p>Il a d\u00e9but\u00e9 sa carri\u00e8re au milieu des ann\u00e9es 60 sur la sc\u00e8ne musicale rock de Londres, photographiant plusieurs stars l\u00e9gendaires et compilant leurs photos dans un album consid\u00e9r\u00e9 comme un classique par les collectionneurs.<\/p>\n<p>Vers la fin des ann\u00e9es soixante, il se mit \u00e0 r\u00e9fl\u00e9chir sur sa vie et son destin; il entama une qu\u00eate spirituelle qui l\u2019amena d\u2019abord en Inde, puis dans le monde musulman. Durant ses voyages, le photographe prit de nombreux clich\u00e9s des derniers vestiges des soci\u00e9t\u00e9s islamiques traditionnelles allant doucement vers leur d\u00e9clin. L\u2019int\u00e9r\u00eat personnel de Sanders et son amour profond pour la culture islamique traditionnelle l\u2019ont amen\u00e9 \u00e0 entrer en contact \u00e9troit avec des gens et des lieux que tr\u00e8s peu de photographes ont pu atteindre.<\/p>\n<p>\u00ab Mon \u0153uvre a toujours \u00e9t\u00e9 comme un prolongement de ma vie \u00bb, dit-il. \u00ab La photographie est un merveilleux processus \u2013 un cadeau de Dieu \u2013 qui m\u2019a permis d\u2019apprendre \u00e9norm\u00e9ment sur moi-m\u00eame et sur le monde qui m\u2019entoure. C\u2019est comme si je me lan\u00e7ais \u00e0 la poursuite de l\u2019instant, comme lorsque je tente d\u2019immortaliser un oiseau en plein vol. \u00bb \u00ab Ses photos sont extraordinairement belles \u00bb, affirme pour sa part le critique d\u2019art Tsuyoshi Kawasoe.<\/p>\n<p>\u00ab Nul ne doit sous-estimer l\u2019importance de l\u2019\u0153uvre de Peter Sanders \u00bb, affirme quant \u00e0 lui l\u2019\u00e9crivain am\u00e9ricain Michael Sugich. \u00ab De nos jours, il est le seul photographe qui a, de fa\u00e7on syst\u00e9matique et avec un grand d\u00e9vouement, couvert la plupart des r\u00e9gions du monde islamique en tant que membre de cette communaut\u00e9 internationale. Gr\u00e2ce \u00e0 sa compr\u00e9hension de la culture islamique et \u00e0 son irr\u00e9prochable courtoisie, il a \u00e9t\u00e9 en mesure de photographier des endroits et des gens auxquels nul photographe occidental ne pourrait jamais avoir acc\u00e8s. Il laissera derri\u00e8re lui un t\u00e9moignage splendide, po\u00e9tique et ind\u00e9l\u00e9bile d\u2019une \u00e9poque extraordinaire et d\u2019une culture fascinante d\u2019une grande richesse. \u00bb<\/p>\n<p>On a \u00e9galement dit de Peter Sanders qu\u2019il \u00ab sait capturer la beaut\u00e9 spirituelle de la cr\u00e9ation. \u00bb<\/p>\n<p>Les photos de Peter Sanders ont \u00e9t\u00e9 publi\u00e9es par de nombreuses publications internationales, dont le Time Magazine, Paris Match, The Observer, The Sunday Times Magazine, Aramco World et le magazine panarabe bas\u00e9 \u00e0 Londres, Al-Majalla, qui a publi\u00e9 certaines de ses \u0153uvres en page couverture.<\/p>\n<p>Ses photos intimistes des deux villes sacr\u00e9es de la Mecque et de M\u00e9dine sont tr\u00e8s en demande.<\/p>\n<p>Peter Sanders Photography Limited inclut des photos de voyage, de m\u00eame que des photos d\u2019ext\u00e9rieur et de studio, soit une collection de plus de 120 000 clich\u00e9s. La compagnie fait \u00e9galement dans les \u00e9preuves artistiques.<\/p>\n<p>Enfin, Peter Sanders a produit un livre intitul\u00e9 \u00ab In the Shade of the Tree \u00bb, une odyss\u00e9e photographique du monde musulman.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/peter-sanders-photographe-royaume-uni<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peter Sanders est n\u00e9 \u00e0 Londres en 1946. Il d\u00e9bute sa carri\u00e8re professionnelle vers le milieu des ann\u00e9es soixante, \u00e9poque o\u00f9 il photographe la plupart des grandes stars du moment dont Bob Dylan, Jimi Hendrix, The Doors, The Who et les Rolling Stones. Vers la fin des ann\u00e9es soixante, il se met \u00e0 r\u00e9fl\u00e9chir sur &#8230; <a title=\"Peter Sanders, photographe, Royaume-Uni\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/peter-sanders-photographe-royaume-uni\/\" aria-label=\"Read more about Peter Sanders, photographe, Royaume-Uni\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7679","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"Peter Sanders est n\u00e9 \u00e0 Londres en 1946. Il d\u00e9bute sa carri\u00e8re professionnelle vers le milieu des ann\u00e9es soixante, \u00e9poque o\u00f9 il photographe la plupart des grandes stars du moment dont Bob Dylan, Jimi Hendrix, The Doors, The Who et les Rolling Stones. Vers la fin des ann\u00e9es soixante, il se met \u00e0 r\u00e9fl\u00e9chir sur\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1ZR","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7679,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7679,"position":1},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8660,"url":"https:\/\/www.ask-a-muslim.com\/de\/reverend-david-benjamin-keldani-katholischer-priester-rumaenien\/","url_meta":{"origin":7679,"position":2},"title":"Reverend David Benjamin Keldani, katholischer Priester, Rum\u00e4nien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Auf die Frage, wie er zum Islam gekommen war, schrieb er: \u201cMeine Konvertierung zum Islam kann man keinem anderen Grund zuordnen, als der gn\u00e4digen Rechtleitung Allahs, des Allm\u00e4chtigen. Ohne diese G\u00f6ttliche Leitung kann einen jedes Lernen, Suchen und andere Anstrengungen, die Wahrheit zu finden, sogar in die Irre f\u00fchren. Von\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8672,"url":"https:\/\/www.ask-a-muslim.com\/de\/kommentare-der-wissenschaftler-ueber-die-wissenschaftlichen-wunder-im-heiligen-quran\/","url_meta":{"origin":7679,"position":3},"title":"Kommentare der Wissenschaftler \u00fcber die wissenschaftlichen Wunder im Heiligen Quran","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Es folgen einige Kommentare von Wissenschaftlern[1] \u00fcber die wissenschaftlichen Wunder im Heiligen Quran. All diese Kommentare wurden von der Videoaufnahme Dies ist die Wahrheit \u00fcbernommen. In dieser Videoaufnahme kann man die Wissenschaftler h\u00f6ren und sehen, die sich folgenderma\u00dfen \u00e4u\u00dferten. (Um das RealPlayer-Video f\u00fcr einen Kommentar zu sehen, klicken Sie auf\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8492,"url":"https:\/\/www.ask-a-muslim.com\/de\/prophezeiungen-des-quran-die-sich-an-muhammad-wenden\/","url_meta":{"origin":7679,"position":4},"title":"Prophezeiungen des Quran, die sich an Muhammad wenden","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Betreten von Mekkas Heiliger Moschee (al-Mas\u011fid al-Haram) Im sechsten Jahr nachdem der Prophet, Gottes Segen und Frieden seien auf ihm, gezwungen war, von Mekka nach Medina auszuwandern, sah er sich selbst Mekka besuchen und die Pilgerfahrt verrichten. Diese Vision erw\u00e4hnt auch der Qur\u00b4an:. \u201cWahrlich, Gott hat Seinem Gesandten das Traumgesicht\u2026","rel":"","context":"Dans &quot;MUHAMMAD, FRIEDE SEI AUF IHM&quot;","block_context":{"text":"MUHAMMAD, FRIEDE SEI AUF IHM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/muhammad-friede-sei-auf-ihm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8673,"url":"https:\/\/www.ask-a-muslim.com\/de\/das-wunder-des-eisens\/","url_meta":{"origin":7679,"position":5},"title":"Das Wunder des Eisens","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Eisen ist eines der Elemente, die im Quran hervorgehoben werden. In dem Kapitel Al-Hadeed, das bedeutet Eisen, werden wir belehrt: \u201cUnd wir haben das Eisen herabkommen lassen. In ihm ist starke Gewalt und Nutzen f\u00fcr die Menschen...\u201d (Quran 57:25) Das Wort \u201canzalna,\u201d als \u201cherabkommen lassen\u201d \u00fcbersetzt und in dem Vers\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7679"}],"version-history":[{"count":3,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7679\/revisions"}],"predecessor-version":[{"id":11279,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7679\/revisions\/11279"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}