{"id":7680,"date":"2020-06-17T02:23:35","date_gmt":"2020-06-17T07:23:35","guid":{"rendered":"https:\/\/www.ask-a-muslim.com\/?p=7680"},"modified":"2020-07-02T06:14:29","modified_gmt":"2020-07-02T11:14:29","slug":"sara-bokker-ancienne-actrice-et-mannequin-usa","status":"publish","type":"post","link":"https:\/\/www.ask-a-muslim.com\/fr\/sara-bokker-ancienne-actrice-et-mannequin-usa\/","title":{"rendered":"Sara Bokker, ancienne actrice et mannequin, USA"},"content":{"rendered":"<p>Je suis une Am\u00e9ricaine, n\u00e9e au c\u0153ur des \u00c9tats-Unis. J\u2019ai grandi comme la plupart des filles d\u2019ici, obs\u00e9d\u00e9e par l\u2019envie de conna\u00eetre la vie tr\u00e9pidante de la \u00ab grande ville \u00bb. Un jour, je d\u00e9m\u00e9nageai donc en Floride, puis \u00e0 South Beach, \u00e0 Miami, le point chaud de ceux qui cherchent \u00e0 vivre \u00ab \u00e0 fond \u00bb, \u00e0 un rythme effr\u00e9n\u00e9 et palpitant. \u00c9videmment, je fis ce que font la plupart des filles de mon \u00e2ge, en Am\u00e9rique du Nord. Ma pr\u00e9occupation premi\u00e8re r\u00e9sidait dans mon apparence et mon sex-appeal, fondant ma valeur personnelle et ma fiert\u00e9 sur l\u2019attention que je recevais des gens en g\u00e9n\u00e9ral.<\/p>\n<p>Je m\u2019entra\u00eenais rigoureusement et je devins professeur de conditionnement physique. J\u2019achetai une luxueuse r\u00e9sidence au bord de la mer, me mis \u00e0 fr\u00e9quenter r\u00e9guli\u00e8rement les plages, exhibant fi\u00e8rement mon corps, bref, je menais la grande vie.<\/p>\n<p>Les ann\u00e9es pass\u00e8rent et je r\u00e9alisai que plus je me concentrais sur mes atours f\u00e9minins, moins je me sentais heureuse et moins j\u2019\u00e9tais satisfaite de ma vie. J\u2019\u00e9tais esclave de la mode, j\u2019\u00e9tais prise en otage par mon apparence physique.<\/p>\n<p>Comme l\u2019\u00e9cart entre mon mode de vie et mon bonheur personnel progressait, je me r\u00e9fugiai d\u2019abord dans l\u2019alcool et les f\u00eates, puis dans la m\u00e9ditation, l\u2019activisme et les religions alternatives, ce qui, en fait, ne fit que progresser encore cet \u00e9cart; ce dernier me sembla soudain aussi vaste qu\u2019une vall\u00e9e profonde. Je compris que tous ces refuges ne servaient qu\u2019\u00e0 me distraire de ma r\u00e9alit\u00e9 sans soulager mon malaise profond.<\/p>\n<p>En tant que f\u00e9ministe libertaire et activiste cherchant \u00e0 rendre le monde meilleur pour tous, mon chemin croisa celui d\u2019un autre activiste d\u00e9j\u00e0 connu dans le domaine de la r\u00e9forme et de la justice sociales. Je me joignis aux campagnes de mon nouveau mentor, dont certaines exigeaient des r\u00e9formes \u00e9lectorales ou le respect de certains droits civiques, entre autres. Mon activisme se transformait; maintenant, plut\u00f4t que de demander justice de fa\u00e7on s\u00e9lective, je d\u00e9couvrais que des id\u00e9aux comme la justice, la libert\u00e9 et le respect revenaient de droit \u00e0 chaque \u00eatre humain et que les int\u00e9r\u00eats personnels et les int\u00e9r\u00eats communs ne s\u2019opposaient pas n\u00e9cessairement. Pour la premi\u00e8re fois, je comprenais r\u00e9ellement ce que signifiait l\u2019expression \u00ab tous sont cr\u00e9\u00e9s \u00e9gaux \u00bb. Mais surtout, j\u2019apprenais que pour voir le monde de fa\u00e7on globale et pour percevoir l\u2019unit\u00e9 dans la cr\u00e9ation, il ne suffisait que d\u2019avoir la foi.<\/p>\n<p>Un jour, je tombai sur un livre g\u00e9n\u00e9ralement mal vu en Occident : le Coran. Jusqu\u2019\u00e0 ce moment, j\u2019avais toujours vaguement associ\u00e9 l\u2019islam \u00e0 des femmes recouvertes d\u2019une \u00ab tente \u00bb, \u00e0 des batteurs de femmes, \u00e0 des harems et au terrorisme. Mais je fus s\u00e9duite, tout d\u2019abord, par le style et par l\u2019approche du Coran, puis par sa vision de l\u2019existence, de la cr\u00e9ation et de la relation entre le Cr\u00e9ateur et Sa cr\u00e9ation. Je trouvai que le Coran s\u2019adressait au plus profond de mon c\u0153ur et de mon \u00e2me sans que j\u2019eus besoin d\u2019interpr\u00e8te ou de clerg\u00e9 pour le comprendre.<\/p>\n<p>Puis, je connus un moment de v\u00e9rit\u00e9 : mon nouvel activisme se transforma en conversion \u00e0 l\u2019islam, mode de vie au sein duquel je sentis que je pouvais vivre en paix, en tant que musulmane pratiquante.<\/p>\n<p>J\u2019achetai une jolie robe longue et un foulard semblables \u00e0 ceux que portent les musulmanes et j\u2019allai me promener, ainsi v\u00eatue, sur ces m\u00eames rues et dans ces m\u00eames quartiers o\u00f9, \u00e0 peine quelques jours auparavant, j\u2019avais d\u00e9ambul\u00e9 en shorts, en bikini ou en \u00ab \u00e9l\u00e9gant \u00bb tailleur. Bien que les gens, les visages et les commerces crois\u00e9s fussent les m\u00eames, une chose \u00e9tait, elle, bien diff\u00e9rente : la paix intense que je ressentais, en tant que femme, pour la toute premi\u00e8re fois. Je sentis que je venais de briser mes cha\u00eenes, que j\u2019\u00e9tais enfin libre. Je me d\u00e9lectais du regard \u00e9tonn\u00e9 des gens, qui avait remplac\u00e9 les regards de convoitise que j\u2019avais tant recherch\u00e9s par le pass\u00e9. Un poids venait de quitter mes \u00e9paules. Je cessai de perdre mon temps \u00e0 faire du shopping, \u00e0 choisir de nouvelles nuances de maquillage, \u00e0 me faire coiffer et \u00e0 m\u2019\u00e9reinter au gym. Enfin, j\u2019\u00e9tais libre.<\/p>\n<p>Puis, retentirent aux nouvelles et dans les journaux les voix de politiciens, d\u2019hommes du clerg\u00e9, de libertaires et de pr\u00e9tendus militants des droits de l\u2019homme condamnant le hijab (foulard) des musulmanes comme opprimant, l\u2019accusant d\u2019\u00eatre un obstacle \u00e0 l\u2019int\u00e9gration sociale et, plus r\u00e9cemment, un politicien \u00e9gyptien en a parl\u00e9 comme d\u2019un \u00ab signe d\u2019arri\u00e9ration \u00bb.<\/p>\n<p>Je trouve profond\u00e9ment hypocrite que de pr\u00e9tendus militants des droits de l\u2019homme s\u2019empressent de d\u00e9fendre les droits des femmes lorsque certains gouvernements cherchent \u00e0 imposer un code vestimentaire modeste et que ces m\u00eames personnes fassent semblant de ne rien voir lorsque des femmes sont priv\u00e9es de leurs droits civiques, de leur droit d\u2019acc\u00e8s \u00e0 l\u2019emploi et \u00e0 l\u2019\u00e9ducation uniquement parce qu\u2019elles choisissent de porter le hijab.<\/p>\n<p>Aujourd\u2019hui, je suis toujours f\u00e9ministe, mais une f\u00e9ministe musulmane qui appelle les musulmanes \u00e0 assumer leurs responsabilit\u00e9s en apportant tout le soutien dont elles sont capables \u00e0 leur mari afin que ces derniers soient de bons musulmans; en \u00e9levant leurs enfants dans l\u2019islam afin que les musulmans redeviennent les phares de l\u2019humanit\u00e9; en invitant les gens au bien et en les d\u00e9tournant du mal; en ne disant que la v\u00e9rit\u00e9 et en osant parler contre tous les maux; en se battant pour le droit au port du hijab et en faisant tout pour plaire \u00e0 leur Cr\u00e9ateur. Et il est tout aussi important que nous, femmes musulmanes, parlions de notre exp\u00e9rience de femmes voil\u00e9es aux autres femmes qui n\u2019ont pas encore compris ce que cela signifie pour nous et la raison pour laquelle le respect de ce code vestimentaire est si cher \u00e0 notre c\u0153ur.<\/p>\n<p>Qu\u2019elles le veuillent ou non, les femmes sont bombard\u00e9es d\u2019images de mode sur lesquelles les mannequins ne portent pratiquement rien et ce, dans tous les m\u00e9dias, partout dans le monde. En tant qu\u2019ancienne non-musulmane, j\u2019insiste sur le droit qu\u2019ont les femmes de conna\u00eetre le hijab, ses vertus, de m\u00eame que la paix et le bonheur qu\u2019il apporte dans la vie d\u2019une femme, comme ce fut le cas pour moi. Hier encore, le bikini \u00e9tait le symbole de ma libert\u00e9 alors qu\u2019en r\u00e9alit\u00e9, il ne me \u00ab lib\u00e9rait \u00bb que de ma spiritualit\u00e9 et des vraies valeurs que j\u2019aurais d\u00fb avoir en tant qu\u2019\u00eatre humain.<\/p>\n<p>Je ne pourrais \u00eatre plus heureuse d\u2019avoir abandonn\u00e9 mon bikini de South Beach et la vie \u00ab tr\u00e9pidante \u00bb que je menais pour vivre en paix avec mon Cr\u00e9ateur et go\u00fbter au bonheur de vivre parmi les gens en toute dignit\u00e9.<\/p>\n<p>De nos jours, le hijab est le nouveau symbole de la lib\u00e9ration de la femme, qui l\u2019aide \u00e0 comprendre qui elle est r\u00e9ellement, la raison de son existence et le genre de lien qu\u2019elle choisit d\u2019avoir avec son Cr\u00e9ateur.<\/p>\n<p>Aux femmes qui acceptent les st\u00e9r\u00e9otypes v\u00e9hicul\u00e9s contre le code vestimentaire modeste encourag\u00e9 par l\u2019islam, je dis : vous ne savez pas ce que vous manquez.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Source: https:\/\/www.islamland.com\/fre\/articles\/sara-bokker-ancienne-actrice-et-mannequin-usa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je suis une Am\u00e9ricaine, n\u00e9e au c\u0153ur des \u00c9tats-Unis. J\u2019ai grandi comme la plupart des filles d\u2019ici, obs\u00e9d\u00e9e par l\u2019envie de conna\u00eetre la vie tr\u00e9pidante de la \u00ab grande ville \u00bb. Un jour, je d\u00e9m\u00e9nageai donc en Floride, puis \u00e0 South Beach, \u00e0 Miami, le point chaud de ceux qui cherchent \u00e0 vivre \u00ab \u00e0 &#8230; <a title=\"Sara Bokker, ancienne actrice et mannequin, USA\" class=\"read-more\" href=\"https:\/\/www.ask-a-muslim.com\/fr\/sara-bokker-ancienne-actrice-et-mannequin-usa\/\" aria-label=\"Read more about Sara Bokker, ancienne actrice et mannequin, USA\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[130],"tags":[],"class_list":["post-7680","post","type-post","status-publish","format-standard","hentry","category-pourquoi-suis-je-devenu-musulman"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Site Admin","author_link":"https:\/\/www.ask-a-muslim.com\/fr\/author\/admin2\/"},"uagb_comment_info":0,"uagb_excerpt":"Je suis une Am\u00e9ricaine, n\u00e9e au c\u0153ur des \u00c9tats-Unis. J\u2019ai grandi comme la plupart des filles d\u2019ici, obs\u00e9d\u00e9e par l\u2019envie de conna\u00eetre la vie tr\u00e9pidante de la \u00ab grande ville \u00bb. Un jour, je d\u00e9m\u00e9nageai donc en Floride, puis \u00e0 South Beach, \u00e0 Miami, le point chaud de ceux qui cherchent \u00e0 vivre \u00ab \u00e0\u2026","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcT0IL-1ZS","jetpack-related-posts":[{"id":8549,"url":"https:\/\/www.ask-a-muslim.com\/de\/jermaine-jackson-usa\/","url_meta":{"origin":7680,"position":0},"title":"Jermaine Jackson, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"(teil 1 von 2) \u00a0 Wann und wie begann ihre Reise zum Islam? Es war 1989 als ich gemeinsam mit meiner Schwester eine Tour durch mehrere L\u00e4nder des Mittleren Osten unternahm. W\u00e4hrend unseres Aufenthalts in Bahrain wurden wir sehr herzlich empfangen. Dort hatte ich Gelegenheit, ein paar Kinder zu treffen\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8622,"url":"https:\/\/www.ask-a-muslim.com\/de\/la-bianca-ex-christin-australien\/","url_meta":{"origin":7680,"position":1},"title":"La Bianca, Ex-Christin, Australien","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Dieser Artikel hat ein Interview mit Sandra La Bianca zur Grundlage, einer konvertierten Muslima, die in Perth, Westaustralien lebt. La Bianca ist ein M\u00e4dchen vom Lande; sie ist auf einer Farm in Westaustralien aufgewachsen. Als sie noch ein Kind gewesen ist, hatte sie ein K\u00e4nguru als Haustier und half bei\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8643,"url":"https:\/\/www.ask-a-muslim.com\/de\/latasha-ex-christin-usa\/","url_meta":{"origin":7680,"position":2},"title":"Latasha, Ex-Christin, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Ich bin Amerikanerin, die in einer streng religi\u00f6sen christlichen Familie aufgewachsen ist. W\u00e4hrend der Zeit, als ich 16 wurde, wurde ich selbst sehr fromm und religi\u00f6s. Die Kirche war wie ein Heim weit entfernt von zuhause. Ich genoss sie von Grund auf. Ich hatte die Bibel regelm\u00e4\u00dfig gelesen und studiert.\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8688,"url":"https:\/\/www.ask-a-muslim.com\/de\/respirationsapparat-ist-ausser-betrieb-in-hochluftschichten\/","url_meta":{"origin":7680,"position":3},"title":"RESPIRATIONSAPPARAT IST AUSSER BETRIEB IN HOCHLUFTSCHICHTEN","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den Islam. Und wen Er irref\u00fchren will, dem macht Er die Brust beklommen und bedr\u00fcckt, so als ob er in den Himmel hoch steigen w\u00fcrde Allah, der Erhabene sagt: \"Wen Gott rechtleiten will, dem weitet Er die Brust f\u00fcr den\u2026","rel":"","context":"Dans &quot;WISSENSCHAFTLICHE WUNDER&quot;","block_context":{"text":"WISSENSCHAFTLICHE WUNDER","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/wissenschaftliche-wunder\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8571,"url":"https:\/\/www.ask-a-muslim.com\/de\/musa-caplan-ex-jude-usa\/","url_meta":{"origin":7680,"position":4},"title":"Musa Caplan, Ex-Jude, USA","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Vor meiner Konvertierung zum Islam lebte ich mein Leben als Jude. Obwohl meine Familie nicht traditionell war, lernte ich das Judentum von traditionellen Juden. Ich ging zu einer orthodoxen j\u00fcdischen Synagoge und zu einer orthodoxen j\u00fcdischen Schule. Ich lebte und lebe immer noch in einer j\u00fcdischen Gemeinde in den USA,\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8576,"url":"https:\/\/www.ask-a-muslim.com\/de\/dr-ali-selman-benoist-ex-katholik-frankreich\/","url_meta":{"origin":7680,"position":5},"title":"Dr. Ali Selman Benoist, Ex-Katholik, Frankreich","author":"Site Admin","date":"20 juin 2020","format":false,"excerpt":"Als Doktor der Medizin und Nachkomme einer franz\u00f6sischen katholischen Familie hat gerade meine Berufswahl mir eine solide wissenschaftliche Kultur gegeben, die mich nur wenig f\u00fcr ein mystisches Leben vorbereitet. Nicht dass ich nicht an Gott geglaubt h\u00e4tte, aber die Dogmen und Riten des Christentums im allgemeinen und insbesondere des Katholizismus\u2026","rel":"","context":"Dans &quot;WARUM WURDE ICH MUSLIM&quot;","block_context":{"text":"WARUM WURDE ICH MUSLIM","link":"https:\/\/www.ask-a-muslim.com\/de\/category\/warum-wurde-ich-muslim\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/comments?post=7680"}],"version-history":[{"count":2,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7680\/revisions"}],"predecessor-version":[{"id":11277,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/posts\/7680\/revisions\/11277"}],"wp:attachment":[{"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/media?parent=7680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/categories?post=7680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ask-a-muslim.com\/fr\/wp-json\/wp\/v2\/tags?post=7680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}